{"id":10059,"date":"2011-05-26T13:00:00","date_gmt":"2011-05-26T16:00:00","guid":{"rendered":"http:\/\/admin-canais.cancaonova.com\/eventos\/?p=10059"},"modified":"2014-08-13T05:33:57","modified_gmt":"2014-08-13T08:33:57","slug":"seguir-jesus-passa-pela-moralidade-crista","status":"publish","type":"post","link":"https:\/\/admin-canais.cancaonova.com\/eventos\/pregacoes\/seguir-jesus-passa-pela-moralidade-crista\/","title":{"rendered":"Seguir Jesus passa pela moralidade crist\u00e3"},"content":{"rendered":"<div id=\"foto\" style=\"margin: 0pt auto;padding: 5px;width: 180px;float: left\">\n<div id=\"foto\"><!--ABRE LINK DA FOTO--><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.cancaonova.com\/portal\/arquivos\/fotos\/2011\/maio\/26_eventos-007.jpg\" border=\"0\" width=\"180\" height=\"220\" \/><!--FECHA LINK DA FOTO--><\/div>\n<div id=\"texto\"><!--TEXTO DA FOTO-->Padre Donizete Heleno<!--TEXTO DA FOTO--><\/div>\n<div id=\"credito\"><!--CREDITO DA FOTO-->Foto: Maria Andr&eacute;a\/CN<!--CREDITO DA FOTO--><\/div>\n<\/div>\n<div align=\"justify\">Se n&atilde;o fizermos uma experi&ecirc;ncia profunda com o amor de Jesus, fica dif&iacute;cil viver a Sua lei, guardar Seus mandamentos. Por que estamos assistindo certa repugn&acirc;ncia ao amor de Deus? Porque as pessoas n&atilde;o experimentaram o Seu amor. Experimentar um Jesus milagreiro &eacute; muito f&aacute;cil, mas a Palavra de hoje nos convida a experimentar Cristo na Sua totalidade. <\/p>\n<p>  Jesus p&ocirc;de cumprir plenamente a vontade do Pai, porque permaneceu no amor d&#039;Ele. Isso vale tamb&eacute;m para n&oacute;s, para as pessoas que est&atilde;o ao nosso lado, dentro da nossa casa e que precisam de um encontro pessoal com o Senhor. Agora &eacute; a hora de mostrar a eles o amor do Senhor. Precisamos mostrar &agrave;s pessoas que o amor de Deus &eacute; para todos n&oacute;s.<\/p>\n<p>  Deus Pai precisa derramar sobre n&oacute;s o Seu Esp&iacute;rito, para que percamos a nossa mesquinhez. <strong>N&atilde;o imponha um fardo nas costas do seu irm&atilde;o se voc&ecirc; n&atilde;o carrega nem o seu! Aprenda a acolher o seu irm&atilde;o mesmo com as fraquezas dele. <br \/><\/strong><br \/>  A Igreja Cat&oacute;lica leva &agrave; frente a Pessoa de Cristo e O anuncia na Sua inteireza. Ela acolhe a todos, n&atilde;o deixa ningu&eacute;m de fora, a come&ccedil;ar por mim e por voc&ecirc; que somos pecadores. No Cora&ccedil;&atilde;o de Deus cabem os marginalizados, os perdidos. Aqueles que n&oacute;s colocamos para fora, Jesus coloca para dentro.<\/p>\n<p>  &ldquo;<em>Ao fim de uma grande discuss&atilde;o, Pedro levantou-se e lhes disse: Irm&atilde;os, v&oacute;s sabeis que j&aacute; h&aacute; muito tempo Deus me escolheu dentre v&oacute;s, para que da minha boca os pag&atilde;os ouvissem a palavra do Evangelho e cressem. Ora, Deus, que conhece os cora&ccedil;&otilde;es, testemunhou a seu respeito, dando-lhes o Esp&iacute;rito Santo, da mesma forma que a n&oacute;s. 9.Nem fez distin&ccedil;&atilde;o alguma entre n&oacute;s e eles, purificando pela f&eacute; os seus cora&ccedil;&otilde;es<\/em>&rdquo; (At 15,7-9).<\/p>\n<div id=\"foto\" style=\"margin: 0pt auto;padding: 5px;width: 370px;float: none\">\n<div id=\"foto\"><!--ABRE LINK DA FOTO--><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.cancaonova.com\/portal\/arquivos\/fotos\/2011\/maio\/26_eventos-008.jpg\" border=\"0\" width=\"370\" height=\"250\" \/><!--FECHA LINK DA FOTO--><\/div>\n<div id=\"texto\"><!--TEXTO DA FOTO-->&quot;Aprenda a acolher o seu irm&atilde;o mesmo com as fraquezas dele&quot;<!--TEXTO DA FOTO--><\/div>\n<div id=\"credito\"><!--CREDITO DA FOTO-->Foto: Maria Andr&eacute;a\/CN<!--CREDITO DA FOTO--><\/div>\n<\/div>\n<p>N&oacute;s achamos que s&oacute; nos temos palavras de sabedoria, s&oacute; n&oacute;s sabemos ouvir a Palavra de Deus e que apenas n&oacute;s somos iluminados. N&atilde;o. Todos podem ouvir o Senhor. A salva&ccedil;&atilde;o &eacute; uma gra&ccedil;a, &eacute; um dom divino. Sei que voc&ecirc; reza, participa da Eucaristia, mas a salva&ccedil;&atilde;o n&atilde;o &eacute; um m&eacute;rito seu, n&atilde;o &eacute; um pr&ecirc;mio por aquilo que fazemos a Deus. A salva&ccedil;&atilde;o &eacute; um dom do Senhor, do Cora&ccedil;&atilde;o d&#039;Ele. &Eacute; a gra&ccedil;a de Deus.<\/p>\n<p>  Essa mesma salva&ccedil;&atilde;o foi destinada a cada um dos membros da sua fam&iacute;lia. Nosso m&eacute;rito e nosso esfor&ccedil;o, n&oacute;s os fazemos porque precisamos. O que voc&ecirc; faz ou deixa de fazer n&atilde;o acrescenta nem tira nada de Deus, mas o fazemos porque nos aproxima dEle. O Esp&iacute;rito Santo &eacute; para todos, n&atilde;o para alguns privilegiados. O perd&atilde;o &eacute; para todos, a reconcilia&ccedil;&atilde;o em Jesus Cristo tamb&eacute;m &eacute; para todas as pessoas.<\/p>\n<p>  Voc&ecirc; foi marcado para a eternidade e pertence a Deus. Voc&ecirc; &eacute; um consagrado. <\/p>\n<p>  &ldquo;<em>Por isso, julgo que n&atilde;o se devem inquietar os que dentre os gentios se convertem a Deus. 20.Mas que se lhes escreva somente que se abstenham das carnes oferecidas aos &iacute;dolos, da impureza, das carnes sufocadas e do sangue<\/em>&rdquo; (At 15,19-20). <\/p>\n<p>  Thiago apresenta quatro prescri&ccedil;&otilde;es: n&atilde;o comer carne sacrificada aos &iacute;dolos, n&atilde;o comer carne de animais sufocados, n&atilde;o aproveitar o sangue dos animais e as uni&otilde;es ileg&iacute;timas. Por isso &eacute; importante experimentar o amor de Jesus Cristo, pois se o vivermos, n&atilde;o iremos cair nessas realidades.<\/p>\n<p>  <strong>Voc&ecirc;s est&atilde;o ouvindo, a todo momento, a press&atilde;o que a m&iacute;dia est&aacute; fazendo para aprovar leis contr&aacute;rias &agrave; dignidade humana. Mas eu quero que voc&ecirc; coloque a m&atilde;o na sua consci&ecirc;ncia e cobre do senador em quem voc&ecirc; votou uma postura crist&atilde;<\/strong>.  <strong>Seguir Jesus passa pela moralidade crist&atilde;<\/strong>. A Igreja &eacute; chamada de conservadora, e ela o &eacute;, pois conserva puramente a doutrina deixada por Jesus Cristo. Conservar &eacute; n&atilde;o tirar nada. <\/p>\n<p>  Comece, dentro da sua casa, a dar uma educa&ccedil;&atilde;o sexual para seus filhos, ensinado a eles o valor da sexualidade que eles t&ecirc;m. N&atilde;o deixe para a escola fazer isso. Acolha-os com muito amor e n&atilde;o deixe de lhes anunciar a verdade. <\/p>\n<p>  &Eacute; em Jesus que devemos colocar a nossa vida e a nossa confian&ccedil;a! <\/p>\n<p><em>Transcri&ccedil;&atilde;o e adapta&ccedil;&atilde;o: Michelle Mimoso<\/em><\/p>\n<hr \/>\n<p class=\"western\" align=\"CENTER\"><font size=\"2\"><strong>Adquira essa prega&ccedil;&atilde;o pelo telefone<span class=\"skype_pnh_print_container\"> (12) 3186-2600<\/span><span class=\"skype_pnh_container\"><span class=\"skype_pnh_mark\"> <\/span><span class=\"skype_pnh_highlighting_inactive_common\"><span class=\"skype_pnh_left_span\"><\/span><\/span><\/span><br \/><\/strong><\/font> <\/p>\n<hr \/>\n<p style=\"margin-bottom: 0cm\" class=\"western\" align=\"JUSTIFY\"><strong>Conhe&ccedil;a mais do nosso conte&uacute;do:<\/p>\n<p><\/strong><a href=\"http:\/\/www.webtvcn.com\/\" target=\"_blank\"><font color=\"#0033cc\">:: WebTVCN, muitos v&iacute;deos para voc&ecirc;<\/font><\/a><br \/><a href=\"http:\/\/gentedefe.com\/\" target=\"_blank\"><font color=\"#0033cc\">:: Gente de f&eacute;, a sua comunidade crist&atilde; de relacionamento<\/font><\/a><br \/><a href=\"http:\/\/podcast.cancaonova.com\/\" target=\"_blank\"><font color=\"#0033cc\">:: Podcasts: ou&ccedil;a &aacute;udios sobre variados assuntos<\/font><\/a><br \/><a href=\"http:\/\/paroquias.cancaonova.com\/\" target=\"_blank\"><font color=\"#0033cc\">:: Cadastre sua par&oacute;quia ou capela no Portal Can&ccedil;&atilde;o Nova<\/font><\/a><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Padre Donizete Heleno Foto: Maria Andr&eacute;a\/CN Se n&atilde;o fizermos uma experi&ecirc;ncia profunda com o amor de Jesus, fica dif&iacute;cil viver a Sua lei, guardar Seus mandamentos. Por que estamos assistindo certa repugn&acirc;ncia ao amor de Deus? Porque as pessoas n&atilde;o&#8230;<\/p>\n","protected":false},"author":114,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7],"tags":[],"modified_by":"","_links":{"self":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/10059"}],"collection":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/users\/114"}],"replies":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/comments?post=10059"}],"version-history":[{"count":1,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/10059\/revisions"}],"predecessor-version":[{"id":10060,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/10059\/revisions\/10060"}],"wp:attachment":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media?parent=10059"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/categories?post=10059"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/tags?post=10059"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}