{"id":10170,"date":"2011-11-24T20:55:00","date_gmt":"2011-11-24T23:55:00","guid":{"rendered":"http:\/\/admin-canais.cancaonova.com\/eventos\/?p=10170"},"modified":"2014-08-13T05:38:52","modified_gmt":"2014-08-13T08:38:52","slug":"mantenha-seu-espirito-nas-coisas-superiores","status":"publish","type":"post","link":"https:\/\/admin-canais.cancaonova.com\/eventos\/pregacoes\/mantenha-seu-espirito-nas-coisas-superiores\/","title":{"rendered":"Mantenha seu esp\u00edrito nas coisas superiores"},"content":{"rendered":"<div id=\"foto\" style=\"margin: 0pt auto;padding: 5px;width: 180px;float: left\">\n<div id=\"foto\"><!--ABRE LINK DA FOTO--><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.cancaonova.com\/portal\/arquivos\/fotos\/2011\/novembro\/24_eventos-005.jpg\" border=\"0\" width=\"180\" height=\"220\" \/><!--FECHA LINK DA FOTO--><\/div>\n<div id=\"texto\"><!--TEXTO DA FOTO-->Padre Crystian Shankar<!--TEXTO DA FOTO--><\/div>\n<div id=\"credito\"><!--CREDITO DA FOTO-->Foto: Maria Andr&eacute;a\/cancaonova.com<!--CREDITO DA FOTO--><\/div>\n<\/div>\n<div align=\"justify\">Como reagimos diante de um problema? A leitura de hoje &eacute; providencial &agrave; vida de quem deseja ser vitorioso. A primeira leitura de hoje fala de Daniel, um homem de f&eacute; devido &agrave; sua superioridade de esp&iacute;rito.<\/p>\n<p>  A  nossa ocupa&ccedil;&atilde;o deve manter o nosso esp&iacute;rito nas coisas superiores e n&atilde;o na mediocridade que o mundo nos ensina. Daniel n&atilde;o se perdia nas micholas desse mundo. <\/p>\n<p>  A B&iacute;blia nos ensina a ter uma fam&iacute;lia de b&ecirc;n&ccedil;&atilde;o, de autoridade e de poder. Se voc&ecirc; observa algumas fam&iacute;lias em certos programas que de &ldquo;fam&iacute;lia&rdquo; n&atilde;o mostra nada, estar&aacute; nivelando a sua por baixo. Infelizmente, h&aacute; pessoas que ainda n&atilde;o se converteram e se incomodam com o seu esp&iacute;rito superior, porque voc&ecirc; reza, vai &agrave; Missa; eles querem que voc&ecirc; se nivele por baixo como eles. Ent&atilde;o, criam situa&ccedil;&otilde;es para que voc&ecirc; seja jogado na cova dos le&otilde;es.<\/p>\n<p>  Ser&aacute; que Deus, quando olha para n&oacute;s, v&ecirc; pessoas &iacute;ntegras, irrepreens&iacute;veis? Se assim for, sairemos vitoriosos. N&atilde;o seja inocente, pois nem todas as pessoas que est&atilde;o ao seu lado e sorriem para voc&ecirc;, gostam de voc&ecirc;. A inveja corr&oacute;i e algumas pessoas t&ecirc;m o cora&ccedil;&atilde;o amargo como um fel. <\/p>\n<p>  Daniel, quando soube que o rei havia proibido a todos de rezar, voltou para sua casa, ajoelhou-se e orou a Deus. O Senhor habita no louvor, n&atilde;o na reclama&ccedil;&atilde;o. <\/p>\n<p>  Meus irm&atilde;os, n&atilde;o fale tanto de Deus, mas viva-O em sua vida. O rei, ent&atilde;o, disse a Daniel: &ldquo;Servo do Deus vivo, teu Deus, a quem prestas culto com perseveran&ccedil;a, p&ocirc;de salvar-te dos le&otilde;es?&rdquo; . O homem respondeu: &ldquo;Vida longa ao Rei! O meu Deus enviou seu anjo e fechou a boca dos le&otilde;es; os le&otilde;es n&atilde;o me fizeram mal, porque, na presen&ccedil;a dele, foi provada a minha inoc&ecirc;ncia; tampouco pratiquei qualquer crime contra ti, &oacute; rei&rdquo; (Daniel 6,21.23).<\/p>\n<p>  Muitas pessoas n&atilde;o podem eliminar voc&ecirc;, mas usam a boca para destruir a sua imagem. &Eacute; preciso que o anjo do Senhor passeie em nosso meio e cale muitas bocas, porque onde h&aacute; uma boca fofoqueira, h&aacute; um ouvido desocupado. <\/p>\n<div id=\"foto\" style=\"margin: 0pt auto;padding: 5px;width: 370px;float: none\">\n<div id=\"foto\"><!--ABRE LINK DA FOTO--><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.cancaonova.com\/portal\/arquivos\/fotos\/2011\/novembro\/24_eventos-006.jpg\" border=\"0\" width=\"370\" height=\"250\" \/><!--FECHA LINK DA FOTO--><\/div>\n<div id=\"texto\"><!--TEXTO DA FOTO-->&quot;N&atilde;o fale tanto de Deus, mas viva-O em sua vida.&quot;<!--TEXTO DA FOTO--><\/div>\n<div id=\"credito\"><!--CREDITO DA FOTO-->Foto: Maria Andr&eacute;a\/cancaonova.com<!--CREDITO DA FOTO--><\/div>\n<\/div>\n<p>  A hist&oacute;ria nos revela que Daniel foi tirado ileso da cova dos le&otilde;es e o rei se converteu. Daniel converteu o rei pela sua fidelidade, pela sua f&eacute;. Quando voc&ecirc; estiver na cova dos le&otilde;es, passe a louvar ao Senhor, pois Ele mandar&aacute; um anjo para fechar a boca de muitos le&otilde;es.<\/p>\n<p>  Nossa l&iacute;ngua pode ser um manancial de bem ou de maldi&ccedil;&atilde;o. Muitos, quando veem os problemas, param de louvar a Deus. N&atilde;o podemos ser a pessoa que joga as outras aos le&otilde;es. Se voc&ecirc; tem criado situa&ccedil;&otilde;es para que as pessoas se deem mal, voc&ecirc; n&atilde;o tem esp&iacute;rito superior.<\/p>\n<p>  N&atilde;o deixe que aquilo que n&atilde;o &eacute; divino entre na sua casa, influencie sua fam&iacute;lia. Hoje em dia, tr&ecirc;s situa&ccedil;&otilde;es s&atilde;o usadas pelo inimigo para destruir as fam&iacute;lias:<\/p>\n<p>  1 &ndash; A televis&atilde;o. Ela &eacute; boa, h&aacute; boas programa&ccedil;&otilde;es, mas quando usada para o servi&ccedil;o do mal, o dem&ocirc;nio entra na nossa casa. Voc&ecirc; colocaria Jesus ao seu lado para assistir com voc&ecirc; as coisas que voc&ecirc; v&ecirc; na TV?<\/p>\n<p>  2 &ndash; O celular. Quando mal usado, &eacute; uma arma do inimigo. N&atilde;o d&ecirc; brecha para que o inimigo use dele para destruir a sua fam&iacute;lia.<\/p>\n<p>  3 &ndash; a internet. Se usada de maneira correta, para o bem, &eacute; uma b&ecirc;n&ccedil;&atilde;o. Mas quantos filhos comentem coisas horrorosas porque conheceu algu&eacute;m pela net e saiu de casa! Ser&aacute; que isso foi da noite para o dia? N&atilde;o. Tudo come&ccedil;a pequeno, mas tende a crescer. <\/p>\n<p>  Pais e m&atilde;es, quem ama diz &#039;n&atilde;o&#039;, porque, se n&atilde;o, vai colher coisas que n&atilde;o prestam no futuro. Se voc&ecirc; quer uma fam&iacute;lia de Deus, ore e vigie para n&atilde;o cair em tenta&ccedil;&atilde;o. <\/p>\n<p>  Deus n&atilde;o perdeu o controle da hist&oacute;ria, da sua fam&iacute;lia. O nome dela est&aacute; tatuado nas palmas das m&atilde;os do Senhor. Na hora certa, veremos o Senhor reinar com gl&oacute;ria na sua casa. Aproxima-se a liberta&ccedil;&atilde;o de toda sua fam&iacute;lia. Temos de acreditar nisso, porque &eacute; Palavra de Deus.<\/p>\n<p>  Por mais problema que tenhamos, temos de nos animar, levantar a cabe&ccedil;a, porque a nossa liberta&ccedil;&atilde;o est&aacute; pr&oacute;xima.<\/p>\n<p><em>Transcri&ccedil;&atilde;o e adapta&ccedil;&atilde;o: Michelle Mimoso<\/em><\/p>\n<div align=\"center\"><font><font><font><font><font><font><font color=\"#0033cc\"><font color=\"#0033cc\"><font color=\"#0033cc\"><font color=\"#0033cc\"><font color=\"#0033cc\"><font color=\"#0033cc\"><a href=\"http:\/\/www.casanovacancaonova.com\/\" target=\"_blank\"><strong><font color=\"#0033cc\">Participe da Promo&ccedil;&atilde;o &quot;Casa Nova, Can&ccedil;&atilde;o Nova&quot;. <\/font><\/strong><font color=\"#0033cc\"><br \/><strong>Evangeliza&ccedil;&atilde;o e muitos pr&ecirc;mios para voc&ecirc; <\/strong><\/font><\/a><\/font><\/font><\/font><\/font><\/font><\/font><\/font><\/font><\/font><\/font><\/font><\/font><\/div>\n<p> <\/p>\n<hr \/>\n<p class=\"western\" align=\"CENTER\"><font size=\"2\"><strong>Adquira esta prega&ccedil;&atilde;o pelo telefone<span class=\"skype_pnh_print_container\"> (12) 3186-2600<\/span><span class=\"skype_pnh_container\"><span class=\"skype_pnh_mark\"><\/span><span class=\"skype_pnh_mark\"><\/span><\/span><br \/><\/strong><\/font> <\/p>\n<hr \/>\n<p style=\"margin-bottom: 0cm\" class=\"western\" align=\"JUSTIFY\"><strong>Veja tamb&eacute;m:<\/strong><\/p>\n<div align=\"justify\">&nbsp;<\/div>\n<div align=\"justify\"><a href=\"http:\/\/www.cancaonova.com\/portal\/canais\/eventos\/novoeventos\/cobertura.php?tit=Comunidade+Jesus+Menino+lan%E7a+CD+na+Can%E7%E3o+Nova&amp;cod=2483&amp;sob=7001\" target=\"_blank\">:: Aconteceu: Lan&ccedil;amento do CD da Comunidade Jesus Menino<\/a><\/div>\n<div align=\"justify\"><a href=\"http:\/\/tv.cancaonova.com\/conteudo_programas.php?pid=6603\" target=\"_blank\">:: Na TV programa &#039;&#039;Par&aacute;bolas de Cora&ccedil;&otilde;es Especiais&#039;&#039;<\/a><\/div>\n<div align=\"justify\"><a href=\"http:\/\/www.cancaonova.com\/portal\/canais\/eventos\/novoeventos\/cobertura.php?cod=61&amp;pre=164&amp;tit=O%20c%E9u%20come%E7a%20aqui\" target=\"_blank\">:: Conhe&ccedil;a outros membros da Comunidade Jesus Menino<\/a><\/div>\n<div align=\"justify\">&nbsp;<\/div>\n<p><strong>Conhe&ccedil;a mais do nosso conte&uacute;do:<\/strong><\/p>\n<p><a href=\"http:\/\/www.webtvcn.com\/\" target=\"_blank\"><font color=\"#0033cc\">:: WebTVCN, muitos v&iacute;deos para voc&ecirc;<\/font><\/a><br \/> <a href=\"http:\/\/gentedefe.com\/\" target=\"_blank\"><font color=\"#0033cc\">:: Gente de f&eacute;, a sua comunidade de relacionamento crist&atilde;<\/font><\/a><br \/><a href=\"http:\/\/podcast.cancaonova.com\/\" target=\"_blank\"><font color=\"#0033cc\">:: Podcasts: ou&ccedil;a &aacute;udios sobre variados assuntos<\/font><\/a><br \/><a href=\"http:\/\/paroquias.cancaonova.com\/\" target=\"_blank\"><font color=\"#0033cc\">:: Cadastre sua par&oacute;quia ou capela no Portal Can&ccedil;&atilde;o Nova<\/font><\/a><\/p>\n<p><strong>Para o seu celular:<\/strong><\/p>\n<p><a href=\"http:\/\/www.cancaonovamobile.com\/\" target=\"_blank\"><font color=\"#0033cc\">:: Can&ccedil;&atilde;o Nova Mobile<\/font><\/a><br \/><a href=\"http:\/\/cnchama.com.br\/\" target=\"_blank\"><font color=\"#0033cc\">:: CN Chama, a Palavra de Deus no seu celular<\/font><\/a><br \/><a href=\"http:\/\/iphone.cancaonova.com\/\" target=\"_blank\"><font color=\"#0033cc\">:: Iphone<\/font><\/a><\/p>\n<p><strong>Mais canais na web:<\/strong><\/p>\n<p><a href=\"http:\/\/meadiciona.com\/cancaonova\" target=\"_blank\"><font color=\"#0033cc\">:: meadiciona.com\/cancaonova<\/font><\/a><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Padre Crystian Shankar Foto: Maria Andr&eacute;a\/cancaonova.com Como reagimos diante de um problema? A leitura de hoje &eacute; providencial &agrave; vida de quem deseja ser vitorioso. A primeira leitura de hoje fala de Daniel, um homem de f&eacute; devido &agrave; sua&#8230;<\/p>\n","protected":false},"author":114,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7],"tags":[],"modified_by":"","_links":{"self":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/10170"}],"collection":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/users\/114"}],"replies":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/comments?post=10170"}],"version-history":[{"count":1,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/10170\/revisions"}],"predecessor-version":[{"id":10171,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/10170\/revisions\/10171"}],"wp:attachment":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media?parent=10170"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/categories?post=10170"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/tags?post=10170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}