{"id":10679,"date":"2010-12-05T20:29:36","date_gmt":"2010-12-05T20:29:36","guid":{"rendered":"http:\/\/hosanabrasil.cancaonova.com\/?p=1382"},"modified":"2010-12-05T20:29:36","modified_gmt":"2010-12-05T20:29:36","slug":"o-espirito-da-vitoria-as-nacoes","status":"publish","type":"post","link":"https:\/\/admin-canais.cancaonova.com\/eventos\/cobertura\/o-espirito-da-vitoria-as-nacoes\/","title":{"rendered":"'O Esp\u00edrito d\u00e1 vit\u00f3ria \u00e0s na\u00e7\u00f5es'"},"content":{"rendered":"<p><!-- \t\t@page { margin: 2cm } \t\tP { margin-bottom: 0.21cm } --><\/p>\n<div class=\"mceTemp mceIEcenter\">\n<dl id=\"attachment_1383\" class=\"wp-caption aligncenter\" style=\"width: 610px\">\n<dt class=\"wp-caption-dt\"><a href=\"http:\/\/hosanabrasil.cancaonova.com\/wp-content\/uploads\/2010\/12\/600x332-PeFabricio.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-1383\" title=\"600x332-PeFabricio\" src=\"http:\/\/hosanabrasil.cancaonova.com\/wp-content\/uploads\/2010\/12\/600x332-PeFabricio.jpg\" alt=\"\" width=\"600\" height=\"332\" \/><\/a><\/dt>\n<\/dl>\n<\/div>\n<p style=\"text-align: justify\">A liturgia rege toda a vida da Can\u00e7\u00e3o Nova, porque somos uma comunidade da Palavra, e esse Hosana vem nos coroar com uma liturgia que fala de homens que prepararam o caminho do Senhor para que as na\u00e7\u00f5es vejam a sua vit\u00f3ria. A identidade da Can\u00e7\u00e3o Nova est\u00e1 na Palavra e se alimenta dessa liturgia que hoje nos fala de tr\u00eas homens que nos apresentaram a miss\u00e3o de preparar o caminho. Est\u00e1 no cora\u00e7\u00e3o desses homens o Hosana Brasil.<\/p>\n<p style=\"text-align: justify\">O profeta Isa\u00edas anuncia acontecimentos futuros, profeta do Antigo Testamento que vem preparar o caminho do Senhor. &#8220;Naqueles dias, nascer\u00e1 uma haste do tronco de Jess\u00e9 e a partir da raiz, surgir\u00e1 o rebento de uma flor; sobre ele repousar\u00e1 o esp\u00edrito do Senhor&#8230;&#8221; Isa\u00edas 11,1-2. Jess\u00e9 \u00e9 pai do rei Davi, da\u00ed vem a linhagem de Jesus.<\/p>\n<p style=\"text-align: justify\">J\u00e1 na segunda leitura encontramos Paulo, que se apresenta como ministro de Jesus Cristo junto aos pag\u00e3os. &#8220;Quanto aos pag\u00e3os, eles glorificam a Deus, em raz\u00e3o da sua miseric\u00f3rdia, como est\u00e1 escrito: &#8216;Por isso, eu vos glorificarei entre os pag\u00e3os e cantarei louvores ao vosso nome.&#8217; &#8221; Romanos 15,9<\/p>\n<p style=\"text-align: justify\">Cantar louvores \u00e9 cantar uma can\u00e7\u00e3o nova, que glorifica a miseric\u00f3rdia do Senhor que nos visitou. Talvez voc\u00ea tenha vindo para o Hosana sem esperan\u00e7a, e a Palavra vem responder,\u00a0 quando Paulo cita Isa\u00edas, que por sua vez, diz: &#8220;Despontar\u00e1 o rebento de Jess\u00e9, para governar as na\u00e7\u00f5es. &#8220;Nele, elas colocar\u00e3o a sua esperan\u00e7a&#8221;. Aqui est\u00e1 a profecia para a uni\u00e3o das na\u00e7\u00f5es.<\/p>\n<p style=\"text-align: justify\"><strong>Os projetos humanos que excluem a presen\u00e7a do Senhor das vit\u00f3rias est\u00e3o fadados ao fracasso<\/strong>. Fora de Jesus \u00e9 ilus\u00e3o a uni\u00e3o das fam\u00edlias, da Igreja, qualquer uni\u00e3o fora de Jesus est\u00e1 fadada ao fracasso. Aqui est\u00e1 o anuncio: N\u00f3s temos um Deus de esperan\u00e7a!<\/p>\n<p style=\"text-align: justify\">No Evangelho encontramos Jo\u00e3o Batista, que est\u00e1 no meio, \u00e9 o \u00faltimo dos profetas, aquilo que Isa\u00edas anteviu na f\u00e9, Jo\u00e3o apontou: &#8220;Eis o Cordeiro de Deus.&#8221; (Jo\u00e3o 1,36). E ele nos ensina a estarmos cheios de paz, alegria e de f\u00e9.<\/p>\n<p style=\"text-align: justify\"><strong>O tempo de Isa\u00edas foi o Antigo Testamento; o tempo de Paulo foi o tempo da Igreja primitiva; o tempo de Jo\u00e3o foi das prim\u00edcias do Novo Testamento e hoje entramos num tempo novo, no qual o grande sinal n\u00e3o \u00e9 mais um batismo de convers\u00e3o anunciado por Jo\u00e3o Batista, mas um batismo no Esp\u00edrito Santo<\/strong>. Isa\u00edas foi um homem cheio do Esp\u00edrito Santo, Paulo estava repleto do Esp\u00edrito Santo e Jo\u00e3o Batista foi conduzido pelo Esp\u00edrito Santo.<\/p>\n<p style=\"text-align: justify\">N\u00f3s crist\u00e3os n\u00e3o podemos receber o Reino sem o Esp\u00edrito Santo, e Deus tem sido pr\u00f3digo no derramamento do Seu Esp\u00edrito. Que a partir de hoje voc\u00ea tenha uma abertura de cora\u00e7\u00e3o, para acolher o dom do Esp\u00edrito Santo, que nos tornar\u00e1 cheios de paz, alegria, esperan\u00e7a e f\u00e9. E n\u00e3o tem como receber o dom do Esp\u00edrito e permanecer do mesmo jeito, portanto, pe\u00e7a ao Senhor o Esp\u00edrito Santo.<\/p>\n<p style=\"text-align: justify\">E n\u00f3s hoje temos um outro profeta que, muitas vezes, perdeu a cabe\u00e7a,\u00a0 perdeu a voz, os cabelos, a sa\u00fade, se gastou, para conduzir, na simplicidade, uma multid\u00e3o, sempre em obedi\u00eancia com a Igreja: monsenhor Jonas Abib.<br \/>\n<em><br \/>\nTranscri\u00e7\u00e3o e adapta\u00e7\u00e3o: Willieny Isaias<\/em><br \/>\n<span style=\"font-family: DejaVu Sans\">\ufeff<\/span><\/p>\n<p><strong>Veja tamb\u00e9m:<\/strong><\/p>\n<p><strong> <a href=\"http:\/\/hosanabrasil.cancaonova.com\/materias\/dunga-lanca-dvd-inspirado-na-arte-urbana-durante-o-hosana-brasil-2010\/\" target=\"_blank\"><span style=\"color: #0000ff\">.:  Dunga lan\u00e7a DVD inspirado na arte urbana<\/span><\/a><\/strong><\/p>\n<p><strong><a href=\"http:\/\/hosanabrasil.cancaonova.com\/pregacao\/quebrar-as-desarmonias-interiores\/\"><span style=\"color: #0000ff\"><span style=\"color: #0000ff\">.: Quebrar as desarmonias interior, homilia do padre F\u00e1bio de Melo<\/span><\/span><\/a><span style=\"color: #0000ff\"><br \/>\n<\/span> <\/strong><\/p>\n<p><a href=\"http:\/\/hosanabrasil.cancaonova.com\/multimidia\/\" target=\"_blank\"><span style=\"color: #0000ff\"><strong>.:  V\u00eddeos e \u00e1udios exclusivos de bastidores do Hosana Brasil<\/strong><\/span><\/a><\/p>\n<p><a href=\"http:\/\/hosanabrasil.cancaonova.com\/materias\/destaque-menor\/padre-fabio-de-melo-faz-show-%e2%80%9ciluminar%e2%80%9d-no-hosana-brasil\/\" target=\"_blank\"><strong><span style=\"color: #0000ff\">.: Show com padre F\u00e1bio de Melo<\/span><\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A liturgia rege toda a vida da Can\u00e7\u00e3o Nova, porque somos uma comunidade da Palavra, e esse Hosana vem nos coroar com uma liturgia que fala de homens que prepararam o caminho do Senhor para que as na\u00e7\u00f5es vejam a&#8230;<\/p>\n","protected":false},"author":114,"featured_media":1384,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[8],"tags":[93,99,135,137,138,97],"modified_by":"","_links":{"self":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/10679"}],"collection":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/users\/114"}],"replies":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/comments?post=10679"}],"version-history":[{"count":0,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/10679\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/1384"}],"wp:attachment":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media?parent=10679"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/categories?post=10679"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/tags?post=10679"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}