{"id":11637,"date":"2006-05-11T04:00:00","date_gmt":"2006-05-11T07:00:00","guid":{"rendered":"http:\/\/admin-canais.cancaonova.com\/eventos\/?p=11637"},"modified":"2014-08-15T16:28:12","modified_gmt":"2014-08-15T19:28:12","slug":"o-que-devo-fazer-para-ter-a-vida-eterna","status":"publish","type":"post","link":"https:\/\/admin-canais.cancaonova.com\/eventos\/pregacoes\/o-que-devo-fazer-para-ter-a-vida-eterna\/","title":{"rendered":"O que devo fazer para ter a vida eterna?"},"content":{"rendered":"<p><a href=\"http:\/\/www.webhdtv.net\/eventos\/2006\/cnbb\/bispo-1.asx\"><font color=\"#0033cc\">.: Ou\u00e7a esta homilia na \u00edntegra <\/font><\/a><br \/>\n<img decoding=\"async\" src=\"http:\/\/www.cancaonova.com\/portal\/canais\/eventos\/novoeventos\/fotos\/cnbb2006\/homilia11_l.jpg\" align=\"left\">Queridos irm\u00e3os e irm\u00e3s que nos acompanham com o grande contributo das ora\u00e7\u00f5es, para que esta assembl\u00e9ia seja capaz de acolher o sopro do Esp\u00edrito, que acompanha a Igreja, ajudando-a a interpretar os sinais dos tempos, para que o Evangelho se traduza em resposta de Deus ao clamor do seu povo.<\/p>\n<p>O Tema central que esta assembl\u00e9ia est\u00e1 aprofundando \u0096 \\&#8217;A Evangeliza\u00e7\u00e3o da Juventude\\&#8217;, nos coloca como Igreja e como pastores, diante do mundo juvenil, com suas ang\u00fastias e esperan\u00e7as, suas potencialidades e fragilidades.<\/p>\n<p>Nos coloca diante da Igreja e do nosso minist\u00e9rio pastoral, nos convocando a uma profunda reflex\u00e3o, sobre nossos meios e formas, nossos m\u00e9todos e linguagem, utilizadas em nossos processos de evangeliza\u00e7\u00e3o.<\/p>\n<p>Mais que a uma reflex\u00e3o, somos chamados a uma maior proximidade do mundo juvenil, para que, a partir da pr\u00f3pria juventude, descubramos caminhos novos na evangeliza\u00e7\u00e3o, contemplando seus reais anseios e <b>apresentando-lhes a pessoa de Jesus Cristo, com seu rosto verdadeiro<\/b>, capaz de encantar e atrair, para que os jovens o conhe\u00e7am, o sigam e encontrem nele uma resposta convincente; consigam acolher uma mensagem e tornarem-se seus disc\u00edpulos.<\/p>\n<p><b>Ao falarmos da evangeliza\u00e7\u00e3o da juventude, estamos falando de 34 milh\u00f5es de jovens de 15 a 24 anos, ou seja, 20% da popula\u00e7\u00e3o brasileira. Se acrescentarmos a faixa et\u00e1ria de 25 a 29 anos, os chamados jovens adultos, passamos a 47 milh\u00f5es de jovens, distribu\u00eddos em v\u00e1rias culturas juvenis, marcados por uma extrema diversidade e manifestando as desigualdades sociais que caracterizam nossa sociedade.<\/b><\/p>\n<p>Esta \u00e9 a juventude que caminha pelo Brasil, buscando ingressar e contribuir na sociedade, lutando por seu espa\u00e7o, gritando pelos seus direitos. Juventude nem sempre ouvida, considerada e levada a s\u00e9rio.<\/p>\n<p>Uma juventude muitas vezes usada, manipulada, rotulada negativamente pelos meios de comunica\u00e7\u00e3o, mas que traz consigo imensos valores, como o entusiasmo, a coragem, a ousadia e a alegria contagiante da pr\u00f3pria juventude.<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/www.cancaonova.com\/portal\/canais\/eventos\/novoeventos\/fotos\/cnbb2006\/homilia11_c.jpg\">function open_gl(param){window.open(\\&#8217;http:\/\/200.168.231.201\/portal\/canais\/galerias\/index.php?id=\\&#8217;+param,\\&#8217;\\&#8217;,\\&#8217;width=537, height=478, toolbar=no, status=no, menubar=no, scrollbars=no, resizable=no\\&#8217;);}<b><a href=\"open_gl(2354)\"><font color=\"#0033cc\"><br \/>\n[+ fotos da celebra\u00e7\u00e3o da Santa Missa ]<\/font><\/b><\/a><br \/>\nUma juventude sempre aberta e constantemente em busca, que interpela a Igreja, como aquele jovem que de joelhos interroga Jesus: \\&#8217;Bom Mestre, que farei para alcan\u00e7ar a vida eterna?\\&#8217; (Mc 10,17).<\/p>\n<p>Jesus p\u00e1ra, acolhe aquele jovem, estabelece com ele um di\u00e1logo e lhe aponta um caminho. Jesus fixou nele o olhar, amou-o e disse-lhe: \\&#8217;uma s\u00f3 coisa te falta; vai, vende tudo o que tens e d\u00e1 aos pobres, e ter\u00e1s um tesouro no c\u00e9u; depois vem e segue-me\\&#8217;.<\/p>\n<p>A Igreja, como continuadora da miss\u00e3o de Cristo no mundo, \u00e9 chamada a essa mesma postura de Jesus, frente \u00e0 juventude: uma Igreja capaz de aproximar-se, acolher, dispon\u00edvel a uma escuta atenta, aberta a um di\u00e1logo sincero. Uma Igreja capaz de fixar seu olhar sobre a juventude, amando-a e propondo a pessoa de Jesus como um caminho seguro, capaz de responder aos anseios mais profundos da vida humana e dar um sentido amplo \u00e0 nossa exist\u00eancia.<\/p>\n<p>Cabe \u00e0 Igreja abrir-se \u00e0s interpela\u00e7\u00f5es da juventude, oferecer ao jovem uma forma\u00e7\u00e3o e acompanhamento em todas as etapas do seu caminho espiritual, para que possa fundamentar seu projeto de vida e suas op\u00e7\u00f5es, nos valores evang\u00e9licos, construindo de forma segura seu discipulado.<\/p>\n<p>Jo\u00e3o nos recorda, no Evangelho que ouvimos, a grande li\u00e7\u00e3o que Jesus deu aos disc\u00edpulos e que deixou \u00e0 Igreja, atrav\u00e9s do gesto simb\u00f3lico do lava-p\u00e9s. A Igreja nasce servidora, samaritana, enviada ao mundo para expressar atrav\u00e9s do servi\u00e7o, o amor de Deus pela humanidade, manifestado sobretudo em seu filho Jesus, que n\u00e3o veio para  ser servido, mas para servir e dar a vida (Mc 10,45).<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/www.cancaonova.com\/portal\/canais\/eventos\/novoeventos\/fotos\/cnbb2006\/homilia11_l2.jpg\" align=\"left\"><b>A evangeliza\u00e7\u00e3o \u00e9 o primeiro e grande servi\u00e7o que a Igreja deve prestar \u00e0 humanidade de todos os tempos e todas as culturas.<\/b><\/p>\n<p>Uma evangeliza\u00e7\u00e3o que se inicia em nossa capacidade de servir, que nos abre ao di\u00e1logo, que nos possibilita o an\u00fancio do Evangelho, que nos convida a sermos testemunhas de comunh\u00e3o.<\/p>\n<p>A evangeliza\u00e7\u00e3o da juventude n\u00e3o se justifica apenas pela preocupa\u00e7\u00e3o da Igreja, em aumentar os seus membros, ou garantir seu futuro. O empenho da Igreja na evangeliza\u00e7\u00e3o da juventude nasce da consci\u00eancia da pr\u00f3pria Igreja de sua miss\u00e3o evangelizadora, de sua fidelidade ao mandato recebido e pela convic\u00e7\u00e3o da riqueza presente na juventude, e que sem ela, a Igreja seria fartamente empobrecida.<\/p>\n<p>A juventude tem algo a dizer \u00e0 Igreja, e muito a contribuir, a partir daquilo que lhe \u00e9 peculiar.<\/p>\n<p>Recordamos Jo\u00e3o Paulo II, que afirmou por ocasi\u00e3o do jubileu, no encontro com a juventude: \\&#8217;Os jovens revelam-se mais uma vez, para a Igreja, um dom especial do Esp\u00edrito de Deus\\&#8217;.<\/p>\n<p>Que o Esp\u00edrito de Deus, que renova todas as coisas, que rejuvenesce a Igreja com seus dons, nos inspire nesta assembl\u00e9ia, para que possamos falar, n\u00e3o apenas sobre os jovens, mas ao cora\u00e7\u00e3o dos jovens, reafirmando como Igreja nossa op\u00e7\u00e3o por eles, abrindo o cora\u00e7\u00e3o da Igreja para acolher, dialogar, orientar e formar a juventude, ajudando-a em sua busca de felicidade, marcada muitas vezes por ambig\u00fcidades, mas sedenta dos valores aut\u00eanticos e profundos, que tem em Cristo sua plenitude.<\/p>\n<p>Que esta assembl\u00e9ia nos ajude a encontrar um jeito novo de ajudar os nossos jovens a um encontro pessoal com aquele que continua convidando: vem e segue-me. Que este apelo encontre na generosidade dos jovens a abertura para assumirem o discipulado e sua miss\u00e3o no mundo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>.: Ou\u00e7a esta homilia na \u00edntegra Queridos irm\u00e3os e irm\u00e3s que nos acompanham com o grande contributo das ora\u00e7\u00f5es, para que esta assembl\u00e9ia seja capaz de acolher o sopro do Esp\u00edrito, que acompanha a Igreja, ajudando-a a interpretar os sinais&#8230;<\/p>\n","protected":false},"author":114,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7],"tags":[],"modified_by":"","_links":{"self":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/11637"}],"collection":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/users\/114"}],"replies":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/comments?post=11637"}],"version-history":[{"count":1,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/11637\/revisions"}],"predecessor-version":[{"id":11638,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/11637\/revisions\/11638"}],"wp:attachment":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media?parent=11637"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/categories?post=11637"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/tags?post=11637"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}