{"id":11681,"date":"2006-11-18T08:00:00","date_gmt":"2006-11-18T11:00:00","guid":{"rendered":"http:\/\/admin-canais.cancaonova.com\/eventos\/?p=11681"},"modified":"2014-08-15T16:30:11","modified_gmt":"2014-08-15T19:30:11","slug":"tomar-posse-do-que-sou","status":"publish","type":"post","link":"https:\/\/admin-canais.cancaonova.com\/eventos\/pregacoes\/tomar-posse-do-que-sou\/","title":{"rendered":"Tomar posse do que sou"},"content":{"rendered":"<p><font size=\"2\" color=\"#999999\"><strong><a href=\"http:\/\/www.webhdtv.net\/eventos\/2006\/festival_artes\/hom_pecleidimar171106_2.asx\" target=\"_blank\"><\/a><\/strong><\/font><font size=\"2\" color=\"#999999\"><strong><a href=\"http:\/\/www.webhdtv.net\/eventos\/2006\/festival_artes\/hom_pecleidimar171106_2.asx\" target=\"_blank\"><\/a><\/p>\n<p align=\"center\"><a href=\"http:\/\/www.webhdtv.net\/eventos\/2006\/festival_artes\/homilia_inteirapefabio_181106.asx\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.cancaonova.com\/cnova\/ministerio\/materias\/images\/03eos300d.jpg\" border=\"0\" width=\"72\" height=\"22\" \/><\/a>Confira, na &iacute;ntegra,&nbsp;<a href=\"http:\/\/www.webhdtv.net\/eventos\/2006\/festival_artes\/homilia_inteirapefabio_181106.asx\" title=\"homilia\"><font size=\"2\" color=\"#3300cc\"><strong>homilia<\/strong><\/font><\/a><font size=\"2\" color=\"#999999\"><strong> presidida<br \/>por Padre F&aacute;bio de Melo<\/strong><\/font> <\/p>\n<p><\/strong><\/font><\/p>\n<hr \/>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.cancaonova.com\/portal\/canais\/eventos\/novoeventos\/fotos\/festival_artes_2006\/missa_sab_pefabio2.jpg\" border=\"0\" width=\"200\" height=\"200\" align=\"left\" \/>O homem e a mulher que traz a arte em si &eacute; como uma &lsquo;faca de dois gumes&rsquo;. Sejamos sinceros, n&oacute;s n&atilde;o somos muito normais. Vivemos sonhando, somos f&aacute;cil de sair do discurso concreto para o sonho. Meu corpo esta andando e minha mente est&aacute; parada &lsquo;sonhando&rsquo;. <\/p>\n<p>O artista tem o seu caminho. N&atilde;o somos melhores, somos diferentes. A Igreja precisa descobrir como tocar o cora&ccedil;&atilde;o do artista, porque tem um jeito diferente de ser e precisar ser cuidado. O rom&acirc;ntico, por exemplo,&nbsp;tem o risco de passar a vida sem viver porque sonha tanto que deixa a vida passar. <\/p>\n<p>Voc&ecirc; j&aacute; viu quando a inveja toma conta de n&oacute;s e achamos que o outro &eacute; melhor?&nbsp; &Eacute; um risco que o artista tem e o leva a cair. Ele precisa tomar posse daquilo que &eacute;, porque se n&atilde;o se vive isso, n&atilde;o &eacute; vida. <br \/>Ser pessoa &eacute; dispor-se de si e depois dispor-se para o outro. S&oacute; pode ser dispon&iacute;vel quem se disp&otilde;e de si. <\/p>\n<p>Convers&atilde;o &eacute; tomar posse daquilo que se &eacute;. Por isso, Deus n&atilde;o pode trabalhar com uma pessoa mascarada, que n&atilde;o se aceita. Ser pessoa &eacute; antes de tudo&nbsp;ter concie&ecirc;ncia:&nbsp;&ldquo;Eu sei quem sou eu. Tenho diante de mim minhas dificuldades, mas eu me aceito!&#039;<br \/>N&atilde;o existe crist&atilde;o que n&atilde;o se aceita do jeito que se &eacute;. Voc&ecirc; &eacute; o que voc&ecirc; &eacute;, e a sua convers&atilde;o passar&aacute; por aquilo que voc&ecirc; &eacute;! <br \/>Eu tomo posse daquilo que sou. <\/p>\n<p>Jesus quando viu Maria Madalena, Ele fez com que a aquela mulher voltasse a ver aquilo que ela era, n&atilde;o uma prostituta, mas uma filha de Deus projetada por Ele, e n&atilde;o aquilo que a sociedade criou. <br \/>N&oacute;s ca&iacute;mos muito nos artif&iacute;cios que nos s&atilde;o apresentados. Nossa vida se ilumina por novidades e gostamos muito do est&eacute;tico, e seguimos aquilo que &eacute; diferen&ccedil;a, n&atilde;o somos f&atilde; da disciplina. <br \/>Corremos atr&aacute;s de coisas e duas semanas depois vemos que realmente aquilo n&atilde;o &eacute; t&atilde;o bom como parecia.<br \/>Por que os artistas n&atilde;o &#039;duram&#039; muito nos casamentos? &Eacute; por causa disso. Querem respostas r&aacute;pidas, rom&acirc;nticas, buscam o brilho eterno e acabam desanimando. Ent&atilde;o, o outro come&ccedil;a a decidir por n&oacute;s e ficamos perdidos. Muitas pessoas, ora&nbsp;d&atilde;o um testemunho que acredita em Deus, e passado um tempo&nbsp;depois, j&aacute;&nbsp; dizem acreditar em Buda, depois Maom&eacute;, na energia&#8230; N&atilde;o ficam presos em nada. <\/p>\n<p>Cuidado em seguir somente as vaidades, esse neg&oacute;cio de usar uma blusa com uma imagem crist&atilde; ou uma cruz, mas tudo por vaidade. Sim, n&oacute;s artistas somos vaidosos, mas n&atilde;o podemos ser levados pela vaidade. N&atilde;o invente um personagem, seja aquilo que voc&ecirc; &eacute;. Seja aut&ecirc;ntico, assim voc&ecirc; provoca autenticidade nas pessoas a seu redor. <br \/>Eu s&oacute; posso ser padre na verdade, n&atilde;o posso pedir para que as pessoas finjam para que assim eu goste delas. <\/p>\n<p>Entre o que os outros imaginam e o que Deus fez eu prefiro ser o que Deus fez. Deus n&atilde;o vem plantar a sua floresta mas Ele te d&aacute; uma semente e voc&ecirc; que vai plantar.&nbsp;Procure ser aquilo que Deus te fez. Se voc&ecirc; est&aacute; correndo atr&aacute;s de porcaria cuidado para n&atilde;o acabar deixando de ser aquilo que Deus fez. N&atilde;o corra atr&aacute;s de porcaria, isso &eacute; a maior arte. A arte de ser aquilo que n&oacute;s somos requer arte. <\/p>\n<p><em>&ldquo;N&atilde;o sou perfeito, mas estou correndo atr&aacute;s daquilo que sou&rdquo;.<\/em> <\/p>\n<p>Deus acontece plenamente no cora&ccedil;&atilde;o quando n&oacute;s permitimos ser aquilo que n&oacute;s somos. A nossa divindade s&oacute; acontece na participa&ccedil;&atilde;o. <br \/>Deus &eacute; tudo para mim! Retire-me o Evangelho e eu n&atilde;o sei mais para onde olhar. Se tira-me da mira de&nbsp;tudo aquilo que eu considero santo e sagrado, eu passo a n&atilde;o conhecer mais&nbsp;minha pr&oacute;pria identidade. Isso &eacute; humano e divino. Apaixone-se por voc&ecirc;. N&atilde;o seja aquilo que dizem que voc&ecirc; &eacute;. Parece estranho, mas n&atilde;o podemos dar aquilo que n&atilde;o temos. <\/p>\n<p><\/p>\n<div style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.cancaonova.com\/portal\/canais\/eventos\/novoeventos\/fotos\/festival_artes_2006\/missa_sab_pefabio1.jpg\" border=\"0\" width=\"370\" height=\"210\" \/><\/div>\n<p>Se voc&ecirc; n&atilde;o descobrir que voc&ecirc; &eacute; sagrado, voc&ecirc; n&atilde;o vai perceber a sacralidade que o outro &eacute;! <\/p>\n<p>Ou voc&ecirc; vive no amor por voc&ecirc; ou voc&ecirc; n&atilde;o sabe o que &eacute; o amor de Deus. Quem n&atilde;o se ama n&atilde;o sabe amar ningu&eacute;m. &Eacute; uma pessoa ausente de si mesmo. Os amores estragados que passaram minou aquilo que se era. <br \/>Tem pessoas que vemos que n&atilde;o tem amor pr&oacute;prio, e voc&ecirc; n&atilde;o tem o direito de perder esse amor. <\/p>\n<p>O homem e a mulher que se ama o diabo n&atilde;o tem vez. Quem se ama n&atilde;o traz v&iacute;cios para si mesmo porque se ama!<br \/>Por que me drogar? Eu me amo n&atilde;o caio nisso! N&atilde;o &eacute; poss&iacute;vel uma pessoa se amar e se destruir. <br \/>Tome posse do que voc&ecirc; &eacute; para depois&nbsp;dar-se ao outro. Seja o que voc&ecirc; &eacute; mesmo que pare&ccedil;a feio, &lsquo;n&oacute;s damos um banho na lama e vai sobrar um diamante lindo&rsquo;. <\/p>\n<p>Que o seu teatro desperte verdade, a verdade daquilo que n&oacute;s somos que nos prenda a Deus, porque s&oacute; quem &eacute; preso em Deus &eacute; livre no mundo, e &eacute; isso que eu gostaria que voc&ecirc; fosse. <\/p>\n<p><\/p>\n<div align=\"center\">\n<hr \/>\n<\/div>\n<p align=\"center\"><strong><font size=\"2\" color=\"#666666\">Adquira&nbsp;essa palestra&nbsp;atrav&eacute;s do<br \/>(12) 3186 2600<\/font><\/strong> <em><\/p>\n<div align=\"center\">\n<hr \/>\n<\/div>\n<p><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Confira, na &iacute;ntegra,&nbsp;homilia presididapor Padre F&aacute;bio de Melo O homem e a mulher que traz a arte em si &eacute; como uma &lsquo;faca de dois gumes&rsquo;. Sejamos sinceros, n&oacute;s n&atilde;o somos muito normais. Vivemos sonhando, somos f&aacute;cil de sair do&#8230;<\/p>\n","protected":false},"author":114,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7],"tags":[],"modified_by":"","_links":{"self":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/11681"}],"collection":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/users\/114"}],"replies":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/comments?post=11681"}],"version-history":[{"count":1,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/11681\/revisions"}],"predecessor-version":[{"id":11682,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/11681\/revisions\/11682"}],"wp:attachment":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media?parent=11681"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/categories?post=11681"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/tags?post=11681"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}