{"id":11968,"date":"2007-02-18T06:25:00","date_gmt":"2007-02-18T09:25:00","guid":{"rendered":"http:\/\/admin-canais.cancaonova.com\/eventos\/?p=11968"},"modified":"2014-08-15T16:40:26","modified_gmt":"2014-08-15T19:40:26","slug":"manifestacao-do-amor-de-deus-2","status":"publish","type":"post","link":"https:\/\/admin-canais.cancaonova.com\/eventos\/pregacoes\/manifestacao-do-amor-de-deus-2\/","title":{"rendered":"Manifesta\u00e7\u00e3o do amor de Deus"},"content":{"rendered":"<p align=\"justify\">O que aconteceu conosco nesta ora&ccedil;&atilde;o da manh&atilde; foi o que est&aacute; escrito em 1 Cor 2,4: &quot;A minha palavra e a minha prega&ccedil;&atilde;o longe estavam da eloq&uuml;&ecirc;ncia persuasiva da sabedoria; eram, antes, uma demonstra&ccedil;&atilde;o do Esp&iacute;rito e do poder divino, para que vossa f&eacute; n&atilde;o se baseasse na sabedoria dos homens, mas no poder de Deus&quot;.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.cancaonova.com\/portal\/canais\/eventos\/novoeventos\/fotos\/2007\/carnaval\/dom_preg1_pjonas01.jpg\" border=\"0\" width=\"150\" height=\"216\" align=\"left\" \/>Deus usou padre Jos&eacute; Augusto em manifesta&ccedil;&atilde;o do poder do Esp&iacute;rito. <br \/>Isso tamb&eacute;m retrata o que est&aacute; no in&iacute;cio desta mesma carta de S&atilde;o Paulo aos cor&iacute;ntios. <\/p>\n<p><strong><a href=\"http:\/\/cancaonova2.hdtvweb.net\/eventos\/carnaval\/preg_pejonas18022007-1-1.wma\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.cancaonova.com\/cnova\/ministerio\/materias\/images\/03eos300d.jpg\" border=\"0\" width=\"72\" height=\"22\" align=\"left\" \/><\/a><a href=\"http:\/\/cancaonova2.hdtvweb.net\/eventos\/carnaval\/preg_pejonas18022007-1-1.wma\" target=\"_blank\"><font color=\"#0033cc\">Ou&ccedil;a: &quot;N&atilde;o nos falta DOM algum&quot;<br \/><\/font><\/a><\/strong><br \/>Algumas pessoas pensam que os dons do Esp&iacute;rito Santo s&atilde;o para algumas pessoas muito especiais, muito escolhidas, muito santas. N&oacute;s tamb&eacute;m nos acostumamos a ver os dons do Esp&iacute;rito Santo na vida dos santos. Vimos dons de milagres, cura, profecia e pensamos que foi pela grande santidade deles, como pr&ecirc;mios. <\/p>\n<p>Mas quem nos santifica n&atilde;o somos n&oacute;s. N&atilde;o &eacute; como o povo diz de que quem &eacute; santo j&aacute; nasce santo. Quem faz essa santifica&ccedil;&atilde;o &eacute; Deus. <\/p>\n<p>Corinto era uma cidade portu&aacute;ria do imp&eacute;rio romano. Na movimenta&ccedil;&atilde;o de marinheiros, a prostitui&ccedil;&atilde;o era uma coisa terr&iacute;vel. Havia bebidas alucinantes que equivaliam &agrave;s drogas. A cidade tornou-se alucinante. Quando Deus mandou Paulo para l&aacute;, ele tremeu na base. Ele estava resistindo, mas foi d&oacute;cil e obedeceu a Deus.<\/p>\n<p>Se Deus disse para ele n&atilde;o ter medo, &eacute; porque ele estava cheio de medo (Atos 18,9). Ele estava inibido, n&atilde;o tinha coragem nenhuma de falar. J&aacute; fazia bastante tempo que ele estava pregando e Jesus teve que dizer a ele: <strong>&quot;Fala e n&atilde;o te cales, porque eu estou contigo. Ningu&eacute;m se aproximar&aacute; de ti para te fazer mal, pois tenho um numeroso povo nesta cidade&quot;<\/strong>.<\/p>\n<p>Paulo usa os dons de profecias, de milagres. At&eacute; ressurrei&ccedil;&atilde;o Deus concedeu que ele realizasse. Aquele aleijado que Paulo mandou levantar, aquele jovem que caiu da janela e ele ressuscitou, era uma demonstra&ccedil;&atilde;o do poder de Deus. Ele pregava em cima dos dons. Era esse o m&eacute;todo de Paulo. Mas quando ele chegou a Corinto, estava cheio de medo.<\/p>\n<div align=\"justify\" style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.cancaonova.com\/portal\/canais\/eventos\/novoeventos\/fotos\/2007\/carnaval\/dom_preg1_pjonas02.jpg\" border=\"0\" width=\"380\" height=\"161\" \/><\/div>\n<p align=\"justify\">H&aacute; pessoas que zombam, gozam e se p&otilde;em contra voc&ecirc;. N&atilde;o precisa uma Corinto n&atilde;o, mas talvez seja dentro de sua casa. Mas o Senhor est&aacute; declarando: &quot;Ele me pertence! Ela me pertence!&rdquo; J&aacute; na sua casa, Deus est&aacute; dizendo: &ldquo;N&atilde;o temas! Fala e n&atilde;o te cales&quot;. E se voc&ecirc; n&atilde;o pode falar e n&atilde;o seja mais importante falar, reza, cria calos nos joelhos se for preciso. Vai fazer adora&ccedil;&atilde;o, vai l&aacute; ao quarto dele ou dela e canta em l&iacute;nguas por ele ou ela.<\/p>\n<p>At&eacute; voc&ecirc;, mulher, seu marido est&aacute; ali na mesma cama com voc&ecirc; e &eacute; muito f&aacute;cil voc&ecirc; impostar a m&atilde;o sobre ele e orar em l&iacute;nguas. A Palavra de Deus nos diz que n&oacute;s n&atilde;o sabemos o que pedir e como pedir, mas o Esp&iacute;rito sabe e ora em n&oacute;s com gemidos inef&aacute;veis, ora segundo a vontade do Pai e de Jesus.<\/p>\n<p><strong><a href=\"http:\/\/cancaonova2.hdtvweb.net\/eventos\/carnaval\/preg_pejonas18022007-1-1.wma\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.cancaonova.com\/cnova\/ministerio\/materias\/images\/03eos300d.jpg\" border=\"0\" width=\"72\" height=\"22\" align=\"left\" \/><\/a><a href=\"http:\/\/cancaonova2.hdtvweb.net\/eventos\/carnaval\/preg_pejonas18022007-2-1.wma\" target=\"_blank\"><font color=\"#0033cc\">Ou&ccedil;a: &quot;Dom de l&iacute;nguas n&atilde;o fomos n&oacute;s que inventamos&quot;<\/font><\/a><\/strong><\/p>\n<p>Debochar de um dom de Deus &eacute; um sacril&eacute;gio.<strong> Dom de l&iacute;nguas n&atilde;o fomos n&oacute;s que inventamos.<\/strong> Est&aacute; na B&iacute;blia. &Eacute; ineg&aacute;vel. Esse dom n&atilde;o &eacute; brincadeira, &eacute; de Deus. <\/p>\n<p>A partir daquele derramamento do Esp&iacute;rito Santo h&aacute; 40 anos atr&aacute;s, no dias 17 a 19 de fevereiro, v&aacute;rios daqueles jovens come&ccedil;aram a orar em l&iacute;nguas. Em v&aacute;rias partes do mundo j&aacute; se ora assim.<\/p>\n<p>Negar o dom de l&iacute;nguas &eacute; negar uma evid&ecirc;ncia. Zombar desse dom &eacute; um sacril&eacute;gio. Deus, sabendo que n&atilde;o sabemos o que e como orar, nos d&aacute; o dom de l&iacute;nguas. <br \/>Voc&ecirc; precisa come&ccedil;ar a soltar a sua l&iacute;ngua, a soltar os seus l&aacute;bios. Voc&ecirc; d&aacute; a partida. O dom da partida &eacute; dom de l&iacute;nguas. <\/p>\n<p><strong>Ore em l&iacute;nguas pelo seu marido.<\/strong> <\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.cancaonova.com\/portal\/canais\/eventos\/novoeventos\/fotos\/2007\/carnaval\/dom_preg1_pjonas03.jpg\" border=\"0\" width=\"150\" height=\"140\" align=\"right\" \/>Diga: &quot;Eu vou usar os dons do Esp&iacute;rito Santo na minha &#039;Corinto&#039;&quot;. E se voc&ecirc;, meu irm&atilde;o, &eacute; uma &quot;Corinto&quot;, v&aacute; buscar primeiro o batismo no Esp&iacute;rito Santo, porque Deus faz coisas maravilhosas. Foi pelo batismo no Esp&iacute;rito que muita gente se converteu. <\/p>\n<p>Quando eu recebi o batismo no Esp&iacute;rito, eu n&atilde;o entendi, mas Deus foi t&atilde;o bom comigo que eu quis do fundo do meu cora&ccedil;&atilde;o. Eu pedi assim: &quot;Senhor, &eacute; isso que eu preciso. Ent&atilde;o, me d&aacute;&quot;. Naquele dia mesmo, de tardezinha, Deus me deu. Eu percebi que a ora&ccedil;&atilde;o brotava de dentro de mim. At&eacute; mesmo a minha prega&ccedil;&atilde;o mudou. O que acontece comigo &eacute; conseq&uuml;&ecirc;ncia da gra&ccedil;a que eu recebi. Eu sou apenas um &quot;alto-falante&quot;.<\/p>\n<p>Eu estou pedindo, Senhor, que cada um desses que est&atilde;o me acompanhando por cada um destes meios, queira do fundo do cora&ccedil;&atilde;o. E isto quem d&aacute; &eacute;s Tu, Senhor, &eacute; uma gra&ccedil;a tua. E eu sei que o Senhor quer dar. <\/p>\n<p>Deus d&aacute; para aqueles precisam. Justamente porque meus irm&atilde;os pedem e precisam, o Senhor vai nos usar nesse ou naquele dom, mas no dom de l&iacute;nguas o Senhor vai nos usar sempre. D&aacute; o dom l&iacute;nguas a cada um desses meus irm&atilde;os e irm&atilde;s. Que eles sejam o&aacute;sis de amor.<\/p>\n<p>E n&oacute;s sabemos que tudo pode ser mudado pela ora&ccedil;&atilde;o. Senhor, tudo &eacute; poss&iacute;vel para aquele que cr&ecirc; e tudo pode ser mudado pela ora&ccedil;&atilde;o.<\/p>\n<p><strong><a href=\"http:\/\/cancaonova2.hdtvweb.net\/eventos\/carnaval\/preg_pejonas18022007-3-1.wma\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.cancaonova.com\/cnova\/ministerio\/materias\/images\/03eos300d.jpg\" border=\"0\" width=\"72\" height=\"22\" align=\"left\" \/><\/a><a href=\"http:\/\/cancaonova2.hdtvweb.net\/eventos\/carnaval\/preg_pejonas18022007-3-1.wma\" target=\"_blank\"><font color=\"#0033cc\">Ou&ccedil;a: Padre Jonas reza clamando o batismo no Esp&iacute;rito Santo<\/font><\/a><\/strong><\/p>\n<p><em>Transcri&ccedil;&atilde;o: Maur&iacute;cio Rebou&ccedil;as<br \/>Fotos: Lucilene Silva<\/p>\n<div align=\"justify\"><strong><font size=\"2\"><\/p>\n<hr \/>\n<p><\/font><\/strong><\/div>\n<div align=\"center\"><strong><font size=\"2\">Adquira essa prega&ccedil;&atilde;o pelo telefone:<br \/>(12) 3186-2600<\/font><\/strong><font color=\"#0033ff\"> <\/font><\/div>\n<p><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O que aconteceu conosco nesta ora&ccedil;&atilde;o da manh&atilde; foi o que est&aacute; escrito em 1 Cor 2,4: &quot;A minha palavra e a minha prega&ccedil;&atilde;o longe estavam da eloq&uuml;&ecirc;ncia persuasiva da sabedoria; eram, antes, uma demonstra&ccedil;&atilde;o do Esp&iacute;rito e do poder&#8230;<\/p>\n","protected":false},"author":114,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7],"tags":[],"modified_by":"","_links":{"self":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/11968"}],"collection":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/users\/114"}],"replies":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/comments?post=11968"}],"version-history":[{"count":1,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/11968\/revisions"}],"predecessor-version":[{"id":11969,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/11968\/revisions\/11969"}],"wp:attachment":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media?parent=11968"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/categories?post=11968"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/tags?post=11968"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}