{"id":12832,"date":"2011-10-15T13:00:00","date_gmt":"2011-10-15T16:00:00","guid":{"rendered":"http:\/\/admin-canais.cancaonova.com\/eventos\/?p=12832"},"modified":"2014-08-15T17:22:04","modified_gmt":"2014-08-15T20:22:04","slug":"a-paciencia-tudo-alcanca-4","status":"publish","type":"post","link":"https:\/\/admin-canais.cancaonova.com\/eventos\/pregacoes\/a-paciencia-tudo-alcanca-4\/","title":{"rendered":"A paci\u00eancia tudo alcan\u00e7a"},"content":{"rendered":"<div id=\"foto\" style=\"width: 180px;margin: 0pt auto;padding: 5px;float: left\">\n<div id=\"foto\"><!--ABRE LINK DA FOTO--><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.cancaonova.com\/portal\/arquivos\/fotos\/2011\/outubro\/15_eventos-011.jpg\" border=\"0\" width=\"180\" height=\"220\" \/><!--FECHA LINK DA FOTO--><\/div>\n<div id=\"texto\"><!--TEXTO DA FOTO-->   \t \t \t \t \t<!-- \t\t@page { margin: 2cm } \t\tP { margin-bottom: 0.21cm } \t--><font color=\"#000000\">Dom Irineu Danelon<\/font> <!--TEXTO DA FOTO--><\/div>\n<div id=\"credito\"><!--CREDITO DA FOTO-->Foto: Maria Andrea<!--CREDITO DA FOTO--><\/div>\n<\/div>\n<p> <font color=\"#000000\">N&oacute;s geralmente temos a no&ccedil;&atilde;o de que santos s&atilde;o aqueles que protegem a gente, eles tamb&eacute;m exercem esta fun&ccedil;&atilde;o, mas principalmente devemos olhar para um santo e pelo seu testemunho de vida&nbsp; buscar imit&aacute;-los. Santa Tereza de &Aacute;vila dizia: &ldquo;S&oacute; Deus basta&rdquo;. Ela colocou Deus como ponto alto na sua vida e dizia muito da viv&ecirc;ncia da paci&ecirc;ncia. Portanto vou falar um pouco sobre a paci&ecirc;ncia. <\/p>\n<p> O que ser&aacute; da pastoral da sobriedade sem a paci&ecirc;ncia? Santo &eacute; aquele que tamb&eacute;m cai, mas sempre se levanta. Deus perdoa a todos porque compreende cada um de n&oacute;s. Conhecemos v&aacute;rios dependentes qu&iacute;micos que nos irritavam ao vender tudo para comprar drogas, mas at&eacute; nesses momentos precisamos dizer: &quot;Paci&ecirc;ncia&quot;. A paci&ecirc;ncia nos ensina a corrigir as pessoas no momento adequado e da forma adequada. A paci&ecirc;ncia aguarda o momento da corre&ccedil;&atilde;o, mas n&atilde;o dispensa a corre&ccedil;&atilde;o.<\/p>\n<p> Um certo dia ouvi esta frase de um amigo: &quot;Procure me amar mais quando menos mere&ccedil;o, pois &eacute; quando mais preciso&quot;. Nos &eacute; necess&aacute;rio viver isso, pois &eacute; ai que tamb&eacute;m exercitamos a paci&ecirc;ncia para com os outros, sendo muitas vezes sustento em tempos dif&iacute;ceis. <br \/><\/font><\/p>\n<p><font color=\"#000000\"> &ldquo;Use a raz&atilde;o e n&atilde;o o bast&atilde;o&rdquo;, dizia Dom Bosco. Explique e seja sempre coerente.<\/p>\n<p> Atrav&eacute;s da sua paci&ecirc;ncia voc&ecirc; vai possuir a sua vida. Quem tem paci&ecirc;ncia tem produtividade na vida.<\/p>\n<p> Santa Tereza dizia &ldquo;A paci&ecirc;ncia tudo alcan&ccedil;a&rdquo;. Vamos pedir a intercess&atilde;o dela para que nada nos perturbe.<\/font><\/p>\n<div id=\"foto\" style=\"width: 370px;margin: 0pt auto;padding: 5px;float: none\">\n<div id=\"foto\"><!--ABRE LINK DA FOTO--><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.cancaonova.com\/portal\/arquivos\/fotos\/2011\/outubro\/15_eventos-009.jpg\" border=\"0\" width=\"370\" height=\"250\" \/><!--FECHA LINK DA FOTO--><\/div>\n<div id=\"texto\"><!--TEXTO DA FOTO-->&quot;A paci&ecirc;ncia tudo alcan&ccedil;a&quot; Dom Irineu Danelon<!--TEXTO DA FOTO--><\/div>\n<div id=\"credito\"><!--CREDITO DA FOTO-->Foto: Maria Andrea<!--CREDITO DA FOTO--><\/div>\n<\/div>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dom Irineu Danelon Foto: Maria Andrea N&oacute;s geralmente temos a no&ccedil;&atilde;o de que santos s&atilde;o aqueles que protegem a gente, eles tamb&eacute;m exercem esta fun&ccedil;&atilde;o, mas principalmente devemos olhar para um santo e pelo seu testemunho de vida&nbsp; buscar imit&aacute;-los&#8230;.<\/p>\n","protected":false},"author":114,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7],"tags":[],"modified_by":"","_links":{"self":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/12832"}],"collection":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/users\/114"}],"replies":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/comments?post=12832"}],"version-history":[{"count":1,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/12832\/revisions"}],"predecessor-version":[{"id":12833,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/12832\/revisions\/12833"}],"wp:attachment":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media?parent=12832"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/categories?post=12832"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/tags?post=12832"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}