{"id":12843,"date":"2012-10-26T17:00:00","date_gmt":"2012-10-26T20:00:00","guid":{"rendered":"http:\/\/admin-canais.cancaonova.com\/eventos\/?p=12843"},"modified":"2014-08-15T17:22:19","modified_gmt":"2014-08-15T20:22:19","slug":"deus-pode-renovar-a-nossa-vida-pela-fe-2","status":"publish","type":"post","link":"https:\/\/admin-canais.cancaonova.com\/eventos\/pregacoes\/deus-pode-renovar-a-nossa-vida-pela-fe-2\/","title":{"rendered":"Deus pode renovar a nossa vida pela f\u00e9"},"content":{"rendered":"<div id=\"foto\" style=\"width: 180px;margin: 0px auto;padding: 0px 5px 0px 0px;float: left\">\n<div id=\"foto\"><!--ABRE LINK DA FOTO--><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.cancaonova.com\/portal\/arquivos\/fotos\/2012\/outubro\/26_domirineudanelon-001.jpg\" border=\"0\" width=\"180\" height=\"220\" \/><!--FECHA LINK DA FOTO--><\/div>\n<div id=\"texto\"><!--TEXTO DA FOTO-->Dom Irineu Danelon<!--TEXTO DA FOTO--><\/div>\n<div id=\"credito\"><!--CREDITO DA FOTO-->Foto: Natalino Ueda\/Cancaonova.com<!--CREDITO DA FOTO--><\/div>\n<\/div>\n<p>  N&oacute;s estamos come&ccedil;ando o &ldquo;Ano da f&eacute;&rdquo;.  Quando lemos a b&iacute;blia, temos que l&ecirc;-la com f&eacute;, ou seja, Deus est&aacute; falando conosco atrav&eacute;s de sua Palavra e precisamos dar a Ele uma resposta.<\/p>\n<p>  <strong>Precisamos viver de f&eacute;<\/strong>, e a Pastoral da Sobriedade, coloca f&eacute; naquilo que as pessoas podem vir a ser, mas ainda n&atilde;o s&atilde;o. Com cuidado e carinho podem se transformar. Pois, Jesus disse: <em>&ldquo;Eis que fa&ccedil;o nova todas as coisas.&rdquo;<\/em><\/p>\n<p>  Eu usava &oacute;culos desde os 15 anos. Certo dia, fui ao oculista e ele me disse que eu estava com catarata. Fez uma opera&ccedil;&atilde;o e agora posso ver com perfei&ccedil;&atilde;o. Ent&atilde;o, <strong>se o m&eacute;dico pode renovar a  minha vista, Deus pode transformar a nossa vida! <\/strong>Voc&ecirc; acreditar nisso? S&oacute; o fato de acreditar, j&aacute; &eacute; um ato de f&eacute;.  Mas, se eu pude recuperar a minha vista, eu que tinha seis graus de miopia e catarata, se o m&eacute;dico conseguiu fazer isso,<strong> Deus  certamente &eacute; capaz de fazer coisas muito maiores e melhores que esta.<\/strong><\/p>\n<div id=\"foto\" style=\"width: 370px;margin: 0px auto;padding: 5px 0px;float: none\">\n<div id=\"foto\"><!--ABRE LINK DA FOTO--><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.cancaonova.com\/portal\/arquivos\/fotos\/2012\/outubro\/26_domirineudanelon-002.jpg\" border=\"0\" width=\"370\" height=\"250\" \/><!--FECHA LINK DA FOTO--><\/div>\n<div id=\"texto\"><!--TEXTO DA FOTO-->&quot;Quem n&atilde;o tem f&eacute;, n&atilde;o &eacute; capaz de acreditar na recupera&ccedil;&atilde;o da pessoas&quot; afirma Dom Irineu Danelon<!--TEXTO DA FOTO--><\/div>\n<div id=\"credito\"><!--CREDITO DA FOTO-->Foto: Natalino Ueda\/Cancaonova.com<!--CREDITO DA FOTO--><\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<p style=\"margin: 0px;padding: 0px;color: #000000;font-family: Verdana,Arial,Helvetica,sans-serif;font-size: 10px;font-style: normal;font-variant: normal;font-weight: normal;letter-spacing: normal;line-height: normal;text-indent: 0px;background-color: #ffffff\" align=\"center\"><a href=\"http:\/\/www.flickr.com\/photos\/cancaonova\/sets\/72157631860661254\/\" target=\"_blank\"><em style=\"color: #5a5a5a;font-family: Verdana,Arial,Helvetica,sans-serif;font-size: 10px;font-variant: normal;font-weight: normal;letter-spacing: normal;line-height: normal;text-align: justify;text-indent: 0px;background-color: #ffffff\"><span style=\"color: #5a5a5a;text-decoration: none\"><font color=\"#000000\"><strong><font color=\"#0033cc\">Veja + fotos no Flick<\/font><font color=\"#ff00cc\">r<\/font><\/strong><\/font><\/span><\/em><\/a><\/p>\n<p><em style=\"color: #5a5a5a;font-family: Verdana,Arial,Helvetica,sans-serif;font-size: 10px;font-variant: normal;font-weight: normal;letter-spacing: normal;line-height: normal;text-align: justify;text-indent: 0px;background-color: #ffffff\"><\/p>\n<p style=\"margin: 0px;padding: 0px;color: #000000;font-family: Verdana,Arial,Helvetica,sans-serif;font-size: 10px;font-style: normal;font-variant: normal;font-weight: normal;letter-spacing: normal;line-height: normal;text-indent: 0px;background-color: #ffffff\" align=\"center\"><a href=\"https:\/\/www.facebook.com\/media\/set\/?set=a.10151105778329632.445561.45027114631&amp;type=1\" target=\"_blank\"><\/a><a target=\"_blank\"><span style=\"color: #5a5a5a;text-decoration: none;font-family: Verdana,Arial,Helvetica,sans-serif;font-size: 10px;font-style: normal;font-variant: normal;font-weight: normal;letter-spacing: normal;line-height: normal;text-indent: 0px;background-color: #ffffff\"><font style=\"color: #5a5a5a;font-family: Verdana,Arial,Helvetica,sans-serif;font-size: 10px;font-style: normal;font-variant: normal;font-weight: normal;letter-spacing: normal;line-height: normal;text-align: justify;text-indent: 0px;background-color: #ffffff\"><strong><span style=\"color: #5a5a5a;text-decoration: none\"><font color=\"#0033cc\">:: Comente as fotos no Facebook<\/font><\/span><\/strong><\/font><\/span><\/a> <\/p>\n<p><\/em><\/p>\n<p>&nbsp;<\/p>\n<p>  Quem n&atilde;o tem f&eacute;, n&atilde;o &eacute; capaz de acreditar na recupera&ccedil;&atilde;o da pessoas, como faz a Pastoral da Sobriedade. A pastoral da Sobriedade prop&otilde;e um caminho de convers&atilde;o que requer doze passos:  <\/p>\n<p><em>&ldquo;Admitir, confiar, entregar. <\/em><br \/><em> Arrepender-se, confessar, renascer <\/em><br \/><em> Reparar, professar a F&eacute;, orar e vigiar <\/em><br \/><em> Servir, celebrar e festejar&quot;<\/em><\/p>\n<p> Nesse Acampamento, aprofundaremos um desses passos, que &eacute; o &ldquo;Professar a F&eacute;&rdquo;. Isso significa: &#039;ir em dire&ccedil;&atilde;o&#039;. N&oacute;s professamos a nossa f&eacute;, todas as vezes que participamos da Santa Missa. Logo ap&oacute;s de ouvir a homilia, nos levantamos e professamos a nossa f&eacute; rezando o &ldquo;Credo&rdquo;. Mas, para que esta f&eacute; cren&ccedil;a e se fortale&ccedil;a em nosso cora&ccedil;&atilde;o, precisamos nos instruir na Palavra de Deus, atrav&eacute;s das leituras b&iacute;blicas, das homilias e prega&ccedil;&otilde;es que ouvimos e dos documentos da Igreja.&rdquo;<\/p>\n<p>&nbsp;<\/p>\n<p align=\"center\"><em style=\"font-family: Verdana,Arial,Helvetica,sans-serif;font-size: 10px;font-variant: normal;font-weight: normal;letter-spacing: normal;line-height: normal;text-indent: 0px;background-color: #ffffff\">Transcri&ccedil;&atilde;o e Adapta&ccedil;&atilde;o: Mariana Lazarin Gabriel<font color=\"#0033ff\"> (<a href=\"https:\/\/twitter.com\/marilg\" target=\"_blank\">@marilg<\/a>)<\/font><\/em><\/p>\n<p align=\"center\">&nbsp;<\/p>\n<div align=\"justify\" style=\"color: #5a5a5a;font-family: Verdana,Arial,Helvetica,sans-serif;font-size: 10px;font-style: normal;font-variant: normal;font-weight: normal;letter-spacing: normal;line-height: normal;text-align: justify;text-indent: 0px;background-color: #ffffff\">\n<div align=\"center\">\n<hr width=\"100%\" size=\"2\" \/>&nbsp;<font size=\"2\" color=\"#000000\"><strong>Adquira essa prega&ccedil;&atilde;o pelo telefone<\/strong><\/font><font size=\"2\"><br \/><\/font><font size=\"2\" color=\"#000000\"><strong>(12) 3186-2600<\/strong><\/font><\/div>\n<\/div>\n<div align=\"justify\" style=\"color: #5a5a5a;font-family: Verdana,Arial,Helvetica,sans-serif;font-size: 10px;font-style: normal;font-variant: normal;font-weight: normal;letter-spacing: normal;line-height: normal;text-align: justify;text-indent: 0px;background-color: #ffffff\">\n<hr width=\"100%\" size=\"2\" \/><font color=\"#000000\"><strong><br \/>Conhe&ccedil;a mais do nosso conte&uacute;do<font color=\"#000000\">:<\/font><br \/><\/strong><font color=\"#0033cc\"><font color=\"#0033cc\"><font color=\"#0033cc\"><br \/><a href=\"http:\/\/www.webtvcn.com\/\" target=\"_blank\"><font color=\"#0033cc\">:: WebTVCN, muitos v&iacute;deos para voc&ecirc;<\/font><\/a><br \/><a href=\"http:\/\/gentedefe.com\/\" target=\"_blank\"><font color=\"#0033cc\">:: Gente de f&eacute;, a sua comunidade de relacionamento crist&atilde;<\/font><\/a><br \/><a href=\"http:\/\/podcast.cancaonova.com\/\" target=\"_blank\"><font color=\"#0033cc\">:: Podcasts: ou&ccedil;a &aacute;udios sobre variados assuntos<\/font><\/a><br \/><a href=\"http:\/\/paroquias.cancaonova.com\/\" target=\"_blank\"><font color=\"#0033cc\">:: Cadastre sua par&oacute;quia ou capela no Portal Can&ccedil;&atilde;o Nova<\/font><\/a><br \/><strong><br \/><font color=\"#000000\">Para o seu celular:<\/font><\/strong><\/p>\n<p><a href=\"http:\/\/m.cancaonova.com\/\" target=\"_blank\"><font color=\"#0033cc\">:: Can&ccedil;&atilde;o Nova Mobile<\/font><\/a><br \/><a href=\"http:\/\/m.cancaonova.com\/mobile\/?cat=1\" target=\"_blank\"><font color=\"#0033cc\">:: Conhe&ccedil;a nossos aplicativos para iOS<\/font><\/a><br \/><a href=\"http:\/\/m.cancaonova.com\/mobile\/?cat=6\" target=\"_blank\"><font color=\"#0033cc\">:: Conhe&ccedil;a nossos aplicativos para Android<\/font><\/a><\/p>\n<p><strong><font color=\"#000000\">Mais canais na web:<\/font><\/strong><\/p>\n<p><a href=\"http:\/\/meadiciona.com\/cancaonova\" target=\"_blank\"><font color=\"#0033cc\">:: meadiciona.com\/cancaonova<\/font><\/a><\/font><\/font><\/font><\/font><\/div>\n<p align=\"center\">&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dom Irineu Danelon Foto: Natalino Ueda\/Cancaonova.com N&oacute;s estamos come&ccedil;ando o &ldquo;Ano da f&eacute;&rdquo;. Quando lemos a b&iacute;blia, temos que l&ecirc;-la com f&eacute;, ou seja, Deus est&aacute; falando conosco atrav&eacute;s de sua Palavra e precisamos dar a Ele uma resposta. Precisamos&#8230;<\/p>\n","protected":false},"author":114,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7],"tags":[],"modified_by":"","_links":{"self":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/12843"}],"collection":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/users\/114"}],"replies":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/comments?post=12843"}],"version-history":[{"count":1,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/12843\/revisions"}],"predecessor-version":[{"id":12844,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/12843\/revisions\/12844"}],"wp:attachment":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media?parent=12843"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/categories?post=12843"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/tags?post=12843"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}