{"id":13770,"date":"2008-09-19T21:00:00","date_gmt":"2008-09-20T00:00:00","guid":{"rendered":"http:\/\/admin-canais.cancaonova.com\/eventos\/?p=13770"},"modified":"2014-08-15T17:54:29","modified_gmt":"2014-08-15T20:54:29","slug":"renove-sua-fe-e-testemunhe-a-acao-de-deus-em-sua-vida","status":"publish","type":"post","link":"https:\/\/admin-canais.cancaonova.com\/eventos\/cobertura\/renove-sua-fe-e-testemunhe-a-acao-de-deus-em-sua-vida\/","title":{"rendered":"Renove sua f\u00e9 e testemunhe a a\u00e7\u00e3o de Deus em sua vida"},"content":{"rendered":"<p>Neste s&aacute;bado, dia 20, acontece na sede da Comunidade Can&ccedil;&atilde;o Nova em Cachoeira Paulista (SP), o Acampamento de Cura e Liberta&ccedil;&atilde;o com monsenhor Jonas Abib, Padre Roger e Padre Jos&eacute; Augusto. J&aacute; nesta manh&atilde;, muitas pessoas se sentiram tocadas pelo Esp&iacute;rito Santo e deixaram suas experi&ecirc;ncias, testemunhando a a&ccedil;&atilde;o de Deus em suas vidas. <\/p>\n<div id=\"foto\" style=\"margin: 0pt auto;padding: 5px 5px 5px 0px;width: 180px;float: left\">\n<div id=\"foto\"><!--ABRE LINK DA FOTO--><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.cancaonova.com\/portal\/arquivos\/fotos\/2008\/setembro\/20_eventos-003.jpg\" border=\"0\" width=\"180\" height=\"220\" \/><!--FECHA LINK DA FOTO--><\/div>\n<div id=\"texto\"><!--TEXTO DA FOTO-->Ana Maria Freitas<!--TEXTO DA FOTO--><\/div>\n<div id=\"credito\"><!--CREDITO DA FOTO-->Foto: Eliziane Alves<!--CREDITO DA FOTO--><\/div>\n<\/div>\n<p>&nbsp;&quot;Tudo aqui na Can&ccedil;&atilde;o Nova &eacute; maravilhoso. Desde que cheguei eu me senti muito animada pela ora&ccedil;&atilde;o da Salette Ferreira e com as palavras de monsenhor Jonas Abib. Estou para cima e hoje tiveram muitas coisas que ouvi que me deram uma &ldquo;sacudida&rdquo; para a vida. Ter mais f&eacute;, coragem, buscar mais em Deus, porque por qualquer motivo n&oacute;s come&ccedil;amos a nos entregar e n&atilde;o &eacute; assim. Temos ent&atilde;o que acreditar, por isso que acredito e n&atilde;o tenho porqu&ecirc; ficar triste. Assim como o La&eacute;rcio nos disse que h&aacute; tantas pessoas adormecidas no barco, eu naquela hora, senti que era para mim aquelas palavras, ent&atilde;o:  &lsquo;Tenho que acordar para a vida que a vida &eacute; bela&rsquo;.&quot; <\/p>\n<p>  <strong>Ana Maria de Freitas Sousa, 47 anos, do lar, Betim( MG). <br \/><\/strong><\/p>\n<div id=\"foto\" style=\"margin: 0pt auto;padding: 5px 0px 5px 5px;width: 180px;float: right\">\n<div id=\"foto\"><!--ABRE LINK DA FOTO--><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.cancaonova.com\/portal\/arquivos\/fotos\/2008\/setembro\/20_eventos-006.jpg\" border=\"0\" width=\"180\" height=\"220\" \/><!--FECHA LINK DA FOTO--><\/div>\n<div id=\"texto\"><!--TEXTO DA FOTO-->Carlos Jos&eacute; Cardoso Silva<!--TEXTO DA FOTO--><\/div>\n<div id=\"credito\"><!--CREDITO DA FOTO-->Foto: Eliziane Alves<!--CREDITO DA FOTO--><\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&quot;Essa ora&ccedil;&atilde;o vai movendo e fazendo-nos buscar dentro de n&oacute;s as &aacute;reas necess&aacute;rias de liberta&ccedil;&atilde;o e de mudan&ccedil;a que precisamos. <strong>Estas coisas que nos atrapalham de sermos felizes, nos atrapalham de ver esse amor que &eacute; a ess&ecirc;ncia de Jesus. <\/strong> Essas coisa que nos oprimem e n&atilde;o deixando as maravilhas que Jesus quer nos fazer. H&aacute; tantas coisas em nossa hist&oacute;ria passada que precisa de liberta&ccedil;&atilde;o e de cura. Valeu a pena ter vindo, acho tamb&eacute;m que &eacute; uma provid&ecirc;ncia divina, pois quer&iacute;amos estar na semana que vem e agora Deus vem nos atingindo de maneira t&atilde;o profunda e simples. Jesus tem nos surpreendido com a Sua a&ccedil;&atilde;o.&quot; <\/p>\n<p>  <strong>Carlos Jos&eacute; Cardoso Silva, 29 anos, professor, S&atilde;o Jo&atilde;o do Para&iacute;so (RJ). <\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<div id=\"foto\" style=\"margin: 0pt auto;padding: 5px 5px 5px 0px;width: 180px;float: left\">\n<div id=\"foto\"><!--ABRE LINK DA FOTO--><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.cancaonova.com\/portal\/arquivos\/fotos\/2008\/setembro\/20_eventos-007.jpg\" border=\"0\" width=\"180\" height=\"220\" \/><!--FECHA LINK DA FOTO--><\/div>\n<div id=\"texto\"><!--TEXTO DA FOTO-->Edinaldo Pereira Vieira<!--TEXTO DA FOTO--><\/div>\n<div id=\"credito\"><!--CREDITO DA FOTO-->Foto: Eliziane Alves<!--CREDITO DA FOTO--><\/div>\n<\/div>\n<p><em>&nbsp;<\/em>&quot;&Eacute; a&ccedil;&atilde;o de Deus pura, o Esp&iacute;rito Santo sobre o povo. Inclusive num determinado momento O senti preenchendo todos os vazios de meu cora&ccedil;&atilde;o. Quando a Salette pediu para esvaziarmos de tudo que n&atilde;o &eacute; de Deus e que nos preench&ecirc;ssemos com tudo que vem de Deus.  E com a prega&ccedil;&atilde;o do monsenhor Jonas Abib que canalizou todas as a&ccedil;&otilde;es de Deus e com ora&ccedil;&atilde;o do Padre Roger foi tudo maravilhoso, sensacional a&ccedil;&atilde;o de Deus mesmo.  &quot;<\/p>\n<p>  <strong>Edinaldo Pereira Vieira, 31 anos, frentista, Duque de Caixias (RJ). <\/strong><\/p>\n<p>Voc&ecirc; tem testemunhos da a&ccedil;&atilde;o de Deus em sua vida? Deixe para n&oacute;s os seu testemunhos nos coment&aacute;rios abaixo. <\/p>\n<p>  <strong>Deus aben&ccedil;oe! <\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Neste s&aacute;bado, dia 20, acontece na sede da Comunidade Can&ccedil;&atilde;o Nova em Cachoeira Paulista (SP), o Acampamento de Cura e Liberta&ccedil;&atilde;o com monsenhor Jonas Abib, Padre Roger e Padre Jos&eacute; Augusto. J&aacute; nesta manh&atilde;, muitas pessoas se sentiram tocadas pelo&#8230;<\/p>\n","protected":false},"author":114,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[8],"tags":[],"modified_by":"","_links":{"self":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/13770"}],"collection":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/users\/114"}],"replies":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/comments?post=13770"}],"version-history":[{"count":1,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/13770\/revisions"}],"predecessor-version":[{"id":13771,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/13770\/revisions\/13771"}],"wp:attachment":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media?parent=13770"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/categories?post=13770"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/tags?post=13770"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}