{"id":14127,"date":"2010-09-19T21:00:00","date_gmt":"2010-09-20T00:00:00","guid":{"rendered":"http:\/\/admin-canais.cancaonova.com\/eventos\/?p=14127"},"modified":"2014-08-15T17:58:34","modified_gmt":"2014-08-15T20:58:34","slug":"como-e-por-que-fazer-jejum","status":"publish","type":"post","link":"https:\/\/admin-canais.cancaonova.com\/eventos\/cobertura\/como-e-por-que-fazer-jejum\/","title":{"rendered":"Como e por que fazer jejum?"},"content":{"rendered":"<div align=\"justify\">Voc&ecirc; sabia que o jejum pode ajudar voc&ecirc; a alcan&ccedil;ar a cura e a liberta&ccedil;&atilde;o que tanto deseja? O tema do <a href=\"http:\/\/www.cancaonova.com\/portal\/canais\/eventos\/novoeventos\/cobertura.php?cob=2471&amp;tit=Acampamento%20de%20Ora%E7%E3o\" target=\"_blank\"><font color=\"#0033cc\">Acampamento de Ora&ccedil;&atilde;o<\/font><\/a> que acontece de 8 a 10 de outubro &eacute; &quot;Quebrando as muralhas&quot;. E, uma forma de vencer as tenta&ccedil;&otilde;es do dem&ocirc;nio &eacute; com esta pr&aacute;tica.<\/p>\n<p>  O jejum &eacute; uma forma de purificar o corpo para fortalecer o esp&iacute;rito na luta contra as tenta&ccedil;&otilde;es do pecado. A pr&aacute;tica tem como finalidade nos levar a um equil&iacute;brio necess&aacute;rio e ao desprendimento daquilo que podemos chamar de &quot;atitude consumista&quot;, caracter&iacute;stica da nossa civiliza&ccedil;&atilde;o.<\/p>\n<p>  H&aacute; v&aacute;rios tipos de jejum, mas, nesta oportunidade, vamos apresentar os presentes no livro <a href=\"http:\/\/shopping.cancaonova.com\/Livraria\/Espiritualidade\/Praticas-de-jejum.html?acao=DT&amp;prod_id=46876&amp;dep=692&amp;secao=3817&amp;pedido=39610483&amp;codbar=01.00106\" target=\"_blank\"><font color=\"#0033cc\">&ldquo;Pr&aacute;ticas de jejum&rdquo;<\/font><\/a>, do monsenhor Jonas Abib, que s&atilde;o: o jejum da Igreja, jejum a p&atilde;o e &aacute;gua, jejum &agrave; base de l&iacute;quidos e jejum completo.<\/p>\n<p>  Saiba mais sobre cada um deles:<\/p>\n<div style=\"text-align: center\"><a href=\"http:\/\/wiki.cancaonova.com\/index.php\/Jejum\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.cancaonova.com\/portal\/arquivos\/fotos\/2010\/setembro\/jejum.jpg\" border=\"0\" width=\"350\" height=\"174\" \/><\/a><\/div>\n<p><\/p>\n<div align=\"center\">  :: Clique na imagem para ler<\/div>\n<\/div>\n<p><strong>Conhe&ccedil;a mais do nosso conte&uacute;do:<\/p>\n<p><\/strong><a href=\"http:\/\/www.webtvcn.com\/\" target=\"_blank\"><font color=\"#0033cc\">:: WebTVCN, muitos v&iacute;deos para voc&ecirc;<\/font><\/a><br \/> <a href=\"http:\/\/gentedefe.com\/\" target=\"_blank\"><font color=\"#0033cc\">:: Gente de f&eacute;, a sua comunidade de relacionamento crist&atilde;<\/font><\/a><br \/><a href=\"http:\/\/podcast.cancaonova.com\/\" target=\"_blank\"><font color=\"#0033cc\">:: Podcasts: ou&ccedil;a &aacute;udios sobre variados assuntos<\/font><\/a><br \/><a href=\"http:\/\/paroquias.cancaonova.com\/\" target=\"_blank\"><font color=\"#0033cc\">:: Cadastre sua par&oacute;quia ou capela no Portal Can&ccedil;&atilde;o Nova<\/font><\/a><a href=\"http:\/\/paroquias.cancaonova.com\/\" target=\"_blank\"><font color=\"#0033cc\"><br \/><\/font><\/a><br \/><strong>Para o seu celular:<\/strong><\/p>\n<p><a href=\"http:\/\/www.cancaonovamobile.com\/\" target=\"_blank\"><font color=\"#0033cc\">:: Can&ccedil;&atilde;o Nova Mobile<\/font><\/a><br \/><a href=\"http:\/\/cnchama.com.br\/\" target=\"_blank\"><font color=\"#0033cc\">:: CN Chama, a Palavra de Deus no seu celular<\/font><\/a><br \/><a href=\"http:\/\/iphone.cancaonova.com\/\" target=\"_blank\"><font color=\"#0033cc\">:: Iphone<\/font><\/a><\/p>\n<p><strong>Mais canais na web:<\/strong><\/p>\n<p><a href=\"http:\/\/meadiciona.com\/cancaonova\" target=\"_blank\"><font color=\"#0033cc\">:: meadiciona.com\/cancaonova <\/font><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Voc&ecirc; sabia que o jejum pode ajudar voc&ecirc; a alcan&ccedil;ar a cura e a liberta&ccedil;&atilde;o que tanto deseja? O tema do Acampamento de Ora&ccedil;&atilde;o que acontece de 8 a 10 de outubro &eacute; &quot;Quebrando as muralhas&quot;. E, uma forma de&#8230;<\/p>\n","protected":false},"author":114,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[8],"tags":[],"modified_by":"","_links":{"self":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/14127"}],"collection":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/users\/114"}],"replies":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/comments?post=14127"}],"version-history":[{"count":1,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/14127\/revisions"}],"predecessor-version":[{"id":14128,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/14127\/revisions\/14128"}],"wp:attachment":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media?parent=14127"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/categories?post=14127"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/tags?post=14127"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}