{"id":16952,"date":"2013-05-01T21:00:00","date_gmt":"2013-05-02T00:00:00","guid":{"rendered":"http:\/\/admin-canais.cancaonova.com\/eventos\/?p=16952"},"modified":"2014-08-15T18:32:47","modified_gmt":"2014-08-15T21:32:47","slug":"infraestrutura-para-o-encontro-da-obra-de-maria","status":"publish","type":"post","link":"https:\/\/admin-canais.cancaonova.com\/eventos\/cobertura\/infraestrutura-para-o-encontro-da-obra-de-maria\/","title":{"rendered":"Infraestrutura para o Encontro da Obra de Maria"},"content":{"rendered":"<p>\t\tNeste fim de semana, teremos, na sede da<a href=\"http:\/\/wiki.cancaonova.com\/index.php\/Comunidade_Can%C3%A7%C3%A3o_Nova\" target=\"_blank\"><font color=\"#0033cc\"> Comunidade Can&ccedil;&atilde;o Nova,<\/font><\/a> o tradicional <a href=\"http:\/\/www.cancaonova.com\/portal\/canais\/eventos\/novoeventos\/cobertura.php?cob=2812&amp;tit=Encontro%20da%20Comunidade%20Obra%20de%20Maria\" target=\"_blank\"><font color=\"#0033cc\">Encontro com a Obra de Maria<\/font><\/a>. Para este evento, s&atilde;o esperadas cerca de 5 a 7 mil pessoas, que devem passar pela Ch&aacute;cara Santa Cruz nestes tr&ecirc;s dias.  <\/p>\n<p>&nbsp;<\/p>\n<div style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.cancaonova.com\/portal\/arquivos\/fotos\/2013\/maio\/03_eventos-001.jpg\" border=\"0\" width=\"370\" height=\"250\" \/><\/div>\n<p><font color=\"#000000\">O mission&aacute;rio Aldenir Andrade, colaborador no Departamento de<\/font> <a href=\"http:\/\/wiki.cancaonova.com\/index.php\/Infraestrutura\" target=\"_blank\"><font color=\"#0033cc\">Infraestrutura da Can&ccedil;&atilde;o Nova<\/font><\/a><font color=\"#000000\">, conta como est&aacute; sendo a prepara&ccedil;&atilde;o para este encontro, o qual n&atilde;o se preocupa apenas com a estrutura f&iacute;sica, mas tamb&eacute;m espiritual: &ldquo;A prepara&ccedil;&atilde;o come&ccedil;a com a ora&ccedil;&atilde;o. Temos uma boa equipe! S&atilde;o bombeiros e seguran&ccedil;as para garantir que a evangeliza&ccedil;&atilde;o chegue ao cora&ccedil;&atilde;o de cada pessoa. Por&eacute;m, al&eacute;m da ora&ccedil;&atilde;o, &eacute; necess&aacute;rio uma estrutura, e n&oacute;s temos lanchonetes abertas durante os acampamentos e uma &aacute;rea de camping para acolher os peregrinos. Ent&atilde;o, voc&ecirc; que est&aacute; vindo para a Ch&aacute;cara de Santa Cruz, traga barracas com seguran&ccedil;a, verifique-a em casa, antes de sair, veja se todos os equipamentos est&atilde;o certos para n&atilde;o chegar, aqui, e perceber que est&aacute; faltando algo. Temos tamb&eacute;m, dentro da ch&aacute;cara, a Loja Can&ccedil;&atilde;o Nova para que o peregrino possa adquirir nossos produtos, um estacionamento amplo para ve&iacute;culos e &ocirc;nibus. Para dar suporte a tudo isso, trabalhamos com toda quest&atilde;o de estrutura f&iacute;sica, com muita organiza&ccedil;&atilde;o para que o peregrino consiga ter um encontro pessoal com Deus&rdquo;. <\/font><\/p>\n<p><a href=\"http:\/\/wiki.cancaonova.com\/index.php\/Infraestrutura\" target=\"_blank\"><font color=\"#0033cc\"><strong>:: Clique e saiba mais sobre a Infraestrutura<\/strong><\/font><\/a><\/p>\n<p> <font color=\"#000000\">Durante o encontro, teremos prega&ccedil;&otilde;es com padres e membros consagrados &agrave; Obra de Maria. O tema a ser trabalhado este ano &eacute;: &ldquo;Maria, mulher de f&eacute;&rdquo;. Um assunto bem prop&iacute;cio ao m&ecirc;s de maio. A anima&ccedil;&atilde;o de todo o encontro ser&aacute; feita pelo Minist&eacute;rio de M&uacute;sica da Obra de Maria, da miss&atilde;o de Bras&iacute;lia. <\/p>\n<p>&quot;&Eacute; um encontro favor&aacute;vel para este m&ecirc;s dedicado &agrave;s m&atilde;es, e a Obra de Maria est&aacute; vindo com muita alegria. No s&aacute;bado, &agrave; noite, haver&aacute; o show com a dupla DDD. Convidamos voc&ecirc; a fazer parte dessa programa&ccedil;&atilde;o. Venha com o cora&ccedil;&atilde;o aberto,  porque Deus vai falar a voc&ecirc;&quot;, concluiu o mission&aacute;rio, deixando um convite: &ldquo;Voc&ecirc;, que est&aacute; em sua casa, est&aacute; pensando em vir, venha participar conosco, pois ser&aacute; muito bom. Estaremos, aqui, acolhendo voc&ecirc; com toda estrutura da Comunidade Can&ccedil;&atilde;o Nova.&rdquo; <\/p>\n<p><\/font><br \/><font color=\"#000000\"><strong>Veja prega&ccedil;&otilde;es dos &uacute;ltimos encontros<\/strong>:<\/font><br \/><a href=\"http:\/\/www.cancaonova.com\/portal\/canais\/eventos\/novoeventos\/cobertura.php?cod=2557&amp;pre=6984&amp;tit=\" target=\"_blank\"><font color=\"#0033cc\">.: &quot;Eis a tua M&atilde;e&quot;<\/font><\/a><br \/><a href=\"http:\/\/www.cancaonova.com\/portal\/canais\/eventos\/novoeventos\/cobertura.php?cod=2557&amp;pre=6990&amp;tit=Nossa%20meta%20%E9%20o%20c%E9u\" target=\"_blank\"><font color=\"#0033cc\">.: Nossa meta &eacute; o C&eacute;u<\/font><\/a><br \/><a href=\"http:\/\/www.cancaonova.com\/portal\/canais\/eventos\/novoeventos\/cobertura.php?cod=2692&amp;pre=7458&amp;tit=Maria%20M%E3e%20de%20todos%20n%F3s\" target=\"_blank\"><font color=\"#0033cc\">.: Maria, M&atilde;e de todos n&oacute;s<\/font><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><font color=\"#000000\"><font color=\"#000000\"><strong>Conhe&ccedil;a mais do nosso conte&uacute;do<font color=\"#000000\">:<\/font><br \/><\/strong><font color=\"#0033cc\" style=\"text-align: justify;background-color: #ffffff;text-indent: 0px;font-style: normal;font-variant: normal;font-weight: normal;font-size: 10px;line-height: normal;font-family: Verdana,Arial,Helvetica,sans-serif;letter-spacing: normal\"><font color=\"#0033cc\"><font color=\"#0033cc\"><br \/><a href=\"http:\/\/www.webtvcn.com\/\" target=\"_blank\"><font color=\"#0033cc\">:: WebTVCN, muitos v&iacute;deos para voc&ecirc;<\/font><\/a><br \/><a href=\"http:\/\/gentedefe.com\/\" target=\"_blank\"><font color=\"#0033cc\">:: Gente de f&eacute;, a sua comunidade de relacionamento crist&atilde;<\/font><\/a><br \/><a href=\"http:\/\/podcast.cancaonova.com\/\" target=\"_blank\"><font color=\"#0033cc\">:: Podcasts: ou&ccedil;a &aacute;udios sobre variados assuntos<\/font><\/a><br \/><a href=\"http:\/\/paroquias.cancaonova.com\/\" target=\"_blank\"><font color=\"#0033cc\">:: Cadastre sua par&oacute;quia ou capela no Portal Can&ccedil;&atilde;o Nova<\/font><\/a><br \/><strong><br \/><font color=\"#000000\">Para o seu celular:<\/font><\/strong><\/p>\n<p><a href=\"http:\/\/m.cancaonova.com\/\" target=\"_blank\"><font color=\"#0033cc\">:: Can&ccedil;&atilde;o Nova Mobile<\/font><\/a><br \/><a href=\"http:\/\/m.cancaonova.com\/mobile\/?cat=1\" target=\"_blank\"><font color=\"#0033cc\">:: Conhe&ccedil;a nossos aplicativos para iOS<\/font><\/a><br \/><a href=\"http:\/\/m.cancaonova.com\/mobile\/?cat=6\" target=\"_blank\"><font color=\"#0033cc\">:: Conhe&ccedil;a nossos aplicativos para Android<\/font><\/a><\/p>\n<p><strong><font color=\"#000000\">Mais canais na web:<\/font><\/strong><\/p>\n<p><a href=\"http:\/\/meadiciona.com\/cancaonova\" target=\"_blank\"><font color=\"#0033cc\">:: meadiciona.com\/cancaonova<\/font><\/a><\/font><\/font><\/font><\/font>&nbsp;&nbsp;&nbsp;&nbsp; <\/font><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Neste fim de semana, teremos, na sede da Comunidade Can&ccedil;&atilde;o Nova, o tradicional Encontro com a Obra de Maria. Para este evento, s&atilde;o esperadas cerca de 5 a 7 mil pessoas, que devem passar pela Ch&aacute;cara Santa Cruz nestes tr&ecirc;s&#8230;<\/p>\n","protected":false},"author":114,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[8],"tags":[],"modified_by":"","_links":{"self":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/16952"}],"collection":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/users\/114"}],"replies":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/comments?post=16952"}],"version-history":[{"count":1,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/16952\/revisions"}],"predecessor-version":[{"id":16953,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/16952\/revisions\/16953"}],"wp:attachment":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media?parent=16952"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/categories?post=16952"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/tags?post=16952"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}