{"id":1780,"date":"2006-04-14T12:30:00","date_gmt":"2006-04-14T15:30:00","guid":{"rendered":"http:\/\/admin-canais.cancaonova.com\/eventos\/?p=1780"},"modified":"2018-09-17T11:06:49","modified_gmt":"2018-09-17T14:06:49","slug":"batizados-na-morte-de-jesus","status":"publish","type":"post","link":"https:\/\/admin-canais.cancaonova.com\/eventos\/acampamento-de-semana-santa\/pregacoes\/batizados-na-morte-de-jesus\/","title":{"rendered":"Batizados na morte de Jesus"},"content":{"rendered":"<h2>&#8220;\u00d3 Pai, em tuas m\u00e3os Eu entrego o meu esp\u00edrito&#8221;&nbsp;<i>(Salmo 30)<\/i><\/h2>\n<p>Voc\u00ea sabe que a Palavra de Jesus que acabamos de cantar \u00e9 a proclama\u00e7\u00e3o da Sua vit\u00f3ria? Ele dizia: &#8220;Pai, fiz a Tua vontade e agora Tu sabes como est\u00e1 o meu corpo, como est\u00e1 o meu esp\u00edrito, mas eu entrego nas Tuas m\u00e3os a minha vida&#8221;.<\/p>\n<p>Era um vitorioso que se entregava ao Pai.<\/p>\n<p>As palavras de Jesus &#8220;Tudo est\u00e1 consumado&#8221; n\u00e3o \u00e9 no sentido de &#8220;acabou&#8221;. Em outras palavras, Jesus est\u00e1 dizendo: &#8220;Pai, miss\u00e3o cumprida. Tudo aquilo que eu devia fazer, eu fiz&#8221;.<\/p>\n<p><em>&#8220;Inclinando a cabe\u00e7a, Jesus entregou o esp\u00edrito&#8221;&nbsp;(Jo\u00e3o 19,30).<\/em><\/p>\n<p><span style=\"color: #000000\"><strong>.: Ou\u00e7a homilia do monsenhor Jonas, na \u00edntegra:<\/strong><\/span><\/p>\n<div class='embeds-audio'><iframe frameborder='0' width=\"300\" height=\"35\" src='https:\/\/apps.cancaonova.com\/embeds\/Embeds\/get?id=7263&output=iframe&post_link=aHR0cHM6Ly9hZG1pbi1jYW5haXMuY2FuY2Fvbm92YS5jb20vZXZlbnRvcy9hY2FtcGFtZW50by1kZS1zZW1hbmEtc2FudGEvcHJlZ2Fjb2VzL2JhdGl6YWRvcy1uYS1tb3J0ZS1kZS1qZXN1cy8=&player_id=38660432' style='overflow:hidden;' class='iframe_embed' allowfullscreen><\/iframe><\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h3>Entremos no cora\u00e7\u00e3o aberto de Jesus<\/h3>\n<p>Os exegetas s\u00e3o concordes em dizer que esse &#8220;entregou o esp\u00edrito&#8221; quer dizer: &#8220;deu o Seu Esp\u00edrito sobre toda a terra, sobre toda a humanidade&#8221;.<\/p>\n<p>Com a lan\u00e7a ficou aberta, a partir de ent\u00e3o, a entrada ao cora\u00e7\u00e3o de Jesus. Escancarou-se a Miseric\u00f3rdia do cora\u00e7\u00e3o de Jesus, para que voc\u00ea e eu entremos.<\/p>\n<p>Jesus derramou o Seu Esp\u00edrito e Ele est\u00e1 continuamente conosco. \u00c9 um ato que se deu ali, naquele momento, mas Jesus, estar\u00e1 derramando Seu Esp\u00edrito sobre todos aqueles que se abrirem para receb\u00ea-Lo.<\/p>\n<p>O C\u00e9u inteiro est\u00e1 convidando, cada um de n\u00f3s, a entrar no cora\u00e7\u00e3o aberto de Jesus. N\u00e3o resista mais. O v\u00e9u foi rasgado, o cora\u00e7\u00e3o est\u00e1 aberto. A porta est\u00e1 aberta para todos aqueles que precisam.<\/p>\n<h3>Jesus ama voc\u00ea pessoalmente, do jeito que voc\u00ea \u00e9 e com toda a sua hist\u00f3ria<\/h3>\n<p>Gra\u00e7as a Deus, voc\u00ea n\u00e3o est\u00e1 longe, mas \u00e9 preciso adentrar ainda mais nesse amor que vem do cora\u00e7\u00e3o de Jesus. Est\u00e1 a\u00ed a infinita demonstra\u00e7\u00e3o do amor de Deus.<\/p>\n<p>Jesus ama voc\u00ea pessoalmente, do jeito que voc\u00ea \u00e9, com toda a sua hist\u00f3ria, como sua situa\u00e7\u00e3o presente.<\/p>\n<p>\u00c9 isso que Jesus est\u00e1 dizendo a voc\u00ea: &#8220;Desce depressa. Voc\u00ea precisa ficar hoje na minha casa, entrar dentro, no fundo do meu cora\u00e7\u00e3o. Estou chamando voc\u00ea como chamei Zaqueu&#8221;.<\/p>\n<p>Assim como Jesus acolheu Madalena, pois quando se agachou, Ele se p\u00f4s na altura dela, face a face com aquela mulher. Os outros viram a apar\u00eancia dela, mas Jesus estava conhecendo toda a sua hist\u00f3ria.<\/p>\n<p>Seja voc\u00ea quem for, seja o que voc\u00ea tenha incrustado na sua vida. O que Jesus disse para aquela mulher, Ele diz a voc\u00ea: &#8220;Eu tamb\u00e9m n\u00e3o o condeno. Seja o que for que est\u00e1 a\u00ed no seu cora\u00e7\u00e3o. Eu n\u00e3o o condeno. Vai e n\u00e3o peque mais&#8221;.<\/p>\n<h3>&#8220;Eu n\u00e3o vim chamar justos, mas os pecadores&#8221;<\/h3>\n<p>Jesus n\u00e3o quer que voc\u00ea peque, simplesmente porque faz mal para voc\u00ea e para os outros.<\/p>\n<p>Aquele Jesus que chamou Mateus, que era cobrador de impostos, uma pessoa corrupta. Diante do que Jesus disse, Mateus largou tudo e O seguiu imediatamente.<\/p>\n<p><em>&#8220;Eu n\u00e3o vim chamar justos, mas os pecadores&#8221;.&nbsp;<\/em>A\u00ed est\u00e1 o infinito amor de Jesus por voc\u00ea. Ele est\u00e1 chamando voc\u00ea como chamou Pedro, como aquela mulher que identificamos como Maria, irm\u00e3 de Marta, que derrama um vaso de alabastro pur\u00edssimo sobre os p\u00e9s de Jesus.<\/p>\n<p>Jesus conhecia profundamente aquela mulher, Ele esperava por ela. \u00c9 uma maravilha vermos a paci\u00eancia que Jesus teve com aquela mulher, mas s\u00f3 ali, ela se rende. \u00c9 assim que Jesus espera por n\u00f3s. Jesus, de quem n\u00f3s somos \u00edntimos, mas talvez haja coisas nos amarrando. Mas, hoje, amorosamente, Ele est\u00e1 o atraindo e chamando voc\u00ea.<\/p>\n<p>Jesus sabia que ela O amava e Ele esperou, esperou, esperou&#8230; Primeiro, ressuscitou seu irm\u00e3o L\u00e1zaro e agora ressuscitou a ela, Maria.<\/p>\n<h3>&#8220;Jesus, eu me ponho nos p\u00e9s da Tua cruz, deixando que o Teu Esp\u00edrito caia sobre mim&#8221;<\/h3>\n<p>\u00c9 essa ressurrei\u00e7\u00e3o que Jesus tem para voc\u00ea agora; pois somos pecadores e acabamos pecando. Agora \u00e9 o momento de nos reconhecermos pecadores diante do Senhor e necessitados de salva\u00e7\u00e3o.<\/p>\n<p>\u00c9 certo que falta muito para sermos aquilo que Jesus quer que n\u00f3s sejamos.&nbsp;Mas, temos de ser firmes e prosseguir. Rezemos:<\/p>\n<p>&#8220;Senhor, eu confesso o meu pecado. Confesso que sou pecador e, \u00e9 por isso que ainda estou amarrado, preso e n\u00e3o me deixo transformar o quanto preciso. Tu me atrais para a santidade. Jesus, eu quero aquilo que Tu queres. Se Tu queres que eu seja santo, eu tamb\u00e9m quero e me abro para receber, agora, nesta hora, o fruto da Tua reden\u00e7\u00e3o&#8221;.<\/p>\n<p>Jesus, eu me ponho nos p\u00e9s da Tua cruz, deixando que o Teu sangue caia sobre mim. Lave-me, me purifique entrando nas entranhas do meu ser e atingindo l\u00e1 onde o pecado se aninha.<br \/>\n Lava-me, Jesus. Estou aqui como Pedro, como Maria, irm\u00e3 de L\u00e1zaro. Tu sabes que eu Te tenho negado, mas Tu sabes que eu Te amo&#8221;.<\/p>\n<p>Obrigado, Senhor, porque me recebes assim.<br \/>\n Com profunda gratid\u00e3o eu me entrego a Ti. Eu me jogo agora na Tua infinita miseric\u00f3rdia.<\/p>\n<p>Tu \u00e9s o meu Salvador. Sou completamente banhado na sua miseric\u00f3rdia e Tu \u00e9s o Senhor da minha vida.<\/p>\n<p>Coloco tudo que tenho e sou no Teu senhorio. Tu \u00e9s o Senhor da minha vida. E para que isso continue at\u00e9 a Tua vinda ou at\u00e9 a minha chegada a Ti, derrama sobre mim o Teu Esp\u00edrito. Batiza-me, Esp\u00edrito Santo. Batiza-me na Morte, no Sangue de Jesus. Am\u00e9m&#8221;.<\/p>\n<p><i>Transcri\u00e7\u00e3o: Maur\u00edcio Rebou\u00e7as<br \/>\n Fotos: Claudenilson Jos\u00e9<\/i><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;\u00d3 Pai, em tuas m\u00e3os Eu entrego o meu esp\u00edrito&#8221;&nbsp;(Salmo 30) Voc\u00ea sabe que a Palavra de Jesus que acabamos de cantar \u00e9 a proclama\u00e7\u00e3o da Sua vit\u00f3ria? Ele dizia: &#8220;Pai, fiz a Tua vontade e agora Tu sabes como&#8230;<\/p>\n","protected":false},"author":114,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7],"tags":[],"modified_by":"Marc\u00edlia","_links":{"self":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/1780"}],"collection":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/users\/114"}],"replies":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/comments?post=1780"}],"version-history":[{"count":6,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/1780\/revisions"}],"predecessor-version":[{"id":71390,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/1780\/revisions\/71390"}],"wp:attachment":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media?parent=1780"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/categories?post=1780"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/tags?post=1780"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}