{"id":18068,"date":"2010-02-23T21:00:00","date_gmt":"2010-02-24T00:00:00","guid":{"rendered":"http:\/\/admin-canais.cancaonova.com\/eventos\/?p=18068"},"modified":"2014-08-15T18:47:20","modified_gmt":"2014-08-15T21:47:20","slug":"internauta-vencedora-da-promocao-do-portal-cancao-nova-2","status":"publish","type":"post","link":"https:\/\/admin-canais.cancaonova.com\/eventos\/cobertura\/internauta-vencedora-da-promocao-do-portal-cancao-nova-2\/","title":{"rendered":"Internauta vencedora da promo\u00e7\u00e3o do Portal Can\u00e7\u00e3o Nova"},"content":{"rendered":"<div align=\"justify\">A internauta <a href=\"http:\/\/twitter.com\/nina_anjo\" target=\"_blank\"><font color=\"#0033cc\">Cristina Ramos (@nina_anjo)<\/font><\/a>, de S&atilde;o Paulo (SP), foi a sorteada para participar de uma das prega&ccedil;&otilde;es do padre F&aacute;bio de Melo no <a href=\"http:\/\/www.cancaonova.com\/portal\/canais\/eventos\/novoeventos\/cobertura.php?cob=2406&amp;tit=Kairos%20com%20padre%20F%E1bio%20de%20Melo\" target=\"_blank\"><font color=\"#0033cc\">Kairos<\/font><\/a> deste domingo, dia 28, na sede da Can&ccedil;&atilde;o Nova, em Cachoeira Paulista (SP). Ela vai acompanhar a palestra nas cadeiras azuis do Centro de Evangeliza&ccedil;&atilde;o Dom Jo&atilde;o Hip&oacute;lito de Moraes, que fica no palco. <br \/><a href=\"http:\/\/sorteie.me\/69O\" target=\"_blank\"><font color=\"#0033cc\"><\/p>\n<div style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.cancaonova.com\/portal\/arquivos\/fotos\/2010\/fevereiro\/24_eventos-001.jpg\" border=\"0\" width=\"370\" height=\"226\" \/><\/div>\n<p><\/font><\/a><\/p>\n<div align=\"center\"><a href=\"http:\/\/sorteie.me\/69O\" target=\"_blank\"><font color=\"#0033cc\">  :: Clique aqui para ver o resultado <\/font><\/a><\/div>\n<p> Para participar, os internautas tiveram que postar no microblog Twitter a mensagem: &ldquo;Tudo posso n&#039;Aquele que me fortalece http:\/\/migre.me\/kQBu&rdquo;. A promo&ccedil;&atilde;o foi v&aacute;lida de ontem (23) at&eacute; hoje &agrave;s 12h. O sorteio foi feito pela ferramenta Sorteie.me, sistema que gera resultados aleat&oacute;rios por meio do random.org.<\/div>\n<p>  <\/p>\n<hr \/>\n<div align=\"center\"> <a href=\"http:\/\/www.cancaonova.com\/portal\/canais\/eventos\/novoeventos\/cobertura.php?cob=2406&amp;tit=Kairos%20com%20padre%20F%E1bio%20de%20Melo\" target=\"_blank\"><font color=\"#0033cc\"><strong>Participe do Kairos com padre F&aacute;bio de Melo, neste domingo, 28 de fevereiro! <\/strong><\/font><\/a><\/div>\n<hr \/>\n<p><strong>Conhe&ccedil;a mais do nosso conte&uacute;do:<\/p>\n<p><\/strong><a href=\"http:\/\/www.webtvcn.com\/\" target=\"_blank\"><font color=\"#0033cc\">:: WebTVCN, muitos v&iacute;deos para voc&ecirc;<\/font><\/a><br \/> <a href=\"http:\/\/gentedefe.com\/\" target=\"_blank\"><font color=\"#0033cc\">:: Gente de f&eacute;, a sua comunidade de relacionamento crist&atilde;<\/font><\/a><br \/><a href=\"http:\/\/podcast.cancaonova.com\/\" target=\"_blank\"><font color=\"#0033cc\">:: Podcasts: ou&ccedil;a &aacute;udios sobre variados assuntos<\/font><\/a><br \/><a href=\"http:\/\/paroquias.cancaonova.com\/\" target=\"_blank\"><font color=\"#0033cc\">:: Cadastre sua par&oacute;quia ou capela no Portal Can&ccedil;&atilde;o Nova<\/font><\/a><a href=\"http:\/\/paroquias.cancaonova.com\/\" target=\"_blank\"><font color=\"#0033cc\"><br \/><\/font><\/a><br \/><strong>Para o seu celular:<\/strong><\/p>\n<p><a href=\"http:\/\/www.cancaonovamobile.com\/\" target=\"_blank\"><font color=\"#0033cc\">:: Can&ccedil;&atilde;o Nova Mobile<\/font><\/a><br \/><a href=\"http:\/\/cnchama.com.br\/\" target=\"_blank\"><font color=\"#0033cc\">:: CN Chama, a Palavra de Deus no seu celular<\/font><\/a><br \/><a href=\"http:\/\/iphone.cancaonova.com\/\" target=\"_blank\"><font color=\"#0033cc\">:: Iphone<\/font><\/a><\/p>\n<p><strong>Mais canais na web:<\/strong><\/p>\n<p><a href=\"http:\/\/meadiciona.com\/cancaonova\" target=\"_blank\"><font color=\"#0033cc\">:: meadiciona.com\/cancaonova <\/font><\/a><\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A internauta Cristina Ramos (@nina_anjo), de S&atilde;o Paulo (SP), foi a sorteada para participar de uma das prega&ccedil;&otilde;es do padre F&aacute;bio de Melo no Kairos deste domingo, dia 28, na sede da Can&ccedil;&atilde;o Nova, em Cachoeira Paulista (SP). Ela vai&#8230;<\/p>\n","protected":false},"author":114,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[8],"tags":[],"modified_by":"","_links":{"self":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/18068"}],"collection":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/users\/114"}],"replies":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/comments?post=18068"}],"version-history":[{"count":1,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/18068\/revisions"}],"predecessor-version":[{"id":18069,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/18068\/revisions\/18069"}],"wp:attachment":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media?parent=18068"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/categories?post=18068"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/tags?post=18068"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}