{"id":1837,"date":"2012-07-07T13:00:00","date_gmt":"2012-07-07T16:00:00","guid":{"rendered":"http:\/\/admin-canais.cancaonova.com\/eventos\/?p=1837"},"modified":"2014-08-13T00:47:58","modified_gmt":"2014-08-13T03:47:58","slug":"odres-novos-no-encontro-com-cristo","status":"publish","type":"post","link":"https:\/\/admin-canais.cancaonova.com\/eventos\/pregacoes\/odres-novos-no-encontro-com-cristo\/","title":{"rendered":"Odres novos no encontro com Cristo"},"content":{"rendered":"<div id=\"foto\" style=\"width: 180px;margin: 0px auto;padding: 0px 5px 5px 0px;float: left\">\n<div id=\"foto\"><!--ABRE LINK DA FOTO--><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.cancaonova.com\/portal\/arquivos\/fotos\/2012\/julho\/07_padreroger-002.jpg\" border=\"0\" width=\"180\" height=\"220\" \/><!--FECHA LINK DA FOTO--><\/div>\n<div id=\"texto\"><!--TEXTO DA FOTO-->Padre Roger Luis<!--TEXTO DA FOTO--><\/div>\n<div id=\"credito\"><!--CREDITO DA FOTO-->Foto: Maria Andrea\/cancaonova.com<!--CREDITO DA FOTO--><\/div>\n<\/div>\n<p><font color=\"#000000\">Durante todo o dia de hoje, fomos convidados pelo Esp&iacute;rito a fazermos a experi&ecirc;ncia de encontrarmos o Cristo. O povo de Israel relatado na primeira leitura estava sem esperan&ccedil;a, pois n&atilde;o obedeceram &agrave; Palavra e sofreram as consequ&ecirc;ncias disso. <\/p>\n<p> Colocando-nos no lugar deste povo que n&atilde;o tinha lugar para adorar ao Senhor, vemos que apresentavam dificuldades de recuperar a esperan&ccedil;a diante da ru&iacute;na da Casa de Davi. No cora&ccedil;&atilde;o deste povo existia a lembran&ccedil;a da promessa de Deus, mesmo estando longe da pr&aacute;tica da f&eacute; e humilhados, diante disso precisavam ter esperan&ccedil;a. Somos tentados a viver sem esperan&ccedil;a como este povo. Muitas vezes, n&atilde;o acreditamos que na dor que vivemos, podemos encontr&aacute;-la, durante a prova&ccedil;&atilde;o ficamos desesperados e n&atilde;o encontramos a Deus. Onde est&aacute; Deus diante dos meus sofrimentos? <\/p>\n<p> Sabemos que &ldquo;A esperan&ccedil;a n&atilde;o decepciona&rdquo; Rm 5,5 e o desejo de Deus &eacute; que sua promessa seja cumprida por meu de seu Filho Jesus, pois <strong>as promessas de Deus s&atilde;o bem maiores do que nossas expectativas.<\/strong> Se acreditarmos nisto, por que ainda nos desesperamos? Precisamos dar um passo concreto em nossa vida e n&atilde;o podemos desistir. A maior tenta&ccedil;&atilde;o que o inimigo nos faz &eacute; acreditar que nada tem mais jeito, mas em Cristo precisamos que Ele realiza os imposs&iacute;veis. Deus cumpre a profecia de Am&oacute;s em Lc 1, 36 <em>&ldquo;Ele ser&aacute; grande e chamar-se-&aacute; Filho do Alt&iacute;ssimo, e o Senhor Deus lhe dar&aacute; o trono de seu pai Davi; e reinar&aacute; eternamente na casa de Jac&oacute;, e o seu reino n&atilde;o ter&aacute; fim.&rdquo; <\/em> <br \/><\/font><\/p>\n<div id=\"foto\" style=\"width: 370px;margin: 0px auto;padding: 5px 0px;float: none\">\n<div id=\"foto\"><!--ABRE LINK DA FOTO--><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.cancaonova.com\/portal\/arquivos\/fotos\/2012\/julho\/07_padreroger-001.jpg\" border=\"0\" width=\"370\" height=\"250\" \/><!--FECHA LINK DA FOTO--><\/div>\n<div id=\"texto\"><!--TEXTO DA FOTO-->&ldquo;A esperan&ccedil;a n&atilde;o decepciona&rdquo; Rm 5,5<!--TEXTO DA FOTO--><\/div>\n<div id=\"credito\"><!--CREDITO DA FOTO-->Foto: Maria Andrea\/cancaonova.com<!--CREDITO DA FOTO--><\/div>\n<\/div>\n<div align=\"center\">&nbsp;<a href=\"http:\/\/www.flickr.com\/photos\/cancaonova\/collections\/72157630463427276\/\" target=\"_blank\"> <span style=\"color: #5a5a5a;text-decoration: none;font-family: Verdana,Arial,Helvetica,sans-serif;font-size: 10px;font-style: normal;font-variant: normal;font-weight: normal;letter-spacing: normal;line-height: normal;text-align: justify;text-indent: 0px;background-color: #ffffff\"><strong><font color=\"#0033cc\">: Veja + fotos no Flick<\/font><font color=\"#ff00cc\">r<\/font><\/strong><\/span><\/a><br \/><a href=\"https:\/\/www.facebook.com\/media\/set\/?set=a.10150918349199632.418168.45027114631&amp;type=3\" target=\"_blank\"><span style=\"color: #5a5a5a;text-decoration: none;font-family: Verdana,Arial,Helvetica,sans-serif;font-size: 10px;font-style: normal;font-variant: normal;font-weight: normal;letter-spacing: normal;line-height: normal;text-indent: 0px;background-color: #ffffff\"><span style=\"color: #5a5a5a;text-decoration: none;font-family: Verdana,Arial,Helvetica,sans-serif;font-size: 10px;font-style: normal;font-variant: normal;font-weight: normal;letter-spacing: normal;line-height: normal;text-indent: 0px;background-color: #ffffff\"><font style=\"color: #5a5a5a;font-family: Verdana,Arial,Helvetica,sans-serif;font-size: 10px;font-style: normal;font-variant: normal;font-weight: normal;letter-spacing: normal;line-height: normal;text-align: justify;text-indent: 0px;background-color: #ffffff\"><strong><span style=\"color: #5a5a5a;text-decoration: none\"><font color=\"#0033cc\">:: Comente as fotos no Facebook<\/font><\/span><\/strong><\/font><\/span><\/span><\/a><br \/><font color=\"#000000\"><br \/><a href=\"https:\/\/www.facebook.com\/media\/set\/?set=a.10150918349199632.418168.45027114631&amp;type=3\" target=\"_blank\"><span style=\"color: #5a5a5a;text-decoration: none;font-family: Verdana,Arial,Helvetica,sans-serif;font-size: 10px;font-style: normal;font-variant: normal;font-weight: normal;letter-spacing: normal;line-height: normal;text-indent: 0px;background-color: #ffffff\"><span style=\"color: #5a5a5a;text-decoration: none;font-family: Verdana,Arial,Helvetica,sans-serif;font-size: 10px;font-style: normal;font-variant: normal;font-weight: normal;letter-spacing: normal;line-height: normal;text-indent: 0px;background-color: #ffffff\"><font style=\"color: #5a5a5a;font-family: Verdana,Arial,Helvetica,sans-serif;font-size: 10px;font-style: normal;font-variant: normal;font-weight: normal;letter-spacing: normal;line-height: normal;text-align: justify;text-indent: 0px;background-color: #ffffff\"><strong><span style=\"color: #5a5a5a;text-decoration: none\"><\/span><\/strong><\/font><\/span><\/span><\/a><\/font><\/div>\n<p><font color=\"#000000\"> Precisamos  colocar em Deus a nossa esperan&ccedil;a, o encontro com o Cristo nos leva a fazer parte deste povo que n&atilde;o perde a esperan&ccedil;a. Aquele que se encontra com o Cristo n&atilde;o nunca desiste! Mesmo diante dos sofrimentos e nas decep&ccedil;&otilde;es que vivemos,  quer em nossa comunidade, quer em nossa casa, n&atilde;o podemos desistir, somos predestinados ao C&eacute;u.   <em>&ldquo;Nele, Deus nos escolheu, antes da funda&ccedil;&atilde;o do mundo, para sermos santos e &iacute;ntegros diante dele, no amor. Conforme o des&iacute;gnio benevolente de sua vontade, ele nos predestinou &agrave; ado&ccedil;&atilde;o como filhos, por obra de Jesus Cristo, para o louvor de sua gra&ccedil;a gloriosa, com que nos agraciou no seu bem-amado.&rdquo;<\/em> Ef 1, 4-6 <\/p>\n<p> Muitas vezes, o vinho da alegria &eacute; perdido pela falta de f&eacute;. N&atilde;o podemos permitir que o vinho da alegria que &eacute; pertencermos ao Corpo de Cristo, seja transformado em vinagre. Se n&oacute;s permitirmos que a tenta&ccedil;&atilde;o nos leve a enxergar somente o lado negativo, perdemos a esperan&ccedil;a. A sua esperan&ccedil;a &eacute; o Senhor, voc&ecirc; precisa confiar e colocar a sua f&eacute; nesse Deus que &eacute; fiel para cumprir suas promessas, tenha a coragem de colocar sua confian&ccedil;a em Deus. N&oacute;s somos os escolhidos para sermos os primeiros a colocar a esperan&ccedil;a em Cristo. Os disc&iacute;pulos de Jesus tinham a promessa encarnada em suas vidas. J&aacute;, os disc&iacute;pulos de Jo&atilde;o n&atilde;o entendiam isso, pois n&atilde;o haviam feito a experi&ecirc;ncia com o Cristo. <\/font><\/p>\n<div id=\"foto\" style=\"width: 370px;margin: 0px auto;padding: 5px 0px;float: none\">\n<div id=\"foto\"><!--ABRE LINK DA FOTO--><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.cancaonova.com\/portal\/arquivos\/fotos\/2012\/julho\/07_padreroger-003.jpg\" border=\"0\" width=\"370\" height=\"250\" \/><!--FECHA LINK DA FOTO--><\/div>\n<div id=\"texto\"><!--TEXTO DA FOTO-->&quot;S&oacute; teremos uma vida nova, se n&oacute;s formos amigos do Senhor,&quot; afirma o padre<!--TEXTO DA FOTO--><\/div>\n<div id=\"credito\"><!--CREDITO DA FOTO-->Foto: Maria Andrea\/cancaonova.com<!--CREDITO DA FOTO--><\/div>\n<\/div>\n<p> <font color=\"#000000\">Jesus veio trazer a nova mensagem que n&atilde;o cabe na antiga. Mas, Ele n&atilde;o aboliu o que era antigo. Na nova mensagem, Jesus trouxe a miseric&oacute;rdia, e &eacute; por isso que o nosso cora&ccedil;&atilde;o deve sempre estar aberto &agrave; novidade do Esp&iacute;rito e isso precisa acontecer diariamente, n&atilde;o parou no nosso encontro pessoal com Jesus, mas deve ser encarnado em nossas vidas todos os dias. &ldquo;Portanto, se algu&eacute;m est&aacute; em Cristo, &eacute; criatura nova. O que era antigo passou, agora tudo &eacute; novo.&rdquo; II Cor 5,17  <\/p>\n<p> No Cristianismo a mensagem &eacute; sempre nova. Quem nos capacita a sermos odres novos &eacute; o Esp&iacute;rito Santo. Precisamos ser amigos de Jesus. O encontro com o Cristo deve nos levar a amizade com Ele. S&oacute; teremos uma vida nova, se n&oacute;s formos amigos do Senhor. O Papa Bento XVI, em uma de suas catequeses disse, <strong>o encontro cotidiano com o Senhor permite-nos abrir o nosso cora&ccedil;&atilde;o para vivermos e fazer a experi&ecirc;ncia com o O&aacute;sis da paz.<br \/><\/strong><em><br \/>Transcri&ccedil;&atilde;o e adapta&ccedil;&atilde;o: Luana Oliveira<\/em><strong> <\/strong><\/font><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Padre Roger Luis Foto: Maria Andrea\/cancaonova.com Durante todo o dia de hoje, fomos convidados pelo Esp&iacute;rito a fazermos a experi&ecirc;ncia de encontrarmos o Cristo. O povo de Israel relatado na primeira leitura estava sem esperan&ccedil;a, pois n&atilde;o obedeceram &agrave; Palavra&#8230;<\/p>\n","protected":false},"author":114,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7],"tags":[],"modified_by":"","_links":{"self":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/1837"}],"collection":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/users\/114"}],"replies":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/comments?post=1837"}],"version-history":[{"count":1,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/1837\/revisions"}],"predecessor-version":[{"id":1838,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/1837\/revisions\/1838"}],"wp:attachment":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media?parent=1837"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/categories?post=1837"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/tags?post=1837"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}