{"id":20670,"date":"2014-08-21T16:09:15","date_gmt":"2014-08-21T19:09:15","guid":{"rendered":"http:\/\/admin-canais.cancaonova.com\/eventos\/?p=20670"},"modified":"2014-08-21T16:18:32","modified_gmt":"2014-08-21T19:18:32","slug":"para-que-jesus-me-chama","status":"publish","type":"post","link":"https:\/\/admin-canais.cancaonova.com\/eventos\/quinta-feira-de-adoracao\/pregacoes\/para-que-jesus-me-chama\/","title":{"rendered":"Para que Jesus me chama"},"content":{"rendered":"<div id=\"attachment_20671\" style=\"width: 255px\" class=\"wp-caption alignleft\"><a href=\"http:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2014\/08\/FabioLira.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-20671\" class=\"size-medium wp-image-20671\" src=\"http:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2014\/08\/FabioLira-245x300.jpg\" alt=\"F\u00e1bio Lira. Cr\u00e9dito da foto: Wesley Almeida\/Cancaonova.com\" width=\"245\" height=\"300\" srcset=\"https:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2014\/08\/FabioLira-245x300.jpg 245w, https:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2014\/08\/FabioLira.jpg 269w\" sizes=\"(max-width: 245px) 100vw, 245px\" \/><\/a><p id=\"caption-attachment-20671\" class=\"wp-caption-text\">F\u00e1bio Lira. Cr\u00e9dito da foto: Wesley Almeida\/Cancaonova.com<\/p><\/div>\n<p style=\"text-align: justify\">O tema para essa prega\u00e7\u00e3o \u00e9: &#8220;Para que Jesus me chama?&#8221;. O Senhor nos chama, pois tem um prop\u00f3sito para cada um de n\u00f3s. Deus procura filhos e filhas dispostos a levar a Sua Palavra, e todos n\u00f3s fomos escolhidos para essa miss\u00e3o! At\u00e9 mesmo quando nem exist\u00edamos, Ele j\u00e1 tinha um chamado para n\u00f3s, o nosso nome j\u00e1 estava escrito no livro da vida.<\/p>\n<p style=\"text-align: justify\">E para que Deus nos chama? Para a vida religiosa, para sermos chamados Seus filhos. Mas, \u00e9 mais do que isso: fomos chamados para a santidade, para sermos santos. O Senhor nos chama pelo nome para vivermos a santidade. Mas o que \u00e9 ser santo? Santo \u00e9 aquele que n\u00e3o se estaciona diante das situa\u00e7\u00f5es, \u00e9 aquele que n\u00e3o aceita o pecado depois que encontrou Jesus Cristo; santo \u00e9 aquele que n\u00e3o se conforma com o pecado, mas quer estar sempre na presen\u00e7a de Deus.<\/p>\n<p style=\"text-align: justify\"><em>&#8220;Por isso, estejam de esp\u00edrito pronto para agir, sejam s\u00f3brios e ponham toda a esperan\u00e7a na gra\u00e7a que ser\u00e1 trazida a voc\u00eas quando Jesus Cristo se manifestar. Como filhos obedientes, n\u00e3o devem mais viver como antes, quando ainda eram ignorantes e se deixavam guiar pelas paix\u00f5es. Pelo contr\u00e1rio, assim como \u00e9 santo o Deus que os chamou, tamb\u00e9m voc\u00eas tornem-se santos em todo o porque a Escritura diz: &#8220;sejam santos, porque eu sou santo&#8221;<\/em> (I Pedro 1, 13-16).<\/p>\n<p style=\"text-align: justify\">A Palavra nos diz: &#8220;N\u00e3o vos conformeis com o pecado&#8221;. Deus repousa sobre a nossa vida e tem um chamado para cada um de n\u00f3s. Mas ser santo do\u00ed, \u00e9 uma luta di\u00e1ria! O Senhor n\u00e3o nos chamou para o pecado, \u00a0e sim para sermos Seus filhos!<\/p>\n<p style=\"text-align: justify\">Deus deu a Sua vida pela nossa e, n\u00e3o fica alegre com a situa\u00e7\u00e3o de pecado que muitos de n\u00f3s t\u00eam vivido, por isso nos chama, todos os dias, \u00e0 santidade. Mas o caminho da santidade n\u00e3o \u00e9 f\u00e1cil, \u00e9 uma luta di\u00e1ria, uma batalha que precisamos vencer todos os dias. O Senhor nos convida a ser santos, assim como Ele \u00e9 Santo!<\/p>\n<p style=\"text-align: justify\">Fomos escolhidos por Deus. O Senhor olhou para n\u00f3s assim como olhou para Davi. Deus n\u00e3o chama pregui\u00e7osos. Talvez, as pessoas n\u00e3o acreditem em voc\u00ea, n\u00e3o o valorizem, mas o Senhor quer fazer da sua vida um tempo novo de gra\u00e7a. Ser santo \u00e9 ser uma nova criatura! O saudoso Jo\u00e3o Paulo II dizia: &#8220;O mundo precisa de santos&#8221;.<\/p>\n<div id=\"attachment_20672\" style=\"width: 605px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2014\/08\/FabioLira-Pessoas.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-20672\" class=\"size-full wp-image-20672\" src=\"http:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2014\/08\/FabioLira-Pessoas.jpg\" alt=\"&quot;O Senhor n\u00e3o nos fez para a pris\u00e3o do pecado, Ele nos fez para o c\u00e9u!&quot;, afirma F\u00e1bio Lira. Cr\u00e9dito da foto: Wesley Almeida\/Cancaonova.com\" width=\"595\" height=\"420\" srcset=\"https:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2014\/08\/FabioLira-Pessoas.jpg 595w, https:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2014\/08\/FabioLira-Pessoas-300x211.jpg 300w\" sizes=\"(max-width: 595px) 100vw, 595px\" \/><\/a><p id=\"caption-attachment-20672\" class=\"wp-caption-text\">&#8220;O Senhor n\u00e3o nos fez para a pris\u00e3o do pecado, mas sim para o c\u00e9u!&#8221;, afirma F\u00e1bio Lira. Cr\u00e9dito da foto: Wesley Almeida\/cancaonova.com<\/p><\/div>\n<p style=\"text-align: justify\">\nN\u00f3s temos um mapa que se chama &#8220;Palavra de Deus&#8221;, a qual nos conduz at\u00e9 o Pai. Precisamos voltar \u00e0 radicalidade do Evangelho, precisamos mudar o nosso modo de ver, falar e agir; precisamos voltar aos bra\u00e7os de Deus. Somos estrangeiros neste mundo, o c\u00e9u \u00e9 o nosso lugar; aqui na terra, tudo passar\u00e1. Voltemo-nos a Deus, \u00e0 Sua Palavra!<\/p>\n<p style=\"text-align: justify\">H\u00e1 quanto tempo voc\u00ea \u00e9 prisioneiro do pecado? O Senhor n\u00e3o nos fez para a pris\u00e3o do pecado, Ele nos fez para o c\u00e9u! O mundo precisa de santos, a nossa santifica\u00e7\u00e3o se faz nas pequenas coisas do dia a dia, a nossa santidade acontece quando, em vez de sermos aliados do pecado, dobramos o nosso joelho para rezar, para pedir a intercess\u00e3o do Pai.<\/p>\n<p style=\"text-align: justify\">Muitos, quando pensam em ser santos, n\u00e3o querem sofrer, n\u00e3o querem enfrentar as coisas. Essas pessoas precisam entender que as coisas mundanas n\u00e3o lhes fazem bem, pois n\u00e3o s\u00e3o feitas para a escravid\u00e3o. A vontade de Deus \u00e9 que voc\u00ea seja santo! Entregue-se \u00e0 vontade d&#8217;Ele, decida-se por Jesus Cristo e a sua vida mudar\u00e1. Volte a buscar a santidade e ganhe um lugar no c\u00e9u.<\/p>\n<p style=\"text-align: justify\">O que \u00e9 preciso mudar para ser santo? Para chegar \u00e0 santidade, precisamos de muita ora\u00e7\u00e3o e mudan\u00e7a de conduta. Os santos tiveram uma trajet\u00f3ria normal em suas vidas, mas se encontraram com Deus. Eles n\u00e3o nasceram &#8220;super-homens&#8221;, o que mudou na vida deles foi o fato de terem feito a op\u00e7\u00e3o por Jesus, mesmo nos momentos mais dif\u00edceis. Eles n\u00e3o s\u00e3o her\u00f3is, s\u00e3o pessoas normais que decidiram renunciar ao pecado e levar uma vida em Cristo.<\/p>\n<p style=\"text-align: justify\">Os santos s\u00e3o alegres. Talvez, seja por esse motivo que as pessoas n\u00e3o mudam, pois est\u00e3o sempre de cara amarrada, tristes. Satan\u00e1s quer nos ver tristes, mas Deus n\u00e3o! A tristeza \u00e9 apenas uma passagem e, um dia, vamos morar no c\u00e9u, mas para isso precisamos aceitar o chamado de Deus. Santo \u00e9 o pecador inconformado com o pecado.<\/p>\n<p style=\"text-align: justify\">Muitos podem estar rindo de voc\u00ea, rindo da sua escolha de viver ao lado de Deus, mas Ele tem algo melhor para voc\u00ea. Acredite nisso! Todos somos chamados a caminhar na santidade.<\/p>\n<p style=\"text-align: justify\">A nossa Igreja \u00e9 recheada de exemplos de santidade: Santo Ant\u00f4nio, Santa Rita, S\u00e3o Jo\u00e3o Batista entre outros. Precisamos pedir a gra\u00e7a de estar na presen\u00e7a de Deus, de caminhar ao lado d&#8217;Ele. Precisamos pedir a cada dia: &#8220;Faze-me fiel, d\u00e1-me a gra\u00e7a, de todos os dias, estar junto de Ti&#8221;.<\/p>\n<p style=\"text-align: justify\"><em>Transcri\u00e7\u00e3o e adapta\u00e7\u00e3o: Karina Aparecida\u00a0<\/em><\/p>\n<p style=\"text-align: justify\">\n","protected":false},"excerpt":{"rendered":"<p>O tema para essa prega\u00e7\u00e3o \u00e9: &#8220;Para que Jesus me chama?&#8221;. O Senhor nos chama, pois tem um prop\u00f3sito para cada um de n\u00f3s. Deus procura filhos e filhas dispostos a levar a Sua Palavra, e todos n\u00f3s fomos escolhidos&#8230;<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7],"tags":[],"modified_by":"michelle","_links":{"self":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/20670"}],"collection":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/comments?post=20670"}],"version-history":[{"count":5,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/20670\/revisions"}],"predecessor-version":[{"id":20681,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/20670\/revisions\/20681"}],"wp:attachment":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media?parent=20670"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/categories?post=20670"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/tags?post=20670"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}