{"id":21545,"date":"2014-09-20T13:38:10","date_gmt":"2014-09-20T16:38:10","guid":{"rendered":"http:\/\/admin-canais.cancaonova.com\/eventos\/?p=21545"},"modified":"2014-09-22T12:11:11","modified_gmt":"2014-09-22T15:11:11","slug":"demolir-os-idolos","status":"publish","type":"post","link":"https:\/\/admin-canais.cancaonova.com\/eventos\/6--encontro-da-divina-misericordia\/pregacoes\/demolir-os-idolos\/","title":{"rendered":"Demolir os \u00eddolos"},"content":{"rendered":"<div id=\"attachment_21546\" style=\"width: 279px\" class=\"wp-caption alignright\"><a href=\"http:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2014\/09\/Eliana-S\u00e1.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-21546\" class=\"size-full wp-image-21546\" src=\"http:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2014\/09\/Eliana-S\u00e1.jpg\" alt=\"Eliana S\u00e1. Fotos: Wesley Almeida\/ Cn\" width=\"269\" height=\"329\" srcset=\"https:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2014\/09\/Eliana-S\u00e1.jpg 269w, https:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2014\/09\/Eliana-S\u00e1-245x300.jpg 245w\" sizes=\"(max-width: 269px) 100vw, 269px\" \/><\/a><p id=\"caption-attachment-21546\" class=\"wp-caption-text\">Eliana S\u00e1. Fotos: Wesley Almeida\/ Cn<\/p><\/div>\n<p style=\"text-align: justify\">Quando Ricardo e eu\u00a0est\u00e1vamos morando na miss\u00e3o do Rio de Janeiro ficamos amigos de dois padres: Ant\u00f4nio Aguiar e Alexandre Paciolli. O padre Ant\u00f4nio disse para mim: &#8220;Voc\u00ea est\u00e1 indo para Cachoeira Paulista, realiza l\u00e1 o Acampamento da Divina Miseric\u00f3rdia&#8221;.<\/p>\n<p style=\"text-align: justify\">Padre Jos\u00e9 Augusto abra\u00e7ou essa causa comigo. Um dia, eu estava na capela da Sagrada Fam\u00edlia adorando a Jesus Sacramentado. E olhei para o Sant\u00edssimo e disse: &#8220;Jesus, o padre me incentivou a fazer a Festa da Miseric\u00f3rdia, mas a festa \u00e9 Sua. Convide as pessoas para a Sua festa&#8221;. E na hora veio ao meu cora\u00e7\u00e3o: <em>&#8220;Eu sou o Deus do padre L\u00e9o; Eu sou o Deus do monsenhor Jonas Abib e Eu vou atrair uma multid\u00e3o para a minha festa&#8221;<\/em>. E eu corri para o padre Jos\u00e9 Augusto e disse a ele: &#8220;Vai vir uma multid\u00e3o!&#8221;.<\/p>\n<p style=\"text-align: justify\">No s\u00e1bado que antecedia \u00e0 primeira festa, no \u00faltimo dia da novena, eu via muitos \u00f4nibus chegando. Eu confiava no que Jesus havia falado, mas, ao mesmo tempo, eu usava a minha l\u00f3gica, e achava que n\u00e3o era poss\u00edvel virem tantas pessoas. Ent\u00e3o comecei a ver o povo de Deus chegando. E liguei para a Luzia e disse que havia nove \u00f4nibus. Ela me respondeu: &#8220;Bem, se n\u00e3o vier muita gente n\u00e3o se preocupe&#8221;. Mas quando eu acordei, no domingo de manh\u00e3, eu vi muitos \u00f4nibus chegando.<\/p>\n<p style=\"text-align: justify\">No domingo come\u00e7ou a Festa da Miseric\u00f3rdia e havia muita gente. Mas a festa come\u00e7ou no lado aberto do cora\u00e7\u00e3o de Jesus, no Calv\u00e1rio. A Festa da Miseric\u00f3rdia come\u00e7ou no Calv\u00e1rio!<\/p>\n<p style=\"text-align: justify\">\u00c9 preciso ter gratid\u00e3o. S\u00e3o quatorze anos que eu luto contra a depress\u00e3o. Eu sou uma pessoa que diz como Santa Terezinha: &#8220;S\u00f3 por hoje eu vou acordar, s\u00f3 por hoje eu vou sorrir, s\u00f3 por hoje eu vou fazer uma comida gostosa para o meu esposo&#8221;.<\/p>\n<p style=\"text-align: justify\">Nessa madrugada eu acordei, rezei o ter\u00e7o, e depois mais tarde, sem sono, eu despertei de novo e fui ver os e-mails. Vi quantas pessoas que est\u00e3o no vale de l\u00e1grimas. Deus quis que a nossa gera\u00e7\u00e3o vivesse esse tempo de Miseric\u00f3rdia. N\u00f3s precisamos demolir os altares no nosso cora\u00e7\u00e3o que constru\u00edmos para os \u00eddolos da ingratid\u00e3o. Voc\u00ea tem gratid\u00e3o pelas pessoas que passaram na sua vida e o convidaram para ir a Jesus? N\u00f3s temos um altar dentro de n\u00f3s de m\u00e1goas. Talvez tenhams um temperamento forte, mas eu quero dizer a voc\u00ea que est\u00e1 aqui e que criou um altar de m\u00e1goas no seu cora\u00e7\u00e3o: em nome de Jesus, liberte-se das suas m\u00e1goas! N\u00e3o vivamos do passado, querendo justific\u00e1-lo. Temos tamb\u00e9m o altar das novelas, que nos tira o tempo para rezar, e nos prende \u00e0 televis\u00e3o.<\/p>\n<div id=\"attachment_21547\" style=\"width: 605px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2014\/09\/Peregrinos2.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-21547\" class=\"size-full wp-image-21547\" src=\"http:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2014\/09\/Peregrinos2.jpg\" alt=\"Peregrinos participam do 6\u00ba encontro da Divina Miseric\u00f3rdia. Fotos: Wesley Almeida\/ Cn\" width=\"595\" height=\"420\" srcset=\"https:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2014\/09\/Peregrinos2.jpg 595w, https:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2014\/09\/Peregrinos2-300x211.jpg 300w\" sizes=\"(max-width: 595px) 100vw, 595px\" \/><\/a><p id=\"caption-attachment-21547\" class=\"wp-caption-text\">Peregrinos participam do 6\u00ba encontro da Divina Miseric\u00f3rdia. Fotos: Wesley Almeida\/ Cn<\/p><\/div>\n<p style=\"text-align: center\"><a href=\"https:\/\/www.flickr.com\/photos\/cancaonova\/sets\/72157647807058671\/\" target=\"_blank\"><span style=\"color: #000000\">::<strong><span style=\"color: #0000ff\">Flick<span style=\"color: #ff00ff\">r<\/span><\/span><\/strong> <\/span>Can\u00e7\u00e3o Nova<\/a><\/p>\n<p style=\"text-align: justify\"><strong>N\u00f3s precisamos demolir do nosso cora\u00e7\u00e3o os \u00eddolos!\u00a0<\/strong>Pais, voc\u00eas precisam estar por inteiros em casa. N\u00e3o \u00e9 a quantidade, mas a qualidade do tempo que vai contar. \u00c9 preciso deixar o deus do dinheiro para estar com a fam\u00edlia.<\/p>\n<p style=\"text-align: justify\">Sabe qual deus que muitas vezes tamb\u00e9m est\u00e1 no nosso cora\u00e7\u00e3o? A cultura de morte. As pessoas n\u00e3o querem ter filhos. O dem\u00f4nio colocou na cabe\u00e7a das pessoas, e at\u00e9 dos crist\u00e3os, que basta ter um filho. Mas isso n\u00e3o \u00e9 verdade. Como diz a m\u00fasica &#8220;Utopia&#8221; do padre Zezinho: &#8216;<em>Faltava tudo, mas a gente n\u00e3o ligava, o importante n\u00e3o faltava<\/em>&#8216;. Para quem se abre \u00e0 vida n\u00e3o falta nada. Quanto mais filhos tivermos, tanto mais vamos povoar este mundo de f\u00e9. O pr\u00edncipe deste mundo \u00e9 o autor da morte. Vamos demolir o \u00eddolo da morte e do apego ao dinheiro!<\/p>\n<p style=\"text-align: justify\">O Papa Francisco fala de um mal que assolou e assola a Igreja, que \u00e9 a lepra do &#8220;carreirismo&#8221;. N\u00f3s vamos \u00e0 igreja, rezamos, mas n\u00e3o dizemos ao Senhor: &#8216;Muito obrigada&#8217;. A mentalidade mundana e os desejos mundanos t\u00eam entrado em nosso cora\u00e7\u00e3o. Com a mentalidade mundana n\u00f3s queremos fugir da cruz. \u00c9 preciso buscar, antes de tudo, a salva\u00e7\u00e3o para os nossos familiares, n\u00e3o apenas a mudan\u00e7a, mas a salva\u00e7\u00e3o deles. Sem a cruz n\u00e3o tem como chegar ao c\u00e9u.<\/p>\n<p style=\"text-align: justify\">&#8220;A mundanidade espiritual mata! Mata a alma, as pessoas e a Igreja&#8221;, disse Papa Francisco.<\/p>\n<p style=\"text-align: justify\"><em>Transcri\u00e7\u00e3o e adapta\u00e7\u00e3o: Jakeline Megda D&#8217;Onofrio<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quando Ricardo e eu\u00a0est\u00e1vamos morando na miss\u00e3o do Rio de Janeiro ficamos amigos de dois padres: Ant\u00f4nio Aguiar e Alexandre Paciolli. O padre Ant\u00f4nio disse para mim: &#8220;Voc\u00ea est\u00e1 indo para Cachoeira Paulista, realiza l\u00e1 o Acampamento da Divina Miseric\u00f3rdia&#8221;&#8230;.<\/p>\n","protected":false},"author":116,"featured_media":21552,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7],"tags":[],"modified_by":null,"_links":{"self":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/21545"}],"collection":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/users\/116"}],"replies":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/comments?post=21545"}],"version-history":[{"count":7,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/21545\/revisions"}],"predecessor-version":[{"id":21600,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/21545\/revisions\/21600"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media\/21552"}],"wp:attachment":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media?parent=21545"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/categories?post=21545"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/tags?post=21545"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}