{"id":23019,"date":"2014-11-13T15:03:02","date_gmt":"2014-11-13T18:03:02","guid":{"rendered":"http:\/\/admin-canais.cancaonova.com\/eventos\/?p=23019"},"modified":"2014-11-13T15:29:04","modified_gmt":"2014-11-13T18:29:04","slug":"o-cristao-verdadeiro-e-sempre-missionario-de-cristo","status":"publish","type":"post","link":"https:\/\/admin-canais.cancaonova.com\/eventos\/quinta-feira-de-adoracao\/pregacoes\/o-cristao-verdadeiro-e-sempre-missionario-de-cristo\/","title":{"rendered":"O crist\u00e3o verdadeiro \u00e9 sempre mission\u00e1rio de Cristo"},"content":{"rendered":"<div id=\"attachment_23020\" style=\"width: 279px\" class=\"wp-caption alignleft\"><a href=\"http:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2014\/11\/Prega\u00e7\u00e3o-Italo-Perfil.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-23020\" class=\"size-full wp-image-23020\" src=\"http:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2014\/11\/Prega\u00e7\u00e3o-Italo-Perfil.jpg\" alt=\" Italo J. Passanezi Fasanella. Foto: Daniel Mafra\/ cancaonova.com. \" width=\"269\" height=\"329\" srcset=\"https:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2014\/11\/Prega\u00e7\u00e3o-Italo-Perfil.jpg 269w, https:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2014\/11\/Prega\u00e7\u00e3o-Italo-Perfil-245x300.jpg 245w\" sizes=\"(max-width: 269px) 100vw, 269px\" \/><\/a><p id=\"caption-attachment-23020\" class=\"wp-caption-text\">Italo Fasanella. Foto: Daniel Mafra\/ cancaonova.com.<\/p><\/div>\n<p style=\"text-align: justify\">Acolhamos este convite de Deus em nossos cora\u00e7\u00f5es: ser um disc\u00edpulo mission\u00e1rio.<\/p>\n<p>Um pouco antes de o Senhor partir deste mundo, deixou as \u00faltimas instru\u00e7\u00f5es para aqueles que, um dia, seriam Seus seguidores: <em>\u201cIde e fazei disc\u00edpulos meus entre todas as na\u00e7\u00f5es\u201d<\/em> (Mt 28,19). Deus nos garante Sua presen\u00e7a entre n\u00f3s. Ele vai, mas promete estar sempre ao nosso lado. Precisamos ter essa presen\u00e7a viva junto de n\u00f3s, principalmente nos tempos de hoje, quando muitos crist\u00e3os sofrem tantas persegui\u00e7\u00f5es.<\/p>\n<p style=\"text-align: justify\">De certa forma, cada um que aceita o seu batismo sofre persegui\u00e7\u00f5es. Se n\u00f3s, que somos batizados, n\u00e3o entendermos isso, n\u00e3o conseguiremos entender a nossa miss\u00e3o! O disc\u00edpulo \u00e9 aquele que vai ao encontro do Mestre, que est\u00e1 aos p\u00e9s d&#8217;Ele. \u00c9 uma caracter\u00edstica do disc\u00edpulo ter essa proximidade com Jesus. Ele\u00a0se torna mission\u00e1rio a partir do momento em que anuncia as palavras que escutou de Jesus. \u00c9 um colaborador da vit\u00f3ria de Deus.<\/p>\n<p style=\"text-align: justify\">Precisamos ter essa consci\u00eancia: quando somos convocados por Deus, precisamos estar aos Seus p\u00e9s, ouvir Suas Palavras e anunci\u00e1-las aos demais. Quando nasce o disc\u00edpulo, nasce tamb\u00e9m o mission\u00e1rio!<\/p>\n<p style=\"text-align: justify\">\u00c9 imposs\u00edvel ser um mission\u00e1rio sem antes ser um disc\u00edpulo. O encontro com Cristo e a cruz s\u00e3o sinais de que Ele derrama sobre n\u00f3s o Esp\u00edrito Santo, o dom do Alto. Homens e mulheres novos s\u00f3 passam a existir quando o Esp\u00edrito \u00e9 aceito para agir com Seu poder!<\/p>\n<p style=\"text-align: justify\">O Par\u00e1clito \u00e9 o agente principal da evangeliza\u00e7\u00e3o, \u00e9 Ele quem nos impele a anunciar o Evangelho. Precisamos nos render a essa for\u00e7a, n\u00e3o podemos ficar de bra\u00e7os cruzados,\u00a0mas\u00a0fazer aquilo que o Papa Francisco nos ensinou: \u201cIde e fazei disc\u00edpulos entre todas as na\u00e7\u00f5es\u201d.<\/p>\n<p style=\"text-align: justify\"><em>\u201cEle tomou a palavra, dizendo a todos: Eu vos batizo na \u00e1gua, mas eis que vem outro mais poderoso do que eu, a quem n\u00e3o sou digno de lhe desatar a correia das sand\u00e1lias; ele vos batizar\u00e1 no Esp\u00edrito Santo e no fogo\u201d <\/em>(Lucas 3, 16).<\/p>\n<p style=\"text-align: justify\">Voc\u00ea j\u00e1 empenhou todas as suas for\u00e7as na evangeliza\u00e7\u00e3o? Vamos atender a este apelo da Igreja, o apelo vivo e presente que nos faz hoje o Papa Francisco, o apelo que Cristo nos fez! \u00c0s vezes, nem precisamos ir t\u00e3o longe para evangelizar, pois o mission\u00e1rio que percorre mil quil\u00f4metros e o que d\u00e1 um passo tem a mesma oportunidade de evangeliza\u00e7\u00e3o. O momento em que fomos mergulhados na \u00e1gua do batismo, foi o nosso primeiro encontro com o Esp\u00edrito Santo.<\/p>\n<p style=\"text-align: justify\"><em>\u201cPorque Jo\u00e3o batizou na \u00e1gua, mas v\u00f3s sereis batizados no Esp\u00edrito Santo daqui h\u00e1 poucos dias. Assim reunidos, eles o interrogavam: Senhor, \u00e9 porventura agora que ides instaurar o reino de Israel? Respondeu-lhes ele: N\u00e3o vos pertence a v\u00f3s saber os tempos nem os momentos que o Pai fixou em seu poder, mas descer\u00e1 sobre v\u00f3s o Esp\u00edrito Santo e vos dar\u00e1 for\u00e7a; e sereis minhas testemunhas em Jerusal\u00e9m, em toda a Judeia e Samaria e at\u00e9 os confins do mundo\u201d\u00a0<\/em>(Atos dos Ap\u00f3stolos 1, 5-8).<\/p>\n<p style=\"text-align: justify\">Fico pensando: &#8220;Por que alguns crist\u00e3os s\u00e3o t\u00e3o fraquinhos?&#8221;. Porque lhes falta a for\u00e7a do Alto! Papa Francisco deseja uma Igreja &#8220;em sa\u00edda&#8221;, em Pentecostes. Estamos fechados em n\u00f3s mesmos, precisamos ser uma Igreja em sa\u00edda, aquela que abre portas, janelas, que rompe os traumas do passado.<\/p>\n<div id=\"attachment_23021\" style=\"width: 605px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2014\/11\/Prega\u00e7\u00e3o-Italo-Pessoas.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-23021\" class=\"wp-image-23021 size-full\" src=\"http:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2014\/11\/Prega\u00e7\u00e3o-Italo-Pessoas.jpg\" alt=\"&quot;Precisamos de fam\u00edlias que acolham, que testemunhem a alegria do Evangelho de Cristo!&quot;, ensina Italo. Foto: Daniel Mafra\/ cancaonova.com.\" width=\"595\" height=\"420\" srcset=\"https:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2014\/11\/Prega\u00e7\u00e3o-Italo-Pessoas.jpg 595w, https:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2014\/11\/Prega\u00e7\u00e3o-Italo-Pessoas-300x211.jpg 300w\" sizes=\"(max-width: 595px) 100vw, 595px\" \/><\/a><p id=\"caption-attachment-23021\" class=\"wp-caption-text\">&#8220;Precisamos de fam\u00edlias que acolham, que testemunhem a alegria do Evangelho de Cristo!&#8221;, ensina \u00cdtalo. Foto: Daniel Mafra\/ cancaonova.com.<\/p><\/div>\n<p style=\"text-align: justify\">A Igreja nasce do cora\u00e7\u00e3o aberto de Deus e n\u00f3s crist\u00e3os n\u00e3o podemos estar fechados em n\u00f3s mesmos! Como seguidores e mission\u00e1rios, devemos estar sempre abertos para essa for\u00e7a de Cristo que nos tira do medo.<\/p>\n<p style=\"text-align: justify\">Como dizia S\u00e3o Francisco: \u201cEvangelizem muito e, se for preciso, usem palavras!\u201d. O mundo est\u00e1 precisando de alegria e n\u00f3s somos portadores dela. Quando conhecemos Jesus, a alegria brota dentro de n\u00f3s! Ser disc\u00edpulo n\u00e3o \u00e9 uma roupa, uma fantasia, muito menos um papel que desempenhamos. Quem exerce a miss\u00e3o \u00e9 um mission\u00e1rio!<\/p>\n<p style=\"text-align: justify\">O sacramento do crisma confirma aquilo que recebemos no batismo. Ele nos torna crist\u00e3os, disc\u00edpulos, mission\u00e1rios e santos.\u00a0A condi\u00e7\u00e3o de crist\u00e3o precisa ser despertada, pois enquanto n\u00e3o acordarmos, os discursos ficar\u00e3o apenas no documento, no papel!<\/p>\n<p style=\"text-align: justify\">No cora\u00e7\u00e3o do Evangelho est\u00e1 a verdade, e devemos transmitir ao mundo a beleza do amor de Deus, que envia Seu Filho para morrer pela nossa salva\u00e7\u00e3o. N\u00f3s devemos ser portadores dessa beleza do amor de Deus! Como \u00e9 belo ser crist\u00e3o, ser filho de Deus, ser amado e resgatado por Ele!<\/p>\n<p style=\"text-align: justify\">O mundo precisa formar novas fam\u00edlias, e esta deve ser uma \u201cf\u00e1brica\u201d de mission\u00e1rios, de santos. Quando educamos nossos filhos na f\u00e9, estamos fazendo deles mission\u00e1rios. Precisamos de fam\u00edlias que acolham, que testemunhem a alegria do Evangelho de Cristo!<\/p>\n<p style=\"text-align: justify\"><em>Transcri\u00e7\u00e3o e adapta\u00e7\u00e3o: Karina Aparecida<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Acolhamos este convite de Deus em nossos cora\u00e7\u00f5es: ser um disc\u00edpulo mission\u00e1rio. Um pouco antes de o Senhor partir deste mundo, deixou as \u00faltimas instru\u00e7\u00f5es para aqueles que, um dia, seriam Seus seguidores: \u201cIde e fazei disc\u00edpulos meus entre todas&#8230;<\/p>\n","protected":false},"author":9,"featured_media":23022,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7],"tags":[],"modified_by":"Karina","_links":{"self":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/23019"}],"collection":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/comments?post=23019"}],"version-history":[{"count":5,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/23019\/revisions"}],"predecessor-version":[{"id":23027,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/23019\/revisions\/23027"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media\/23022"}],"wp:attachment":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media?parent=23019"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/categories?post=23019"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/tags?post=23019"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}