{"id":2396,"date":"2010-09-03T17:00:00","date_gmt":"2010-09-03T20:00:00","guid":{"rendered":"http:\/\/admin-canais.cancaonova.com\/eventos\/?p=2396"},"modified":"2014-08-13T01:02:13","modified_gmt":"2014-08-13T04:02:13","slug":"familia-misterio-de-deus-2","status":"publish","type":"post","link":"https:\/\/admin-canais.cancaonova.com\/eventos\/pregacoes\/familia-misterio-de-deus-2\/","title":{"rendered":"Fam\u00edlia mist\u00e9rio de Deus"},"content":{"rendered":"<p>A fam&iacute;lia &eacute; um mist&eacute;rio de Deus, ela acontece como des&iacute;gnio de Deus. A &quot;sa&uacute;de&quot; de uma fam&iacute;lia interfere em uma sociedade e em um povo.  <\/p>\n<p>  Resolvendo os problemas da fam&iacute;lia, resolvemos a situa&ccedil;&atilde;o das droga, da prostitui&ccedil;&atilde;o,  muitas outras coisas quem tem que resolver &eacute; a fam&iacute;lia. Como est&aacute; sua fam&iacute;lia?  <\/p>\n<p>  O futuro passa pela fam&iacute;lia. Quantos filhos &oacute;rf&atilde;os de pais vivos, existe o esposo  e esposas vi&uacute;vos com maridos vivos, porque s&atilde;o pessoas casadas, mas que n&atilde;o se relacionam. E quantos pais choram vendo seus filhos morrendo aos poucos. <\/p>\n<div id=\"foto\" style=\"margin: 0pt auto;width: 370px;padding-left: 0px;padding-top: 0px;padding-bottom: 0px;float: none\">\n<div id=\"foto\"><!--ABRE LINK DA FOTO--><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.cancaonova.com\/portal\/arquivos\/fotos\/2010\/setembro\/padrefabricio2.jpg\" border=\"0\" width=\"370\" height=\"250\" \/><!--FECHA LINK DA FOTO--><\/div>\n<div id=\"texto\"><!--TEXTO DA FOTO-->&#039;Fam&iacute;lia mist&eacute;rio de Deus`<!--TEXTO DA FOTO--><\/div>\n<div id=\"credito\"><!--CREDITO DA FOTO-->Foto:Robson Siqueira<\/p>\n<p><!--CREDITO DA FOTO--><\/div>\n<\/div>\n<p> <strong><br \/>   A fam&iacute;lia tem fundamentos concretos. Essa hist&oacute;ria de dizer que fam&iacute;lia &eacute; do jeito que cada um quer , isso &eacute; remendo para estragar as fam&iacute;lias. <\/strong><\/p>\n<p>  Ef&eacute;sios 5 diz o que &eacute; fam&iacute;lia: <em>&ldquo;Sujeitai-vos uns aos outros no temor de Cristo. As mulheres sejam submissas a seus maridos, como ao Senhor, pois o marido &eacute; o chefe da mulher, como Cristo &eacute; o chefe da Igreja, seu corpo, da qual ele &eacute; o Salvador. Ora, assim como a Igreja &eacute; submissa a Cristo, assim tamb&eacute;m o sejam em tudo as mulheres a seus maridos. Maridos, amai as vossas mulheres, como Cristo amou a Igreja e se entregou por ela, para santific&aacute;-la, purificando-a pela &aacute;gua do batismo com a palavra, para apresent&aacute;-la a si mesmo toda gloriosa, sem m&aacute;cula, sem ruga, sem qualquer outro defeito semelhante, mas santa e irrepreens&iacute;vel.&rdquo;&nbsp; <\/em><\/p>\n<p>  Voc&ecirc; sabia que sua fam&iacute;lia &eacute; uma igreja dom&eacute;stica, igreja particular? A minha fam&iacute;lia &eacute; um mist&eacute;rio, um dom de Deus. Ent&atilde;o n&atilde;o se pode falar de fam&iacute;lia sem refer&ecirc;ncia &agrave; Igreja e a Cristo. <\/p>\n<div id=\"foto\" style=\"margin: 0pt auto;width: 370px;padding-left: 0px;padding-top: 0px;padding-bottom: 0px;float: none\">\n<div id=\"foto\"><!--ABRE LINK DA FOTO--><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.cancaonova.com\/portal\/arquivos\/fotos\/2010\/setembro\/padrefabricio1.jpg\" border=\"0\" width=\"370\" height=\"250\" \/><!--FECHA LINK DA FOTO--><\/div>\n<div id=\"texto\"><!--TEXTO DA FOTO-->&#039;  As propostas novas para fam&iacute;lia j&aacute; s&atilde;o projeto de futuro condenado`<!--TEXTO DA FOTO--><\/div>\n<div id=\"credito\"><!--CREDITO DA FOTO-->Foto:Robson Siqueira<\/p>\n<p><!--CREDITO DA FOTO--><\/div>\n<\/div>\n<p>  O ap&oacute;stolo Paulo diz que somos administradores dos mist&eacute;rios de Deus. Somos administradores de um minist&eacute;rio de Deus, eu n&atilde;o posso fazer com minha fam&iacute;lia o que eu quero, pois &eacute; um mist&eacute;rio do Senhor. <br \/><em><br \/>  &ldquo;Irm&atilde;os, que todo o mundo nos considere como servidores de Cristo e administradores dos mist&eacute;rios de Deus. A este respeito, o que se exige dos administradores &eacute; que sejam fi&eacute;is<\/em>&rdquo;. (I Cor. 4,1) <\/p>\n<p>  Como voc&ecirc; tem administrado o mist&eacute;rio de Deus que &eacute; sua fam&iacute;lia? <\/p>\n<p>  Hoje a fam&iacute;lia est&aacute; sendo profanada pelo &aacute;lcool, cigarro, adult&eacute;rio, crack&#8230; tudo isso acaba com as fam&iacute;lias. Uma crian&ccedil;a de dois anos fumando, isso &eacute; profana&ccedil;&atilde;o da fam&iacute;lia. Para que respeitemos as fam&iacute;lias, precisamos enxergar que se profanarmos a fam&iacute;lias estaremos perdidos. <\/p>\n<p>   Um documento que voc&ecirc; pai, e voc&ecirc; m&atilde;e precisam ler &eacute; <a href=\"http:\/\/www.vatican.va\/archive\/hist_councils\/ii_vatican_council\/documents\/vat-ii_const_19651207_gaudium-et-spes_po.html\" target=\"_blank\"><font color=\"#0033cc\">CONSTITUI&Ccedil;&Atilde;O PASTORAL  GAUDIUM ET SPES<\/font><\/a>  &#8211; Sobre a Igreja no mundo atual.<\/p>\n<p>&ldquo;A salva&ccedil;&atilde;o da pessoa e da sociedade humana est&aacute; estreitamente ligada ao bem estar da comunidade conjugal e familiar&rdquo; (CONSTITUI&Ccedil;&Atilde;O PASTORAL GAUDIUM ET SPES n&ordm; 47).  O futuro da nossa sociedade depende de como est&aacute; a nossa fam&iacute;lia. O primeiro lugar que Deus escolheu para a salva&ccedil;&atilde;o foi a fam&iacute;lia.  As propostas novas para fam&iacute;lia j&aacute; s&atilde;o projeto de futuro condenado.     Mesmo as fam&iacute;lias que se dizem cat&oacute;licas necessitam do primeiro an&uacute;ncio  fundamental da f&eacute; e da catequese, para que possam fazer sua ades&atilde;o pessoal livre a Jesus Cristo e ao Evangelho.   Vamos deixar que esse processo de restaura&ccedil;&atilde;o de nossas fam&iacute;lias comece agora. Quando sua fam&iacute;lia come&ccedil;ar&aacute; a mudar? Quando voc&ecirc; come&ccedil;ar a mudar. A fam&iacute;lia n&atilde;o &eacute; mist&eacute;rio humano &eacute; mist&eacute;rio de Deus.<\/p>\n<div style=\"text-align: center\"><\/div>\n<p>      <\/p>\n<p>&nbsp;<\/p>\n<hr width=\"100%\" size=\"2\" \/>\n<p align=\"center\"><font size=\"1\"><strong>ADQUIRA ESSA PREGA&Ccedil;&Atilde;O PELO TELEFONE<br \/>(12) 3186-2600<\/strong><\/font><\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A fam&iacute;lia &eacute; um mist&eacute;rio de Deus, ela acontece como des&iacute;gnio de Deus. A &quot;sa&uacute;de&quot; de uma fam&iacute;lia interfere em uma sociedade e em um povo. Resolvendo os problemas da fam&iacute;lia, resolvemos a situa&ccedil;&atilde;o das droga, da prostitui&ccedil;&atilde;o, muitas outras&#8230;<\/p>\n","protected":false},"author":114,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7],"tags":[],"modified_by":"","_links":{"self":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/2396"}],"collection":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/users\/114"}],"replies":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/comments?post=2396"}],"version-history":[{"count":1,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/2396\/revisions"}],"predecessor-version":[{"id":2397,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/2396\/revisions\/2397"}],"wp:attachment":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media?parent=2396"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/categories?post=2396"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/tags?post=2396"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}