{"id":2515,"date":"2012-04-21T06:15:00","date_gmt":"2012-04-21T09:15:00","guid":{"rendered":"http:\/\/admin-canais.cancaonova.com\/eventos\/?p=2515"},"modified":"2014-08-13T01:05:02","modified_gmt":"2014-08-13T04:05:02","slug":"musico-toma-a-sua-cruz-e-siga-me","status":"publish","type":"post","link":"https:\/\/admin-canais.cancaonova.com\/eventos\/pregacoes\/musico-toma-a-sua-cruz-e-siga-me\/","title":{"rendered":"M\u00fasico, toma a sua cruz e siga-me"},"content":{"rendered":"<div id=\"foto\" style=\"width: 180px;margin: 0pt auto;padding: 0px 5px 0px 0px;float: left\">\n<div id=\"foto\"><!--ABRE LINK DA FOTO--><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.cancaonova.com\/portal\/arquivos\/fotos\/2012\/abril\/21_eventos-003.jpg\" border=\"0\" width=\"180\" height=\"220\" \/><!--FECHA LINK DA FOTO--><\/div>\n<div id=\"texto\"><!--TEXTO DA FOTO-->Ricardo S&aacute;<!--TEXTO DA FOTO--><\/div>\n<div id=\"credito\"><!--CREDITO DA FOTO-->Foto: Wesley Almeida\/Cancaonova.com<!--CREDITO DA FOTO--><\/div>\n<\/div>\n<p> <font color=\"#000000\">A Palavra de Deus que vai nortear esta prega&ccedil;&atilde;o est&aacute; no Evangelho de S&atilde;o Mateus 16,24:<em> &ldquo;Ent&atilde;o Jesus disse aos disc&iacute;pulos: &ldquo;Se algu&eacute;m quer vir ap&oacute;s mim, renuncie a si mesmo, tome sua cruz e siga-me.&rdquo;<\/em> <\/p>\n<p>  O primeiro ponto que eu gostaria de partilhar com voc&ecirc; &eacute; a import&acirc;ncia de darmos espa&ccedil;o para que a Palavra de Deus entre em voc&ecirc; e atinja a sua vida e o seu cora&ccedil;&atilde;o. <\/p>\n<p>  <strong>A Palavra de Deus &eacute; o alimento de nossa alma,&nbsp; ela ilumina a nossa intelig&ecirc;ncia e emo&ccedil;&otilde;es<\/strong>, &eacute; dela de que n&oacute;s somos ministros, por isso ela precisa ganhar espa&ccedil;o dentro de n&oacute;s, ministros de m&uacute;sica. <\/p>\n<p>  Quando Nosso Senhor coloca um &ldquo;se&rdquo; na frente de uma frase, Ele sabe que nem todos os que estavam ali presentes  iriam segui-Lo, mas, mesmo assim, Ele lan&ccedil;a o convite e semeia a Palavra de Deus em cada cora&ccedil;&atilde;o. <\/p>\n<p>  Toda Palavra boa e m&uacute;sica boa come&ccedil;am e terminam com um profundo sil&ecirc;ncio de interioriza&ccedil;&atilde;o. Muitas vezes, n&oacute;s j&aacute; ouvimos a Palavra de Deus, mas n&oacute;s n&atilde;o damos tempo para que ela chegue at&eacute; o nosso cora&ccedil;&atilde;o.<\/p>\n<p>  O centro dessa Palavra est&aacute; em uma decis&atilde;o: ren&uacute;ncia e seguimento de Nosso Senhor Jesus Cristo.<\/p>\n<p><\/font><a href=\"http:\/\/www.cancaonova.com\/cnova\/ministerio\/temp\/principal.php\" target=\"_blank\"><font color=\"#0033ff\">.: Conhe&ccedil;a o Canal da M&uacute;sica<\/font><\/a><br \/><font color=\"#000000\"><br \/>  <strong>O nosso minist&eacute;rio precisa identificar quem somos: seguidores de Cristo Jesus<\/strong>, e nossa identifica&ccedil;&atilde;o com Cristo precisa ser a cruz de Nosso Senhor!<\/p>\n<p>  <strong>O lugar do m&uacute;sico &eacute; aos p&eacute;s da cruz.<\/strong><\/p>\n<p>  No exerc&iacute;cio do seu minist&eacute;rio, o que o indentifica com a cruz de Cristo? M&uacute;sico, o seu jeito de compor, de cantar e se comportar precisa expressar quem voc&ecirc; &eacute;: crist&atilde;o, e n&atilde;o existe crist&atilde;o sem Cristo, e nem Cristo sem cruz. Eis o sinal da nossa salva&ccedil;&atilde;o.<\/p>\n<p>  Infelizmente, estamos vivendo em uma realidade que descristianizada, porque quem j&aacute; tirou a cruz das paredes j&aacute; a retirou do cora&ccedil;&atilde;o faz tempo. <\/p>\n<p> Voc&ecirc; precisa aprender a identificar qual &eacute; a sua cruz, e a cruz que os outros o veem carregar, assim voc&ecirc; ter&aacute; efic&aacute;cia na sua miss&atilde;o; unindo o seu sofrimento &agrave; cruz de Nosso Senhor Jesus Cristo. A Can&ccedil;&atilde;o Nova nasce de um cora&ccedil;&atilde;o que est&aacute; em aberto, mesmo que este cora&ccedil;&atilde;o esteja machucado, ele est&aacute; unido ao cora&ccedil;&atilde;o de Jesus Cristo Crucificado.<br \/><\/font><br \/>   <font color=\"#000000\">Precisamos ter a coragem de carregar a nossa cruz em p&uacute;blico.<\/p>\n<p>O nosso minist&eacute;rio precisa se identificar com Cristo Ressuscitado, precisamos ser cada vez mais semelhantes a Cristo, e para viver assim, precisamos conhecer o cora&ccedil;&atilde;o do Crucificado.<\/p>\n<p><strong>O seu minist&eacute;rio precisa ser um transbordar daquilo que voc&ecirc; &eacute; no cora&ccedil;&atilde;o de Deus.<\/strong><\/font>  <font color=\"#000000\">Sua filia&ccedil;&atilde;o divina deve ser transbordante em seu minist&eacute;rio. <\/font><\/p>\n<div id=\"foto\" style=\"width: 370px;margin: 0pt auto;padding: 5px 0px;float: none\">\n<div id=\"foto\"><!--ABRE LINK DA FOTO--><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.cancaonova.com\/portal\/arquivos\/fotos\/2012\/abril\/21_eventos-001.jpg\" border=\"0\" width=\"370\" height=\"250\" \/><!--FECHA LINK DA FOTO--><\/div>\n<div id=\"texto\"><!--TEXTO DA FOTO-->&quot;M&uacute;sico, o seu minist&eacute;rio precisa ser um sustento para seu irm&atilde;o&quot;, exorta Ricardo S&aacute;. <!--TEXTO DA FOTO--><\/div>\n<div id=\"credito\"><!--CREDITO DA FOTO-->Foto: Wesley Almeida\/Cancaonova.com<!--CREDITO DA FOTO--><\/div>\n<\/div>\n<p align=\"center\"><a href=\"http:\/\/www.flickr.com\/photos\/cancaonova\/\"><strong><font color=\"#0033cc\">:: Veja fotos no<span class=\"Apple-converted-space\">&nbsp;<\/span><font color=\"#0000ff\"><font size=\"-0\">Flick<font color=\"#ff0000\">r<\/font><\/font><\/font><\/font><\/strong><\/a><br \/><a href=\"http:\/\/www.facebook.com\/media\/set\/?set=a.10150684327734632.400158.45027114631&amp;type=3\" target=\"_blank\"><strong><font size=\"-0\"><font size=\"1\" color=\"#0033cc\">:: Veja + fotos tamb&eacute;m no Facebook<\/font><\/font><\/strong><\/a><a href=\"http:\/\/www.facebook.com\/media\/set\/?set=a.10150684327734632.400158.45027114631&amp;type=3\" target=\"_blank\"><strong><font size=\"-0\"><font size=\"1\" color=\"#0033cc\"><\/font><\/font><\/strong><\/a> <\/p>\n<p>&nbsp;<\/p>\n<p> Voc&ecirc; n&atilde;o pode desconsiderar a cruz do outro, voc&ecirc; precisa olh&aacute;-la com um desejo de ser Cirineu na vida dele.<\/p>\n<p>  Imaginemos que hoje Nosso Senhor esteja carregando Sua cruz conosco, precisamos sustentar uns aos outros no carregar dessa cruz.  <\/p>\n<p><strong>  Se come&ccedil;armos a rir das quedas dos nossos irm&atilde;os, perderemos a for&ccedil;a, mas se rezamos por eles, seremos sustento e instrumentos de cura para eles.  <\/strong><\/p>\n<p> &Eacute; importante voc&ecirc; saber que para ser de Deus precisamos de um amigo, precisamos de um irm&atilde;o para ser sustento e  sustentados por eles. Por isso Deus nos fez irm&atilde;os!<\/p>\n<p><em>Transcri&ccedil;&atilde;o e Adapta&ccedil;&atilde;o: Mariana Lazarin Gabriel<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Assista um trecho desta prega&ccedil;&atilde;o:<\/strong><\/p>\n<div style=\"text-align: center\"><\/div>\n<p>&nbsp;<\/p>\n<hr width=\"100%\" size=\"2\" \/><em style=\"color: #5a5a5a;font-family: Verdana,Arial,Helvetica,sans-serif;font-size: 10px;font-variant: normal;font-weight: normal;letter-spacing: normal;line-height: normal;text-align: justify;text-indent: 0px;background-color: #ffffff\"><br \/><\/em><\/p>\n<div align=\"center\" style=\"color: #5a5a5a;font-family: Verdana,Arial,Helvetica,sans-serif;font-size: 10px;font-style: normal;font-variant: normal;font-weight: normal;letter-spacing: normal;line-height: normal;text-indent: 0px;background-color: #ffffff\"><font size=\"2\"><strong>Adquira essa prega&ccedil;&atilde;o pelo telefone<span class=\"skype_pnh_print_container\"><span class=\"Apple-converted-space\">&nbsp;<\/span>(12) 3186-2600<\/span><\/strong><\/font><\/div>\n<p style=\"margin: 0px;padding: 0px;color: #000000;font-family: Verdana,Arial,Helvetica,sans-serif;font-size: 10px;font-style: normal;font-variant: normal;font-weight: normal;letter-spacing: normal;line-height: normal;text-align: justify;text-indent: 0px;background-color: #ffffff\">&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ricardo S&aacute; Foto: Wesley Almeida\/Cancaonova.com A Palavra de Deus que vai nortear esta prega&ccedil;&atilde;o est&aacute; no Evangelho de S&atilde;o Mateus 16,24: &ldquo;Ent&atilde;o Jesus disse aos disc&iacute;pulos: &ldquo;Se algu&eacute;m quer vir ap&oacute;s mim, renuncie a si mesmo, tome sua cruz e&#8230;<\/p>\n","protected":false},"author":114,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7],"tags":[],"modified_by":"","_links":{"self":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/2515"}],"collection":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/users\/114"}],"replies":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/comments?post=2515"}],"version-history":[{"count":1,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/2515\/revisions"}],"predecessor-version":[{"id":2516,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/2515\/revisions\/2516"}],"wp:attachment":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media?parent=2515"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/categories?post=2515"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/tags?post=2515"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}