{"id":26469,"date":"2015-04-09T16:40:07","date_gmt":"2015-04-09T19:40:07","guid":{"rendered":"http:\/\/admin-canais.cancaonova.com\/eventos\/?p=26469"},"modified":"2015-04-09T16:44:34","modified_gmt":"2015-04-09T19:44:34","slug":"gratidao-gera-vida","status":"publish","type":"post","link":"https:\/\/admin-canais.cancaonova.com\/eventos\/quinta-feira-de-adoracao\/pregacoes\/gratidao-gera-vida\/","title":{"rendered":"Gratid\u00e3o gera vida"},"content":{"rendered":"<div id=\"attachment_26470\" style=\"width: 279px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-26470\" class=\"size-full wp-image-26470\" src=\"http:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2015\/04\/gratidaogeravida1.jpg\" alt=\"Gabrielle Sanchotene. Foto: Wesley Almeida\/cancaonova.com\" width=\"269\" height=\"329\" srcset=\"https:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2015\/04\/gratidaogeravida1.jpg 269w, https:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2015\/04\/gratidaogeravida1-245x300.jpg 245w\" sizes=\"(max-width: 269px) 100vw, 269px\" \/><p id=\"caption-attachment-26470\" class=\"wp-caption-text\">Gabrielle Sanchotene. Foto: Wesley Almeida\/cancaonova.com<\/p><\/div>\n<p>Vivemos, h\u00e1 poucos dias, a Semana Santa. Nesse tempo, pudemos perceber a grandiosidade deste Homem que se fez humano e se entregou por n\u00f3s. Agora, vivenciamos a chamada Oitava da P\u00e1scoa, ou seja, de um domingo a outro vivemos a P\u00e1scoa.<\/p>\n<p>Qual \u00e9 a verdade que n\u00e3o podemos perder nesta semana? N\u00e3o podemos nos esquecer que Jesus se fez humano para nos salvar. N\u00f3s, como criaturas, n\u00e3o merec\u00edamos nada, mas o amor de Deus \u00e9 t\u00e3o grande que se dobrou por n\u00f3s.<\/p>\n<p>Celebraremos, neste fim de semana, a Festa da Miseric\u00f3rdia a pedido de Jesus. Ele quis que n\u00f3s perceb\u00eassemos que a Sua miseric\u00f3rdia \u00e9 tamb\u00e9m nossa. Voc\u00ea pode estar se perguntando: &#8220;De onde veio a ideia da Festa da Divina Miseric\u00f3rdia? Quem \u00e9 Santa Faustina?&#8221;.<\/p>\n<p>No dia 22 de fevereiro de 1931, Jesus disse a Santa Faustina: &#8220;Pinta uma imagem de acordo com o modelo que v\u00eas com a inscri\u00e7\u00e3o embaixo: &#8216;Jesus, eu confio em V\u00f3s!&#8217;. Desejo que essa imagem seja venerada primeiro na vossa capela e depois no mundo inteiro. Prometo que a alma que venerar essa imagem n\u00e3o perecer\u00e1. Prometo tamb\u00e9m a vit\u00f3ria sobre os inimigos j\u00e1 nesta terra, mas especialmente na hora da morte. Eu mesmo a defenderei com a minha pr\u00f3pria gl\u00f3ria. Eu desejo que haja a Festa da Miseric\u00f3rdia, quero que essa imagem que pintar\u00e1s com o pincel seja benzida solenemente no primeiro domingo depois da P\u00e1scoa.&#8221;<\/p>\n<p>Santa Faustina era uma irm\u00e3 simples, uma freia que tinha o costume de ir \u00e0 capela todos os dias. Um dia, ela foi se recolher na capela por um minuto e teve o seu encontro com o Senhor. \u00a0Por causa dessa experi\u00eancia do encontro, Jesus pediu a Santa Faustina que pintasse a imagem.<\/p>\n<p>Por meio do seu di\u00e1rio, Santa Faustina descrevia suas experi\u00eancias com Jesus misericordioso. A santa era tida no convento como uma alucinada, como uma doida e ningu\u00e9m acreditava nela.<\/p>\n<div id=\"attachment_26471\" style=\"width: 605px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-26471\" class=\"size-full wp-image-26471\" src=\"http:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2015\/04\/gratidaogeravida.jpg\" alt=\"Peregrinos participam da Quinta-feira de Adora\u00e7\u00e3o na Can\u00e7\u00e3o Nova. Foto: Wesley Almeida\/cancaonova.com\" width=\"595\" height=\"420\" srcset=\"https:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2015\/04\/gratidaogeravida.jpg 595w, https:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2015\/04\/gratidaogeravida-300x212.jpg 300w\" sizes=\"(max-width: 595px) 100vw, 595px\" \/><p id=\"caption-attachment-26471\" class=\"wp-caption-text\">Peregrinos participam da Quinta-feira de Adora\u00e7\u00e3o na Can\u00e7\u00e3o Nova. Foto: Wesley Almeida\/cancaonova.com<\/p><\/div>\n<p>J\u00e1 estava na hora de instituir a Festa da Divina Miseric\u00f3rdia entre n\u00f3s, pois essa era a vontade de Deus: que a Sua miseric\u00f3rdia chegasse at\u00e9 n\u00f3s. A miseric\u00f3rdia de Deus para conosco \u00e9 de sempre para sempre!<\/p>\n<p>No ano 2000, o Papa Jo\u00e3o Paulo II institui a Festa da Divina Miseric\u00f3rdia e canonizou Santa Faustina como a &#8220;santa dos altares&#8221;. Ela era considerada uma mulher simples, mas que podia escrever coisas grandiosas.<\/p>\n<p>Essa festa quer mostrar que n\u00e3o devemos perder esse amor que foi capaz de dar a vida por n\u00f3s; e se, por alguma raz\u00e3o, Ele ficou no esquecimento, cabe ao nosso cora\u00e7\u00e3o fazer mem\u00f3ria dessa generosidade por amor a cada um de n\u00f3s!<\/p>\n<p>Lendo um pouco mais sobre a Divina Miseric\u00f3rdia, encontrei no Di\u00e1rio de Santa Faustina n\u00ba 299:\u00a0 \u201cOs raios que saem do Cora\u00e7\u00e3o de Jesus t\u00eam um significado maravilhoso revelado pelo pr\u00f3prio Senhor. Eles relembram o sangue e a \u00e1gua que jorraram de Seu cora\u00e7\u00e3o quando este foi perfurado pela lan\u00e7a. Os raios vermelhos simbolizam o sangue de Jesus, que salva o homem. O raio azul claro simboliza a \u00c1gua Viva, o Esp\u00edrito Santo, que brota do Cora\u00e7\u00e3o de Jesus e nos purifica de todo pecado. Segundo as palavras do pr\u00f3prio Jesus, &#8220;Os dois raios representam o Sangue e a \u00c1gua: o raio p\u00e1lido significa a \u00c1gua que justifica as almas; o raio vermelho significa o Sangue que \u00e9 a vida das almas. Ambos os raios jorraram das entranhas da minha miseric\u00f3rdia, quando na Cruz, o meu cora\u00e7\u00e3o agonizante foi aberto pela lan\u00e7a. Estes raios defendem as almas da ira do meu Pai. Feliz aquele que viver \u00e0 Sua sombra, porque n\u00e3o ser\u00e1 atingido pelo bra\u00e7o da justi\u00e7a de Deus. Desejo que o primeiro domingo depois da P\u00e1scoa seja a Festa da Miseric\u00f3rdia.\u201d<\/p>\n<p>Jesus nos fala por meio dessa simples serva, considerada a secret\u00e1ria da Divina Miseric\u00f3rdia. N\u00f3s nos esquecemos muito f\u00e1cil de tudo, mas n\u00e3o nos esque\u00e7amos dessa verdade: o Senhor se deu por n\u00f3s, pela nossa salva\u00e7\u00e3o!<\/p>\n<p>Na terra do seu cora\u00e7\u00e3o foi jogada a semente do amor que quer gerar em voc\u00ea uma vida nova. O Esp\u00edrito Santo quer lhe mostrar onde voc\u00ea pode ser melhor para Deus, porque a experi\u00eancia desse amor n\u00e3o pode nos deixar no mesmo lugar.<\/p>\n<p>\u201cDesejo que a Festa da Miseric\u00f3rdia seja ref\u00fagio e abrigo para todas as almas, especialmente para os pecadores. Neste dia, est\u00e3o abertas as entranhas da minha Miseric\u00f3rdia. Derramo todo um mar de gra\u00e7as sobre as almas que se aproximam da fonte da minha miseric\u00f3rdia. A alma que se confessar e comungar alcan\u00e7ar\u00e1 o perd\u00e3o das culpas e das penas. Nesse dia, est\u00e3o abertas todas as comportas divinas, pelas quais fluem as gra\u00e7as. Que nenhuma alma tenha medo de se aproximar de mim, ainda que seus pecados sejam como escarlate. A minha miseric\u00f3rdia \u00e9 t\u00e3o grande que, por toda a eternidade, nenhuma mente, nem humana nem ang\u00e9lica a aprofundar\u00e1. Tudo o que existe saiu das entranhas da minha miseric\u00f3rdia. Toda alma contemplar\u00e1 em rela\u00e7\u00e3o a mim, por toda a eternidade, todo o meu amor e a minha miseric\u00f3rdia. A Festa da Miseric\u00f3rdia saiu das minhas entranhas. Desejo que seja celebrada solenemente no primeiro domingo depois da P\u00e1scoa. A humanidade n\u00e3o ter\u00e1 paz enquanto n\u00e3o se voltar \u00e0 fonte da minha miseric\u00f3rdia.\u201d (Di\u00e1rio de Santa Faustina n\u00ba 699).<\/p>\n<p>Que possamos, em nosso dia a dia, experimentar a miseric\u00f3rdia de Deus!<\/p>\n<p><em>Transcri\u00e7\u00e3o e adapta\u00e7\u00e3o: Karina Aparecida<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vivemos, h\u00e1 poucos dias, a Semana Santa. Nesse tempo, pudemos perceber a grandiosidade deste Homem que se fez humano e se entregou por n\u00f3s. Agora, vivenciamos a chamada Oitava da P\u00e1scoa, ou seja, de um domingo a outro vivemos a&#8230;<\/p>\n","protected":false},"author":9,"featured_media":26472,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7],"tags":[],"modified_by":"Karina","_links":{"self":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/26469"}],"collection":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/comments?post=26469"}],"version-history":[{"count":4,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/26469\/revisions"}],"predecessor-version":[{"id":26477,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/26469\/revisions\/26477"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media\/26472"}],"wp:attachment":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media?parent=26469"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/categories?post=26469"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/tags?post=26469"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}