{"id":26623,"date":"2015-04-16T17:12:37","date_gmt":"2015-04-16T20:12:37","guid":{"rendered":"http:\/\/admin-canais.cancaonova.com\/eventos\/?p=26623"},"modified":"2015-04-17T09:09:18","modified_gmt":"2015-04-17T12:09:18","slug":"o-que-e-a-obediencia","status":"publish","type":"post","link":"https:\/\/admin-canais.cancaonova.com\/eventos\/quinta-feira-de-adoracao\/pregacoes\/o-que-e-a-obediencia\/","title":{"rendered":"O que \u00e9 a obedi\u00eancia?"},"content":{"rendered":"<div id=\"attachment_26625\" style=\"width: 279px\" class=\"wp-caption alignleft\"><a href=\"http:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2015\/04\/missa-com-padre-antonio-xavier-269x329.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-26625\" class=\"wp-image-26625 size-full\" src=\"http:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2015\/04\/missa-com-padre-antonio-xavier-269x329.jpg\" alt=\"missa com padre antonio xavier 269x329\" width=\"269\" height=\"329\" srcset=\"https:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2015\/04\/missa-com-padre-antonio-xavier-269x329.jpg 269w, https:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2015\/04\/missa-com-padre-antonio-xavier-269x329-245x300.jpg 245w\" sizes=\"(max-width: 269px) 100vw, 269px\" \/><\/a><p id=\"caption-attachment-26625\" class=\"wp-caption-text\">Padre Ant\u00f4nio Xavier &#8211; Foto: Daniel Mafra<\/p><\/div>\n<p>Quando observamos todos os acontecimentos narrados no momento em que Jesus estava para morrer, percebemos que os disc\u00edpulos estavam assustados e medrosos com tudo o que havia ocorrido na Semana Santa. Pedro chega at\u00e9 a negar Jesus. Por\u00e9m, nesses dias, vemos, nos Atos dos Ap\u00f3stolos, disc\u00edpulos tomados de coragem, porque viram Jesus ressuscitado.<\/p>\n<p>Tudo isso n\u00e3o acontece logo ap\u00f3s a ressurrei\u00e7\u00e3o de Jesus, mas depois que eles vivem uma experi\u00eancia com Ele. A partir de ent\u00e3o, podemos observar que o Evangelho de hoje nos fala das coisas que s\u00e3o do Alto e que s\u00e3o da Terra.<\/p>\n<p>O caminho \u00e9 este que Pedro diz aos judeus. Este disc\u00edpulo afirma que \u00e9 preciso obedecer antes a Deus do que ao homem. Precisamos aprender a compreender aquilo que \u00e9 natural em nossa vida e aquilo que \u00e9 sobrenatural.<\/p>\n<p>O que \u00e9 de Deus vai sendo constru\u00eddo em nossa vida aos poucos. \u00c0 medida que amadurecemos aquilo que \u00e9 do Senhor, Sua Palavra vai ganhando for\u00e7a e consist\u00eancia dentro de n\u00f3s. Os disc\u00edpulos viveram tr\u00eas anos com Jesus, viram Ele morrer, ressuscitar e subir aos c\u00e9us, mas, ainda assim, tiveram dificuldades em viver o que era necess\u00e1rio.<\/p>\n<p>E o que \u00e9 o amor a Deus sen\u00e3o a obedi\u00eancia? \u00c9 importante deixarmos que o Senhor entre em nosso cora\u00e7\u00e3o para descobrirmos que ainda n\u00e3o crescemos. Sempre h\u00e1 coisas para ser acertadas dentro de n\u00f3s, e s\u00f3 conseguiremos prosseguir se cuidarmos das pequenas convers\u00f5es di\u00e1rias.<\/p>\n<p>O Esp\u00edrito Santo \u00e9 dado \u00e0quele que, realmente, obedece ao Senhor; e Ele se interessa pelos pequenos detalhes. Para uma pessoa matar a outra, por exemplo, muitas coisas aconteceram antes desse fato. Um erro grande \u00e9 precedido de pequenos erros.<\/p>\n<p>As coisas pequenas podem impedir que Deus aja com perfei\u00e7\u00e3o em nossa vida. Cometemos \u201cerrinhos\u201d aqui e ali e acabamos nos acostumando com isso. As pessoas ao nosso redor come\u00e7am a se incomodar e, assim, surgem os conflitos. A conviv\u00eancia fica comprometida. O ideal \u00e9 que n\u00e3o cheguemos a esse ponto. Deus n\u00e3o quer ficar arrumando as coisas em nossa vida, Ele quer fazer coisas novas. \u00c9 certo que vamos errar, e quando isso ocorrer, ser\u00e1 necess\u00e1rio nos confessarmos e come\u00e7ar de novo. O que n\u00e3o d\u00e1 \u00e9 para parar no pecado.<\/p>\n<p>Deus tem coisas grandes para n\u00f3s, mas a maioria dessas coisas vem a n\u00f3s de pouco em pouco.<\/p>\n<p>Vivendo num mundo de pecado, acreditamos que n\u00e3o seremos atingidos por eles, porque estamos com Deus, mas isso n\u00e3o \u00e9 verdade. Voc\u00ea acha que o mosquito da dengue n\u00e3o vai chegar perto de voc\u00ea nem o picar, porque voc\u00ea \u00e9 de Deus? Claro que n\u00e3o \u00e9 assim! As coisas n\u00e3o acontecem desse jeito. Nossa f\u00e9 n\u00e3o \u00e9 um ant\u00eddoto contra os problemas.<\/p>\n<p>Vamos viver da mesma forma que os outros vivem, exceto no pecado. \u00c9 a essa vida que o Senhor nos chama. O que temos de diferente das outras pessoas \u00e9 o fato de o Senhor dar sentido \u00e0 nossa vida. Quem est\u00e1 preso na terra, enxerga as coisas da terra; mas n\u00f3s, que nascemos da gra\u00e7a de Deus, precisamos levantar os nossos olhos para o Senhor e viver com Ele.<\/p>\n<div id=\"attachment_26626\" style=\"width: 605px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2015\/04\/missa-com-padre-antonio-xavier-595x420.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-26626\" class=\"wp-image-26626 size-full\" src=\"http:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2015\/04\/missa-com-padre-antonio-xavier-595x420.jpg\" alt=\"Fi\u00e9is participam da Quinta-Feira de Adora\u00e7\u00e3o na Can\u00e7\u00e3o Nova - Foto: Daniel Mafra\" width=\"595\" height=\"420\" srcset=\"https:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2015\/04\/missa-com-padre-antonio-xavier-595x420.jpg 595w, https:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2015\/04\/missa-com-padre-antonio-xavier-595x420-300x212.jpg 300w\" sizes=\"(max-width: 595px) 100vw, 595px\" \/><\/a><p id=\"caption-attachment-26626\" class=\"wp-caption-text\">Fi\u00e9is participam da Quinta-Feira de Adora\u00e7\u00e3o na Can\u00e7\u00e3o Nova &#8211; Foto: Daniel Mafra<\/p><\/div>\n<p>Devemos andar para frente na certeza de que l\u00e1 h\u00e1 algo nos esperando. A tend\u00eancia normal do mundo \u00e9 fazer com que a nossa vis\u00e3o v\u00e1 baixando, baixando, baixando&#8230; E quando nos damos conta, n\u00e3o vemos mais nada. O que a tenta\u00e7\u00e3o quer \u00e9 fazer com que desanimemos e entreguemos os pontos, mas n\u00e3o \u00e9 essa a inten\u00e7\u00e3o de Deus. O Senhor quer nos tirar das situa\u00e7\u00f5es ruins para nos colocar na vontade d&#8217;Ele.<\/p>\n<p>Existem coisas em nossa vida que precisam ser cultivadas todos os dias para que n\u00e3o as percamos; o relacionamento com Deus \u00e9 uma delas. Se o Senhor nos pede para mudar algo, mudemos. A perseveran\u00e7a \u00e9 constru\u00edda a partir de coisas pequenas, t\u00e3o pequenas como as engrenagens de um rel\u00f3gio de pulso, mas s\u00e3o elas que o fazem funcionar.<\/p>\n<p>N\u00e3o podemos nos esmerar em algo no in\u00edcio e, no meio do caminho, permitir que outras coisas tomem espa\u00e7o em n\u00f3s a ponto de nos esquecermos do que come\u00e7amos. Trabalhamos para dar boas condi\u00e7\u00f5es \u00e0s nossas fam\u00edlias, mas corremos o risco de nos apaixonar pelo trabalho e as esquecermos. O mesmo pode acontecer quando vamos demais \u00e0 igreja e nos esquecemos de ficar em casa. Cuidado! Rem\u00e9dio demais mata.<\/p>\n<p>Existem duas formas de olhar a vida: a terrena, quando todas as pessoas precisam se sentir realizadas, grandes e ter mais condi\u00e7\u00f5es; e a forma celeste, que \u00e9 olhar com santidade para as pessoas sem sentir alegria pelos sofrimentos delas, e ter um cora\u00e7\u00e3o humilde. Essa \u00e9 a vontade de Deus, que n\u00f3s aceitemos o que Ele nos deu.<\/p>\n<p><em>Transcri\u00e7\u00e3o e adapta\u00e7\u00e3o: Rog\u00e9ria Nair<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quando observamos todos os acontecimentos narrados no momento em que Jesus estava para morrer, percebemos que os disc\u00edpulos estavam assustados e medrosos com tudo o que havia ocorrido na Semana Santa. Pedro chega at\u00e9 a negar Jesus. Por\u00e9m, nesses dias,&#8230;<\/p>\n","protected":false},"author":88,"featured_media":26624,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7],"tags":[],"modified_by":null,"_links":{"self":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/26623"}],"collection":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/users\/88"}],"replies":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/comments?post=26623"}],"version-history":[{"count":6,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/26623\/revisions"}],"predecessor-version":[{"id":26637,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/26623\/revisions\/26637"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media\/26624"}],"wp:attachment":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media?parent=26623"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/categories?post=26623"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/tags?post=26623"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}