{"id":27473,"date":"2015-05-30T15:47:20","date_gmt":"2015-05-30T18:47:20","guid":{"rendered":"http:\/\/admin-canais.cancaonova.com\/eventos\/?p=27473"},"modified":"2015-05-30T15:47:20","modified_gmt":"2015-05-30T18:47:20","slug":"somos-imagem-e-semelhanca-de-deus-que-e-amor","status":"publish","type":"post","link":"https:\/\/admin-canais.cancaonova.com\/eventos\/festa-da-santissima-trindade\/pregacoes\/somos-imagem-e-semelhanca-de-deus-que-e-amor\/","title":{"rendered":"Somos imagem e semelhan\u00e7a de Deus, que \u00e9 Amor"},"content":{"rendered":"<div id=\"attachment_27476\" style=\"width: 279px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-27476\" class=\"size-full wp-image-27476\" src=\"http:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2015\/05\/Somos_imagem_e_semelhanca_de_Deus_que_e_Amor.jpg\" alt=\"Somos_imagem_e_semelhanca_de_Deus_que_e_Amor\" width=\"269\" height=\"329\" srcset=\"https:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2015\/05\/Somos_imagem_e_semelhanca_de_Deus_que_e_Amor.jpg 269w, https:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2015\/05\/Somos_imagem_e_semelhanca_de_Deus_que_e_Amor-245x300.jpg 245w\" sizes=\"(max-width: 269px) 100vw, 269px\" \/><p id=\"caption-attachment-27476\" class=\"wp-caption-text\">Padre Evandro Lima. Foto: Fernanda Mazoti\/cancaonova.com<\/p><\/div>\n<p><strong>Fomos criados com muito amor, Deus nos criou \u00e0 Sua imagem e semelhan\u00e7a<\/strong><\/p>\n<p>A Sant\u00edssima Trindade quer se fazer mais presente na nossa vida, quer se manifestar de uma forma diferente. Mas talvez, diante do que vivemos, ainda n\u00e3o tenhamos parado para pensar em quem \u00e9 Deus.<\/p>\n<p>O Senhor, em Sua bondade, criou todas as coisas. No relato da cria\u00e7\u00e3o, em G\u00eanesis 1,17, Deus diz que criou o homem \u00e0 Sua imagem e semelhan\u00e7a; e Ele fez isso com muito amor. No entanto, para entendermos que fomos criados dessa forma, precisamos compreender quem Ele \u00e9.<\/p>\n<p>H\u00e1 um \u00fanico Deus, n\u00e3o tr\u00eas, porque Ele \u00e9 uno e trino. Apesar de ser um, o Senhor \u00e9 considerado por n\u00f3s cat\u00f3licos como tr\u00eas Pessoas que nos foram reveladas por Jesus Cristo. <strong>Estamos falando de um Deus que \u00e9 Pai, Filho e Esp\u00edrito Santo, tr\u00eas Pessoas num \u00fanico Deus.<\/strong> Cristo, ao encarnar-se, veio nos trazer essa novidade.<\/p>\n<p>A natureza divina \u00e9 uma s\u00f3, a subst\u00e2ncia e ess\u00eancia de Deus s\u00e3o \u00fanicas, mesmo que sejam tr\u00eas Pessoas. A ess\u00eancia do Pai \u00e9 uma s\u00f3. O Magist\u00e9rio da Igreja nos ajuda a tentar compreender um pouco mais a Trindade Santa.<\/p>\n<p>Deus \u00e9 um, Ele foi gerado. Esse grande mist\u00e9rio diz de uma gera\u00e7\u00e3o, diz daquilo que sai d\u2019Ele. Deus n\u00e3o foi criado, mas gerado de uma forma \u00fanica: Pai, Filho e Esp\u00edrito Santo. Ao ser gerado, Ele gerou Seu Filho, e esse amor que une Pai e Filho chama-se Esp\u00edrito Santo, a Terceira Pessoa da Sant\u00edssima Trindade, o relacionamento entre Pai e Filho, que \u00e9 amor.<\/p>\n<p>O Senhor Deus tem um plano de amor para n\u00f3s. Ele quer que fa\u00e7amos uma experi\u00eancia de amor com o Pai, com o Filho e com o Esp\u00edrito Santo, sem nos esquecer de que Eles s\u00e3o um \u00fanico Deus e n\u00f3s somos frutos desse amor.<\/p>\n<div id=\"attachment_27477\" style=\"width: 605px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-27477\" class=\"size-full wp-image-27477\" src=\"http:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2015\/05\/Somosimagemesemelhancade_DeusqueeAmor.jpg\" alt=\"Somosimagemesemelhancade_DeusqueeAmor\" width=\"595\" height=\"420\" srcset=\"https:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2015\/05\/Somosimagemesemelhancade_DeusqueeAmor.jpg 595w, https:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2015\/05\/Somosimagemesemelhancade_DeusqueeAmor-300x212.jpg 300w\" sizes=\"(max-width: 595px) 100vw, 595px\" \/><p id=\"caption-attachment-27477\" class=\"wp-caption-text\">&#8220;A experi\u00eancia que fazemos \u00e9 com um Deus que cuida de n\u00f3s e se coloca \u00e0 nossa disposi\u00e7\u00e3o&#8221;, disse padre Evandro. Foto: Fernanda Mazoti\/cancaonova.com<\/p><\/div>\n<p>O Pai criou tudo, e por gostar de tudo o que criou, Ele quis que n\u00f3s, seres humanos, particip\u00e1ssemos de Sua vida. E mesmo que voc\u00ea n\u00e3o saiba, certamente j\u00e1 fez uma experi\u00eancia com Ele. Se voc\u00ea respira, voc\u00ea faz uma experi\u00eancia com Deus, porque Ele lhe d\u00e1 a vida. A experi\u00eancia que fazemos \u00e9 com um Deus que cuida de n\u00f3s e se coloca \u00e0 nossa disposi\u00e7\u00e3o; como exemplo disso, temos a cruz.<\/p>\n<p>Olhando toda a cria\u00e7\u00e3o, o Pai viu que faltava algo, ent\u00e3o Ele nos criou. Somos fruto do amor entre Pai, Filho e Esp\u00edrito. Por nos amar, Ele n\u00e3o quer perder nenhum de n\u00f3s, por isso, quando nos criou, o Senhor j\u00e1 estava antevendo nossa salva\u00e7\u00e3o. Mas para isso acontecer, n\u00f3s temos de querer ser salvos.<\/p>\n<p>O homem estava no erro, no pecado. Deus, em Seu plano salv\u00edfico, enviou Jesus Cristo para resgatar em n\u00f3s aquilo que \u00e9 vontade d\u2019Ele desde o in\u00edcio. Jesus Cristo \u00e9 a salva\u00e7\u00e3o enviada por Deus que se fez homem, veio para resgatar cada um de n\u00f3s e nos mostrar quem Ele \u00e9. A fun\u00e7\u00e3o de Jesus Cristo, na terra, \u00e9 nos mostrar quem \u00e9 nosso Pai.<\/p>\n<p>Esse \u00e9 um mist\u00e9rio que precisa da f\u00e9 para ser compreendido. E essa compreens\u00e3o n\u00e3o acontece apenas com a raz\u00e3o, mas com a for\u00e7a do cora\u00e7\u00e3o. <strong>A Trindade habita em nosso cora\u00e7\u00e3o; e Deus s\u00f3 consegue realizar tudo, porque \u00e9 Amor.<\/strong><\/p>\n<p>O amor do Senhor por n\u00f3s vai al\u00e9m de nossos pecados. Queremos ser bons, h\u00e1 uma ess\u00eancia boa em n\u00f3s, h\u00e1 amor dentro de n\u00f3s e vontade de manifest\u00e1-lo, mas, em algumas situa\u00e7\u00f5es, sentimo-nos abatidos. Nessa hora, precisamos contar com Deus para voltarmos ao caminho original, voltar para Seus bra\u00e7os, porque Ele \u00e9 amor, \u00e9 miseric\u00f3rdia e quer sempre que retornemos para Ele. O Senhor est\u00e1 sempre aberto para nos perdoar.<\/p>\n<p>Quando Deus ama, Ele manifesta tudo aquilo que \u00e9. Em 1 Jo\u00e3o 4,8, lemos que o Senhor \u00e9 amor e nada pode mudar isso. As nossas falhas e pecados n\u00e3o t\u00eam a capacidade de mudar o fato de que Deus nos ama. O que Ele mais quer de n\u00f3s \u00e9 que nos abramos ao Seu amor!<\/p>\n<p><em>Transcri\u00e7\u00e3o e adapta\u00e7\u00e3o: M\u00edriam Bernardes<\/em><\/p>\n<p><a href=\"http:\/\/bit.ly\/doacaocnova\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-27329\" src=\"http:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2015\/05\/contribuicaocn1.jpg\" alt=\"contribuicaocn\" width=\"300\" height=\"72\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fomos criados com muito amor, Deus nos criou \u00e0 Sua imagem e semelhan\u00e7a A Sant\u00edssima Trindade quer se fazer mais presente na nossa vida, quer se manifestar de uma forma diferente. Mas talvez, diante do que vivemos, ainda n\u00e3o tenhamos&#8230;<\/p>\n","protected":false},"author":134,"featured_media":27475,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7],"tags":[],"modified_by":"miriam","_links":{"self":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/27473"}],"collection":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/users\/134"}],"replies":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/comments?post=27473"}],"version-history":[{"count":2,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/27473\/revisions"}],"predecessor-version":[{"id":27478,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/27473\/revisions\/27478"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media\/27475"}],"wp:attachment":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media?parent=27473"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/categories?post=27473"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/tags?post=27473"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}