{"id":28149,"date":"2015-07-03T21:49:14","date_gmt":"2015-07-04T00:49:14","guid":{"rendered":"http:\/\/admin-canais.cancaonova.com\/eventos\/?p=28149"},"modified":"2015-07-04T09:59:22","modified_gmt":"2015-07-04T12:59:22","slug":"jesus-nao-desiste-do-incredulo","status":"publish","type":"post","link":"https:\/\/admin-canais.cancaonova.com\/eventos\/acampamento-encontramos-o-cristo\/pregacoes\/jesus-nao-desiste-do-incredulo\/","title":{"rendered":"Jesus n\u00e3o desiste do incr\u00e9dulo"},"content":{"rendered":"<div id=\"attachment_28151\" style=\"width: 279px\" class=\"wp-caption alignleft\"><a href=\"http:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2015\/07\/jesus_nao_desiste_do_incredulo.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-28151\" class=\"wp-image-28151 size-full\" title=\"jesus_nao_desiste_do_incredulo\" src=\"http:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2015\/07\/jesus_nao_desiste_do_incredulo.jpg\" alt=\"jesus_nao_desiste_do_incredulo\" width=\"269\" height=\"329\" srcset=\"https:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2015\/07\/jesus_nao_desiste_do_incredulo.jpg 269w, https:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2015\/07\/jesus_nao_desiste_do_incredulo-245x300.jpg 245w\" sizes=\"(max-width: 269px) 100vw, 269px\" \/><\/a><p id=\"caption-attachment-28151\" class=\"wp-caption-text\">Padre Roger Lu\u00eds. Foto: Arquivo\/cancaonova.com<\/p><\/div>\n<p>Ao celebrarmos esta <a href=\"http:\/\/santo.cancaonova.com\/santo\/sao-tome-pertenceu-ao-grupo-dos-doze-apostolos\/\" target=\"_blank\">festa<\/a>, somos convocados a ser colocados diante da realidade deste mundo em que vivemos, no qual, na era p\u00f3s-moderna, temos que ver para crer. No qual a sociedade \u00e9 marcada pelo seguinte comportamento: s\u00f3 se acredita naquilo que pode ser provado e testado cientificamente. Muitas vezes, a nossa sociedade vive distante do sobrenatural se formos entrar naquilo que a doutrina da Igreja fala, como a Enc\u00edclica do Papa Francisco &#8216;<a href=\"http:\/\/noticias.cancaonova.com\/entenda-o-objetivo-do-papa-com-a-enciclica-laudato-si\/\" target=\"_blank\">Laudato Si&#8217;<\/a>, que mostra a cria\u00e7\u00e3o como uma grande revela\u00e7\u00e3o. A pr\u00f3pria realidade da perfei\u00e7\u00e3o do corpo humano, que tem liga\u00e7\u00f5es com tudo aquilo que vemos, e conclu\u00edmos que esta revela\u00e7\u00e3o s\u00f3 pode ser a cria\u00e7\u00e3o de Deus.<\/p>\n<p>Estou voltando do retiro dos sacerdotes, e de l\u00e1, onde est\u00e1vamos, pod\u00edamos ver uma serra linda! S\u00e3o tantas circunst\u00e2ncias que v\u00e3o nos mostrando as revela\u00e7\u00f5es de Deus.<\/p>\n<p>Vamos olhar para esta figura hist\u00f3rica, este homem que, ao longo da hist\u00f3ria, foi escolhido por Deus.<strong> Deus escolhe a quem Ele quer sem excluir ningu\u00e9m.<\/strong>\u00a0S\u00e3o Tom\u00e9 foi um dos escolhidos a estar mais pr\u00f3ximo do Senhor, podia ver os milagres de Jesus e escutar grandes ensinamentos do Mestre. Tom\u00e9 tocava na dimens\u00e3o grandiosa da revela\u00e7\u00e3o do Filho de Deus naquele tempo.<\/p>\n<p>Quando vemos esta <a href=\"http:\/\/liturgia.cancaonova.com\/liturgia\/sao-tome-apostolo-sexta-feira-03072015\/\" target=\"_blank\">Primeira Leitura<\/a>, parece que Tom\u00e9 se resume somente ao questionamento feito por ele, mas n\u00e3o \u00e9 somente isso. No Evangelho de Jo\u00e3o, em outra passagem, vemos que ele [Tom\u00e9] estava fazendo o caminho de seguimento do Senhor.<\/p>\n<p>N\u00f3s estamos celebrando o mart\u00edrio de algu\u00e9m que teve a vida transformada por Deus. N\u00f3s olhamos para Tom\u00e9 e vemos, por interm\u00e9dio da atitude dele, uma coisa muito importante: &#8220;Eu jamais quero me separar de Ti, Jesus!\u201d.\u00a0Quem encontra Jesus tem esta disposi\u00e7\u00e3o tamb\u00e9m de jamais querer se separar d&#8217;Ele. Seguir e viver o Evangelho quer dizer: \u201cEu vou aonde o Senhor for\u201d. <strong>O disc\u00edpulo de Jesus deve acolher Jesus e ir aonde Ele for<\/strong>. A nossa vida de crist\u00e3o \u00e9 definida como uma vida com Jesus Cristo.<\/p>\n<p>Na sua vida de crist\u00e3o, de consagrado, de sacerdote, voc\u00ea tem vivido com Jesus? Temos visto, na sociedade, muitas na\u00e7\u00f5es que tramam contra o Cristo, o Evangelho e a Palavra.\u00a0<strong>Encontrar o Cristo significa ficar com Ele e permanecer com Ele.<\/strong> Este era o desejo do cora\u00e7\u00e3o de Tom\u00e9.<\/p>\n<p>A segunda coisa que quero destacar de Tom\u00e9 \u00e9 que, na \u00daltima Ceia, Jesus fala que vai preparar um lugar para eles e ele diz: &#8220;Senhor, n\u00f3s n\u00e3o sabemos para onde vais. Como podemos conhecer o caminho?&#8221; (Jo 14, 5.) E Jesus respondeu: \u201cEu sou o caminho, a verdade e a vida&#8221; (Jo\u00e3o 14, 6). A imaturidade dele fez com que Jesus revelasse quem Ele era. Tom\u00e9 acaba sendo para n\u00f3s um modelo para que compreendamos que seguir Jesus comporta a possibilidade de question\u00e1-Lo\u00a0e esperar uma resposta d&#8217;Ele. Vemos um Tom\u00e9 incr\u00e9dulo devido \u00e0 aus\u00eancia de Jesus naquele momento, existia um vazio existencial no cora\u00e7\u00e3o daqueles homens e de <a href=\"http:\/\/liturgia.cancaonova.com\/liturgia\/sao-tome-apostolo-sexta-feira-03072015\/\" target=\"_blank\">Tom\u00e9.<\/a><\/p>\n<p>O bonito \u00e9 que Jesus n\u00e3o desiste do incr\u00e9dulo. <strong>Jesus tamb\u00e9m quer encontrar-se com voc\u00ea<\/strong>\u00a0como Ele se encontrou com o incr\u00e9dulo Tom\u00e9. Jesus vai supreender voc\u00ea como supreendeu S\u00e3o Tom\u00e9. As portas estavam fechadas e Jesus se colocou no meio deles para que fosse tocado por aquele que n\u00e3o acreditava [que Ele havia ressuscitado].<\/p>\n<p>Jesus surpreende Tom\u00e9. A Palavra n\u00e3o diz que Tom\u00e9 colocou a m\u00e3o no lado aberto e nas chagas de Cristo, mas a Palavra diz que Tom\u00e9 respondeu: \u201cMeu Senhor e meu Deus!\u201d (Jo 20, 28).<\/p>\n<p>Mais feliz \u00e9 aquele que cr\u00ea sem ter visto! N\u00f3s estamos em um tempo t\u00e3o complicado no qual a f\u00e9 tem sido traduzida em coisas materiais. Esta f\u00e9 materializada est\u00e1 mais para supersti\u00e7\u00e3o do que para f\u00e9. Uma f\u00e9 supersticiosa. \u00c9 feliz quem acredita naquilo que a Igreja lhe d\u00e1 como plenitude de salva\u00e7\u00e3o. A Igreja tem todos os meios para a nossa salva\u00e7\u00e3o: a Sant\u00edssima Trindade, a Palavra de Deus, os sacramentos, a Virgem Maria.<\/p>\n<p><em>Transcri\u00e7\u00e3o e adapta\u00e7\u00e3o: Jakeline Megda D&#8217;Onofrio<\/em>.<\/p>\n<p><strong>Adquira esta prega\u00e7\u00e3o pelo telefone (012) 3186-2600<\/strong><\/p>\n<p><a href=\"http:\/\/clube.cancaonova.com\/\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-27879 aligncenter\" src=\"http:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2015\/06\/contribuicaocn.jpg\" alt=\"contribuicaocn\" width=\"300\" height=\"72\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ao celebrarmos esta festa, somos convocados a ser colocados diante da realidade deste mundo em que vivemos, no qual, na era p\u00f3s-moderna, temos que ver para crer. No qual a sociedade \u00e9 marcada pelo seguinte comportamento: s\u00f3 se acredita naquilo&#8230;<\/p>\n","protected":false},"author":116,"featured_media":28152,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7],"tags":[],"modified_by":null,"_links":{"self":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/28149"}],"collection":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/users\/116"}],"replies":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/comments?post=28149"}],"version-history":[{"count":17,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/28149\/revisions"}],"predecessor-version":[{"id":28169,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/28149\/revisions\/28169"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media\/28152"}],"wp:attachment":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media?parent=28149"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/categories?post=28149"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/tags?post=28149"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}