{"id":2833,"date":"2013-07-05T13:00:00","date_gmt":"2013-07-05T16:00:00","guid":{"rendered":"http:\/\/admin-canais.cancaonova.com\/eventos\/?p=2833"},"modified":"2014-08-13T01:12:42","modified_gmt":"2014-08-13T04:12:42","slug":"teve-misericordia-e-escolheu-me","status":"publish","type":"post","link":"https:\/\/admin-canais.cancaonova.com\/eventos\/pregacoes\/teve-misericordia-e-escolheu-me\/","title":{"rendered":"Teve miseric\u00f3rdia e escolheu-me"},"content":{"rendered":"<div id=\"foto\" style=\"margin: 0px auto;padding: 5px;width: 180px;float: left\">\n<div id=\"foto\"><!--ABRE LINK DA FOTO--><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.cancaonova.com\/portal\/arquivos\/fotos\/2013\/julho\/05_padrepauloricardo-001.jpg\" border=\"0\" width=\"180\" height=\"220\" \/><!--FECHA LINK DA FOTO--><\/div>\n<div id=\"texto\"><!--TEXTO DA FOTO-->Padre Paulo Ricardo<!--TEXTO DA FOTO--><\/div>\n<div id=\"credito\"><!--CREDITO DA FOTO-->Foto: Wesley Almeida\/cancaonova.com<!--CREDITO DA FOTO--><\/div>\n<\/div>\n<p>O Evangelho de hoje &eacute; muito prop&iacute;cio para falar do mensageiro de Deus que iremos receber: o Papa Francisco. Pouca gente sabe, mas o Evangelho de hoje &eacute;, justamente, o lema do Papa Francisco.<\/p>\n<p>  Este lema &eacute; tirado da homilia de um monge ingl&ecirc;s chamado S&atilde;o Beda. Nesta homilia, ele destaca a miseric&oacute;rdia presente no chamado vocacional do ap&oacute;stolo Mateus.<\/p>\n<p>  Muitas pessoas acreditam que Deus olha para a humanidade e, entre tantas pessoas, encontra uma pessoa cheia de virtudes e com caracter&iacute;sticas de santo. Por&eacute;m, &eacute; justamente o contr&aacute;rio, como nos mostra as Escrituras de hoje, quando ele escolhe Mateus, no meio do seu pecado, que era a coleta de impostos.<\/p>\n<p>  Quando Papa Francisco foi escolhido bispo, ele era um padre jesu&iacute;ta e assumia como bispo auxiliar. Desde aquele momento, ele escolheu esse lema, pois compreendeu que o olhar de Deus sobre ele tinha sido por pura miseric&oacute;rdia.<\/p>\n<p>  Assim como Mateus saiu da banca de impostos, voc&ecirc; precisa sair da sua mis&eacute;ria, sair da mundanidade. N&oacute;s n&atilde;o podemos ser mundanos, pois, se optamos por isso, n&atilde;o seremos de Cristo, e transformaremos a Igreja em apenas uma ONG.<\/p>\n<p>  Se voc&ecirc; olha para os outros como se fossem coisas, e olha para as coisas, mas as trata como se fossem deuses, isso quer dizer que voc&ecirc; est&aacute; vivendo uma idolatria. Tendo os olhos virados para algo que n&atilde;o merece sua rever&ecirc;ncia; assim como Mateus, que idolatrava suas moedas e se transformava cada vez mais em metal frio e insens&iacute;vel.<\/p>\n<p>  Jesus n&atilde;o disse para Mateus se afastar do pecado, mas, ap&oacute;s um per&iacute;odo livre do v&iacute;cio, Ele voltou para convoc&aacute;-lo&nbsp; a ser ap&oacute;stolo. Ele fez diferente do que o mundo geralmente faria, Ele olhou para Mateus e disse: &quot;Segue-me&quot;.<\/p>\n<p>  Agora, se voc&ecirc; quer ter f&eacute;, mas n&atilde;o quer transformar a sua vida, ent&atilde;o esque&ccedil;a, voc&ecirc; n&atilde;o ir&aacute; transformar a sua vida, porque a f&eacute; significa uma ruptura com o pecado, significa estar diferente aos olhos do mundo.<\/p>\n<div id=\"foto\" style=\"margin: 0px auto;padding: 5px;width: 370px;float: none\">\n<div id=\"foto\"><!--ABRE LINK DA FOTO--><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.cancaonova.com\/portal\/arquivos\/fotos\/2013\/julho\/05_padrepauloricardo-003.jpg\" border=\"0\" width=\"370\" height=\"250\" \/><!--FECHA LINK DA FOTO--><\/div>\n<div id=\"texto\"><!--TEXTO DA FOTO-->&quot;Deus escolheu voc&ecirc; para ser santo!&quot;, diz padre Paulo Ricardo<!--TEXTO DA FOTO--><\/div>\n<div id=\"credito\"><!--CREDITO DA FOTO-->Foto: Wesley Almeida\/cancaonova.com<!--CREDITO DA FOTO--><\/div>\n<\/div>\n<p>  Eu tenho certeza que Jesus olha, hoje, para voc&ecirc;, assim como olhou para Mateus, e o chama para uma longa viagem. Exatamente por isso, o Beato Jo&atilde;o Paulo II sempre quis que a JMJ fosse marcada por um momento de peregrina&ccedil;&atilde;o, como acontece com o deslocamento at&eacute; a vig&iacute;lia. <\/p>\n<p>  Com isso, ele mostra que &eacute; preciso caminhar e gastar sua vida para chegar em nossa meta. O caminhar n&atilde;o significa falta de organiza&ccedil;&atilde;o, mas um est&iacute;mulo ao cora&ccedil;&atilde;o que deseja romper com a mundanidade.<\/p>\n<p>  A pergunta que Deus quer fazer hoje &eacute;: Voc&ecirc; n&atilde;o est&aacute; com saudade de voc&ecirc; mesmo? De quem voc&ecirc; verdadeiramente &eacute; e da forma com que foi sonhado por Deus? Se a sua resposta for positiva, deixe tudo e siga-O.<\/p>\n<p>  Deus escolheu voc&ecirc; para ser santo! N&atilde;o importa o que o mundo diga a respeito de voc&ecirc;, muito menos o que voc&ecirc; viveu at&eacute; chegar o dia de hoje, pois a Miseric&oacute;rdia Divina &eacute; muito maior do que tudo isso. <br \/><em><br \/>Transcri&ccedil;&atilde;o e adapta&ccedil;&atilde;o: Gustavo Souza<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Padre Paulo Ricardo Foto: Wesley Almeida\/cancaonova.com O Evangelho de hoje &eacute; muito prop&iacute;cio para falar do mensageiro de Deus que iremos receber: o Papa Francisco. Pouca gente sabe, mas o Evangelho de hoje &eacute;, justamente, o lema do Papa Francisco&#8230;.<\/p>\n","protected":false},"author":114,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7],"tags":[],"modified_by":"","_links":{"self":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/2833"}],"collection":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/users\/114"}],"replies":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/comments?post=2833"}],"version-history":[{"count":1,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/2833\/revisions"}],"predecessor-version":[{"id":2834,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/2833\/revisions\/2834"}],"wp:attachment":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media?parent=2833"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/categories?post=2833"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/tags?post=2833"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}