{"id":28813,"date":"2015-07-24T15:15:47","date_gmt":"2015-07-24T18:15:47","guid":{"rendered":"http:\/\/admin-canais.cancaonova.com\/eventos\/?p=28813"},"modified":"2015-07-26T14:31:57","modified_gmt":"2015-07-26T17:31:57","slug":"fotos-exclusivas-do-i-encontro-de-carros-historicos-na-cancao-nova","status":"publish","type":"post","link":"https:\/\/admin-canais.cancaonova.com\/eventos\/acampamento-para-casais\/cobertura\/fotos-exclusivas-do-i-encontro-de-carros-historicos-na-cancao-nova\/","title":{"rendered":"Fotos exclusivas do I Encontro de carros hist\u00f3ricos na Can\u00e7\u00e3o Nova"},"content":{"rendered":"<p><strong>Neste fim de semana acontece na Can\u00e7\u00e3o Nova I Encontro de carros hist\u00f3ricos &#8220;Insieme&#8221;<\/strong><i><br \/>\n<\/i><\/p>\n<p>Veja fotos exclusivas:<\/p>\n<p><i> \r\n\t<div class=\"slideshow_container slideshow_container_slideshow-jquery-image-gallery-custom-styles_1\" style=\"height: 800px; \" data-slideshow-id=\"28811\" data-style-name=\"slideshow-jquery-image-gallery-custom-styles_1\" data-style-version=\"1437076754\" >\r\n\r\n\t\t\t\t\t<div class=\"slideshow_loading_icon\"><\/div>\r\n\t\t\r\n\t\t<div class=\"slideshow_content\" style=\"display: none;\">\r\n\r\n\t\t\t<div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2015\/07\/Encontro-CarrosAntigos-fusca-1972.jpg\" alt=\"Encontro de carros hist\u00f3ricos na Can\u00e7\u00e3o Nova\" width=\"910\" height=\"630\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">Encontro de carros hist\u00f3ricos na Can\u00e7\u00e3o Nova<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2015\/07\/Encontro-CarrosAntigos-Caravan-deluxo-1978.jpg\" alt=\"Encontro de carros hist\u00f3ricos na Can\u00e7\u00e3o Nova\" width=\"910\" height=\"630\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">Encontro de carros hist\u00f3ricos na Can\u00e7\u00e3o Nova<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2015\/07\/Encontro-CarrosAntigos-Carava-deluxo02-1978.jpg\" alt=\"Encontro de carros hist\u00f3ricos na Can\u00e7\u00e3o Nova\" width=\"910\" height=\"630\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">Encontro de carros hist\u00f3ricos na Can\u00e7\u00e3o Nova<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2015\/07\/Encontro-CarrosAntigos-09.jpg\" alt=\"Encontro de carros hist\u00f3ricos na Can\u00e7\u00e3o Nova\" width=\"910\" height=\"630\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">Encontro de carros hist\u00f3ricos na Can\u00e7\u00e3o Nova<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2015\/07\/Encontro-CarrosAntigos-08.jpg\" alt=\"Encontro de carros hist\u00f3ricos na Can\u00e7\u00e3o Nova\" width=\"910\" height=\"630\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">Encontro de carros hist\u00f3ricos na Can\u00e7\u00e3o Nova<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2015\/07\/Encontro-CarrosAntigos-07.jpg\" alt=\"Encontro de carros hist\u00f3ricos na Can\u00e7\u00e3o Nova\" width=\"910\" height=\"630\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">Encontro de carros hist\u00f3ricos na Can\u00e7\u00e3o Nova<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2015\/07\/Encontro-CarrosAntigos-06.jpg\" alt=\"Encontro de carros hist\u00f3ricos na Can\u00e7\u00e3o Nova\" width=\"910\" height=\"630\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">Encontro de carros hist\u00f3ricos na Can\u00e7\u00e3o Nova<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2015\/07\/Encontro-CarrosAntigos-05.jpg\" alt=\"Encontro de carros hist\u00f3ricos na Can\u00e7\u00e3o Nova\" width=\"910\" height=\"630\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">Encontro de carros hist\u00f3ricos na Can\u00e7\u00e3o Nova<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2015\/07\/Encontro-CarrosAntigos-04.jpg\" alt=\"Encontro de carros hist\u00f3ricos na Can\u00e7\u00e3o Nova\" width=\"910\" height=\"630\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">Encontro de carros hist\u00f3ricos na Can\u00e7\u00e3o Nova<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2015\/07\/Encontro-CarrosAntigos-03.jpg\" alt=\"Encontro de carros hist\u00f3ricos na Can\u00e7\u00e3o Nova\" width=\"910\" height=\"630\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">Encontro de carros hist\u00f3ricos na Can\u00e7\u00e3o Nova<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2015\/07\/GM-Opala-Comodoro-1981.jpg\" alt=\"Encontro de carros hist\u00f3ricos na Can\u00e7\u00e3o Nova\" width=\"910\" height=\"630\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">Encontro de carros hist\u00f3ricos na Can\u00e7\u00e3o Nova<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2015\/07\/Encontro-CarrosAntigos02.jpg\" alt=\"Encontro de carros hist\u00f3ricos na Can\u00e7\u00e3o Nova\" width=\"910\" height=\"630\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">Encontro de carros hist\u00f3ricos na Can\u00e7\u00e3o Nova<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div>\r\n\t\t<\/div>\r\n\r\n\t\t<div class=\"slideshow_controlPanel slideshow_transparent\" style=\"display: none;\"><ul><li class=\"slideshow_togglePlay\" data-play-text=\"Acionar\" data-pause-text=\"Pausar\"><\/li><\/ul><\/div>\r\n\r\n\t\t<div class=\"slideshow_button slideshow_previous slideshow_transparent\" role=\"button\" data-previous-text=\"Anterior\" style=\"display: none;\"><\/div>\r\n\t\t<div class=\"slideshow_button slideshow_next slideshow_transparent\" role=\"button\" data-next-text=\"Pr\u00f3ximo\" style=\"display: none;\"><\/div>\r\n\r\n\t\t<div class=\"slideshow_pagination\" style=\"display: none;\" data-go-to-text=\"Ir para o slide\"><div class=\"slideshow_pagination_center\"><\/div><\/div>\r\n\r\n\t\t<!-- WordPress Slideshow Version 2.3.1 -->\r\n\r\n\t\t\t<\/div>\r\n\r\n<\/i><\/p>\n<p>Fotos: Wesley Almeida\/cancaonova.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Neste fim de semana acontece na Can\u00e7\u00e3o Nova I Encontro de carros hist\u00f3ricos &#8220;Insieme&#8221; Veja fotos exclusivas: Fotos: Wesley Almeida\/cancaonova.com<\/p>\n","protected":false},"author":88,"featured_media":28888,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[8],"tags":[],"modified_by":"Rog\u00e9ria Nair","_links":{"self":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/28813"}],"collection":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/users\/88"}],"replies":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/comments?post=28813"}],"version-history":[{"count":5,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/28813\/revisions"}],"predecessor-version":[{"id":28895,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/28813\/revisions\/28895"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media\/28888"}],"wp:attachment":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media?parent=28813"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/categories?post=28813"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/tags?post=28813"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}