{"id":28970,"date":"2015-07-30T17:09:54","date_gmt":"2015-07-30T20:09:54","guid":{"rendered":"http:\/\/admin-canais.cancaonova.com\/eventos\/?p=28970"},"modified":"2015-07-30T17:09:54","modified_gmt":"2015-07-30T20:09:54","slug":"o-reino-de-deus-sempre-nos-propoe-escolhas","status":"publish","type":"post","link":"https:\/\/admin-canais.cancaonova.com\/eventos\/quinta-feira-de-adoracao\/pregacoes\/o-reino-de-deus-sempre-nos-propoe-escolhas\/","title":{"rendered":"O Reino de Deus sempre nos prop\u00f5e escolhas"},"content":{"rendered":"<div id=\"attachment_28971\" style=\"width: 279px\" class=\"wp-caption alignleft\"><a href=\"http:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2015\/07\/o_reino_de_deus_sempre_nos_propoe_escolhas.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-28971\" class=\"wp-image-28971 size-full\" title=\"o_reino_de_deus_sempre_nos_propoe_escolhas\" src=\"http:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2015\/07\/o_reino_de_deus_sempre_nos_propoe_escolhas.jpg\" alt=\"o_reino_de_deus_sempre_nos_propoe_escolhas\" width=\"269\" height=\"329\" srcset=\"https:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2015\/07\/o_reino_de_deus_sempre_nos_propoe_escolhas.jpg 269w, https:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2015\/07\/o_reino_de_deus_sempre_nos_propoe_escolhas-245x300.jpg 245w\" sizes=\"(max-width: 269px) 100vw, 269px\" \/><\/a><p id=\"caption-attachment-28971\" class=\"wp-caption-text\">Padre Reinaldo Cazumb\u00e1. Foto: Wesley Almeida\/cancaonova.com<\/p><\/div>\n<p><strong>&#8220;S\u00f3 entram no Reino de Deus quem faz a op\u00e7\u00e3o de permanecer com Jesus Cristo&#8221;.<\/strong><\/p>\n<p>O cap\u00edtulo 13 de S\u00e3o Matheus tem diversas par\u00e1bolas: do &#8216;Reino&#8217; e do &#8216;Semeador&#8217; que saiu a semear; a par\u00e1bola do homem que descobriu uma pedra preciosa no campo e do homem que semeou a semente boa, mas o inimigo colocou o joio. H\u00e1 tamb\u00e9m a par\u00e1bola das redes. Todas elas nos preparam e nos exortam para o Reino de Deus e para a segunda vinda de Cristo.<\/p>\n<p>Por meio das par\u00e1bolas, o Senhor toca em diversas dimens\u00f5es da vida do ser humano e usa uma linguagem bem simples para que ele a entenda. Pense nesta par\u00e1bola agora, na qual o homem lan\u00e7a as redes. Voc\u00ea j\u00e1 viu, em algum filme, algu\u00e9m as lan\u00e7ando? Quando isso acontece, alguns peixes s\u00e3o separados, pois h\u00e1 alguns t\u00e3o pequenos, que precisam de uma sele\u00e7\u00e3o. O Reino de Deus \u00e9 tamb\u00e9m uma separa\u00e7\u00e3o entre aquilo que \u00e9 d&#8217;Ele e aquilo que n\u00e3o o \u00e9.<\/p>\n<p>Talvez, voc\u00ea se pergunte: \u201cPor que todos os tipos de peixes v\u00eam \u00e0 rede?\u201d. Porque seja no rio ou no a\u00e7ude, voc\u00ea n\u00e3o consegue ver aqueles que v\u00e3o entrar na rede.<\/p>\n<p>Todos n\u00f3s somos chamados \u00e0 vida eterna, mas alguns n\u00e3o aceitam o chamado e n\u00e3o o acolhem. Talvez seja porque n\u00e3o se sintam preparados, ou ainda se fazem exclu\u00eddos dessa sele\u00e7\u00e3o. H\u00e1 aqueles que renegam o Senhor, e esses v\u00e3o se perder.<\/p>\n<p><strong>O Reino de Deus sempre nos prop\u00f5e escolhas e tomadas de decis\u00e3o.<\/strong> O Senhor sempre vai nos propor que permane\u00e7amos n&#8217;Ele; ningu\u00e9m \u00e9 exclu\u00eddo pelo Senhor, mas o pr\u00f3prio ser humano, muitas vezes, exclui-se. Para tudo o que voc\u00ea escolher em sua vida haver\u00e1 uma consequ\u00eancia, seja para a salva\u00e7\u00e3o ou condena\u00e7\u00e3o eterna.<\/p>\n<p>S\u00f3 entram no Reino de Deus quem faz a op\u00e7\u00e3o de permanecer com Jesus Cristo. Os maus ser\u00e3o lan\u00e7ados no fogo, onde haver\u00e1 choro e ranger de dentes.<strong> Voc\u00ea precisa lan\u00e7ar seus pecados no fogo da miseric\u00f3rdia, do Esp\u00edrito Santo, para voc\u00ea n\u00e3o ser lan\u00e7ado no fogo eterno.<\/strong><\/p>\n<div id=\"attachment_28972\" style=\"width: 605px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2015\/07\/o_reino_de_deus_sempre_nos_propoe_escolhas1.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-28972\" class=\"wp-image-28972 size-full\" title=\"o_reino_de_deus_sempre_nos_propoe_escolhas\" src=\"http:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2015\/07\/o_reino_de_deus_sempre_nos_propoe_escolhas1.jpg\" alt=\"o_reino_de_deus_sempre_nos_propoe_escolhas\" width=\"595\" height=\"420\" srcset=\"https:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2015\/07\/o_reino_de_deus_sempre_nos_propoe_escolhas1.jpg 595w, https:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2015\/07\/o_reino_de_deus_sempre_nos_propoe_escolhas1-300x212.jpg 300w\" sizes=\"(max-width: 595px) 100vw, 595px\" \/><\/a><p id=\"caption-attachment-28972\" class=\"wp-caption-text\">Peregrinos participam da Santa Missa com padre Reinaldo Cazumb\u00e1 na Can\u00e7\u00e3o Nova. Foto: Wesley Almeida\/cancaonova.com<\/p><\/div>\n<p>Precisamos pedir ao Senhor a convers\u00e3o do nosso cora\u00e7\u00e3o, a fim de que n\u00e3o sejamos lan\u00e7ados no inferno. Se voc\u00ea precisa abrir m\u00e3o de certas coisas, comece a ceder agora. N\u00e3o h\u00e1 como voc\u00ea entrar no Reino do C\u00e9us como voc\u00ea est\u00e1, porque l\u00e1 \u00e9 lugar de purifica\u00e7\u00e3o, e a nossa vida precisa ser purificada para irmos ao encontro de Jesus.<\/p>\n<p>Se estamos \u201ccheios\u201d de coisas que n\u00e3o s\u00e3o de Deus, n\u00e3o conseguiremos ir para o c\u00e9u. Temos de eliminar de nossa vida o que n\u00e3o nos leva para o c\u00e9u. Temos de tirar os pecados da nossa vida para que voc\u00ea possa entrar no Reino. Se n\u00e3o, quando o Senhor puxar a rede, voc\u00ea ser\u00e1 selecionado e descartado. Cuidado com aquilo que est\u00e1 fazendo da sua vida! N\u00e3o existe melhor coisa na vida do que pertencer ao Senhor.<strong> As coisas passam, e ningu\u00e9m leva nada deste mundo.<\/strong><\/p>\n<p>As pessoas s\u00f3 v\u00e3o levar desta vida aquilo que constru\u00edram. Por isso, a nossa vida precisa proclamar todo o tempo, por meio de gestos e atos, o senhorio de Jesus. Cuidado para voc\u00ea n\u00e3o se perder e acabar perdendo o que h\u00e1 de mais precioso em sua vida: Jesus Cristo. O crist\u00e3o precisa tranformar-se n&#8217;Aquele que recebe na comunh\u00e3o.<\/p>\n<p>N\u00f3s estamos nos preparando para o Senhor que vem. Se voc\u00ea est\u00e1 caminhando sem se preparar, cuidado! Porque ele pode vir a qualquer momento. Se esperamos uma visita, n\u00e3o o fa\u00e7amos de qualquer jeito. Quando algu\u00e9m vai \u00e0 sua casa, voc\u00ea faz de tudo para ela ser bem acolhida. E se Jesus vier hoje, na sua vida, Ele ser\u00e1 bem acolhido no seu cora\u00e7\u00e3o? N\u00e3o adianta dar desculpa para Jesus. Ent\u00e3o, prepare-se!<\/p>\n<p><strong>Que a santidade da sua vida apresse o Senhor, que logo vir\u00e1!<\/strong><\/p>\n<p><em>Transcri\u00e7\u00e3o e adapta\u00e7\u00e3o: Jakeline Megda D&#8217;Onofrio.\u00a0<\/em><\/p>\n<p>Adquira esta prega\u00e7\u00e3o pelo telefone: (012) 3186-2600<\/p>\n<p><a href=\"http:\/\/clube.cancaonova.com\/boleto-online\/\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-28820\" src=\"http:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2015\/07\/contribuicaocn1.jpg\" alt=\"contribuicaocn\" width=\"300\" height=\"72\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;S\u00f3 entram no Reino de Deus quem faz a op\u00e7\u00e3o de permanecer com Jesus Cristo&#8221;. O cap\u00edtulo 13 de S\u00e3o Matheus tem diversas par\u00e1bolas: do &#8216;Reino&#8217; e do &#8216;Semeador&#8217; que saiu a semear; a par\u00e1bola do homem que descobriu uma&#8230;<\/p>\n","protected":false},"author":116,"featured_media":28973,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7],"tags":[],"modified_by":null,"_links":{"self":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/28970"}],"collection":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/users\/116"}],"replies":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/comments?post=28970"}],"version-history":[{"count":1,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/28970\/revisions"}],"predecessor-version":[{"id":28974,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/28970\/revisions\/28974"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media\/28973"}],"wp:attachment":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media?parent=28970"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/categories?post=28970"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/tags?post=28970"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}