{"id":30192,"date":"2015-10-10T10:37:11","date_gmt":"2015-10-10T13:37:11","guid":{"rendered":"http:\/\/admin-canais.cancaonova.com\/eventos\/?p=30192"},"modified":"2015-10-11T09:19:23","modified_gmt":"2015-10-11T12:19:23","slug":"vinde-a-mim-sedentos","status":"publish","type":"post","link":"https:\/\/admin-canais.cancaonova.com\/eventos\/acampamento-clamando-por-milagres\/pregacoes\/vinde-a-mim-sedentos\/","title":{"rendered":"Vinde a mim, sedentos"},"content":{"rendered":"<h2>Como clamar o milagre de Deus e buscar Nele a paz e o descanso<\/h2>\n<div id=\"attachment_30194\" style=\"width: 279px\" class=\"wp-caption alignleft\"><a href=\"http:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2015\/10\/269x329-Pregacao-Padre-Antonio-Jose-manha.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-30194\" class=\"wp-image-30194 size-full\" src=\"http:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2015\/10\/269x329-Pregacao-Padre-Antonio-Jose-manha.jpg\" alt=\"Padre Antonio Jose \/ Arquivo CN\" width=\"269\" height=\"329\" srcset=\"https:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2015\/10\/269x329-Pregacao-Padre-Antonio-Jose-manha.jpg 269w, https:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2015\/10\/269x329-Pregacao-Padre-Antonio-Jose-manha-245x300.jpg 245w\" sizes=\"(max-width: 269px) 100vw, 269px\" \/><\/a><p id=\"caption-attachment-30194\" class=\"wp-caption-text\">Padre Antonio Jos\u00e9 \/ Arquivo CN<\/p><\/div>\n<p>Hoje de manh\u00e3, rezando pela partilha, pensei e falei para Deus: &#8216;O que falamos em um Acampamento Clamando por Milagres?&#8217; E Deus me respondeu: &#8216;Fale sobre Jesus! Jesus de Nazar\u00e9, Ele \u00e9 fonte de toda cura, Ele \u00e9 o rem\u00e9dio!&#8217;<\/p>\n<p>As coisas ainda n\u00e3o est\u00e3o perdidas, Deus tem a solu\u00e7\u00e3o que ningu\u00e9m mais tem, a sua solu\u00e7\u00e3o \u00e9 Jesus!<\/p>\n<p>Estamos aqui clamando, Deus se importa com seu clamor.<\/p>\n<p>H\u00e1 momentos na nossa vida que s\u00f3 temos vontade de gritar, e Jesus tamb\u00e9m clama em nossos cora\u00e7\u00f5es.<\/p>\n<p><i>\u201cE no \u00faltimo dia, o grande dia da festa, Jesus p\u00f4s-se em p\u00e9, e clamou, dizendo: Se algu\u00e9m tem sede, venha a mim, e beba.\u00a0Quem cr\u00ea em mim, como diz a Escritura, rios de \u00e1gua viva correr\u00e3o do seu ventre.\u00a0E isto disse ele do Esp\u00edrito que haviam de receber os que nele cressem; porque o Esp\u00edrito Santo ainda n\u00e3o fora dado, por ainda Jesus n\u00e3o ter sido glorificado.\u00a0Ent\u00e3o muitos da multid\u00e3o, ouvindo esta palavra, diziam: Verdadeiramente este \u00e9 o Profeta.\u201d (<\/i>Jo\u00e3o 7, 37-40)<\/p>\n<p>Jesus Cristo \u00e9 o mesmo hoje, ontem e para sempre. Deus que, no templo, enxergava dentro das pessoas, hoje Ele v\u00ea dentro de voc\u00ea. E hoje Jesus lhe diz: &#8216;Se voc\u00ea tem sede, vem a mim, Eu tenho a \u00e1gua viva!&#8217; S\u00f3 entende esse chamado de Jesus quem tem sede e fome no cora\u00e7\u00e3o, e essa sede e fome n\u00e3o \u00e9 saciada por ningu\u00e9m!<\/p>\n<p>Todos n\u00f3s carregamos uma sede e fome de encontrar um lugar pra gente, temos medo de nos sentirmos sozinhos, nosso cora\u00e7\u00e3o tem sede de se sentir amado, e a\u00ed cobramos das pessoas algo que elas n\u00e3o t\u00eam para nos dar. E a\u00ed, muitas vezes, para nos saciar, procuramos casar. E as pessoas querem que o marido, os filhos, saciem essa sede, cobram dos filhos e maridos. Temos sede, e nem filhos e marido v\u00e3o preencher seu cora\u00e7\u00e3o, h\u00e1 um espa\u00e7o dentro do\u00a0seu cora\u00e7\u00e3o que s\u00f3 Jesus pode preencher.<\/p>\n<p>\u00c0s vezes, no meio do caminho, ao inv\u00e9s de buscarmos saciar a sede na fonte, buscamos cisternas rachadas. Quando voc\u00ea v\u00ea jovens drogados, n\u00e3o olhe &#8216;torto&#8217;, lembre que ele est\u00e1 na cisterna rachada, reze e ofere\u00e7a a ele a \u00e1gua viva.<\/p>\n<p>\u00c9 uma pena quando vemos um crist\u00e3o que reza muito, mas fica s\u00f3 no \u201ceu\u201d, voc\u00ea precisa buscar a \u00e1gua viva e transbordar para outras pessoas!<\/p>\n<p><strong>Acesse:<\/strong><\/p>\n<p><a href=\"http:\/\/eventos.cancaonova.com\/acampamento-clamando-por-milagres\/pregacoes\/o-adorador-ve-milagres\/\" target=\"_blank\">.:\u00a0O adorador v\u00ea milagres<\/a><\/p>\n<p>.:<a href=\"http:\/\/eventos.cancaonova.com\/edicao\/acampamento-clamando-por-milagres-7\/\">Outras prega\u00e7\u00f5es deste acampamento<\/a><\/p>\n<div id=\"attachment_30195\" style=\"width: 605px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2015\/10\/595x420-Pregacao-Padre-Antonio-Jose-manha.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-30195\" class=\"wp-image-30195 size-full\" src=\"http:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2015\/10\/595x420-Pregacao-Padre-Antonio-Jose-manha.jpg\" alt=\"Padre Antonio Jose \/ Arquivo CN\" width=\"595\" height=\"420\" srcset=\"https:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2015\/10\/595x420-Pregacao-Padre-Antonio-Jose-manha.jpg 595w, https:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2015\/10\/595x420-Pregacao-Padre-Antonio-Jose-manha-300x212.jpg 300w\" sizes=\"(max-width: 595px) 100vw, 595px\" \/><\/a><p id=\"caption-attachment-30195\" class=\"wp-caption-text\">Padre Antonio Jose \/ Arquivo CN<\/p><\/div>\n<h2>Vinde a mim, todos os que estais cansados<\/h2>\n<p><i>\u201cVinde a mim, todos os que estais cansados e oprimidos, e eu vos aliviarei.<br \/>\nTomai sobre v\u00f3s o meu jugo, e aprendei de mim, que sou manso e humilde de cora\u00e7\u00e3o; e encontrareis descanso para as vossas almas.\u00a0Porque o meu jugo \u00e9 suave e o meu fardo \u00e9 leve.\u201d \u00a0(<\/i>Mateus 11, 28-30)<\/p>\n<p>Para voc\u00ea cumprir a miss\u00e3o que Deus\u00a0lhe\u00a0confiou, voc\u00ea n\u00e3o precisa carregar o mundo nas costas, voc\u00ea precisa lutar, mas voltar para Jesus, porque \u00e9 l\u00e1 que voc\u00ea vai encontrar o descanso. Deus te quer trabalhando em favor do seus, mas sempre em paz, Deus n\u00e3o te quer em farrapos, Ele te quer lutando, mas inteiro. Jesus clama a n\u00f3s a cada dia: &#8216;Venha a mim!&#8217;<\/p>\n<p>Padre Zezinho diz que quando Jesus entra na nossa vida Ele nos d\u00e1 a paz, mas n\u00e3o nos deixa em paz. Jesus nos d\u00e1 o direito de paz. \u00c9 com a paz que voc\u00ea carrega dentro de voc\u00ea que voc\u00ea vai evangelizar.<\/p>\n<p>Sua casa precisa se tornar um lugar de paz, mas para isso voc\u00ea precisa ser uma pessoa cheia de paz, ent\u00e3o n\u00e3o tenha medo de se entregar a Deus.<\/p>\n<p>No mundo do espiritual, onde travamos o bom combate, nosso combate n\u00e3o \u00e9 contra pessoas. No mundo espiritual, o que define de que lado voc\u00ea est\u00e1 ou em\u00a0que ex\u00e9rcito voc\u00ea batalha, s\u00e3o as\u00a0armas que est\u00e1 usando.<\/p>\n<p>Voc\u00ea precisa aprender de Jesus, e para isso voc\u00ea precisa sentar do lado Dele e falar das situa\u00e7\u00f5es. Quando aprendo ouvir o Senhor, quando aprendo a dar tempo a Jesus, eu aprendo, tamb\u00e9m,\u00a0a ouvir as pessoas e compreend\u00ea-las, mas para isso precisamos rezar, rezar mais.<\/p>\n<p>Pergunte a Deus, como o ap\u00f3stolo S\u00e3o Paulo: &#8216;Senhor quem tu \u00e9s? Senhor o que queres de mim?&#8217; S\u00e3o Paulo buscava o Senhor incansavelmente.<\/p>\n<p>Voc\u00ea chega onde sua sede e fome te levam. Porque, a\u00ed voc\u00ea \u00e9 capaz de procurar coisas imposs\u00edveis. Encontra milagres quem tem fome e sede de Deus. Voc\u00ea busca milagres? Procure no seu cora\u00e7\u00e3o a fome e sede de Deus.<\/p>\n<p>Pode ser que voc\u00ea esteja buscando matar essa fome e sede em lugares que voc\u00ea n\u00e3o ser\u00e1 saciado, em compras, em bebidas ou at\u00e9 mesmo em pessoas. Jesus hoje clama a voc\u00ea: &#8216;Venha a mim! Vinde a mim, todos os que estais cansados!&#8217;<\/p>\n<p><em>Transcri\u00e7\u00e3o e adapta\u00e7\u00e3o:\u00a0Elcka Torres<\/em><\/p>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: center;\">Adquira esta prega\u00e7\u00e3o pelo<br \/>\ntelefone (12) 3186-2600<\/h2>\n<p><em>\u00a0<\/em><\/p>\n<p><a href=\"http:\/\/bit.ly\/doacaocnova\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-25618\" src=\"http:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2015\/02\/contribuicaocn3.jpg\" alt=\"contribuicaocn\" width=\"300\" height=\"72\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Como clamar o milagre de Deus e buscar Nele a paz e o descanso Hoje de manh\u00e3, rezando pela partilha, pensei e falei para Deus: &#8216;O que falamos em um Acampamento Clamando por Milagres?&#8217; E Deus me respondeu: &#8216;Fale sobre&#8230;<\/p>\n","protected":false},"author":26,"featured_media":30197,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7],"tags":[],"modified_by":"elcka","_links":{"self":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/30192"}],"collection":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/comments?post=30192"}],"version-history":[{"count":22,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/30192\/revisions"}],"predecessor-version":[{"id":30235,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/30192\/revisions\/30235"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media\/30197"}],"wp:attachment":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media?parent=30192"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/categories?post=30192"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/tags?post=30192"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}