{"id":30335,"date":"2015-10-22T12:16:13","date_gmt":"2015-10-22T14:16:13","guid":{"rendered":"http:\/\/admin-canais.cancaonova.com\/eventos\/?p=30335"},"modified":"2015-10-22T12:26:23","modified_gmt":"2015-10-22T14:26:23","slug":"os-valores-do-mundo-e-a-desvalorizacao-do-ser-humano","status":"publish","type":"post","link":"https:\/\/admin-canais.cancaonova.com\/eventos\/quinta---feira-de-adoracao\/pregacoes\/os-valores-do-mundo-e-a-desvalorizacao-do-ser-humano\/","title":{"rendered":"Os valores do mundo e a desvaloriza\u00e7\u00e3o do ser humano"},"content":{"rendered":"<h2>Enquanto eu quis ganhar a vida, fui vendo-a ser desvalorizada<\/h2>\n<div id=\"attachment_30341\" style=\"width: 279px\" class=\"wp-caption alignleft\"><a href=\"http:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2015\/10\/os_valores_do_mundo_e_a_desvalorizacao_do_ser-humano.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-30341\" class=\"wp-image-30341 size-full\" title=\"os_valores_do_mundo_e_a_desvalorizacao_do_ser humano\" src=\"http:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2015\/10\/os_valores_do_mundo_e_a_desvalorizacao_do_ser-humano.jpg\" alt=\"os_valores_do_mundo_e_a_desvalorizacao_do_ser humano\" width=\"269\" height=\"329\" srcset=\"https:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2015\/10\/os_valores_do_mundo_e_a_desvalorizacao_do_ser-humano.jpg 269w, https:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2015\/10\/os_valores_do_mundo_e_a_desvalorizacao_do_ser-humano-245x300.jpg 245w\" sizes=\"(max-width: 269px) 100vw, 269px\" \/><\/a><p id=\"caption-attachment-30341\" class=\"wp-caption-text\">Gr\u00e9gory Turpin. Foto: Daniel Mafra\/cancaonova.com<\/p><\/div>\n<p>Estou feliz por estar aqui pela segunda vez. Passei pela cidade de S\u00e3o Paulo e vi coisas extraordin\u00e1rias l\u00e1! Visitei lugares onde havia uma extrema pobreza, mas tamb\u00e9m as mais lindas a\u00e7\u00f5es de generosidade. Voc\u00eas s\u00e3o um povo que tem uma f\u00e9 viva, s\u00e3o modelos para n\u00f3s que perdemos a f\u00e9. Eu prometo que, na Fran\u00e7a, falarei de voc\u00eas.<\/p>\n<p>Sou um cantor cat\u00f3lico na Fran\u00e7a. L\u00e1, possu\u00edmos muitas coisas, mas perdemos o essencial, que \u00e9 a f\u00e9. No entanto, os crist\u00e3os, pouco numerosos, s\u00e3o verdadeiramente cheios do Esp\u00edrito Santo.<\/p>\n<p>Nasci em uma pequena fam\u00edlia popular e apaixonada pela m\u00fasica. Eu era extremamente t\u00edmido, era um fracasso nos meus estudos e infeliz. Um dia, no vilarejo onde eu morava, encontrei um sacerdote e ele viu meu desespero. Ele me chamou para cantar nas Missas aos domingos. Meu pai, que n\u00e3o gostava da Igreja, falava que, na Fran\u00e7a, havia velhos e burros. Quando fui cantar na igreja, vi que n\u00e3o era aquilo que meu pai falava, pois havia alguns jovens.<\/p>\n<p>Um tempo depois, na adolesc\u00eancia, comecei a fumar maconha. Um dia, tive um encontro excepcional com Deus. Certa vez, as rel\u00edquias de Santa Teresinha foram nos visitar, e, \u00e0 noite, um cantor cantava o que falava Santa Teresinha. Fui tocado pela m\u00fasica, quis conhecer quem era essa santa e quis entrar para o Carmelo. Quando cheguei ao Carmelo, fui impactado com o que encontrei l\u00e1, a vida com os irm\u00e3os.<\/p>\n<p>L\u00e1, fui crescendo na f\u00e9 e sendo firmado pelo meu amor por Cristo. Passado um tempo, adoeci e n\u00e3o consegui viver a vida em comunidade. Fiquei muito triste, pois tive de deix\u00e1-la.<\/p>\n<p>Comecei a ficar com m\u00e1goa de Deus, pois, quando abria o Evangelho, via as curas de que Ele fazia e pensava: \u201cEu larguei a vida para segui-Lo e o Senhor n\u00e3o fez nada por mim. O Senhor me abandonou\u201d. Quando deixei a comunidade e voltei para a casa do meu pai, ele pediu que eu me formasse e desse continuidade ao pequeno mercado dele. Eu me tornei respons\u00e1vel por frutas e legumes. N\u00e3o ganhava muito e tinha uma profiss\u00e3o de que n\u00e3o gostava.<\/p>\n<p>Em nossa ora\u00e7\u00e3o, falamos o que queremos e achamos que \u00e9 bom para n\u00f3s, mas, na verdade, \u00e9 Deus quem sabe o que \u00e9 bom para n\u00f3s.<\/p>\n<div id=\"attachment_30342\" style=\"width: 605px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2015\/10\/os_valores_do_mundo_e_a_desvalorizacao_do_ser-humano1.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-30342\" class=\"wp-image-30342 size-full\" title=\"os_valores_do_mundo_e_a_desvalorizacao_do_ser humano\" src=\"http:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2015\/10\/os_valores_do_mundo_e_a_desvalorizacao_do_ser-humano1.jpg\" alt=\"os_valores_do_mundo_e_a_desvalorizacao_do_ser humano\" width=\"595\" height=\"420\" srcset=\"https:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2015\/10\/os_valores_do_mundo_e_a_desvalorizacao_do_ser-humano1.jpg 595w, https:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2015\/10\/os_valores_do_mundo_e_a_desvalorizacao_do_ser-humano1-300x212.jpg 300w\" sizes=\"(max-width: 595px) 100vw, 595px\" \/><\/a><p id=\"caption-attachment-30342\" class=\"wp-caption-text\">Fi\u00e9is participam da Quinta-feira de Adora\u00e7\u00e3o. Foto: Daniel Mafra\/cancaonova.com<\/p><\/div>\n<p>Pela revolta que estava no meu cora\u00e7\u00e3o, decidi cantar em bares. Eu cantava todas as noites, ganhava muito dinheiro e as pessoas me rodeavam. Entrei na vida das drogas e ela foi me levando \u00e0 tristeza e ao suic\u00eddio. Decidi que me mataria asfixiado. Um amigo me salvou dessa situa\u00e7\u00e3o, pois passou perto da minha casa e sentiu cheiro de g\u00e1s. Fiquei quinze dias no hospital psiquiatra. Eu pensava que Deus havia me abandonado, mas eram meus atos que me separavam do amor d&#8217;Ele. Quando eu tinha quinze anos, comprometi-me a encontrar um sacerdote a cada m\u00eas e buscar a comunh\u00e3o. Por meio desse sacramento, Deus salvou a minha vida.<\/p>\n<p>Eu dizia ao Senhor: \u201cAntes eu era feliz; hoje tenho tudo o que o mundo pode me oferecer, e n\u00e3o sou feliz\u201d. Voltando para a casa, lembrei-me de uma m\u00fasica de Santa Teresinha: \u201cSe quero ser feliz, eu preciso escolher o &#8216;hoje&#8217;\u201d.<\/p>\n<p>Sei que, gra\u00e7as ao sacramento da reconcilia\u00e7\u00e3o, Deus me perdoou. Decidi que eu queria me comprometer novamente na Igreja. Comprometi-me a n\u00e3o me deixar levar pela fama da m\u00fasica. Quando voltei \u00e0 par\u00f3quia, voltei para as Missas. Eu tinha dificuldade de rezar, porque meus atos me cortaram de Deus. Aos poucos, voltei para a Igreja e ainda n\u00e3o sabia o que o Senhor queria de mim. Durante um m\u00eas, fui para Lisieux, cidade de Santa Teresinha, atr\u00e1s de uma resposta. Estava disposto aceitar todos os esfor\u00e7os para ser feliz.<\/p>\n<p>Durante todo o m\u00eas que fiquei ao lado da santa, fui fortificado na f\u00e9, mas ainda n\u00e3o tinha respostas. Quando voltei para casa, uma religiosa, que eu n\u00e3o via h\u00e1 oito anos, pediu para eu cantar. Eu lhe disse que havia parado com a m\u00fasica. Ela me contou que estava fazendo m\u00fasicas com os poemas de Santa Teresinha e me convidou para compor. Aceitei o convite. Pouco a pouco, percebi que a m\u00fasica era muito importante, algo que me fazia entrar em comunica\u00e7\u00e3o com o outro; a m\u00fasica era meu rem\u00e9dio.<\/p>\n<p>Os franceses n\u00e3o escutam m\u00fasica cat\u00f3lica. Eu permaneci nessa via e fui de par\u00f3quia em par\u00f3quia para cantar. Um dia, decidi mudar para Paris e encontrar os produtores da gravadora que conhecia antes. Eu disse a eles: \u201cVoc\u00eas queriam fechar um CD comigo anos atr\u00e1s. Hoje eu quero, mas cantando m\u00fasicas cat\u00f3licas\u201d. Eles n\u00e3o aceitaram. Ent\u00e3o, fui falar com um produtor da r\u00e1dio, e eles gravaram o CD. Colocamos m\u00fasicas no poema de Santa Teresinha; pela primeira vez, na Fran\u00e7a, t\u00ednhamos um CD crist\u00e3os sendo vendido com milhares de exemplares. Foi uma descoberta e um ensinamento para a Fran\u00e7a a hist\u00f3ria de Santa Teresa do Menino Jesus.<\/p>\n<p>Quero dar a minha vida aos jovens que n\u00e3o creem no Senhor, n\u00e3o O amam nem esperam n&#8217;Ele. Deus colocou essa voca\u00e7\u00e3o no meu cora\u00e7\u00e3o, n\u00e3o como eu imaginei, mas como Ele sonhou.<\/p>\n<p>N\u00f3s crist\u00e3os devemos ter esse olhar de miseric\u00f3rdia para com os outros. Na Fran\u00e7a, esquecemos de falar para o outro que n\u00f3s o amamos. Precisamos olhar para ele com o olhar e o amor de Jesus. Eu sou impactado com a f\u00e9 do Brasil. Gostaria de chegar na Fran\u00e7a e comunicar a alegria que voc\u00eas t\u00eam aqui.<\/p>\n<p><em>Transcri\u00e7\u00e3o e adapta\u00e7\u00e3o: Jakeline Megda D&#8217;Onofrio.<\/em><\/p>\n<p><strong>Adquira esta prega\u00e7\u00e3o pelo telefone: (12) 3186-2600<\/strong><\/p>\n<p><a href=\"http:\/\/clube.cancaonova.com\/cartao-de-credito\/\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-29616 aligncenter\" src=\"http:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2015\/09\/contribuicaocn1.jpg\" alt=\"contribuicaocn1\" width=\"300\" height=\"72\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Enquanto eu quis ganhar a vida, fui vendo-a ser desvalorizada Estou feliz por estar aqui pela segunda vez. Passei pela cidade de S\u00e3o Paulo e vi coisas extraordin\u00e1rias l\u00e1! Visitei lugares onde havia uma extrema pobreza, mas tamb\u00e9m as mais&#8230;<\/p>\n","protected":false},"author":116,"featured_media":30343,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7],"tags":[],"modified_by":"michelle","_links":{"self":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/30335"}],"collection":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/users\/116"}],"replies":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/comments?post=30335"}],"version-history":[{"count":8,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/30335\/revisions"}],"predecessor-version":[{"id":30347,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/30335\/revisions\/30347"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media\/30343"}],"wp:attachment":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media?parent=30335"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/categories?post=30335"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/tags?post=30335"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}