{"id":3119,"date":"2012-04-07T06:15:00","date_gmt":"2012-04-07T09:15:00","guid":{"rendered":"http:\/\/admin-canais.cancaonova.com\/eventos\/?p=3119"},"modified":"2021-03-01T11:56:50","modified_gmt":"2021-03-01T14:56:50","slug":"deus-esta-comigo-nao-vacilarei","status":"publish","type":"post","link":"https:\/\/admin-canais.cancaonova.com\/eventos\/acampamento-semana-santa\/pregacoes\/deus-esta-comigo-nao-vacilarei\/","title":{"rendered":"Deus est\u00e1 comigo, n\u00e3o vacilarei!"},"content":{"rendered":"<p>A paz de Jesus! Que o Senhor nos aben\u00e7oe neste dia! Feliz Semana Santa para voc\u00ea!<\/p>\n<p>Jesus passou a vida junto aos Seus amigos, e estes escreveram parte das Sagradas Escrituras, como os Evangelhos. Na Palavra encontramos aquilo que o Senhor gostava de fazer, as pessoas a quem Ele mais amava. Por isso com a morte do Senhor todos eles [amigos d&#8217;Ele] sofreram muito, pois tinham perdido algu\u00e9m muito pr\u00f3ximo. Somente quem perde algu\u00e9m muito querido sabe a dor dos amigos de Jesus Cristo.<\/p>\n<p>Encontramos tamb\u00e9m um relato bonito daquela disc\u00edpula que foi at\u00e9 o sepulcro de Jesus, e l\u00e1 o Senhor perguntou a ela: \u201cMulher por que choras?\u201d Hoje Cristo Ressuscitado nos pergunta por que estamos nos lamentando? Por que estamos chorando? Enquanto estivermos nos lamentando nos fecharemos \u00e0 gra\u00e7a de Deus. Nossa vis\u00e3o de vida \u00e9 limitada, in\u00fameras vezes nos fechamos \u00e0 gra\u00e7a de Deus porque n\u00e3o temos o pleno conhecimento da vontade d&#8217;Ele e ficamos nos queixando das desgra\u00e7as que nos aconteceram e nos esquecemos de viver, de seguir e nos abandonar, com f\u00e9, aos planos de Deus.<\/p>\n<p><strong>N\u00f3s crist\u00e3os somos diferentes dos homens do mundo em virtude da nossa f\u00e9, pois esta nos faz ver Jesus diante de n\u00f3s. Em Atos dos Ap\u00f3stolos 2, 25-28 encontramos o seguinte relato: \u201cEu via sempre o Senhor diante de mim, porque est\u00e1 \u00e0 minha direita, para que eu n\u00e3o vacile. Por isso alegrou-se meu cora\u00e7\u00e3o e exultou minha l\u00edngua, mais ainda, minha carne repousar\u00e1 na esperan\u00e7a. N\u00e3o abandonar\u00e1s minha alma no reino da morte nem deixar\u00e1s o teu Santo conhecer a decomposi\u00e7\u00e3o. Deste-me a conhecer caminhos de vida e me encher\u00e1s de alegria com a tua presen\u00e7a.\u201d<\/strong><\/p>\n<p>Se o Senhor Jesus nos encontrasse como foi ao encontro daquela mulher e nos perguntasse: \u201cPor que choras?\u201d O que ir\u00edamos responder ao Senhor? Poder\u00edamos at\u00e9 mesmo Lhe contar sobre todos os nossos motivos para chorar, por\u00e9m, nossa resposta est\u00e1 nesta passagem dos Atos dos Ap\u00f3stolos, pois nosso cora\u00e7\u00e3o se alegra porque temos Cristo diante de n\u00f3s, por isso n\u00e3o nos desviamos, n\u00e3o ficamos nos lamentando, uma vez que Jesus \u00e9 a nossa alegria, por meio da f\u00e9.<\/p>\n<p>A f\u00e9 \u00e9, portanto, colocarmos os olhos no Senhor em todas as situa\u00e7\u00f5es da nossa vida, pois Ele est\u00e1 presente em todos os momentos, mesmo nos mais dif\u00edceis, tudo est\u00e1 descoberto diante de Deus. E como \u00e9 duro tomarmos decis\u00f5es quando n\u00e3o temos a certeza por onde caminhar! A passagem b\u00edblica citada acima nos ensina a resposta, para caminharmos, mesmo diante da falta de certeza: \u00e9 necess\u00e1rio termos o Senhor diante de n\u00f3s, n&#8217;Ele vamos caminhar na luz, mesmo diante das incertezas da vida.<\/p>\n<p>A f\u00e9 n\u00e3o nos ilude, ela nos leva a ver a verdade, mesmo que esta esteja escondida sob os olhos da carne. As coisas mais importantes da vida est\u00e3o escondidas aos olhos da carne, n\u00e3o conseguimos enxerg\u00e1-las com esses olhos. O essencial \u00e9 invis\u00edvel aos nossos olhos. O essencial \u00e9 que Jesus Cristo est\u00e1 conosco para n\u00e3o vacilarmos! Por isso n\u00e3o devemos nos apegar a ningu\u00e9m, a n\u00e3o ser a Deus, pois quando nos apegamos ao outro e nos decepcionamos corremos o risco de abandon\u00e1-lo, mas Jesus jamais nos decepcionar\u00e1, Ele \u00e9 o essencial e caminha conosco, portanto, devemos nos apegar somente a Ele.<\/p>\n<p>Sempre vamos viver momentos de tristeza e de frustra\u00e7\u00e3o, com Jesus e sem Jesus, mas quando nos apegamos verdadeiramente a Ele temos a certeza de que n\u00e3o estamos s\u00f3s, que sempre o Senhor caminhar\u00e1 conosco. H\u00e1 gente que quer converter o outro dizendo que se este estiver com Jesus, ele n\u00e3o vai viver dificuldades. No entanto, isso n\u00e3o \u00e9 verdade, sempre vamos viver momentos dif\u00edceis. A diferen\u00e7a \u00e9 que, quando confiamos no Senhor, nada poder\u00e1 nos abalar, pois sabemos que Ele est\u00e1 \u00e0 nossa frente, \u00e0 nossa direita, \u00e0 nossa esquerda, e temos a certeza de que n\u00e3o estamos s\u00f3s.<\/p>\n<p><strong>Quando falta confian\u00e7a ao cora\u00e7\u00e3o de algu\u00e9m o desespero entra. O que nos faz descansar \u00e9 a certeza de que o Senhor n\u00e3o vai nos abandonar. E este \u00e9 o melhor rem\u00e9dio para vivermos bem: confiar em Deus e viver na f\u00e9 cada momento da nossa vida! O Todo-poderosos quer renovar em voc\u00ea a confian\u00e7a n&#8217;Ele, a certeza de que o c\u00e9u existe, que somos amparados pela Miseric\u00f3rdia de Deus em todos os momentos. Desta forma, a vontade de Deus, a confian\u00e7a n&#8217;Ele, est\u00e1 \u00e0 nossa frente em todos os momentos em que nos abandonamos em Seu amor. <\/strong><\/p>\n<p>Tenha a certeza de que Deus ama voc\u00ea!<strong>\u00a0<\/strong><\/p>\n<p><span style=\"color: #000000\">Creia que Ele tem o melhor para n\u00f3s, tenha f\u00e9 em caminhar com Jesus Cristo, abra-se inteiramente \u00e0 vontade Ele, pois o Senhor pode nos livrar de todo o mal, e mesmo que sejamos tentados, se tivermos uma f\u00e9 sincera e honesta, encontraremos a felicidade no seguimento ao Senhor, mesmo diante das dificuldades.<\/span><\/p>\n<p>Quando uma pessoa confia inteiramente em Deus o Esp\u00edrito Santo lan\u00e7a para fora todo o mal, tristeza, confus\u00e3o de sua vida, pois quem cr\u00ea em Jesus Cristo sabe que o Senhor tem o melhor para ele. Por isso a nossa salva\u00e7\u00e3o passa pela f\u00e9 sincera e esta nos liberta de todo o mal. Este \u00e9 o maior exorcismo que podemos levar para a nossa casa, pois onde h\u00e1 f\u00e9 n\u00e3o existe a possibilidade da a\u00e7\u00e3o do inimigo de Deus.<\/p>\n<p>A f\u00e9 \u00e9, portanto, colocarmos os olhos no Senhor em todas as situa\u00e7\u00f5es da nossa vida, pois Ele est\u00e1 presente em todos os momentos, mesmo naqueles mais dif\u00edceis, tudo est\u00e1 descoberto diante de Deus. E como \u00e9 duro tomarmos decis\u00f5es quando n\u00e3o temos a certeza por onde caminhar. A Palavra citada acima nos ensina a resposta, para caminharmos, mesmo diante da falta de certeza, \u00e9 necess\u00e1rio termos o Senhor diante de n\u00f3s. N&#8217;Ele vamos caminhar na luz, mesmo diante das incertezas da vida.<\/p>\n<p>Quem tem f\u00e9 n\u00e3o se envergonha de anunciar e testemunhar que pertence a Deus. Ent\u00e3o se abra \u00e0 f\u00e9, assuma em sua vida a vontade de Deus, pois ela \u00e9 eterna, mesmo que voc\u00ea tenha falhado, n\u00e3o tema em assumir a sua f\u00e9, o Senhor d\u00e1 mais for\u00e7as para quem erra mais. Saiba que todo o seu passado foi perdoado na cruz de Jesus.<br \/>\n<strong><br \/>\nCreia que Jesus ressuscitou e vai ressuscitar voc\u00ea. Tenha f\u00e9, reze, se abra \u00e0 ora\u00e7\u00e3o, pois para quem reza o Senhor pode mudar toda situa\u00e7\u00e3o. Aquele que ressuscitou L\u00e1zaro pode dar uma vida nova para voc\u00ea. Confie no Senhor apesar de tudo, n\u00e3o fique chorando o que j\u00e1 passou. Sempre haver\u00e1 situa\u00e7\u00f5es que querem nos fazer passar a vida chorando, por\u00e9m, quem acredita sabe que o Senhor o ama e tem o melhor para ele.<\/strong> Portanto, tenha f\u00e9 no Senhor e confie que n&#8217;Ele jamais vacilaremos, o Senhor nos ama e quer que caminhemos com Ele at\u00e9 o fim!<\/p>\n<p>Deus nos aben\u00e7oe!<\/p>\n<p><span style=\"color: #000000\"><em>Transcri\u00e7\u00e3o e adapta\u00e7\u00e3o: Ricardo Gaiotti<\/em><br \/>\n<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A paz de Jesus! Que o Senhor nos aben\u00e7oe neste dia! Feliz Semana Santa para voc\u00ea! Jesus passou a vida junto aos Seus amigos, e estes escreveram parte das Sagradas Escrituras, como os Evangelhos. Na Palavra encontramos aquilo que o&#8230;<\/p>\n","protected":false},"author":114,"featured_media":56505,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7],"tags":[],"modified_by":"aliane","_links":{"self":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/3119"}],"collection":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/users\/114"}],"replies":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/comments?post=3119"}],"version-history":[{"count":3,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/3119\/revisions"}],"predecessor-version":[{"id":59569,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/3119\/revisions\/59569"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media\/56505"}],"wp:attachment":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media?parent=3119"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/categories?post=3119"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/tags?post=3119"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}