{"id":34149,"date":"2016-04-14T11:10:34","date_gmt":"2016-04-14T14:10:34","guid":{"rendered":"http:\/\/admin-canais.cancaonova.com\/eventos\/?p=34149"},"modified":"2021-03-11T15:14:51","modified_gmt":"2021-03-11T18:14:51","slug":"consolados-possamos-consolar-os-que-se-acham-em-aflicao","status":"publish","type":"post","link":"https:\/\/admin-canais.cancaonova.com\/eventos\/quinta---feira-de-adoracao\/pregacoes\/consolados-possamos-consolar-os-que-se-acham-em-aflicao\/","title":{"rendered":"Consolados, possamos consolar os que se acham em afli\u00e7\u00e3o"},"content":{"rendered":"<h2>Deus nos consola para que possamos consolar os outros<\/h2>\n<div id=\"attachment_34153\" style=\"width: 255px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-34153\" class=\"size-medium wp-image-34153\" src=\"http:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2016\/04\/Prof.Felipe-Aquino-269x329-245x300.jpg\" alt=\"Prof. Felipe Aquino. Foto: Daniel Mafra\/cancaonova.com\" width=\"245\" height=\"300\" srcset=\"https:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2016\/04\/Prof.Felipe-Aquino-269x329-245x300.jpg 245w, https:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2016\/04\/Prof.Felipe-Aquino-269x329.jpg 269w\" sizes=\"(max-width: 245px) 100vw, 245px\" \/><p id=\"caption-attachment-34153\" class=\"wp-caption-text\">Prof. Felipe Aquino. Foto: Daniel Mafra\/cancaonova.com<\/p><\/div>\n<p>Estamos num momento muito importante para nosso pa\u00eds, por isso precisamos nos lembrar de que, por volta de 1930, o ent\u00e3o Cardeal do Rio de Janeiro, Dom Sebasti\u00e3o Leme, e tamb\u00e9m o Presidente da Rep\u00fablica do Brasil, na \u00e9poca, consagraram o pa\u00eds a Nossa Senhora Aparecida.<\/p>\n<p>\u00c9 importante lembrarmos que \u201co que ligarmos na terra ser\u00e1 ligado tamb\u00e9m no c\u00e9u\u201d, ent\u00e3o, que Nossa Senhora fa\u00e7a, neste tempo, o melhor para o Brasil! Nosso pa\u00eds \u00e9 a terra de Santa Cruz.<\/p>\n<p>Os portugueses eram muito religiosos, por isso mandaram 17 sacerdotes na expedi\u00e7\u00e3o que descobriu essas terras. Este pa\u00eds nasceu sob o signo da cruz. Terra da cruz, terra de Cristo, terra de Deus. Que cada brasileiro consagre o Brasil a Nossa Senhora Aparecida.<\/p>\n<h3><strong>Consolados para levar consola\u00e7\u00e3o<\/strong><\/h3>\n<p>A Palavra para esta prega\u00e7\u00e3o \u00e9: <em>&#8220;Bendito seja o Deus e Pai de nosso Senhor Jesus Cristo, o Pai das miseric\u00f3rdias e Deus de toda consola\u00e7\u00e3o. Ele nos consola em todas as nossas afli\u00e7\u00f5es, para que, com a consola\u00e7\u00e3o que n\u00f3s mesmos recebemos de Deus, possamos consolar os que se acham em toda e qualquer afli\u00e7\u00e3o.<br \/>\nPois, \u00e0 medida que os sofrimentos de Cristo crescem para n\u00f3s, cresce tamb\u00e9m a nossa consola\u00e7\u00e3o por Cristo.<br \/>\nSe passamos por afli\u00e7\u00f5es, \u00e9 para vossa consola\u00e7\u00e3o e salva\u00e7\u00e3o; se somos consolados, \u00e9 para vossa consola\u00e7\u00e3o. E essa consola\u00e7\u00e3o sustenta vossa const\u00e2ncia em meio aos mesmos sofrimentos que n\u00f3s tamb\u00e9m padecemos&#8221;<\/em> (II Cor 1,3-6).<\/p>\n<p>Deus nos consola para que consolemos os outros. Essa \u00e9 a palavra prof\u00e9tica para o dia de hoje.<\/p>\n<p>A consola\u00e7\u00e3o \u00e9 para nossa santifica\u00e7\u00e3o! At\u00e9 Jesus, em Sua via crucis, quis ser consolado. Nossa Senhora veio ao encontro d\u2019Ele, que passou por todo sofrimento poss\u00edvel, tanto no corpo quanto na alma. Mas por qu\u00ea? Porque Ele iria tirar todo pecado da humanidade, por isso sofreu no corpo e na alma.<\/p>\n<p>N\u00e3o sabemos o que Maria e Jesus conversaram, mas sabemos que eles trocaram olhares. Era como se Jesus dissesse a ela: \u201cMinha M\u00e3e, vamos comigo! Vamos salvar a humanidade, vamos at\u00e9 o fim!\u201d.<\/p>\n<h3><strong>Temos tamb\u00e9m a Virgem das Dores para nos consolar<\/strong><\/h3>\n<p>Ningu\u00e9m sofreu como a Virgem Maria. Foi-lhe dito que uma espada transpassaria sua alma. Acho que essa espada ficou na cabe\u00e7a dela a vida inteira&#8230;<\/p>\n<p>Quando Jesus nasceu, quando estava com 40 dias de vida, Jos\u00e9 e Maria tiveram de atravessar o deserto com Ele, um ambiente in\u00f3spito. Quando Ele se perde no templo, podemos imaginar a ang\u00fastia que sua M\u00e3e sentiu! Imagine a M\u00e3e perder Aquele que era o Filho de Deus! \u201cEst\u00e1vamos aflitos \u00e0 Sua procura\u201d, disse Maria ao Menino. Por essa afli\u00e7\u00e3o que experimentou, Nossa Senhora, agora, \u00e9 capaz de nos consolar tamb\u00e9m em nossas dores.<\/p>\n<p>Que dor ela sente quando encontra seu Filho no Calv\u00e1rio! Quando ela O v\u00ea morrendo de dor, pregado no madeiro! Os santos dizem que se n\u00e3o fosse uma gra\u00e7a especial, ela teria morrido de desgosto.<\/p>\n<p>Jo\u00e3o usa a express\u00e3o \u201cde p\u00e9 diante da cruz\u201d, querendo significar que ela sabia o porqu\u00ea de tudo aquilo. Maria oferece suas dores em favor da humanidade, ela oferece a Deus sua dor em nosso favor.<\/p>\n<h3><strong>As dores da M\u00e3e da Consola\u00e7\u00e3o<\/strong><\/h3>\n<p>A outra dor de maria foi receber o corpo de Jesus, todo destru\u00eddo! Imagine uma m\u00e3e ver seu filho morto e esfacelado. Sua \u00faltima dor foi sepultar seu Filho \u00e0s pressas, enterr\u00e1-Lo \u00e0s pressas, pois nenhum corpo poderia ficar na cruz. No domingo, de madrugada, as mulheres foram \u00e0 sepultura. Para qu\u00ea? Para terminar o que n\u00e3o deu tempo de fazer no dia anterior, que n\u00e3o poderia se fazer na sexta-feira.<\/p>\n<p>N\u00e3o h\u00e1 dor que voc\u00ea possa passar nessa vida que Nossa Senhora j\u00e1 n\u00e3o tenha passado! Jesus \u00e9 o Homem das dores; Maria, a mulher das dores. Jesus desatou o n\u00f3 da desobedi\u00eancia de Ad\u00e3o; Maria desatou o n\u00f3 da desobedi\u00eancia de Eva.<\/p>\n<p>Para consolar os outros, n\u00f3s precisamos ser consolados. Por que existe sofrimento? A \u00fanica institui\u00e7\u00e3o que explica o sofrimento de forma coerente \u00e9 a Igreja. Toda l\u00e1grima que existe no mundo \u00e9 consequ\u00eancia do pecado. N\u00e3o s\u00f3 o meu pecado, mas o de toda a humanidade.<\/p>\n<div id=\"attachment_34155\" style=\"width: 605px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-34155\" class=\"wp-image-34155 size-large\" src=\"http:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2016\/04\/Prof.Felipe-Aquino-595x420-595x300.jpg\" alt=\"Peregrinos participam da Quinta-feira de Adora\u00e7\u00e3o na Can\u00e7\u00e3o Nova. Foto: Daniel Mafra\/cancaonova.com\" width=\"595\" height=\"300\" srcset=\"https:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2016\/04\/Prof.Felipe-Aquino-595x420-595x300.jpg 595w, https:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2016\/04\/Prof.Felipe-Aquino-595x420-300x150.jpg 300w, https:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2016\/04\/Prof.Felipe-Aquino-595x420-150x75.jpg 150w\" sizes=\"(max-width: 595px) 100vw, 595px\" \/><p id=\"caption-attachment-34155\" class=\"wp-caption-text\">Peregrinos participam da Quinta-feira de Adora\u00e7\u00e3o na Can\u00e7\u00e3o Nova. Foto: Daniel Mafra\/cancaonova.com<\/p><\/div>\n<h3><strong>A miseric\u00f3rdia supre a justi\u00e7a, mas n\u00e3o a apaga<br \/>\n<\/strong><\/h3>\n<p>A nossa salva\u00e7\u00e3o custou a morte de Deus. Ele, como verbo eterno, n\u00e3o poderia morrer; ent\u00e3o, assumiu a natureza humana para que pudesse sofrer e morrer.<\/p>\n<p>A miseric\u00f3rdia supre a justi\u00e7a divina, mas n\u00e3o a apaga. Deus \u00e9 misericordioso, mas \u00e9 justo.<\/p>\n<p>Imagine algu\u00e9m que deve um dinheiro a voc\u00ea: existe uma consequ\u00eancia nisso. Mas voc\u00ea diz: \u201cN\u00e3o precisa me pagar!\u201d. A justi\u00e7a diz que essa pessoa precisa lhe pagar, mas voc\u00ea decide assume o preju\u00edzo. Jesus disse: \u201cEu assumo, eu morrerei no lugar deles\u201d. O Senhor pagou o pre\u00e7o do nosso perd\u00e3o.<\/p>\n<p>Deus nos consola para consolarmos os outros. Jesus foi consolado por Sua M\u00e3e, foi consolado tamb\u00e9m pelo cirineu. O Senhor passou por uma noite terr\u00edvel de tortura, depois foi flagelado. Ele suava sangue de tanta agonia! Foi jogado num calabou\u00e7o. Ele n\u00e3o tinha mais for\u00e7a. E o que Deus diz sobre isso: \u201cVoc\u00ea ser\u00e1 consolado por um cirineu\u201d.<\/p>\n<p>Jesus foi consolado pelas mulheres, por Maria de Cl\u00e9ofas. E Ele as consolou. Jesus, mesmo sofrendo, consola os outros. \u00c9 Deus dizendo que, quando tiramos o olhar da nossa ang\u00fastia, esquecemos um pouco da nossa dor e assim ela fica suport\u00e1vel.<\/p>\n<h3><strong>O bem, a santidade faz um mundo melhor<\/strong><\/h3>\n<p>Ouvi o testemunho de uma mo\u00e7a que tinha uma depress\u00e3o profunda. Ela disse a si mesma: \u201cVou fazer caridade\u201d. Ela Ia a um asilo e dava banho nos velhinhos. Essa mo\u00e7a se curou e disse: \u201cNunca mais paro de fazer caridade\u201d.<\/p>\n<p>Conheci um garotinho que, um dia, caiu e se machucou, mas ningu\u00e9m ligou para ele. Ent\u00e3o, come\u00e7ou a dizer: \u201cA\u00ed que d\u00f3 de mim!\u201d. N\u00f3s adultos fazemos assim tamb\u00e9m: \u201cA\u00ed que d\u00f3 de mim!\u201d. Essa \u00e9 a receita para voc\u00ea duplicar seu sofrimento e entrar numa depress\u00e3o.<\/p>\n<p>Por que o sofrimento entrou no mundo? Deus nos criou para a imortalidade, mas, por inveja, o dem\u00f4nio fez o ser humano pecar e introduziu a morte no mundo.<\/p>\n<p>A pior coisa que existe no mundo \u00e9 o pecado, porque ele gera tristeza. A santidade, ao contr\u00e1rio, gera alegria, diz Santo Agostinho.<\/p>\n<h3><strong>Jesus est\u00e1 conosco sempre<\/strong><\/h3>\n<p>Jesus n\u00e3o veio para fazer milagres, nem para fazer isso ou aquilo, Ele veio para tirar o pecado do mundo. A Igreja \u00e9 a continua\u00e7\u00e3o de Cristo, e ela existe para tirar o pecado do mundo.<\/p>\n<p>A consola\u00e7\u00e3o vem a n\u00f3s tamb\u00e9m quando vivemos a santidade. Deus colocou os sacramentos, colocou a Virgem Maria para nos consolar, mas a busca da santidade tamb\u00e9m nos conduz \u00e0 consola\u00e7\u00e3o.<\/p>\n<p>Jesus disse que estaria conosco todos os dias, em nossas doen\u00e7as e nossos sofrimentos. Ele se identifica com a pessoa que sofre, Ele est\u00e1 na pessoa do sofredor.<\/p>\n<p>Madre Tereza, certa vez, encontrou um sujeito na rua e o levou embora, para cuidar dele. Um dia, ele lhe perguntou: \u201cPor que a senhora est\u00e1 cuidando de mim? Eu estou vendo a cruz na parede, vejo sinais de Jesus em todo lugar, mas eu sou indu, eu n\u00e3o acredito no Cristo\u201d. Ela disse: \u201cEu cuido de voc\u00ea, porque Jesus est\u00e1 em voc\u00ea\u201d.<\/p>\n<p>Porque Jesus est\u00e1 no sacr\u00e1rio? Para que possamos chegar perto d\u2019Ele. Se Ele estivesse s\u00f3 na Sua gl\u00f3ria, seria dif\u00edcil chegarmos at\u00e9 Ele. Ent\u00e3o, Ele se esconde no sacr\u00e1rio, porque, se aparecesse no esplendor da Sua gl\u00f3ria, ter\u00edamos medo d\u2019Ele.<\/p>\n<h3><strong>Deus tira um bem at\u00e9 mesmo do mal<\/strong><\/h3>\n<p>Entendamos que o Senhor permitiu que pec\u00e1ssemos, porque somos livres. Deus nos fez livres para fazermos o bem ou o mal. E quando fazemos o mal, o Senhor o transforma em mat\u00e9ria-prima de salva\u00e7\u00e3o. Ele pega nosso sofrimento e faz dele mat\u00e9ria-prima de salva\u00e7\u00e3o. Por isso, Jesus usa o sofrimento para salvar a humanidade, e n\u00f3s podemos ofertar nossos sofrimentos pela salva\u00e7\u00e3o da humanidade.<\/p>\n<p>O sofrimento tamb\u00e9m \u00e9 para nossa santifica\u00e7\u00e3o. Na carta aos Hebreus, vemos por que Deus permite que passemos por tribula\u00e7\u00f5es. <em>&#8220;j\u00e1 esquecestes as palavras de encorajamento que vos foram dirigidas como a filhos: \u201cMeu filho, n\u00e3o desprezes a corre\u00e7\u00e3o do Senhor, n\u00e3o te desanimes quando ele te repreende; pois o Senhor corrige a quem ele ama e castiga a quem aceita como filho\u201d. \u00c9 para a vossa corre\u00e7\u00e3o que sofreis; \u00e9 como filhos que Deus vos trata. Pois qual \u00e9 o filho a quem o pai n\u00e3o corrige? Pelo contr\u00e1rio, se ficais fora da corre\u00e7\u00e3o aplicada a todos, ent\u00e3o n\u00e3o sois filhos, mas bastardos&#8221;<\/em> (Hb 12, 5-8. O Senhor criou o mundo e estabeleceu leis. Se algu\u00e9m pular de um pr\u00e9dio de 10 andares, vai sofrer a lei da gravidade, mas se Deus tirar a lei da gravidade, acabar\u00e1 o mundo.<\/p>\n<p>Deus n\u00e3o \u00e9 paternalista, Deus \u00e9 pai. Ele castiga todo aquele que se reconhece como filho. Uma doen\u00e7a, \u00e0s vezes, que voc\u00ea sofre; sua empresa que quebra\u2026 Tudo isso n\u00e3o nos \u00e9 permitido por Deus por maldade, mas para nos tirar do inferno. \u201cEstais sofrendo para vossa corre\u00e7\u00e3o\u201d.<\/p>\n<p>Se Deus n\u00e3o nos corrigisse, n\u00e3o nos teria como filhos, mas por bastardos. N\u00e3o tenhamos medo da corre\u00e7\u00e3o nem do sofrimento, porque este arranca de n\u00f3s as ra\u00edzes do pecado, do apego \u00e0 fama, \u00e0 gl\u00f3ria e \u00e0 gula.<\/p>\n<h3><strong>Como sofrer menos?<\/strong><\/h3>\n<p><span style=\"font-weight: 400\">Qual \u00e9 o jeito de sofrer menos? Pecando menos. Qual o filho que tem mais castigo? \u00c9 o filho desobediente. Aquele filho bom, quase n\u00e3o \u00e9 castigado. Mas Jesus foi obediente e sofreu tanto! Foi para expiar as nossas desobedi\u00eancias. <\/span><\/p>\n<p><span style=\"font-weight: 400\">O justo vive pela f\u00e9. Temos de lutar contra o sofrimento, mas, quando o vivemos, temos de dar gl\u00f3ria a Deus por ele. N\u00e3o pelo sofrimento em si, mas pelo bem que sabemos que Deus vai tirar dele. <\/span><\/p>\n<p><span style=\"font-weight: 400\">N\u00e3o \u00e9 f\u00e1cil viver isso! Para mim, que estou pregando isso, tamb\u00e9m n\u00e3o \u00e9 f\u00e1cil. Eu sei disso! Mas pe\u00e7amos a Deus a gra\u00e7a de chegarmos \u00e0 santidade. <\/span><\/p>\n<p><span style=\"font-weight: 400\">Am\u00e9m!<\/span><\/p>\n<p>Transcri\u00e7\u00e3o e adapta\u00e7\u00e3o: Sandro Arquejada<\/p>\n<p><a href=\"http:\/\/clube.cancaonova.com\/\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-30644 aligncenter\" src=\"http:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2015\/11\/contribuicaocn1.jpg\" alt=\"contribuicaocn1\" width=\"300\" height=\"72\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Deus nos consola para que possamos consolar os outros Estamos num momento muito importante para nosso pa\u00eds, por isso precisamos nos lembrar de que, por volta de 1930, o ent\u00e3o Cardeal do Rio de Janeiro, Dom Sebasti\u00e3o Leme, e tamb\u00e9m&#8230;<\/p>\n","protected":false},"author":759,"featured_media":55765,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7],"tags":[],"modified_by":"aliane","_links":{"self":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/34149"}],"collection":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/users\/759"}],"replies":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/comments?post=34149"}],"version-history":[{"count":5,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/34149\/revisions"}],"predecessor-version":[{"id":59720,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/34149\/revisions\/59720"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media\/55765"}],"wp:attachment":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media?parent=34149"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/categories?post=34149"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/tags?post=34149"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}