{"id":4156,"date":"2010-05-30T12:00:00","date_gmt":"2010-05-30T15:00:00","guid":{"rendered":"http:\/\/admin-canais.cancaonova.com\/eventos\/?p=4156"},"modified":"2014-08-13T02:05:13","modified_gmt":"2014-08-13T05:05:13","slug":"a-beleza-da-santissima-trindade","status":"publish","type":"post","link":"https:\/\/admin-canais.cancaonova.com\/eventos\/pregacoes\/a-beleza-da-santissima-trindade\/","title":{"rendered":"A beleza da Sant\u00edssima Trindade"},"content":{"rendered":"<div id=\"foto\" style=\"margin: 0pt auto;padding: 0px 5px;width: 180px;float: left\">\n<div id=\"foto\"><!--ABRE LINK DA FOTO--><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.cancaonova.com\/portal\/arquivos\/fotos\/2010\/maio\/dombeni_3005.jpg\" border=\"0\" width=\"180\" height=\"220\" \/><!--FECHA LINK DA FOTO--><\/div>\n<div id=\"texto\"><!--TEXTO DA FOTO-->Dom Beni<!--TEXTO DA FOTO--><\/div>\n<div id=\"credito\"><!--CREDITO DA FOTO-->Foto: V&acirc;nia\/CN<!--CREDITO DA FOTO--><\/div>\n<\/div>\n<p>A Igreja celebra neste domingo a Solenidade Lit&uacute;rgica da Sant&iacute;ssima Trindade. A Sant&iacute;ssima Trindade &eacute; a verdade mais importante registrada no Evangelho. A palavra &quot;Evangelho&quot; significa &quot;Boa Nova&quot;, a Boa Nova mais bela que Jesus anunciou foi a exist&ecirc;ncia da Sant&iacute;ssima Trindade. <\/p>\n<p>  A Trindade &eacute; a revela&ccedil;&atilde;o plena e definitiva de Deus; a revela&ccedil;&atilde;o feita pelas religi&otilde;es e at&eacute; mesmo pelo Antigo Testamento &eacute; sempre uma revela&ccedil;&atilde;o imperfeita, s&oacute; Jesus revelou verdadeiramente quem &eacute; Deus e s&oacute; Ele poderia fazer isso, pelo seguinte motivo: Deus &eacute; o grande mist&eacute;rio, diferente de tudo que existe, portanto, s&oacute; Deus conhece a Deus, s&oacute; Deus poderia dizer, de fato, quem Ele &eacute;.  S&oacute; Jesus revelou inteiramente Deus, s&oacute; Jesus poderia revelar a exist&ecirc;ncia da Sant&iacute;ssima Trindade, pois Ele &eacute; Deus, e foi Jesus, Filho de Deus feito homem, quem nos revelou a verdade plena e definitiva sobre o Todo-poderoso. <\/p>\n<p>  No Evangelho de S&atilde;o Mateus, Cristo diz:<em> &ldquo;Ningu&eacute;m conhece o Filho, sen&atilde;o o Pai, e ningu&eacute;m conhece o Pai, sen&atilde;o o Filho e aquele a quem o Filho o quiser revelar&rdquo;<\/em> (S&atilde;o Mateus 11,27). <\/p>\n<p>  E S&atilde;o Paulo, logo no in&iacute;cio da primeira Carta aos Cor&iacute;ntios, afirma que o Esp&iacute;rito Santo perscruta as profundezas de Deus; em outras palavras, s&oacute; Deus conhece a Deus. Jesus nos revelou a exist&ecirc;ncia da Sant&iacute;ssima Trindade, antes de tudo pela Sua vida, por aquela intimidade &uacute;nica e pelo relacionamento pessoal e essencial que Ele tinha com o Pai. <\/p>\n<p>  O Evangelho, prezados irm&atilde;os, registra diversas ora&ccedil;&otilde;es de Jesus, todas elas muito belas; recordemos aquele louvor e agradecimento que Nosso Senhor Jesus Cristo fez ao Pai, pelo sucesso da miss&atilde;o dos disc&iacute;pulos, diz o Evangelho que Ele fez esta ora&ccedil;&atilde;o exultando de alegria no Esp&iacute;rito Santo: <em>&ldquo;Eu te louvo, Pai, Senhor do c&eacute;u e da terra, porque escondeste estas coisas aos s&aacute;bios e entendidos e as revelaste aos pequeninos&rdquo; <\/em>(S&atilde;o Mateus 11,25).  Bel&iacute;ssima e comovente tamb&eacute;m &eacute; a ora&ccedil;&atilde;o que Cristo fez diante do t&uacute;mulo do seu amigo L&aacute;zaro, mas, sem d&uacute;vida, a ora&ccedil;&atilde;o mais bela do Senhor, que n&oacute;s encontramos no Evangelho, &eacute; a ora&ccedil;&atilde;o do Pai-Nosso. <\/p>\n<p>  Todas as ora&ccedil;&otilde;es de Jesus que se encontram no Evangelho, menos uma, come&ccedil;am sempre com a palavra: &quot;Abba&quot;, um voc&aacute;bulo da l&iacute;ngua aramaica, a l&iacute;ngua de Jesus que n&oacute;s traduzimos por: &quot;Pai&quot;, &quot;Pai querido&quot;, &quot;Papai&quot;. &Eacute; dif&iacute;cil traduzir esse voc&aacute;bulo [Abba], pois Ele expressa a intimidade profunda e &uacute;nica que Jesus tinha com o Pai. <\/p>\n<p>  Joaquim Jeremias, um grande conhecedor da Sagrada Escritura, fez uma pesquisa nas ora&ccedil;&otilde;es recitadas pelos judeus no tempo de Cristo e, em nenhuma ora&ccedil;&atilde;o judaica, ele encontrou a palavra &quot;Abba&quot;. Portanto, foi um voc&aacute;bulo usado s&oacute; por Jesus, o que expressa a consci&ecirc;ncia que Ele tinha da Sua filia&ccedil;&atilde;o divina. A rela&ccedil;&atilde;o &iacute;ntima de Cristo com Esp&iacute;rito Santo. <\/p>\n<div id=\"foto\" style=\"margin: 0pt auto;padding: 0px;width: 370px;float: none\">\n<div id=\"foto\"><!--ABRE LINK DA FOTO--><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.cancaonova.com\/portal\/arquivos\/fotos\/2010\/maio\/dombeni_300510.jpg\" border=\"0\" width=\"370\" height=\"250\" \/><!--FECHA LINK DA FOTO--><\/div>\n<div id=\"texto\"><!--TEXTO DA FOTO-->Dom Beni preside Santa Missa na Can&ccedil;&atilde;o Nova<!--TEXTO DA FOTO--><\/div>\n<div id=\"credito\"><!--CREDITO DA FOTO-->Foto: V&acirc;nia\/CN<!--CREDITO DA FOTO--><\/div>\n<\/div>\n<p>  Afirma o Evangelho que de Jesus sa&iacute;a uma for&ccedil;a que curava a todos, essa for&ccedil;a que sa&iacute;a do Senhor operava ao redor &#039;Ele e realizava maravilhas, expressa o Esp&iacute;rito Santo. O Esp&iacute;rito Santo &eacute; chamado no Evangelho &ldquo;dedo de Deus&rdquo;, isto &eacute;, de for&ccedil;a de Deus, e quando Jesus prometeu pela &uacute;ltima vez aos disc&iacute;pulos o dom do Esp&iacute;rito Santo, Ele disse: &quot;Recebereis uma for&ccedil;a que vem do alto&quot;. <\/p>\n<p>  Irm&atilde;os e irm&atilde;s, Nosso Senhor Jesus Cristo &eacute; diferente de todos os carism&aacute;ticos. Os carism&aacute;ticos, inclusive a Igreja, invocam o Esp&iacute;rito Santo para que Ele des&ccedil;a do alto e penetre os cora&ccedil;&otilde;es, Jesus n&atilde;o invoca o Esp&iacute;rito Santo para que Ele des&ccedil;a do alto, Jesus &eacute; o &uacute;nico que doa o Esp&iacute;rito Santo, porque o Esp&iacute;rito Santo est&aacute; presente n&#039;Ele, &eacute; tamanha a comunh&atilde;o entre as Pessoas Divinas que uma est&aacute; presente na outra, sem se confundir. <\/p>\n<p>  Na tarde do Domingo da Ressurrei&ccedil;&atilde;o, Jesus Cristo apareceu aos Seus disc&iacute;pulos, para lhes dar um grande presente pascal: soprou sobre eles e disse: <em>&ldquo;Recebei o Esp&iacute;rito Santo&rdquo;<\/em> (cf. S&atilde;o Jo&atilde;o 20,22). Portanto, o Ressuscitado doa o Esp&iacute;rito Santo que sai d&rsquo;Ele para se comunicar aos outros. Mas Cristo revelou a exist&ecirc;ncia da Sant&iacute;ssima Trindade n&atilde;o s&oacute; por Sua experi&ecirc;ncia com o Pai e com o Esp&iacute;rito Santo, mas Ele tamb&eacute;m revelou a Sant&iacute;ssima Trindade por palavras, os Evangelhos registram diversas refer&ecirc;ncias do Senhor sobre a exist&ecirc;ncia da Sant&iacute;ssima Trindade. <\/p>\n<p>  As tr&ecirc;s Pessoas Divinas possuem tudo em comum, possuem a mesma eternidade, a mesma beleza, o mesmo poder, a mesma natureza, a mesma ess&ecirc;ncia. Na segunda leitura ouvimos um trecho da Carta aos Romanos, na qual S&atilde;o Paulo se refere &agrave; atua&ccedil;&atilde;o de cada Pessoa Divina na Obra da Salva&ccedil;&atilde;o, diz ele que n&oacute;s estamos em paz com Deus Pai, estamos reconciliados com Deus Pai pelo Mist&eacute;rio Pascal de Cristo, por meio de Sua Morte e Ressurrei&ccedil;&atilde;o. Cristo, a segunda Pessoa da Trindade, &eacute; nosso mediador, diz S&atilde;o Paulo, e a seguir ele fala do papel do Esp&iacute;rito Santo na Obra da Salva&ccedil;&atilde;o. <\/p>\n<p>  O amor de Deus Pai &eacute; derramado em nossos cora&ccedil;&otilde;es pelo Esp&iacute;rito Santo, que nos &eacute; dado, este amor n&atilde;o &eacute; um amor qualquer, &eacute; o amor pascal de Cristo, &eacute; o amor capaz de sofrer e dar a vida pelo pr&oacute;ximo, &eacute; aquele amor cheio de esperan&ccedil;a. <strong>Quem ama como Cristo, jamais considera o outro como um caso perdido, ainda que o outro seja escravo da droga, seja escravo do alcoolismo, esteja mergulhado na maldade, sempre &eacute; poss&iacute;vel &ndash; pela a&ccedil;&atilde;o do Esp&iacute;rito Santo &ndash; nascer de novo, ressuscitar, recome&ccedil;ar. <\/strong>Este amor n&atilde;o nasce de baixo, ele vem do alto: &eacute; o Esp&iacute;rito Santo que o infunde em nossos cora&ccedil;&otilde;es, &eacute; Ele quem nos d&aacute; a gra&ccedil;a de amar como Jesus amou. <\/p>\n<p>  Embora a exist&ecirc;ncia da Sant&iacute;ssima Trindade seja a maior e a mais importante Boa Nova que Jesus anunciou, a exist&ecirc;ncia da Trindade Sant&iacute;ssima j&aacute; foi prefigurada de modo misterioso no Antigo Testamento. Na primeira leitura, ouvimos o trecho do Livro dos Prov&eacute;rbios que nos mostra a obra de Deus Criador: o mundo, o seres humanos, a plantas, os animais, e assim por diante, e o texto afirma que Deus Pai criou tudo pela sabedoria, que est&aacute; junto d&rsquo;Ele desde toda a eternidade. Esta sabedoria &eacute; a prefigura&ccedil;&atilde;o da Pessoa do Filho, revelado no Novo Testamento, porque Deus criou tudo pela Sua Palavra, que &eacute; o Filho, mas esta sabedoria de que fala o Livro dos Prov&eacute;rbios prefigura tamb&eacute;m o Esp&iacute;rito Santo, revelado no Novo Testamento. Diz a Sagrada Escritura no Livro do G&ecirc;nesis, que o Esp&iacute;rito Santo, &eacute; semelhante a uma grande ave que pairava nas alturas. Deus criou tudo pelo Seu Filho e tornou tudo belo pela a&ccedil;&atilde;o do Esp&iacute;rito Santo, que &eacute; a beleza da Sant&iacute;ssima Trindade. <\/p>\n<p>  Irm&atilde;os e irm&atilde;s, a Trindade revelada por Jesus no Novo Testamento, significa que Deus n&atilde;o &eacute; um ser isolado, distante, fechado em si mesmo, Trindade significa que Deus &eacute; uma comunh&atilde;o de tr&ecirc;s pessoas: Pai, Filho e Esp&iacute;rito Santo. Trindade significa que as tr&ecirc;s Pessoas Divinas est&atilde;o de tal modo, unidas pela comunh&atilde;o, pelo amor, que n&atilde;o formam tr&ecirc;s deuses, formam um &uacute;nico Deus, n&atilde;o existe uma comunidade mais profunda, mais perfeita do que esta. <\/p>\n<p>  Deus, que &eacute; uma comunh&atilde;o de tr&ecirc;s Pessoas Divinas, criou o ser humano a sua imagem e semelhan&ccedil;a, isto significa que Deus nos criou para vivermos em comunh&atilde;o na fam&iacute;lia, na comunidade, na sociedade. <\/p>\n<p>  O jovem, sobretudo, percebe que existe nele, uma tend&ecirc;ncia profunda para a amizade,  para unir sua vida a vida de outra pessoa, para realizar o matrim&ocirc;nio, fundar uma fam&iacute;lia. Ora, tudo isto, &eacute; uma demonstra&ccedil;&atilde;o que Deus nos criou para a comunh&atilde;o em suas variadas formas. <\/p>\n<p>  Prezados jovens, cada um de voc&ecirc;s, portanto, devem combater o isolamento, o fechamento em si mesmos, combater o ego&iacute;smo e a viol&ecirc;ncia, nada disso traz felicidade. A &uacute;nica coisa que traz felicidade &eacute; a comunh&atilde;o, pois o ser humano foi criado &agrave; semelhan&ccedil;a da comunh&atilde;o das tr&ecirc;s Pessoas Divinas, Pai, Filho e Esp&iacute;rito Santo. <\/p>\n<p>  Deus, de fato, &eacute; o fundamento do universo, o nosso querido Papa Bento XVI, referindo-se ao esfor&ccedil;o da ci&ecirc;ncia para explicar a cria&ccedil;&atilde;o do universo, afirma: &ldquo;Sem Deus as contas n&atilde;o fecham; sem Deus n&atilde;o existe uma resposta definitiva para a origem do universo&rdquo;. O Alt&iacute;ssimo &eacute; o fundamento mais profundo da &eacute;tica, da moral, da reta conduta e quando o nosso relacionamento com o fundamento, que &eacute; Deus, n&atilde;o &eacute; correto, tamb&eacute;m n&atilde;o &eacute; correto o nosso relacionamento com as coisas, com a natureza, com as pessoas, visto que o Senhor &eacute; o fundamento da nossa vida. <\/p>\n<p>  Hoje n&oacute;s presenciamos na sociedade tanta viol&ecirc;ncia e isso &eacute; sinal de vida sem fundamento, de vida sem Deus. E como fazer de Deus o fundamento da nossa vida?   A resposta &eacute; observar os Dez Mandamentos, que regulam de modo perfeito o nosso relacionamento com Deus, com as coisas, com as pessoas, por isso, procurar a felicidade fora dos Mandamentos do Senhor &eacute; cair na ilus&atilde;o, &eacute; procurar a felicidade onde ela n&atilde;o est&aacute;, &eacute; repetir o gesto do filho pr&oacute;digo, de que fala o Evangelho, tamb&eacute;m de um jovem que virou as costas ao pai, que tapou os ouvidos aos Seus Mandamentos, e procurou a felicidade no dinheiro, na sexualidade desenfreada, e no final de tudo tornou-se escravo das suas paix&otilde;es e acabou tornando-se escravo de outras pessoas. <\/p>\n<p>  Por isso, quando n&oacute;s obedecemos aos Mandamentos de Deus, estamos fazendo de Deus o fundamento de nossa vida individual e comunit&aacute;ria. <\/p>\n<p>  Deus, que &eacute; uma Trindade de Pessoas, criou o ser humano &agrave; Sua imagem e semelhan&ccedil;a, para viver em comunh&atilde;o com as coisas, com a natureza, para viver em comunh&atilde;o com o seu semelhante, mas o criou para viver em comunh&atilde;o, eternamente, com a beleza infinita, com a plenitude que &eacute; a Sant&iacute;ssima Trindade: Pai, Filho e Esp&iacute;rito Santo. Am&eacute;m! <\/p>\n<p><em>Transcri&ccedil;&atilde;o: Carlos Eduardo<\/em><\/p>\n<hr width=\"100%\" size=\"2\" \/>\n<div align=\"center\"><font size=\"2\"><strong>Adquira essa  prega&ccedil;&atilde;o pelo telefone<\/strong><br \/><strong>(12) 3186-26<\/strong><\/font>00<\/div>\n<hr width=\"100%\" size=\"2\" \/><strong>Conhe&ccedil;a mais do nosso conte&uacute;do:<\/p>\n<p><\/strong><a href=\"http:\/\/www.webtvcn.com\/\" target=\"_blank\"><font color=\"#0033cc\">::  WebTVCN, muitos v&iacute;deos para  voc&ecirc;<\/font><\/a><br \/> <a href=\"http:\/\/gentedefe.com\/\" target=\"_blank\"><font color=\"#0033cc\">::   Gente de f&eacute;, a sua comunidade de relacionamento crist&atilde;<\/font><\/a><br \/><a href=\"http:\/\/podcast.cancaonova.com\/\" target=\"_blank\"><font color=\"#0033cc\">:: Podcasts: ou&ccedil;a &aacute;udios sobre variados assuntos<\/font><\/a><br \/><a href=\"http:\/\/paroquias.cancaonova.com\/\" target=\"_blank\"><font color=\"#0033cc\">:: Cadastre sua par&oacute;quia ou capela no Portal Can&ccedil;&atilde;o Nova<\/font><\/a><a href=\"http:\/\/paroquias.cancaonova.com\/\" target=\"_blank\"><font color=\"#0033cc\"><br \/><\/font><\/a><br \/><strong>Para o seu celular:<\/strong><\/p>\n<p><a href=\"http:\/\/www.cancaonovamobile.com\/\" target=\"_blank\"><font color=\"#0033cc\">:: Can&ccedil;&atilde;o Nova Mobile<\/font><\/a><br \/><a href=\"http:\/\/cnchama.com.br\/\" target=\"_blank\"><font color=\"#0033cc\">::  CN Chama, a Palavra de Deus no  seu celular<\/font><\/a><br \/><a href=\"http:\/\/iphone.cancaonova.com\/\" target=\"_blank\"><font color=\"#0033cc\">:: Iphone<\/font><\/a><\/p>\n<p><strong>Mais canais na web:<\/strong><\/p>\n<p><a href=\"http:\/\/meadiciona.com\/cancaonova\" target=\"_blank\"><font color=\"#0033cc\">:: meadiciona.com\/cancaonova <\/font><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dom Beni Foto: V&acirc;nia\/CN A Igreja celebra neste domingo a Solenidade Lit&uacute;rgica da Sant&iacute;ssima Trindade. A Sant&iacute;ssima Trindade &eacute; a verdade mais importante registrada no Evangelho. A palavra &quot;Evangelho&quot; significa &quot;Boa Nova&quot;, a Boa Nova mais bela que Jesus anunciou&#8230;<\/p>\n","protected":false},"author":114,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7],"tags":[],"modified_by":"","_links":{"self":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/4156"}],"collection":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/users\/114"}],"replies":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/comments?post=4156"}],"version-history":[{"count":1,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/4156\/revisions"}],"predecessor-version":[{"id":4157,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/4156\/revisions\/4157"}],"wp:attachment":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media?parent=4156"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/categories?post=4156"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/tags?post=4156"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}