{"id":41564,"date":"2017-11-11T12:01:19","date_gmt":"2017-11-11T14:01:19","guid":{"rendered":"https:\/\/admin-canais.cancaonova.com\/eventos\/?p=41564"},"modified":"2020-03-20T12:22:25","modified_gmt":"2020-03-20T15:22:25","slug":"e-se-nos-orassemos-vamos-fazer-uma-oracao-pelo-brasil","status":"publish","type":"post","link":"https:\/\/admin-canais.cancaonova.com\/eventos\/acampamento-no-combate-da-oracao\/pregacoes\/e-se-nos-orassemos-vamos-fazer-uma-oracao-pelo-brasil\/","title":{"rendered":"E se n\u00f3s or\u00e1ssemos?"},"content":{"rendered":"<h2>A ora\u00e7\u00e3o tem o poder de transformar a nossa vida, a dos outros e do Brasil<\/h2>\n<p>O profeta Jeremias 33,1 nos mostra a verdadeira din\u00e2mica para nos colocar em uma constante vigil\u00e2ncia da <a href=\"https:\/\/eventos.cancaonova.com\/quinta---feira-de-adoracao\/pregacoes\/os-adoradores-sao-guerreiros\/\" target=\"_blank\" rel=\"noopener\">ora\u00e7\u00e3o<\/a>. Deus promete e cumpre a promessa feita por aqueles que clamam por Ele.<\/p>\n<p>\u00c9 tempo de alimentarmos nossa mente e esperan\u00e7a com a ora\u00e7\u00e3o, pois precisamos adentrar no mist\u00e9rio da intimidade com o Senhor. A Palavra que o Esp\u00edrito Santo me disse, hoje, \u00e9 que precisamos clamar por Ele, pois Ele vai nos ouvir.<\/p>\n<p><a href=\"https:\/\/eventos.cancaonova.com\/quinta---feira-de-adoracao\/pregacoes\/no-desanimo-permaneca-fiel\/\" target=\"_blank\" rel=\"noopener\">Est\u00e1 dif\u00edcil?<\/a>&nbsp;Lembre-se de que para Deus nada \u00e9 imposs\u00edvel! Devemos sair da vis\u00e3o meramente humana de incapacidade para entrarmos no mist\u00e9rio divino. Jesus tamb\u00e9m nos ensinou algo no Evangelho: tudo \u00e9 poss\u00edvel para aquele que cr\u00ea!<\/p>\n<p>Deus age no meio de um povo de f\u00e9. N\u00f3s podemos transformar todas as coisas pelo poder da ora\u00e7\u00e3o, mas precisamos acreditar e clamar ao Senhor. N\u00e3o podemos desistir nunca, porque tudo pode ser mudado pela for\u00e7a da ora\u00e7\u00e3o.<\/p>\n<h3>E se n\u00f3s orarmos?<\/h3>\n<p>Clame por Jesus e Ele o ouvir\u00e1. Devemos nos perguntar isso quando estivermos passando por alguma situa\u00e7\u00e3o que nos machuca e foge das nossas m\u00e3os.<\/p>\n<p>Se orarmos, a primeira coisa que vai acontecer \u00e9 a <a href=\"https:\/\/eventos.cancaonova.com\/quinta---feira-de-adoracao\/pregacoes\/como-adorar-em-meio-as-dificuldades\/\" target=\"_blank\" rel=\"noopener\">mudan\u00e7a na nossa vida<\/a>. S\u00f3 n\u00e3o seremos transformados se fecharmos nosso cora\u00e7\u00e3o para as gra\u00e7as de Deus. Quando rezamos, a nossa sa\u00fade espiritual ganha for\u00e7a e nossa <a href=\"https:\/\/eventos.cancaonova.com\/acampamento-quem-como-deus-\/pregacoes\/defendei-nos-no-combate-contra-apostasia-e-o-esfriamento-na-fe\/\" target=\"_blank\" rel=\"noopener\">f\u00e9<\/a>&nbsp;aumenta.<\/p>\n<p>Se abrirmos o cora\u00e7\u00e3o, o Senhor vai nos transformando dia a dia! \u00c0s vezes, damos muitas desculpas e acreditamos que n\u00e3o vamos mudar, mas, quando oramos com o cora\u00e7\u00e3o aberto, somos transformados.<\/p>\n<p>Quem reza e intercede-se esquece de si mesmo e come\u00e7a a olhar para as realidades que est\u00e3o a sua volta, tornando-se comprometido com o outro. A ora\u00e7\u00e3o tem como combust\u00edvel o amor, pois \u00e9 preciso ter muito amor e coragem para ir ao encontro das pessoas.<\/p>\n<p>Pelo poder da ora\u00e7\u00e3o vamos transformar a realidade e as pessoas pelas quais rezamos, mas precisamos perseverar. Precisamos de um povo que levanta e clama ao Senhor! Deus quer fazer de cada um de n\u00f3s um intercessor, mesmo diante das limita\u00e7\u00f5es.<\/p>\n<p>A nossa na\u00e7\u00e3o ser\u00e1 transformada pelo <a href=\"https:\/\/formacao.cancaonova.com\/espiritualidade\/vida-de-oracao\/o-que-e-ter-fe-e-tambem-ser-uma-de-pessoa-de-fe\/\" target=\"_blank\" rel=\"noopener\">poder da ora\u00e7\u00e3o<\/a>, por isso devemos ser um povo que cr\u00ea.<\/p>\n<p><strong>Assista a um trecho da prega\u00e7\u00e3o:<\/strong><\/p>\n<div class='embeds-video'><iframe frameborder='0' width=\"560\" height=\"315\" src='https:\/\/apps.cancaonova.com\/embeds\/Embeds\/get?id=5316&output=iframe&post_link=aHR0cHM6Ly9hZG1pbi1jYW5haXMuY2FuY2Fvbm92YS5jb20vZXZlbnRvcy9hY2FtcGFtZW50by1uby1jb21iYXRlLWRhLW9yYWNhby9wcmVnYWNvZXMvZS1zZS1ub3Mtb3Jhc3NlbW9zLXZhbW9zLWZhemVyLXVtYS1vcmFjYW8tcGVsby1icmFzaWwv&player_id=36597661' style='overflow:hidden;' class='iframe_embed' allowfullscreen><\/iframe><\/div>\n<p><strong>Leia mais:<\/strong><br \/>\n<a href=\"https:\/\/eventos.cancaonova.com\/acampamento-quem-como-deus-\/pregacoes\/permaneca-sob-a-protecao-do-altissimo\/\" target=\"_blank\" rel=\"noopener\">.: Permane\u00e7a sob a prote\u00e7\u00e3o do Alt\u00edssimo&nbsp;<\/a><br \/>\n<a href=\"https:\/\/eventos.cancaonova.com\/quinta---feira-de-adoracao\/pregacoes\/reconhecer-que-deus-e-deus\/\" target=\"_blank\" rel=\"noopener\">.: Reconhecer que Deus \u00e9 Deus<\/a><\/p>\n<p><em>Transcri\u00e7\u00e3o e adapta\u00e7\u00e3o: Alessandra Borges<\/em><\/p>\n<p><a href=\"https:\/\/clube.cancaonova.com\/\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-25430 size-full\" src=\"https:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2015\/02\/contribuicaocn1.jpg\" alt=\"contribuicaocn\" width=\"300\" height=\"72\"><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A nossa na\u00e7\u00e3o ser\u00e1 transformada pelo poder da ora\u00e7\u00e3o, por isso devemos ser um povo que cr\u00ea. <a href=\"https:\/\/admin-canais.cancaonova.com\/eventos\/acampamento-no-combate-da-oracao\/pregacoes\/e-se-nos-orassemos-vamos-fazer-uma-oracao-pelo-brasil\/\">Continue lendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":243,"featured_media":53776,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7],"tags":[],"modified_by":"aliane","_links":{"self":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/41564"}],"collection":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/users\/243"}],"replies":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/comments?post=41564"}],"version-history":[{"count":8,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/41564\/revisions"}],"predecessor-version":[{"id":56679,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/41564\/revisions\/56679"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media\/53776"}],"wp:attachment":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media?parent=41564"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/categories?post=41564"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/tags?post=41564"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}