{"id":4163,"date":"2010-06-27T08:15:00","date_gmt":"2010-06-27T11:15:00","guid":{"rendered":"http:\/\/admin-canais.cancaonova.com\/eventos\/?p=4163"},"modified":"2014-08-13T02:05:28","modified_gmt":"2014-08-13T05:05:28","slug":"as-feridas-do-coracao-e-suas-consequencias","status":"publish","type":"post","link":"https:\/\/admin-canais.cancaonova.com\/eventos\/pregacoes\/as-feridas-do-coracao-e-suas-consequencias\/","title":{"rendered":"As feridas do cora\u00e7\u00e3o e suas consequ\u00eancias"},"content":{"rendered":"<p>Todos n&oacute;s estamos sujeitos a sofrer por causa do desamor. Muitos est&atilde;o doentes por causa das ofensas vividas. <\/p>\n<p>  H&aacute; muita gente ferida, magoada e ofendida. A pessoa ferida fica numa situa&ccedil;&atilde;o de desconforto, fica presa, voltada para si, impedida de ser ela mesma no servi&ccedil;o do amor.<\/p>\n<div id=\"foto\" style=\"margin: 0pt auto;padding: 0px;width: 370px;float: none\">\n<div id=\"foto\"><!--ABRE LINK DA FOTO--><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.cancaonova.com\/portal\/arquivos\/fotos\/2010\/junho\/27_irma-mariaeunica3.jpg\" border=\"0\" width=\"370\" height=\"250\" \/><!--FECHA LINK DA FOTO--><\/div>\n<div id=\"texto\"><!--TEXTO DA FOTO-->Irm&atilde; Maria Eunice<!--TEXTO DA FOTO--><\/div>\n<div id=\"credito\"><!--CREDITO DA FOTO-->Foto: S&aacute;vio Gabatel\/CN<!--CREDITO DA FOTO--><\/div>\n<\/div>\n<p><a href=\"http:\/\/blog.cancaonova.com\/mariaeunice\/\" target=\"_blank\"><font color=\"#0033cc\">:: Conhe&ccedil;a o blog da pregadora<\/font><\/a><\/p>\n<p>  Os verbos ferir, magoar, machucar, ofender s&atilde;o aplicados nas realidades dos sofrimentos emocionais. S&atilde;o os sofrimentos do cora&ccedil;&atilde;o. O cora&ccedil;&atilde;o emocional fica ofendido. O cora&ccedil;&atilde;o emocional &eacute; o centro das suas emo&ccedil;&otilde;es.<\/p>\n<p>  N&oacute;s nos sentimos, muitas vezes, rejeitados, n&atilde;o amados. Por isso precisamos correr atr&aacute;s da cura. As feridas trazem consequ&ecirc;ncias danosas: <\/p>\n<p>  <strong>Consequ&ecirc;ncias f&iacute;sicas:<\/strong> &uacute;lceras, dores de cabe&ccedil;a, dores lombares, press&atilde;o alta, diabetes, etc&#8230; <\/p>\n<p>  <strong>Consequ&ecirc;ncias ps&iacute;quicas:<\/strong> depress&otilde;es, ang&uacute;stia, agressividade descontrolada, mau humor, desgosto pela vida, desconfian&ccedil;a generalizada, falta de confian&ccedil;a nas pessoas.<\/p>\n<p>  <strong>Consequ&ecirc;ncias espirituais:<\/strong> dificuldade na ora&ccedil;&atilde;o, reza-se pouco, frieza espiritual, sensa&ccedil;&atilde;o de n&atilde;o ser amado por Deus.<\/p>\n<p>  <strong>Consequ&ecirc;ncias sociais:<\/strong> n&atilde;o sabe liderar, comportamento agressivo, dificuldade de amar, negativo, esp&iacute;rito de cr&iacute;tica.<\/p>\n<p>  As feridas de seu cora&ccedil;&atilde;o podem ser curadas pelo perd&atilde;o, que &eacute; a pomada divina para curar todas essas situa&ccedil;&otilde;es. A cura &eacute; um processo. Voc&ecirc; deve fazer o &quot;curativo&quot; de seu cora&ccedil;&atilde;o com a &quot;pomada do perd&atilde;o&quot; e aplicar quantas vezes for preciso. <\/p>\n<p>  N&atilde;o precisamos mudar de Igreja para ser curados, aqui temos a cura. Do perd&atilde;o para a cura do cora&ccedil;&atilde;o. <\/p>\n<p>  <strong>Roteiro pr&aacute;tico para a cura interior:<\/strong><\/p>\n<p>  &#8211; Invoque a presen&ccedil;a de Jesus. Adore Jesus. Converse com Jesus, diga a Ele que voc&ecirc; quer ser curado.<\/p>\n<p>  &#8211; Traga a sua mente a  pessoa que te ofendeu, fale com essa pessoa perdoando pelas ofensas que lhe causaram medo. Elogie essa pessoa pelas suas boas a&ccedil;&otilde;es e pe&ccedil;a ao Senhor que aben&ccedil;oe essa pessoa com muitas gra&ccedil;as. <\/p>\n<p> &#8211; Diga ao Senhor que voc&ecirc; tem desejo de encontr&aacute;-Lo. Pe&ccedil;a ao Senhor que fique com voc&ecirc;, diga que voc&ecirc; precisa da presen&ccedil;a d&#039;Ele na horas de medos e decis&otilde;es e O reconhece como  Senhor de sua vida. Agrade&ccedil;a a Ele pela ben&ccedil;&atilde;o de viver.<\/p>\n<p>  &#8211; Fale para Jesus que voc&ecirc; est&aacute; ferido. Pe&ccedil;a a Ele que manifeste seu poder para que voc&ecirc; fique curado. Diga que &eacute; bom estar com Ele. Diga que voc&ecirc; quer usar a pomada do perd&atilde;o. Traga a seu cora&ccedil;&atilde;o as pessoas que te ofenderam e converse com elas, dizendo tudo que voc&ecirc; viveu com elas, mas que hoje quer perdoar.  <\/p>\n<p>  &#8211; Agora fale para essa pessoa das qualidades que ela tem. Fa&ccedil;a elogios. E termine falando dessa pessoa para Jesus, que foi bom perdo&aacute;-la, e clame a b&ecirc;n&ccedil;&atilde;o de Deus sobre ela. E agrade&ccedil;a a Deus pela presen&ccedil;a d&#039;Ele durante a ora&ccedil;&atilde;o de perd&atilde;o.<\/p>\n<p>  N&atilde;o basta um curativo, &eacute; preciso renovar esse exerc&iacute;cio de perd&atilde;o quantas vezes for preciso.<\/p>\n<p>  Existe muita gente que sofre de tristeza por ter ofendido outras pessoas, e de algum modo feri-se a si mesmo. Mais tarde voc&ecirc; vai perceber que est&aacute; ferido por voc&ecirc; mesmo. Para curar voc&ecirc; precisa do perd&atilde;o. O perd&atilde;o vai de voc&ecirc; para o outro. <\/p>\n<p>  Tem muita gente carregando pesados fardos por causa dos erros cometidos, auto-condena&ccedil;&atilde;o. A partir da&iacute; come&ccedil;a v&aacute;rios problemas, e o rem&eacute;dio &eacute; o auto-perd&atilde;o. Perdoar quem te feriu, confessar, e se livrar desse mal o mais r&aacute;pido poss&iacute;vel, sen&atilde;o viver&aacute; em tortura. Isso causa um dano na vida da pessoa.<\/p>\n<p>  Muitas pessoas sentem rejei&ccedil;&atilde;o, que &eacute; uma avers&atilde;o a certas coisas, pessoas, ambientes e &eacute; muito prejudicial. Ela nascem dentro de n&oacute;s involuntariamente, ou n&atilde;o, e causam problemas de sa&uacute;des, agressividade, desamor&#8230; <\/p>\n<p>  Sobre tudo isso, invoque o nome de Jesus, fa&ccedil;a o roteiro pr&aacute;tico de cura interior diante do Sant&iacute;ssimo Sacramento e voc&ecirc; ser&aacute; curado.<\/p>\n<p><em>Transcri&ccedil;&atilde;o e adapta&ccedil;&atilde;o: Willieny Isaias<\/em><\/p>\n<hr width=\"100%\" size=\"2\" \/>\n<div align=\"center\"><font size=\"2\"><strong>Adquira essa prega&ccedil;&atilde;o  pelo telefone<\/strong><br \/><strong>(12) 3186-2600<\/strong><br \/><\/font><\/div>\n<hr width=\"100%\" size=\"2\" \/><strong><br \/>Adquira os livros da Irm&atilde; Maria Eunice<\/strong>:<br \/>  <a href=\"http:\/\/shopping.cancaonova.com\/Livraria\/Cura-interior\/Cura-das-feridas-interiores.html?acao=DT&amp;prod_id=80255&amp;dep=692&amp;secao=3252&amp;pedido=33884025&amp;codbar=01.01390\" target=\"_blank\"><font color=\"#0033cc\">:: Cura das feridas interiores<\/font><\/a><br \/><a href=\"http:\/\/shopping.cancaonova.com\/Livraria\/Formacao\/Sob-a-protecao-do-altissimo.html?acao=DT&amp;prod_id=203323&amp;dep=692&amp;secao=3821&amp;pedido=31187152&amp;codbar=01.01598\" target=\"_blank\"><font color=\"#0033cc\">:: Sob a prote&ccedil;&atilde;o do Alt&iacute;ssimo<\/font><\/a><\/p>\n<p><strong>Veja  tamb&eacute;m:<\/strong><br \/><a href=\"http:\/\/blog.cancaonova.com\/redacao\/2010\/06\/18\/cancao-nova-lanca-biblia-on-line-para-dispositivo-movel\/\" target=\"_blank\"><font color=\"#0033cc\">:: Can&ccedil;&atilde;o Nova lan&ccedil;a Bibl&iacute;a   on-line para dispositivos m&oacute;veis<\/font><\/a><\/p>\n<p><strong>Conhe&ccedil;a mais  do  nosso conte&uacute;do:<br \/><\/strong><a href=\"http:\/\/www.webtvcn.com\/\" target=\"_blank\"><font color=\"#0033cc\">::  WebTVCN, muitos v&iacute;deos para  voc&ecirc;<\/font><\/a><br \/> <a href=\"http:\/\/gentedefe.com\/\" target=\"_blank\"><font color=\"#0033cc\">:: Gente de f&eacute;, a sua comunidade  de relacionamento  crist&atilde;<\/font><\/a><br \/><a href=\"http:\/\/podcast.cancaonova.com\/\" target=\"_blank\"><font color=\"#0033cc\">:: Podcasts: ou&ccedil;a &aacute;udios sobre  variados assuntos<\/font><\/a><br \/><a href=\"http:\/\/paroquias.cancaonova.com\/\" target=\"_blank\"><font color=\"#0033cc\">:: Cadastre sua par&oacute;quia ou capela no Portal Can&ccedil;&atilde;o Nova<\/font><\/a><a href=\"http:\/\/paroquias.cancaonova.com\/\" target=\"_blank\"><font color=\"#0033cc\"><br \/><\/font><\/a><br \/><strong>Para o seu celular:<\/strong><br \/><a href=\"http:\/\/www.cancaonovamobile.com\/\" target=\"_blank\"><font color=\"#0033cc\">:: Can&ccedil;&atilde;o Nova Mobile<\/font><\/a><br \/><a href=\"http:\/\/cnchama.com.br\/\" target=\"_blank\"><font color=\"#0033cc\">::  CN Chama, a Palavra de Deus no  seu celular<\/font><\/a><br \/><a href=\"http:\/\/iphone.cancaonova.com\/\" target=\"_blank\"><font color=\"#0033cc\">:: Iphone<\/font><\/a><\/p>\n<p><strong>Mais canais na web:<\/strong><br \/><a href=\"http:\/\/meadiciona.com\/cancaonova\" target=\"_blank\"><font color=\"#0033cc\">:: meadiciona.com\/cancaonova <\/font><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Todos n&oacute;s estamos sujeitos a sofrer por causa do desamor. Muitos est&atilde;o doentes por causa das ofensas vividas. H&aacute; muita gente ferida, magoada e ofendida. A pessoa ferida fica numa situa&ccedil;&atilde;o de desconforto, fica presa, voltada para si, impedida de&#8230;<\/p>\n","protected":false},"author":114,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7],"tags":[],"modified_by":"","_links":{"self":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/4163"}],"collection":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/users\/114"}],"replies":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/comments?post=4163"}],"version-history":[{"count":1,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/4163\/revisions"}],"predecessor-version":[{"id":4164,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/4163\/revisions\/4164"}],"wp:attachment":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media?parent=4163"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/categories?post=4163"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/tags?post=4163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}