{"id":45329,"date":"2018-07-19T13:29:39","date_gmt":"2018-07-19T16:29:39","guid":{"rendered":"https:\/\/admin-canais.cancaonova.com\/eventos\/?p=45329"},"modified":"2018-07-20T09:02:25","modified_gmt":"2018-07-20T12:02:25","slug":"ele-nos-livra-das-fornalhas","status":"publish","type":"post","link":"https:\/\/admin-canais.cancaonova.com\/eventos\/phn\/pregacoes\/ele-nos-livra-das-fornalhas\/","title":{"rendered":"Ele nos livra das fornalhas"},"content":{"rendered":"<div id=\"attachment_45338\" style=\"width: 279px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-45338\" class=\"size-full wp-image-45338\" src=\"https:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2018\/07\/astromar.jpg\" alt=\"\" width=\"269\" height=\"329\" srcset=\"https:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2018\/07\/astromar.jpg 269w, https:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2018\/07\/astromar-245x300.jpg 245w\" sizes=\"(max-width: 269px) 100vw, 269px\" \/><p id=\"caption-attachment-45338\" class=\"wp-caption-text\">Astromar Miranda<br \/>\n Foto: Paula Dizar\u00f3\/cancaonova.com<\/p><\/div>\n<h2>Permitamos que o Senhor nos toque, pois Ele transforma o comum em extraordin\u00e1rio<\/h2>\n<p><span style=\"font-weight: 400;\">A primeira prega\u00e7\u00e3o de hoje foi realizada por\u00a0<a href=\"https:\/\/eventos.cancaonova.com\/phn\/pregacoes\/deus-esta-sempre-com-voce\/\" target=\"_blank\" rel=\"noopener\">Dunga<\/a>, que abordou a hist\u00f3ria de Jos\u00e9. Ele destacou tudo o que Jos\u00e9 prosperava. Essa \u00e9 a l\u00f3gica de Deus, pois tudo o que Senhor toca \u00e9 transformado.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Assim aconteceu comigo. Fui tocado por Deus e mudei totalmente de vida. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Todo jovem tocado por Deus \u00e9 extraordinariamente transformado! Por isso, \u00e9 preciso que permitamos ao Senhor nos tocar, pois s\u00f3 Ele tem a capacidade de transformar algo comum em extraordin\u00e1rio.<\/span><\/p>\n<h3>Transforma\u00e7\u00f5es de vidas<\/h3>\n<p><span style=\"font-weight: 400;\">Tudo come\u00e7ou com Dom Bosco quando chamou quatro jovens a prosseguir com uma obra. Desses quatro, apenas tr\u00eas aceitaram o convite. Assim, Dom Bosco deu in\u00edcio \u00e0 fam\u00edlia salesiana. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Deus tamb\u00e9m tocou no cora\u00e7\u00e3o de um jovem padre salesiano. Ent\u00e3o, este convidou alguns jovens para come\u00e7ar uma obra, e estes aceitaram o convite. Chamaram-na de Comunidade Can\u00e7\u00e3o Nova.\u00a0<\/span><span style=\"font-weight: 400;\">Essa inspira\u00e7\u00e3o que perpassou o cora\u00e7\u00e3o de monsenhor Jonas tamb\u00e9m passou pelo mission\u00e1rio Dunga, dando in\u00edcio ao PHN. <\/span><\/p>\n<h3>Liberdade em Cristo<\/h3>\n<p><span style=\"font-weight: 400;\">A verdadeira liberdade \u00e9 saber recusar tudo o que nos aprisiona, de dizer \u201cn\u00e3o\u201d a tudo aquilo que nos prende.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Os salesianos, atualmente, est\u00e3o presentes nos cinco Continentes devido ao chamado inicial de Dom Bosco. A Can\u00e7\u00e3o Nova tornou-se tudo o que \u00e9 hoje e muito mais a partir de um sonho e de uma inspira\u00e7\u00e3o de seu fundador. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">O PHN, que nasceu pequeno, permitir\u00e1 que, neste fim de semana, 200 mil jovens possam fazer uma experi\u00eancia extraordin\u00e1ria. Isso \u00e9 um sonho se tornando realidade a partir da aceita\u00e7\u00e3o de um chamado de Deus.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Durante esse acampamento, Deus colocar\u00e1 inspira\u00e7\u00f5es e \u00a0sonhos em n\u00f3s. Precisamos voltar para nossas casas n\u00e3o apenas com sonhos, mas com planejamento e meta de vida.<\/span><\/p>\n<p><strong>Leia mais:<\/strong><br \/>\n <a href=\"https:\/\/eventos.cancaonova.com\/edicao\/phn-3\/\" target=\"_blank\" rel=\"noopener\">.: Confira a cobertura do #PHN20Anos<\/a><br \/>\n <a href=\"https:\/\/formacao.cancaonova.com\/testemunhos\/testemunho-de-um-jovem-phn\/\" target=\"_blank\" rel=\"noopener\">.: Testemunho de um jovem PHN<\/a><\/p>\n<h3>Precisamos de metas<\/h3>\n<p><span style=\"font-weight: 400;\"><a href=\"https:\/\/formacao.cancaonova.com\/espiritualidade\/ano-novo\/sera-que-fazer-planos-e-tracar-metas-e-realmente-viver\/\" target=\"_blank\" rel=\"noopener\">Meta<\/a> significa saber onde queremos chegar. Aqueles que n\u00e3o sabem onde chegar, n\u00e3o se importar\u00e3o com a velocidade e a dire\u00e7\u00e3o do caminho. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">A nossa meta precisa ser o C\u00e9u. N\u00e3o podemos querer ir para qualquer lugar.<\/span><\/p>\n<p>.: Confira as<a title=\"fotos do PHN\" href=\"http:\/\/www.flickr.com\/photos\/cancaonova\/albums\/72157697579422941\" target=\"_blank\" rel=\"noopener\"> fotos do PHN<\/a>!<\/p>\n<h3>Todo sonho tem um objetivo<\/h3>\n<p><span style=\"font-weight: 400;\">Nosso <a href=\"https:\/\/formacao.cancaonova.com\/espiritualidade\/cura-interior\/voce-tem-acreditado-nos-seus-sonhos-e-lutado-por-eles\/\" target=\"_blank\" rel=\"noopener\">sonho <\/a>precisa de um objetivo. Nesse fim de semana, dentro de n\u00f3s, ser\u00e3o inspirados muitos sonhos. \u00a0O objetivo consiste no motivo pelo qual quero algo. Aquele que possui um motivo enfrenta qualquer dificuldade. <\/span><\/p>\n<h4>Os sonhos possuem prop\u00f3sitos<\/h4>\n<p><span style=\"font-weight: 400;\">Precisamos de prop\u00f3sitos, ou seja, de um \u201cpara qu\u00ea\u201d estamos fazendo isso. O prop\u00f3sito pode ser chamado tamb\u00e9m de voca\u00e7\u00e3o. \u00c9 aquilo que nascemos para ser e fazer. \u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A partir de metas, objetivos e prop\u00f3sitos, conseguimos tra\u00e7ar nosso caminho rumo \u00e0 felicidade. E\u00a0<\/span><span style=\"font-weight: 400;\">felicidade n\u00e3o \u00e9 lugar onde se chega, mas a forma como se vai!<\/span><\/p>\n<p><strong>Assista a prega\u00e7\u00e3o completa:<\/strong><\/p>\n<p><iframe loading=\"lazy\" title=\"Ele nos livra das fornalhas - Astromar Miranda (19\/07\/18)\" width=\"600\" height=\"338\" src=\"https:\/\/www.youtube.com\/embed\/82fr_Ucsj_Y?feature=oembed&amp;rel=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p><em>Transcri\u00e7\u00e3o e adapta\u00e7\u00e3o: Let\u00edcia Barbosa<\/em><\/p>\n<p><a href=\"https:\/\/www.youtube.com\/playcancaonova\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-44717\" src=\"https:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2018\/06\/cnPlay_materias-1.png\" alt=\"Banner do canal PlayCancaonova no Youtube\" width=\"614\" height=\"92\" srcset=\"https:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2018\/06\/cnPlay_materias-1.png 614w, https:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2018\/06\/cnPlay_materias-1-300x45.png 300w\" sizes=\"(max-width: 614px) 100vw, 614px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Permitamos que o Senhor nos toque, pois Ele transforma o comum em extraordin\u00e1rio A primeira prega\u00e7\u00e3o de hoje foi realizada por\u00a0Dunga, que abordou a hist\u00f3ria de Jos\u00e9. Ele destacou tudo o que Jos\u00e9 prosperava. Essa \u00e9 a l\u00f3gica de Deus,&#8230;<\/p>\n","protected":false},"author":127,"featured_media":45337,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7],"tags":[],"modified_by":"adailton","_links":{"self":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/45329"}],"collection":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/users\/127"}],"replies":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/comments?post=45329"}],"version-history":[{"count":10,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/45329\/revisions"}],"predecessor-version":[{"id":45388,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/45329\/revisions\/45388"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media\/45337"}],"wp:attachment":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media?parent=45329"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/categories?post=45329"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/tags?post=45329"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}