{"id":4580,"date":"2010-09-18T08:15:00","date_gmt":"2010-09-18T11:15:00","guid":{"rendered":"http:\/\/admin-canais.cancaonova.com\/eventos\/?p=4580"},"modified":"2014-08-13T02:21:12","modified_gmt":"2014-08-13T05:21:12","slug":"a-misericordia-e-a-oracao-ao-cordeiro","status":"publish","type":"post","link":"https:\/\/admin-canais.cancaonova.com\/eventos\/pregacoes\/a-misericordia-e-a-oracao-ao-cordeiro\/","title":{"rendered":"A miseric\u00f3rdia e a ora\u00e7\u00e3o ao Cordeiro"},"content":{"rendered":"<p><a href=\"http:\/\/wiki.cancaonova.com\/index.php\/Santa_Faustina\" target=\"_blank\" title=\"Biografia\"><font color=\"#0033cc\">Santa Faustina<\/font><\/a> era uma menina obediente aos pais. Ela n&atilde;o tinha dinheiro para entrar na congrega&ccedil;&atilde;o e  trabalhou numa casa de fam&iacute;lia durante um ano, para ir para a congrega&ccedil;&atilde;o. Que como Santa Faustina tenhamos for&ccedil;a para fazer a vontade do Pai. <\/p>\n<p>  Talvez voc&ecirc; n&atilde;o ame a sua fam&iacute;lia porque nutriu sentimentos de m&aacute;goas, mas voc&ecirc; n&atilde;o &eacute; culpado, as dores pelas quais voc&ecirc; possui em sua fam&iacute;lia n&atilde;o foi o Pai da miseric&oacute;rdia que lhe mandou, os males que acontecessem em nossa vida, infelizmente, recaem sobre n&oacute;s por causas de nossos pecados.<\/p>\n<div id=\"foto\" style=\"margin: 0pt auto;padding: 5px;width: 370px;float: none\">\n<div id=\"foto\"><!--ABRE LINK DA FOTO--><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.cancaonova.com\/portal\/arquivos\/fotos\/2010\/setembro\/elianasa_misericordia01\" border=\"0\" width=\"370\" height=\"250\" \/><!--FECHA LINK DA FOTO--><\/div>\n<div id=\"texto\"><!--TEXTO DA FOTO-->Eliana S&aacute;<!--TEXTO DA FOTO--><\/div>\n<div id=\"credito\"><!--CREDITO DA FOTO-->Foto: Claudio Allan\/ Fotos CN<!--CREDITO DA FOTO--><\/div>\n<\/div>\n<div align=\"center\"><strong><a href=\"http:\/\/www.flickr.com\/photos\/cancaonova\/sets\/72157624978404488\/\" target=\"_blank\"><font color=\"#0033cc\">+Fotos no Flick<font color=\"#ff0066\">r<\/font><\/font><\/a><\/strong><\/div>\n<p><strong>Reze: <\/strong>Senhor Jesus, como nunca rezei em minha vida, porque n&atilde;o tive coragem, fui fraca, pecadora, porque sou t&atilde;o miser&aacute;vel, tem miseric&oacute;rdia de mim Jesus. Visita minha casa, visita minha fam&iacute;lia, entra na minha casa Senhor Jesus, toma posse de cada canto dessa casa; casa material, mas a casa dos cora&ccedil;&otilde;es daqueles que habitam comigo e que eu tanto amo, mas que as vezes me vejo t&atilde;o pecadora diante deles. Senhor Jesus, a minha casa precisa ser uma casa de ora&ccedil;&atilde;o, por isso neste momento, nesta hora, eu consagro no meu nome e no nome da minha casa, toda a minha fam&iacute;lia ao Seu misericordios&iacute;ssimo cora&ccedil;&atilde;o. Jesus, eu confio em V&oacute;s!<\/p>\n<p>  Tira o lixo da sua casa e deixa o precios&iacute;ssimo sangue e a &aacute;gua que jorram do lado de Jesus lavarem a sua casa, a sua fam&iacute;lia.<\/p>\n<p>  Eu n&atilde;o sei pregar, sei rezar, quem sabe pregar &eacute; meu <a href=\"http:\/\/www.cancaonova.com\/portal\/canais\/pejonas\/textos.php?id=24\" target=\"_blank\" title=\"Biografia\"><font color=\"#0033cc\">fundador Monsenhor Jonas Abib<\/font><\/a>, que pediu a Deus a gra&ccedil;a de que seus filhos pregassem melhor que ele, cantassem melhor que ele. Mas a sua vida j&aacute; &eacute; uma prega&ccedil;&atilde;o, ele n&atilde;o precisa estar aqui falando, agora ele est&aacute; l&aacute; cumprindo a sua miss&atilde;o de fundador. Eu n&atilde;o sei pregar. <strong>Fazer o que quero &eacute; f&aacute;cil, mas fazer o que tenho dificuldade &eacute; um desafio<\/strong>, mas estou aqui. Essa prega&ccedil;&atilde;o na verdade &eacute; uma ora&ccedil;&atilde;o.<\/p>\n<p>  Quer morrer bem? Imite <a href=\"http:\/\/wiki.cancaonova.com\/index.php\/Papa_Jo%C3%A3o_Paulo_II\" target=\"_blank\" title=\"Biografia\"><font color=\"#0033cc\">Jo&atilde;o Paulo II<\/font><\/a>.<\/p>\n<p>  No di&aacute;rio de Santa Faustina n&uacute;mero 1732 diz: <em>&ldquo;(&hellip;) Amo a Pol&ocirc;nia de maneira especial e, se ela for obediente &agrave; Minha vontade, Eu a elevarei em poder e santidade. Dela sair&aacute; a centelha que preparar&aacute; o mundo para a Minha Vinda derradeira&rdquo;.<\/em><\/p>\n<p>  Qual &eacute; o nome dessa centelha? Jo&atilde;o Paulo II. Durante seu pontificado, ele marcou a hist&oacute;ria n&atilde;o somente da Igreja Cat&oacute;lica, mas da humanidade. Conhe&ccedil;a a hist&oacute;ria deste homem santo, reze por sua beatifica&ccedil;&atilde;o e canoniza&ccedil;&atilde;o.<\/p>\n<p>  Eu espero que o mundo pag&atilde;o fa&ccedil;a uma experi&ecirc;ncia com a miseric&oacute;rdia. Eu suplico a Deus que os raios de Sua miseric&oacute;rdia recaiam sobre nossa na&ccedil;&atilde;o, pois ela est&aacute; se tornando uma na&ccedil;&atilde;o pag&atilde;. Meus amados, o tempo &eacute; breve.<\/p>\n<p>  Tenho uma not&iacute;cia maravilhosa: O seu lugar e o lugar de sua fam&iacute;lia &eacute; no c&eacute;u. Outra not&iacute;cia, que muita gente morre de medo, &eacute; que voc&ecirc; vai morrer, a vida &eacute; um sopro. Tenho mais duas not&iacute;cias: a primeira, que &eacute; maravilhosa, &eacute; que o Senhor voltar&aacute; glorioso. Vem Senhor Jesus! A segunda not&iacute;cia  &eacute; que se Ele n&atilde;o vier voc&ecirc; ir&aacute; at&eacute;. Ou Jesus volta e estabelecesse novos c&eacute;us e uma nova terra, ou voc&ecirc; vai at&eacute; Ele. Preparemos o nosso cora&ccedil;&atilde;o. Vem Senhor Jesus!<\/p>\n<div style=\"text-align: center\"><\/div>\n<p><em>Transcri&ccedil;&atilde;o e adapta&ccedil;&atilde;o: Willieny Isaias<\/em><\/p>\n<hr width=\"100%\" size=\"2\" \/>\n<div align=\"center\"><strong>ADQUIRA ESSA PREGA&Ccedil;&Atilde;O PELO TELEFONE<\/strong><br \/><strong>(12) 3186-2600<\/strong><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Santa Faustina era uma menina obediente aos pais. Ela n&atilde;o tinha dinheiro para entrar na congrega&ccedil;&atilde;o e trabalhou numa casa de fam&iacute;lia durante um ano, para ir para a congrega&ccedil;&atilde;o. Que como Santa Faustina tenhamos for&ccedil;a para fazer a vontade&#8230;<\/p>\n","protected":false},"author":114,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7],"tags":[],"modified_by":"","_links":{"self":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/4580"}],"collection":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/users\/114"}],"replies":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/comments?post=4580"}],"version-history":[{"count":1,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/4580\/revisions"}],"predecessor-version":[{"id":4581,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/4580\/revisions\/4581"}],"wp:attachment":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media?parent=4580"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/categories?post=4580"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/tags?post=4580"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}