{"id":4692,"date":"2011-11-05T06:05:00","date_gmt":"2011-11-05T09:05:00","guid":{"rendered":"http:\/\/admin-canais.cancaonova.com\/eventos\/?p=4692"},"modified":"2014-08-13T02:23:34","modified_gmt":"2014-08-13T05:23:34","slug":"comunidade-da-cura","status":"publish","type":"post","link":"https:\/\/admin-canais.cancaonova.com\/eventos\/pregacoes\/comunidade-da-cura\/","title":{"rendered":"Comunidade da Cura"},"content":{"rendered":"<p>Essa &eacute; a hora de evangelizar.<\/p>\n<p>  &ldquo;E Pedro e Jo&atilde;o subiam juntos ao templo &agrave; hora da ora&ccedil;&atilde;o, a nona. <\/p>\n<p>   E era trazido um homem que desde o ventre de sua m&atilde;e era coxo, o qual todos os dias punham &agrave; porta do templo, chamada Formosa, para pedir esmola aos que entravam.    O qual, vendo a Pedro e a Jo&atilde;o que iam entrando no templo, pediu que lhe dessem uma esmola.    E Pedro, com Jo&atilde;o, fitando os olhos nele, disse: Olha para n&oacute;s.    E olhou para eles, esperando receber deles alguma coisa.    E disse Pedro: N&atilde;o tenho prata nem ouro; mas o que tenho isso te dou. Em nome de Jesus Cristo, o Nazareno, levanta-te e anda. &ldquo; (Atos 3, 1-6) <\/p>\n<p>  Quantas pessoas d&atilde;o esmolas, e quantas pessoas querem receber esmola, e se sentem incapaz de doar. <\/p>\n<p><a href=\"http:\/\/vobr.webtvcn.com\/2011\/novembro\/comunidadedacura.mp3\" target=\"_blank\"><font color=\"#0033cc\">Ou&ccedil;a esta prega&ccedil;&atilde;o na &iacute;ntegra<br \/><\/font><\/a>  <\/p>\n<div id=\"foto\" style=\"margin: 0pt auto;padding: 5px;width: 370px;float: none\">\n<div id=\"foto\"><!--ABRE LINK DA FOTO--><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.cancaonova.com\/portal\/arquivos\/fotos\/2011\/novembro\/05_eventos-004.jpg\" border=\"0\" width=\"370\" height=\"250\" \/><!--FECHA LINK DA FOTO--><\/div>\n<div id=\"texto\"><!--TEXTO DA FOTO-->&quot;<span class=\"translatable\">Deus gosta de intervir de repente, quando ningu&eacute;m espera<\/span>&quot;<!--TEXTO DA FOTO--><\/div>\n<div id=\"credito\"><!--CREDITO DA FOTO-->Foto: Robson Siqueira\/cancaonova.com<!--CREDITO DA FOTO--><\/div>\n<\/div>\n<p>  Esse homem que era paralitico desde do seio materno. Este homem julgava n&atilde;o ter nada para d&aacute;, nenhum carisma, nenhum dom para partilhar. E quantas pessoas s&oacute; sabem receber e n&atilde;o querem d&aacute;.  Quantos de voc&ecirc;s est&atilde;o esperando esmola da comunidade, dos irm&atilde;os?<\/p>\n<p>   Pedro diz: &ldquo;N&atilde;o tenho prata nem ouro; mas o que tenho isso te dou. Em nome de Jesus Cristo, o Nazareno, levanta-te e anda.&ldquo; Ele n&atilde;o tinha bem financeiro, mas tinha Jesus no  cora&ccedil;&atilde;o, e foi isso  que ele ofereceu.<\/p>\n<p>  A comunidade &eacute; onde damos a m&atilde;o para o irm&atilde;o se levantar. <\/p>\n<p>  Temos muitas pessoas que tem muitas feridas, muitas dores dentro das comunidades que precisa ser levando. Voc&ecirc; j&aacute; levantou algu&eacute;m? E fa&ccedil;o outra pergunta: E voc&ecirc; j&aacute; foi levando por algu&eacute;m? Quem &eacute; seu Pedro.<\/p>\n<p>  Comunidade que n&atilde;o cura n&atilde;o &eacute; comunidade.A comunidade cura, levanta, nos leva a sermos santos<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Essa &eacute; a hora de evangelizar. &ldquo;E Pedro e Jo&atilde;o subiam juntos ao templo &agrave; hora da ora&ccedil;&atilde;o, a nona. E era trazido um homem que desde o ventre de sua m&atilde;e era coxo, o qual todos os dias punham&#8230;<\/p>\n","protected":false},"author":114,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7],"tags":[],"modified_by":"","_links":{"self":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/4692"}],"collection":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/users\/114"}],"replies":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/comments?post=4692"}],"version-history":[{"count":1,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/4692\/revisions"}],"predecessor-version":[{"id":4693,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/4692\/revisions\/4693"}],"wp:attachment":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media?parent=4692"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/categories?post=4692"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/tags?post=4692"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}