{"id":47721,"date":"2018-11-25T13:50:31","date_gmt":"2018-11-25T15:50:31","guid":{"rendered":"https:\/\/admin-canais.cancaonova.com\/eventos\/?p=47721"},"modified":"2020-09-24T23:49:04","modified_gmt":"2020-09-25T02:49:04","slug":"santificar-o-trabalho","status":"publish","type":"post","link":"https:\/\/admin-canais.cancaonova.com\/eventos\/cancao-nova-sertaneja\/pregacoes\/santificar-o-trabalho\/","title":{"rendered":"Santificar o trabalho"},"content":{"rendered":"<h2><span style=\"font-weight: 400\">Confira a prega\u00e7\u00e3o de di\u00e1cono Nelsinho Corr\u00eaa cujo tema \u00e9 &#8216;Santificar o Trabalho&#8217;<\/span><\/h2>\n<p><span style=\"font-weight: 400\">Na manh\u00e3 deste domingo, 25, o mission\u00e1rio da Comunidade Can\u00e7\u00e3o Nova, di\u00e1cono Nelsinho Corr\u00eaa, pregou no <\/span><a href=\"https:\/\/eventos.cancaonova.com\/edicao\/cancao-nova-sertaneja-8\/\"><span style=\"font-weight: 400\">\u201cAcampamento Can\u00e7\u00e3o Nova Sertaneja\u201d<\/span><\/a>,&nbsp;<span style=\"font-weight: 400\">norteado pelo tema \u201csantificar o trabalho\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Em sua reflex\u00e3o, o di\u00e1cono exemplificou a tem\u00e1tica com a vida de S\u00e9rgio Abib, pai do monsenhor Jonas Abib. S\u00e9rgio era pedreiro e muito trabalhador, tornando-se uma grande inspira\u00e7\u00e3o em diversos aspectos para monsenhor Jonas.<\/span><\/p>\n<p><span style=\"font-weight: 400\">O pai de monsenhor Jonas trabalhou a vida toda em prol da fam\u00edlia e, tamb\u00e9m, ajudando aos mais necessitados.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Assista ao v\u00eddeo completo:<\/span><\/p>\n<div class='embeds-video'><iframe frameborder='0' width=\"560\" height=\"315\" src='https:\/\/apps.cancaonova.com\/embeds\/Embeds\/get?id=7799&output=iframe&post_link=aHR0cHM6Ly9hZG1pbi1jYW5haXMuY2FuY2Fvbm92YS5jb20vZXZlbnRvcy9jYW5jYW8tbm92YS1zZXJ0YW5lamEvcHJlZ2Fjb2VzL3NhbnRpZmljYXItby10cmFiYWxoby8=&player_id=36597661' style='overflow:hidden;' class='iframe_embed' allowfullscreen><\/iframe><\/div>\n<p><span style=\"font-weight: 400\">Clique<a href=\"https:\/\/www.flickr.com\/photos\/cancaonova\/albums\/72157702458045261\" target=\"_blank\" rel=\"noopener\"> aqui<\/a> e confira as fotos do acampamento!<\/span><\/p>\n<p><strong>Veja mais:<\/strong><br \/>\n<a href=\"https:\/\/www.flickr.com\/photos\/cancaonova\/sets\/72157702458045261\" target=\"_blank\" rel=\"noopener\">.: Confira as fotos do &#8220;Can\u00e7\u00e3o Nova Sertaneja&#8221;<\/a><br \/>\n<a href=\"https:\/\/eventos.cancaonova.com\/cancao-nova-sertaneja\/pregacoes\/e-com-oracao-que-se-prepara-acao\/\" target=\"_blank\" rel=\"noopener\">.: \u00c9 com a ora\u00e7\u00e3o que se prepara a a\u00e7\u00e3o&nbsp;<\/a><br \/>\n<a href=\"https:\/\/formacao.cancaonova.com\/afetividade-e-sexualidade\/afetividade-feminina\/a-presenca-feminina-no-universo-sertanejo\/\" target=\"_blank\" rel=\"noopener\">.: A presen\u00e7a feminina no universo sertanejo&nbsp;<\/a><br \/>\n<a href=\"https:\/\/eventos.cancaonova.com\/cancao-nova-sertaneja\/cobertura\/caravana-com-50-pessoas-viaja-400km-ate-o-cancao-nova-sertaneja\/\" target=\"_blank\" rel=\"noopener\">.: Caravana com 50 pessoas viaja 400 km at\u00e9 o Can\u00e7\u00e3o Nova Sertaneja<\/a><\/p>\n<p><a href=\"https:\/\/www.youtube.com\/playcancaonova\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2018\/06\/cnPlay_materias-1.png\" alt=\"Banner do canal PlayCancaonova no Youtube\"><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Confira a prega\u00e7\u00e3o de di\u00e1cono Nelsinho Corr\u00eaa cujo tema \u00e9 &#8216;Santificar o Trabalho&#8217; Na manh\u00e3 deste domingo, 25, o mission\u00e1rio da Comunidade Can\u00e7\u00e3o Nova, di\u00e1cono Nelsinho Corr\u00eaa, pregou no \u201cAcampamento Can\u00e7\u00e3o Nova Sertaneja\u201d,&nbsp;norteado pelo tema \u201csantificar o trabalho\u201d. Em sua&#8230;<\/p>\n","protected":false},"author":127,"featured_media":57280,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7],"tags":[],"modified_by":"aliane","_links":{"self":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/47721"}],"collection":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/users\/127"}],"replies":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/comments?post=47721"}],"version-history":[{"count":7,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/47721\/revisions"}],"predecessor-version":[{"id":58662,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/47721\/revisions\/58662"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media\/57280"}],"wp:attachment":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media?parent=47721"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/categories?post=47721"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/tags?post=47721"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}