{"id":5434,"date":"2009-04-18T08:15:00","date_gmt":"2009-04-18T11:15:00","guid":{"rendered":"http:\/\/admin-canais.cancaonova.com\/eventos\/?p=5434"},"modified":"2014-08-13T02:46:32","modified_gmt":"2014-08-13T05:46:32","slug":"o-milagre-da-misericordia-2","status":"publish","type":"post","link":"https:\/\/admin-canais.cancaonova.com\/eventos\/pregacoes\/o-milagre-da-misericordia-2\/","title":{"rendered":"O milagre da miseric\u00f3rdia"},"content":{"rendered":"<div id=\"foto\" style=\"margin: 0pt auto;padding: 10px 10px 10px 0px;width: 180px;float: left\">\n<div id=\"foto\"><!--ABRE LINK DA FOTO--><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.cancaonova.com\/portal\/arquivos\/fotos\/2009\/abril\/18_eventos_0003.jpg\" border=\"0\" width=\"180\" height=\"220\" \/><!--FECHA LINK DA FOTO--><\/div>\n<div id=\"texto\"><!--TEXTO DA FOTO-->Eliana S&aacute;<!--TEXTO DA FOTO--><\/div>\n<div id=\"credito\"><!--CREDITO DA FOTO-->Foto: Robson Siqueira<!--CREDITO DA FOTO--><\/div>\n<\/div>\n<p>Neste ano estamos comemorando a oitava festa da miseric&oacute;rdia, na Can&ccedil;&atilde;o Nova, as gra&ccedil;as j&aacute; est&atilde;o sendo derramadas porque Jesus est&aacute; no meio de n&oacute;s. Jesus disse &agrave; irm&atilde; Faustina: &quot;Desejo que a Festa da Miseric&oacute;rdia seja ref&uacute;gio e abrigo para todas as almas, especialmente para os pobres pecadores. Neste dia est&atilde;o abertas as entranhas da Minha Miseric&oacute;rdia. Derramo todo um mar de gra&ccedil;as sobre aquelas almas que se aproximam da fonte da Minha Miseric&oacute;rdia&quot;. N&atilde;o desvie sua aten&ccedil;&atilde;o de Jesus por nada, toda sua aten&ccedil;&atilde;o seja para Jesus, o centro de nossas vidas. <\/p>\n<p>  <em>&ldquo;1-Ouvi a palavra do SENHOR, magistrados de Sodoma! Prestai aten&ccedil;&atilde;o &agrave; Lei do nosso Deus, povo de Gomorra! 15-Quando estendeis as m&atilde;os para mim, desvio o meu olhar. Ainda que multipliqueis as ora&ccedil;&otilde;es, de forma alguma atenderei. &Eacute; que vossas m&atilde;os est&atilde;o sujas de sangue. 16.Lavai-vos, limpai-vos, tirai da minha vista as injusti&ccedil;as que praticais. Parai de fazer o mal, 17.aprendei a fazer o bem, buscai o que &eacute; correto, defendei o direito do oprimido, fazei justi&ccedil;a para o &oacute;rf&atilde;o, defendei a causa da vi&uacute;va. 18.Depois, vinde, podemos discutir, &mdash; diz o SENHOR. Se vossos pecados forem vermelhos como escarlate, ficar&atilde;o brancos como a neve, se vermelhos como a p&uacute;rpura, ficar&atilde;o iguais &agrave; l&atilde;. 19.Se quiserdes obedecer, continuareis comendo as coisas boas do pa&iacute;s. 20.Se n&atilde;o quiserdes, por&eacute;m, e me irritardes, v&oacute;s &eacute; que sereis comidos pela espada, &mdash; assim falou a boca do SENHOR&rdquo; <\/em>(Isa&iacute;as 1,10;15-20).<\/p>\n<p>  <strong>No domingo da miseric&oacute;rdia nenhuma comporta do c&eacute;u est&aacute; fechada, &eacute; o ref&uacute;gio dos pecadores, por isso Jesus os atrai<\/strong>, por isso vem muitas pessoas aqui. Jesus disse &agrave; irm&atilde; Faustina: &quot;Ainda que a alma esteja em decomposi&ccedil;&atilde;o &#8211; como um cad&aacute;ver, e ainda que humanamente j&aacute; n&atilde;o haja possibilidade de restaura&ccedil;&atilde;o e tudo se encontre perdido, as coisas n&atilde;o s&atilde;o assim para Deus.&quot; N&oacute;s somos pequenos demais para compreendermos a grandeza e a miseric&oacute;rdia de Deus, tudo saiu de suas entranhas, a festa da miseric&oacute;rdia saiu de suas entranhas. A humanidade n&atilde;o ter&aacute; paz enquanto n&atilde;o se voltar a fonte da miseric&oacute;rdia de Jesus. As promessas de Deus nas Sagradas Escrituras s&atilde;o: v.18 <em>Se vossos pecados forem vermelhos como escarlate, ficar&atilde;o brancos como a neve, se vermelhos como a p&uacute;rpura, ficar&atilde;o iguais &agrave; l&atilde;. 19.Se quiserdes obedecer, continuareis comendo as coisas boas do pa&iacute;s.<\/em><\/p>\n<div id=\"foto\" style=\"margin: 0pt auto;padding: 10px 10px 10px 0px;width: 370px;float: none\">\n<div id=\"foto\"><!--ABRE LINK DA FOTO--><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.cancaonova.com\/portal\/arquivos\/fotos\/2009\/abril\/18_eventos_0004.jpg\" border=\"0\" width=\"370\" height=\"250\" \/><!--FECHA LINK DA FOTO--><\/div>\n<div id=\"texto\"><!--TEXTO DA FOTO-->&#039;O milagre da miseric&oacute;rdia&#039;<!--TEXTO DA FOTO--><\/div>\n<div id=\"credito\"><!--CREDITO DA FOTO-->Foto: Robson Siqueira<!--CREDITO DA FOTO--><\/div>\n<\/div>\n<div align=\"center\"><a href=\"http:\/\/www.flickr.com\/photos\/cancaonova\/sets\/72157616982359540\/\" target=\"_blank\" title=\"Fotos\"><strong><font color=\"#0033cc\">+ Fotos no Flick<\/font><font color=\"#ff0099\">r<\/font><\/strong><\/a><\/div>\n<p>  Este ano &eacute; para n&oacute;s um ano de gra&ccedil;a, &eacute; um ano que Deus marcou para n&oacute;s como um ano de gra&ccedil;as e b&ecirc;n&ccedil;&atilde;os. Eu estou proclamando no nome de Jesus, este &eacute; um ano de gra&ccedil;as, n&atilde;o sabemos quanto tempo durar&aacute; este tempo de miseric&oacute;rdia, por&eacute;m tempo &eacute; coisa de gente, que usa rel&oacute;gio. Para Deus n&atilde;o h&aacute; tempo, pois para Deus o tempo &eacute; sempre hoje.<\/p>\n<p>  Proclamamos na Missa a segunda vinda de Jesus, os ap&oacute;stolos esperavam a vinda de Jesus, e Ele prometeu o Esp&iacute;rito Santo. Quando Jesus voltou para o c&eacute;u,os ap&oacute;stolos ficaram olhando para o alto, e o anjo lhes disse: <em>&quot;n&atilde;o fiqueis a&iacute; parado olhando para o alto, pois Aquele que foi, voltar&aacute; glorioso&quot;<\/em> (cf. Atos 1,9-11), estamos esperando h&aacute; 2008 anos a vinda de Cristo. Jesus n&atilde;o voltou ainda pois estamos no tempo da miseric&oacute;rdia, o maior atributo de Deus &eacute; ser miseric&oacute;rdia, estamos num tempo que pode acabar hoje e entrarmos no tempo da justi&ccedil;a.<\/p>\n<p>  Ricardo S&aacute;, disse: Agora &eacute; o tempo da miseric&oacute;rdia, hoje &eacute; o tempo, para Deus sempre o tempo &eacute; agora, para minha vida, minha fam&iacute;lia, meu casamento, meus irm&atilde;os e irm&atilde;s, hoje, agora, neste momento &eacute; tempo de miseric&oacute;rdia, eu quero eu aceito. Vem Jesus misericordioso, envolve-nos, salva-nos.   <\/p>\n<p><em><br \/>Transcri&ccedil;&atilde;o e adapta&ccedil;&atilde;o:Elcka Torres<\/em><\/p>\n<p><\/p>\n<hr \/>\n<div align=\"center\"><font size=\"2\"><strong>ADQUIRA ESTA PALESTRA PELO TELEFONE<br \/> (12) 3186 2600 <\/strong><\/font><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Eliana S&aacute; Foto: Robson Siqueira Neste ano estamos comemorando a oitava festa da miseric&oacute;rdia, na Can&ccedil;&atilde;o Nova, as gra&ccedil;as j&aacute; est&atilde;o sendo derramadas porque Jesus est&aacute; no meio de n&oacute;s. Jesus disse &agrave; irm&atilde; Faustina: &quot;Desejo que a Festa da&#8230;<\/p>\n","protected":false},"author":114,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7],"tags":[],"modified_by":"","_links":{"self":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/5434"}],"collection":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/users\/114"}],"replies":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/comments?post=5434"}],"version-history":[{"count":1,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/5434\/revisions"}],"predecessor-version":[{"id":5435,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/5434\/revisions\/5435"}],"wp:attachment":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media?parent=5434"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/categories?post=5434"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/tags?post=5434"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}