{"id":56577,"date":"2020-03-19T16:30:23","date_gmt":"2020-03-19T19:30:23","guid":{"rendered":"https:\/\/admin-canais.cancaonova.com\/eventos\/?p=56577"},"modified":"2021-08-09T15:57:11","modified_gmt":"2021-08-09T18:57:11","slug":"sao-jose-homem-docil-vontade-de-deus","status":"publish","type":"post","link":"https:\/\/admin-canais.cancaonova.com\/eventos\/quinta---feira-de-adoracao\/pregacoes\/sao-jose-homem-docil-vontade-de-deus\/","title":{"rendered":"S\u00e3o Jos\u00e9, homem d\u00f3cil \u00e0 vontade de Deus"},"content":{"rendered":"<div id=\"attachment_56584\" style=\"width: 279px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-56584\" class=\"wp-image-56584 size-full\" src=\"https:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2020\/03\/fagner.jpg\" alt=\"\" width=\"269\" height=\"329\" srcset=\"https:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2020\/03\/fagner.jpg 269w, https:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2020\/03\/fagner-245x300.jpg 245w\" sizes=\"(max-width: 269px) 100vw, 269px\" \/><p id=\"caption-attachment-56584\" class=\"wp-caption-text\">Fagner Mendon\u00e7a | Foto: Larissa Ferreira\/cancaonova.com<\/p><\/div>\n<p><span style=\"font-weight: 400\">S\u00e3o Jos\u00e9 foi o escolhido de Deus para cumprir t\u00e3o sublime miss\u00e3o. S\u00e3o Jos\u00e9, patrono da nossa Igreja, tinha ao seu lado, Maria, a Bem-aventurada, a Escolhida, a Ave cheia de gra\u00e7a; e o Salvador, Emanuel. Entre esses dois grandes, estava o carpinteiro, t\u00e3o simples e justo.<\/span><\/p>\n<p><span style=\"font-weight: 400\">O Anjo fez o an\u00fancio, primeiro, \u00e0 Maria, e somente depois Jos\u00e9 ficou sabendo o que estava acontecendo. A partir de ent\u00e3o, os C\u00e9us anunciaram a Jos\u00e9 tudo o que deveria ser feito.<\/span><\/p>\n<h2><span style=\"font-weight: 400\">Tamanha era a humildade de S\u00e3o Jos\u00e9<\/span><\/h2>\n<p><span style=\"font-weight: 400\">Era preciso que um homem assumisse tamanha miss\u00e3o, e ele foi o escolhido por Deus. S\u00e3o Jos\u00e9 \u00e9 o terror dos dem\u00f4nios porque ele recebeu de Deus os maiores tesouros: <a href=\"https:\/\/formacao.cancaonova.com\/espiritualidade\/oracao\/oracao-sagrada-familia-de-sao-joao-paulo-ii\/\" target=\"_blank\" rel=\"noopener\">Maria e Jesus<\/a>.<\/span><\/p>\n<h3><b>A simplicidade de S\u00e3o Jos\u00e9<\/b><\/h3>\n<p><span style=\"font-weight: 400\">Se pela desobedi\u00eancia de <a href=\"https:\/\/formacao.cancaonova.com\/igreja\/doutrina\/adao-e-eva-existiram-de-verdade\/\" target=\"_blank\" rel=\"noopener\">Ad\u00e3o e Eva<\/a> o pecado entrou no mundo, pela obedi\u00eancia e simplicidade de S\u00e3o Jos\u00e9, a salva\u00e7\u00e3o entrou no mundo.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Deus quis que Jesus nascesse de uma fam\u00edlia, do fruto de um amor, da entrega de duas pessoas, por isso, essa fam\u00edlia n\u00e3o podia ser qualquer uma. Jos\u00e9 era um homem de Deus, tinha familiaridade, intimidade e proximidade com Ele.<\/span><\/p>\n<h3><span style=\"font-weight: 400\">A Palavra meditada est\u00e1 em Mateus 1,18-24:<\/span><\/h3>\n<p><i><span style=\"font-weight: 400\">&#8220;Eis como nasceu Jesus Cristo: Maria, sua m\u00e3e, estava desposada com Jos\u00e9. Antes de coabitarem, aconteceu que ela concebeu por virtude do Esp\u00edrito Santo. Jos\u00e9, seu esposo, que era homem de bem, n\u00e3o querendo difam\u00e1-la, resolveu rejeit\u00e1-la secretamente. Enquanto assim pensava, eis que um anjo do Senhor lhe apareceu em sonhos e lhe disse: \u2018Jos\u00e9, filho de Davi, n\u00e3o temas receber Maria por esposa, pois o que nela foi concebido vem do Esp\u00edrito Santo. Ela dar\u00e1 \u00e0 luz um filho, a quem por\u00e1s o nome de Jesus, porque ele salvar\u00e1 o seu povo de seus pecados\u2019. Despertando, Jos\u00e9 fez como o anjo do Senhor lhe havia mandado e recebeu em sua casa sua esposa\u201d.<\/span><\/i><\/p>\n<p><span style=\"font-weight: 400\">Ao acordar, Jos\u00e9 cumpriu com a vontade de Deus. Pela sua docilidade, colheu dos seus sonhos os planos de Deus.<\/span><\/p>\n<p><strong>Confira mais:<\/strong><br \/>\n<a href=\"https:\/\/santo.cancaonova.com\/santo\/sao-jose-protetor-da-sagrada-familia\/\" target=\"_blank\" rel=\"noopener\">.:Conhe\u00e7a a hist\u00f3ria de S\u00e3o Jos\u00e9<\/a><br \/>\n<a href=\"https:\/\/formacao.cancaonova.com\/igreja\/santos\/o-nosso-pai-sao-jose\/\" target=\"_blank\" rel=\"noopener\">.:S\u00e3o Jos\u00e9, o nosso pai<\/a><br \/>\n<a href=\"https:\/\/musica.cancaonova.com\/singles\/cancao-simples-jose-na-voz-de-eugenio-jorge\/\" target=\"_blank\" rel=\"noopener\">.:Can\u00e7\u00e3o Simples Jos\u00e9 na voz de Eug\u00eanio Jorge<\/a><\/p>\n<h3><b>O encontro de f\u00e9<\/b><\/h3>\n<p><span style=\"font-weight: 400\"><a href=\"https:\/\/formacao.cancaonova.com\/nossa-senhora\/\" target=\"_blank\" rel=\"noopener\">Nossa Senhora<\/a> deu o Seu \u2018sim\u2019 e S\u00e3o Jos\u00e9 tamb\u00e9m deu \u2018sim\u2019; era preciso muito amor para viver tudo isso e, por meio da docilidade de ambos, houve esse encontro de f\u00e9.<\/span><\/p>\n<p><span style=\"font-weight: 400\">S\u00e3o Jos\u00e9 que tinha tantos sonhos, entregou tudo para viver a vontade de Deus. Os sonhos de S\u00e3o Jos\u00e9 n\u00e3o eram ruins, eram dignos, mas Deus tinha planos maiores para ele.<\/span><\/p>\n<p><span style=\"font-weight: 400\">S\u00e3o Jos\u00e9 foi escravo das promessas de Deus. E o que \u00e9 essa escravid\u00e3o? \u00c9 colocar-se debaixo das promessas de Deus, pois, quando estamos debaixo das promessas de Deus, estamos protegidos.<\/span><\/p>\n<p><span style=\"font-weight: 400\">N\u00e3o tenha medo de ser d\u00f3cil \u00e0 vontade de Deus. Tenha a coragem de ser como S\u00e3o Jos\u00e9: escravo das <a href=\"https:\/\/formacao.cancaonova.com\/espiritualidade\/devocao\/as-12-promessas-do-sagrado-coracao-de-jesus\/\" target=\"_blank\" rel=\"noopener\">promessas de Deus<\/a>.<\/span><\/p>\n<h3><b>Sejamos d\u00f3ceis<\/b><\/h3>\n<p><span style=\"font-weight: 400\">S\u00e3o Jos\u00e9 \u00e9 pouco citado nas Sagradas Escrituras, mas tamanha responsabilidade \u00e9 preciso ter para falar sobre esse homem t\u00e3o calado e que teve uma grande miss\u00e3o.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Que S\u00e3o Jos\u00e9 nos ensine a sermos d\u00f3ceis \u00e0 <a href=\"https:\/\/formacao.cancaonova.com\/espiritualidade\/vida-de-oracao\/voce-tem-coragem-para-seguir-vontade-de-deus\/\" target=\"_blank\" rel=\"noopener\">vontade de Deus<\/a>, ele que \u00e9 o grande modelo de santidade para todos n\u00f3s. Fa\u00e7a a experi\u00eancia de deixar-se ser conduzido pelo homem que aceitou Maria e que tanto ensinou a Jesus.<\/span><\/p>\n<p><em><span style=\"font-weight: 400\">Transcri\u00e7\u00e3o e adapta\u00e7\u00e3o: Karina Silva.<\/span><\/em><\/p>\n<p><span style=\"font-weight: 400\"><br \/>\n<a href=\"http:\/\/bit.ly\/bndcn01\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-56587\" src=\"https:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2020\/03\/4.png\" alt=\"\" width=\"728\" height=\"90\" srcset=\"https:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2020\/03\/4.png 728w, https:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/14\/2020\/03\/4-300x37.png 300w\" sizes=\"(max-width: 728px) 100vw, 728px\" \/><\/a><br \/>\n<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>S\u00e3o Jos\u00e9 foi o escolhido de Deus para cumprir t\u00e3o sublime miss\u00e3o. S\u00e3o Jos\u00e9, patrono da nossa Igreja, tinha ao seu lado, Maria, a Bem-aventurada, a Escolhida, a Ave cheia de gra\u00e7a; e o Salvador, Emanuel. Entre esses dois grandes,&#8230;<\/p>\n","protected":false},"author":387,"featured_media":56582,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7],"tags":[],"modified_by":"aliane","_links":{"self":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/56577"}],"collection":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/users\/387"}],"replies":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/comments?post=56577"}],"version-history":[{"count":8,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/56577\/revisions"}],"predecessor-version":[{"id":59343,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/56577\/revisions\/59343"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media\/56582"}],"wp:attachment":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media?parent=56577"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/categories?post=56577"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/tags?post=56577"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}