{"id":5687,"date":"2006-05-28T11:30:00","date_gmt":"2006-05-28T14:30:00","guid":{"rendered":"http:\/\/admin-canais.cancaonova.com\/eventos\/?p=5687"},"modified":"2014-08-13T02:55:11","modified_gmt":"2014-08-13T05:55:11","slug":"ascensao-retorno-para-o-pai","status":"publish","type":"post","link":"https:\/\/admin-canais.cancaonova.com\/eventos\/pregacoes\/ascensao-retorno-para-o-pai\/","title":{"rendered":"Ascens\u00e3o, retorno para o Pai"},"content":{"rendered":"<p>Dom Fernando Figueiredo, bispo de Santo Amaro\/SP, presidiu a Santa Missa, neste domingo, na sede da Can\u00e7\u00e3o Nova, em Cachoeira Paulista. Padre Jonas Abib, Padre Marcelo Rossi, Dona Lu Alckmin, Gabriel Chalita, dentre outras autoridades tamb\u00e9m estavam presentes e rezaram com milhares de pessoas.<\/p>\n<p><b>Homilia de Dom Fernando, abaixo:<\/b><\/p>\n<p><b><a href=\"http:\/\/www.webhdtv.net\/eventos\/2006\/kairos\/homilia_domfernando_28_05_06.asx\"><font color=\"#0033cc\">.: <u>Assista<\/u> essa homilia, na \u00edntegra<\/font><\/a> <\/b><\/p>\n<p><img decoding=\"async\" src=\"http:\/\/www.cancaonova.com\/portal\/canais\/eventos\/novoeventos\/fotos\/kairos\/dom_figueiredo2805_right.jpg\" align=\"right\">Hoje \u00e9 a festa da Ascen\u00e7\u00e3o de Nosso Senhor Jesus Cristo. <\/p>\n<p>Ele veio at\u00e9 n\u00f3s e n\u00e3o deixou de estar no c\u00e9u. O que ser\u00e1 que Ele quis dizer com essa palavra?<br \/>\nSanto Agostinho, explica que \u00e9 porque Ele \u00e9 o pr\u00f3prio Deus no meio de n\u00f3s. Por isso, Jesus vem at\u00e9 n\u00f3s, Ele que \u00e9 o Filho do Alt\u00edssimo. <\/p>\n<p>Jesus nos revela em sua vida p\u00fablica que Deus \u00e9 o nosso Pai, um Pai misericordioso, a pr\u00f3pria miseric\u00f3rdia. <\/p>\n<p>Queremos cada vez mais reconhec\u00ea-Lo como nosso Pai, mas s\u00f3 podemos O acolher assim quando reconhecemos Jesus como Deus.<\/p>\n<p>Ser\u00e1 que dever\u00edamos levar \u00e0s pessoas uma mensagem de des\u00e2nimo? Claro que n\u00e3o! Porque se reconhecemos como nosso Pai, ent\u00e3o n\u00e3o podemos ser tristes. <b>Quando voc\u00ea acolhe Jesus como Senhor, voc\u00ea acolhe Deus como seu Pai. Essa \u00e9 a revela\u00e7\u00e3o mais elevada que podemos ter.<\/b> <\/p>\n<p>O que \u00e9 acolher Jesus? Maria guardava tudo em seu cora\u00e7\u00e3o e meditava, ela deixava a palavra de Jesus entrar em seu interior. Olhemos para este Centro de Evangeliza\u00e7\u00e3o lotado. N\u00e3o \u00e9 porque as pessoas acolheram a palavra de Jesus que ele est\u00e1 assim? Neste local muitos foram transformados. Voc\u00eas, que est\u00e3o aqui, hoje, acolheram Jesus e se transformaram.<br \/>\nfunction open_gl(param){window.open(\\&#8217;http:\/\/200.168.231.201\/portal\/canais\/galerias\/index.php?id=\\&#8217;+param,\\&#8217;\\&#8217;,\\&#8217;width=537, height=478, toolbar=no, status=no, menubar=no, scrollbars=no, resizable=no\\&#8217;);}<b><a href=\"open_gl(2433)\"><font color=\"#0033cc\"><b><\/p>\n<hr>\n<p>.: Galeria de fotos desta missa :.<\/p>\n<hr>\n<p><\/b><\/font><\/b><\/a><br \/>\n<img decoding=\"async\" src=\"http:\/\/www.cancaonova.com\/portal\/canais\/eventos\/novoeventos\/fotos\/kairos\/dom_figueiredo2805_left.jpg\" align=\"left\">N\u00e3o ficamos presos \u00e0s coisas materiais, mas nosso cora\u00e7\u00e3o se volta para o alto. <\/p>\n<p><b>A ascens\u00e3o de Jesus \u00e9 o nosso cora\u00e7\u00e3o voltado para o c\u00e9u, \u00e9 nosso cora\u00e7\u00e3o criando \\&#8221;asas\\&#8221; do Esp\u00edrito Santo que nos leva para o c\u00e9u.<\/b> O nosso cora\u00e7\u00e3o sobe com Jesus na Sua ascens\u00e3o. Que isso seja vivido por n\u00f3s &#8211; e sempre. <\/p>\n<p>Jesus, subindo ao c\u00e9u em retorno ao Pai, estende a sua m\u00e3o e aben\u00e7oa seus ap\u00f3stolos. E essa ben\u00e7\u00e3o de Jesus derrama a salva\u00e7\u00e3o e a paz, for\u00e7as para os seus ap\u00f3stolos e disc\u00edpulos que iriam pregar o Evangelho para todos os povos. <\/p>\n<p><b>Jesus subiu ao c\u00e9u, mas tamb\u00e9m sobe com Ele o nosso cora\u00e7\u00e3o.<\/b> N\u00f3s recebemos dele todas as b\u00ean\u00e7\u00e3os e todas as gra\u00e7as, por isso podemos dizer que a ascen\u00e7\u00e3o \u00e9 o retorno de Jesus ao c\u00e9u, a peregrina\u00e7\u00e3o de todos n\u00f3s a cada dia.<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/www.cancaonova.com\/portal\/canais\/eventos\/novoeventos\/fotos\/kairos\/homdomferkairhj.jpg\"><br \/>\nEstamos caminhando dia a dia em dire\u00e7\u00e3o ao Pai. Estamos peregrinando! Este local \u00e9 o sinal que de fato estamos em peregrina\u00e7\u00e3o. <\/p>\n<p>Que Deus aben\u00e7oe voc\u00eas e que a for\u00e7a do Esp\u00edrito Santo os guie a cada dia.<\/p>\n<p><i>Transcri\u00e7\u00e3o: Manoela Almeida<br \/>\nFotos: Maur\u00edcio Rebou\u00e7as<\/i><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dom Fernando Figueiredo, bispo de Santo Amaro\/SP, presidiu a Santa Missa, neste domingo, na sede da Can\u00e7\u00e3o Nova, em Cachoeira Paulista. Padre Jonas Abib, Padre Marcelo Rossi, Dona Lu Alckmin, Gabriel Chalita, dentre outras autoridades tamb\u00e9m estavam presentes e rezaram&#8230;<\/p>\n","protected":false},"author":114,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7],"tags":[],"modified_by":"","_links":{"self":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/5687"}],"collection":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/users\/114"}],"replies":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/comments?post=5687"}],"version-history":[{"count":1,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/5687\/revisions"}],"predecessor-version":[{"id":5688,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/5687\/revisions\/5688"}],"wp:attachment":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media?parent=5687"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/categories?post=5687"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/tags?post=5687"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}