{"id":5926,"date":"2008-02-24T08:00:00","date_gmt":"2008-02-24T11:00:00","guid":{"rendered":"http:\/\/admin-canais.cancaonova.com\/eventos\/?p=5926"},"modified":"2014-08-13T03:05:14","modified_gmt":"2014-08-13T06:05:14","slug":"filho-presente-de-deus","status":"publish","type":"post","link":"https:\/\/admin-canais.cancaonova.com\/eventos\/pregacoes\/filho-presente-de-deus\/","title":{"rendered":"Filho, presente de Deus"},"content":{"rendered":"<div id=\"foto\" style=\"margin: 0pt auto;padding: 10px 10px 10px 0px;width: 180px;float: left\">\n<div id=\"foto\"><!--ABRE LINK DA FOTO--><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.cancaonova.com\/portal\/arquivos\/fotos\/2008\/fevereiro\/24_kairos-002.jpg\" border=\"0\" width=\"180\" height=\"220\" \/><!--FECHA LINK DA FOTO--><\/div>\n<div id=\"texto\"><!--TEXTO DA FOTO-->Padre Alir Sanagiotto, scj<!--TEXTO DA FOTO--><\/div>\n<div id=\"credito\"><!--CREDITO DA FOTO-->Foto: Robson Siqueira<!--CREDITO DA FOTO--><\/div>\n<\/div>\n<p><em>&lsquo;Vede, os filhos s&atilde;o um dom de Deus: &eacute; uma recompensa o fruto das entranhas&rsquo; <\/em>(Salmo 126;3).<\/p>\n<p> A B&iacute;blia diz que os filhos s&atilde;o b&ecirc;n&ccedil;&atilde;os de Deus. Um filho vem ao mundo para trazer alegria. <\/p>\n<p> O momento inicial da nossa vida n&atilde;o come&ccedil;a quando o espermatoz&oacute;ide e o &oacute;vulo se fundem, mas quando o homem e mulher t&ecirc;m a rela&ccedil;&atilde;o sexual. <strong>A rela&ccedil;&atilde;o conjugal &eacute; importante para o homem, para mulher e para Deus porque &eacute; o meio que Ele usa para a cria&ccedil;&atilde;o. <\/strong><\/p>\n<p> Deus escolheu nosso pai e nossa m&atilde;e para nos dar de presente a eles. Deus lhes d&aacute; &ndash; como recompensa do amor &ndash; o filho. Mas, infelizmente, as pessoas hoje n&atilde;o querem ter filhos, calculam filho como n&uacute;meros, como gastos. <\/p>\n<p><em> &#039;Chegando eles a Betsaida, trouxeram-lhe um cego e suplicaram-lhe que o tocasse. Jesus tomou o cego pela m&atilde;o e levou-o para fora da aldeia. P&ocirc;s-lhe saliva nos olhos e, impondo-lhe as m&atilde;os, perguntou-lhe: V&ecirc;s alguma coisa?  O cego levantou os olhos e respondeu: Vejo os homens como &aacute;rvores que andam.  Em seguida, Jesus lhe imp&ocirc;s as m&atilde;os nos olhos e ele come&ccedil;ou a ver e ficou curado, de modo que via distintamente de longe. E mandou-o para casa, dizendo-lhe: N&atilde;o entres nem mesmo na aldeia&#039;<\/em> (Marcos 8,22-24). <\/p>\n<p><strong> Se voc&ecirc; est&aacute; com um filho doente, drogado, procure a Jesus, Ele tem a solu&ccedil;&atilde;o. <\/strong><\/p>\n<p> Na rela&ccedil;&atilde;o familiar &eacute; importante o toque, o estar pr&oacute;ximo. Se em uma fam&iacute;lia os pais abra&ccedil;assem e beijassem os filhos todos os dias, tudo seria diferente. Jesus quase n&atilde;o falou nada com este cego, mas o toca e age. Na nossa fam&iacute;lia, muitas vezes, o mais importante s&atilde;o as atitudes e o toque. <\/p>\n<p> Minha m&atilde;e, antes de dormir, passava de quarto em quarto ajeitava as cobertas e n&atilde;o deixava de nos ajeitar na cama. Ali eu me sentia um filho e amado.<\/p>\n<p> Como faz falta o toque, o carinho de homem, o beijo de homem. Lembro que um dia estava indo &agrave; Santa Missa e de repente encontrei com meu tio que me beijou no rosto, esse fato me marcou profundamente. Por isso, homem, n&atilde;o seja duro, ame, beije e abrace os seus filhos, eles precisam do seu toque. <\/p>\n<div id=\"foto\" style=\"margin: 0pt auto;width: 370px;padding-left: 0px;padding-top: 10px;padding-bottom: 10px;float: none\">\n<div id=\"texto\"><!--ABRE LINK DA FOTO--><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.cancaonova.com\/portal\/arquivos\/fotos\/2008\/fevereiro\/24_kairos-003.jpg\" border=\"0\" width=\"370\" height=\"250\" \/><!--FECHA LINK DA FOTO--><br \/>&#039;O filho bem educado &eacute; aquele que tem o mesmo comportamento na frente ou na aus&ecirc;ncia dos pais&#039;  <!--TEXTO DA FOTO--><\/div>\n<div id=\"credito\"><!--CREDITO DA FOTO-->Foto: Robson Siqueira<!--CREDITO DA FOTO--><\/div>\n<\/div>\n<p>Talvez o homem tenha dificuldade de beijar os filhos, fa&ccedil;a isso por amor, toque seus filhos. <em>&lsquo;Jesus tomou o cego pela m&atilde;o&rsquo;<\/em>, Jesus se aproxima, pega na m&atilde;o. O toque &eacute; muito significativo, &eacute; importante. <\/p>\n<p> Cada filho &eacute; &uacute;nico e especial, ent&atilde;o tenha momentos com cada um, evite corrigir seus filhos na presen&ccedil;a dos outros. Jesus pegou na m&atilde;o e o levou para longe de todos, teve um momento reservado com ele. O erro da educa&ccedil;&atilde;o &eacute; muitas palavras e poucas atitudes. <\/p>\n<p> Hoje se fala tanto em colocar limites, mas, o mais importante do que limites &eacute; incentivar as crian&ccedil;as. Elogie seus filhos. Pai e m&atilde;e, voc&ecirc;s s&atilde;o importantes para seus filhos, s&atilde;o refer&ecirc;ncias. <strong>Seu filho n&atilde;o &eacute; um galho, seu filho &eacute; fruto que vai se transformar em outra &aacute;rvore.<\/strong><\/p>\n<p>Quantas m&atilde;es que t&ecirc;m filhos com 18 anos e ainda os trata como crian&ccedil;as, tirando-lhes a oportunidade de crescerem, fazendo-os dependentes. <\/p>\n<p> Seja &quot;gasolina&quot;, acenda o fogo. Seja incentivo. Se seu filho deseja aprender a fazer comida, incentive-o. Se ele quer fazer um arroz, ainda que queimado, deixe-o fazer. <\/p>\n<p><em> &lsquo;Jesus lhe imp&ocirc;s as m&atilde;os nos olhos e ele come&ccedil;ou a ver e ficou curado&rsquo;<\/em>. Imponha as m&atilde;os sobre os seus filhos, reze por eles, pois a ora&ccedil;&atilde;o tem poder. Pe&ccedil;a o Esp&iacute;rito Santo sobre eles. <\/p>\n<p>  O filho bem educado &eacute; aquele que tem o mesmo comportamento na frente ou na aus&ecirc;ncia dos pais.  Eduque seu filho, ensine &#039;<em>que tudo lhe &eacute; permitido, mas nem tudo conv&eacute;m&#039;. <\/em> <\/p>\n<p> <em>Transcri&ccedil;&atilde;o: Elcka Torres<\/em><br \/><em><em><em><br \/><\/em><\/em><\/em><\/p>\n<hr width=\"100%\" size=\"2\" \/>\n<p align=\"center\">&nbsp;<font size=\"2\"><strong>ADQUIRA ESTA PREGA&Ccedil;AO PELO TELEFONE<\/strong><\/font><br \/><font size=\"2\"><strong>(12) 3186-2600<\/strong><\/font><em><em><em><br \/><\/em><\/em><\/em><\/p>\n<hr width=\"100%\" size=\"2\" \/>\n<p align=\"center\">&nbsp;<font size=\"2\"><strong><br \/><\/strong><\/font><font size=\"2\"><\/font><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Padre Alir Sanagiotto, scj Foto: Robson Siqueira &lsquo;Vede, os filhos s&atilde;o um dom de Deus: &eacute; uma recompensa o fruto das entranhas&rsquo; (Salmo 126;3). A B&iacute;blia diz que os filhos s&atilde;o b&ecirc;n&ccedil;&atilde;os de Deus. Um filho vem ao mundo para&#8230;<\/p>\n","protected":false},"author":114,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7],"tags":[],"modified_by":"","_links":{"self":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/5926"}],"collection":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/users\/114"}],"replies":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/comments?post=5926"}],"version-history":[{"count":1,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/5926\/revisions"}],"predecessor-version":[{"id":5927,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/5926\/revisions\/5927"}],"wp:attachment":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media?parent=5926"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/categories?post=5926"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/tags?post=5926"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}