{"id":5966,"date":"2008-05-18T06:00:00","date_gmt":"2008-05-18T09:00:00","guid":{"rendered":"http:\/\/admin-canais.cancaonova.com\/eventos\/?p=5966"},"modified":"2014-08-13T03:06:41","modified_gmt":"2014-08-13T06:06:41","slug":"jovem-escolhe-pois-a-vida","status":"publish","type":"post","link":"https:\/\/admin-canais.cancaonova.com\/eventos\/pregacoes\/jovem-escolhe-pois-a-vida\/","title":{"rendered":"Jovem, escolhe pois a vida!"},"content":{"rendered":"<div id=\"foto\" style=\"padding-right: 5px;padding-left: 0px;float: left;padding-bottom: 5px;margin: 0pt auto;width: 180px;padding-top: 5px\">\n<div id=\"foto\"><!--ABRE LINK DA FOTO--><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.cancaonova.com\/portal\/arquivos\/fotos\/2008\/maio\/18_eventos-003.jpg\" border=\"0\" width=\"180\" height=\"220\" \/><!--FECHA LINK DA FOTO--><\/div>\n<div id=\"texto\"><!--TEXTO DA FOTO-->Padre L&aacute;zaro<!--TEXTO DA FOTO--><\/div>\n<div id=\"credito\"><!--CREDITO DA FOTO-->Foto: Wesley Almeida<!--CREDITO DA FOTO--><\/div>\n<\/div>\n<p>Hoje a Igreja celebra o mist&eacute;rio da Sant&iacute;ssima Trindade. E este mist&eacute;rio quer nos lembrar que este amor de Deus que se manifesta no Pai, no Filho e no Esp&iacute;rito Santo &eacute; t&atilde;o bonito, &eacute; t&atilde;o grande que n&oacute;s n&atilde;o poderemos alcan&ccedil;&aacute;-lo. Nossa racionalidade nunca poder&aacute; alcan&ccedil;ar. Deus quis ser comunit&aacute;rio, mas n&oacute;s temos tanta dificuldade em nos unirmos. <strong>N&oacute;s precisamos olhar para a Sant&iacute;ssima Trindade e acreditar que podemos ser o que Jesus sonhou: um s&oacute; rebanho<\/strong>.<\/p>\n<p>N&oacute;s podemos experimentar as maravilhas da Trindade. A come&ccedil;armos pela juventude, n&oacute;s queremos ser comunidade, queremos viver a unidade. O sonho de Deus &eacute; que haja jovens novos construindo a civiliza&ccedil;&atilde;o do amor.<\/p>\n<p>O Papa em sua visita ao Brasil, usou o exemplo do jovem rico, que poderia ter seguido os passos de Jesus e ser um &oacute;timo mission&aacute;rio, mas infelizmente n&atilde;o teve for&ccedil;a para abandonar-se. Hoje Deus nos pede <em>&ldquo;ousadia&rdquo;<\/em>.<\/p>\n<p>N&oacute;s vemos as not&iacute;cias de pessoas que tiram sua pr&oacute;pria vida, pois est&atilde;o desesperadas, mas olhando para o calv&aacute;rio, olhando para a cruz, temos a inspira&ccedil;&atilde;o em dizer: <em>&ldquo;eu quero viver&rdquo;<\/em>. S&oacute; podemos compreender a vida, a morte, o &lsquo;por que&rsquo; estamos aqui, nossa juventude e a nossa exist&ecirc;ncia aos p&eacute;s da cruz de Cristo. <\/p>\n<p>Quero retomar o texto que deu toda a fundamenta&ccedil;&atilde;o para a Campanha da Fraternidade deste ano. Deuteron&ocirc;mio 30, 19 e seguintes, onde est&aacute; escrito: <\/p>\n<p><em>&ldquo;Cito hoje o c&eacute;u e a terra como testemunhas contra v&oacute;s de que vos propus a vida e a morte, a ben&ccedil;&atilde;o e a maldi&ccedil;&atilde;o. Escolhe pois a vida para que vivas tu e teus descendentes, amando ao Senhor teu Deus, obedecendo a sua voz e apegando-te a Ele, pois Ele &eacute; a tua vida e prolonga os teus dias, afim de que habites na terra que o Senhor jurou dar aos teus pais Abra&atilde;o, Isaac e Jac&oacute;.&rdquo;<\/em><\/p>\n<p>Hoje, como sempre, o Reino de Deus e o mundo caminham juntos, mas a proposta do Reino de Deus &eacute; uma proposta de vida. O que diferenciou Jesus foi justamente a proposta de um reino, reino de vida que Ele trazia. Jesus veio nos falar do Reino de Deus que n&atilde;o cai como um pacote sobre n&oacute;s, mas sim come&ccedil;a em n&oacute;s, acontece em n&oacute;s e o primeiro lugar em que o Reino de Deus precisa ser instaurado &eacute; em nossos cora&ccedil;&otilde;es. <\/p>\n<p><strong>A transforma&ccedil;&atilde;o do mundo come&ccedil;a pela nossa, somente transformando o nosso cora&ccedil;&atilde;o n&oacute;s iremos transformar o mundo. <\/strong>O retrato do mundo hoje &eacute; um mundo que est&aacute; cada vez mais distante de Deus, &eacute; um mundo que pouco fala de Deus, que desvaloriza aquilo que &eacute; pr&oacute;prio do cora&ccedil;&atilde;o de Deus, como a vida. Quantos assassinatos acontecem por nada. <\/p>\n<p>Quem de n&oacute;s n&atilde;o se apavora ouvindo falar sobre os &iacute;ndices de aborto no Brasil? Na natureza os animais protegem seus filhotes, tem bichos organizados que at&eacute; se p&otilde;e em guarda para proteger a f&ecirc;mea que est&aacute; chocando, mas a pessoa humana consegue tirar a vida de outro ser.<\/p>\n<div id=\"foto\" style=\"padding-right: 0px;padding-left: 0px;float: none;padding-bottom: 5px;margin: 0pt auto;width: 370px;padding-top: 5px\">\n<div id=\"foto\"><!--ABRE LINK DA FOTO--><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.cancaonova.com\/portal\/arquivos\/fotos\/2008\/maio\/18_eventos-002.jpg\" border=\"0\" width=\"370\" height=\"250\" \/><!--FECHA LINK DA FOTO--><\/div>\n<div id=\"texto\"><!--TEXTO DA FOTO-->&#039;O sonho de Deus &eacute; que haja jovens novos construindo a civiliza&ccedil;&atilde;o do amor&#039;<!--TEXTO DA FOTO--><\/div>\n<div id=\"credito\"><!--CREDITO DA FOTO-->Foto: Wesley Almeida<!--CREDITO DA FOTO--><\/div>\n<\/div>\n<p>Deus fez todas as coisas e fez tudo pela palavra. Deus disse: &lsquo;Fa&ccedil;a-se o sol, fa&ccedil;a-se a terra&rsquo;, e as coisas foram sendo criadas. Mas em um determinado momento Deus usou as m&atilde;os. Pegou o barro e fez cada um de n&oacute;s. Somos vasos de barro, com todas as limita&ccedil;&otilde;es e fragilidades, mas n&oacute;s n&atilde;o somos s&oacute; isso n&atilde;o. &Eacute; a&iacute; que mora nossa dignidade. Nossa dignidade vem do sopro da vida que Deus deu a n&oacute;s. Nossa vida n&atilde;o &eacute; nossa, foi Deus quem nos deu. N&oacute;s nascemos da explos&atilde;o do amor de Deus.<\/p>\n<p>N&atilde;o somos coisas quaisquer, nossa vida &eacute; t&atilde;o preciosa que custou o pre&ccedil;o da vida de Deus. N&oacute;s devemos agradecer pela salva&ccedil;&atilde;o de Deus a n&oacute;s. Olhando para a cruz de Cristo devemos ter o sentimento de agradecimento por um amor t&atilde;o grande. Os bra&ccedil;os abertos de Cristo na cruz lembram um abra&ccedil;o, pois &eacute; como se Ele olhasse querendo abra&ccedil;ar a cada um de n&oacute;s e apesar de t&atilde;o grande amor por n&oacute;s, muitas vezes n&oacute;s preferimos ficar com o mundo. <\/p>\n<p>Todo encontro com Jesus &eacute; revolucion&aacute;rio e gera vida. N&atilde;o teve nenhum encontro em que Jesus gerou morte, todos eles geraram vida. Por exemplo, aquela mulher que foi pega em adult&eacute;rio. A vida daquela mulher mudou a partir daquele encontro. <\/p>\n<p><strong>A Igreja de Jesus Cristo confia muito em voc&ecirc;s jovens porque Deus ama muito voc&ecirc;s. voc&ecirc;s s&atilde;o prediletos, porque Deus cuida de voc&ecirc;s. <\/strong>Queridos jovens se nossas m&atilde;es est&atilde;o sempre cuidando de n&oacute;s, imagine Deus. <\/p>\n<p>Dizem tantas coisas por a&iacute; dos jovens, o mundo pode dizer muitas coisas de voc&ecirc;s, mas voc&ecirc;s n&atilde;o s&atilde;o isso que eles dizem. Voc&ecirc;s s&atilde;o esperan&ccedil;a. A nossa juventude &eacute; curt&iacute;ssima, mas ela dita o resto da vida. Se cometer um erro na juventude voc&ecirc; talvez levar&aacute; a conseq&uuml;&ecirc;ncia para o resto de sua vida. Portanto, jovem: o que voc&ecirc; est&aacute; escolhendo? As b&ecirc;n&ccedil;&atilde;os, a vida, ou as maldi&ccedil;&otilde;es?<\/p>\n<p>N&oacute;s temos que passar o suave odor de Cristo. N&oacute;s temos que levar ao mundo o Reino de Deus e n&atilde;o traz&ecirc;-lo para dentro da Igreja. N&oacute;s temos facilidade para isto. N&oacute;s conseguimos trazer sentimentos do mundo para dentro da Igreja, mas o desejo de Jesus &eacute; que saiamos no mundo levando o Reino, que preguemos a cultura da vida onde se tem pregado a cultura de morte, devemos ter alegria em sermos crist&atilde;os e n&atilde;o sermos crist&atilde;os desanimados que n&atilde;o acreditam na un&ccedil;&atilde;o que temos e em quem nos ungiu. <\/p>\n<div id=\"foto\" style=\"padding-right: 0px;padding-left: 0px;float: none;padding-bottom: 5px;margin: 0pt auto;width: 370px;padding-top: 5px\">\n<div id=\"foto\"><!--ABRE LINK DA FOTO--><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.cancaonova.com\/portal\/arquivos\/fotos\/2008\/maio\/18_eventos-001.jpg\" border=\"0\" width=\"370\" height=\"250\" \/><!--FECHA LINK DA FOTO--><\/div>\n<div id=\"texto\"><!--TEXTO DA FOTO-->&#039;Queridos jovens se nossas m&atilde;es est&atilde;o sempre cuidando de n&oacute;s, imaginem Deus!&#039;<!--TEXTO DA FOTO--><\/div>\n<div id=\"credito\"><!--CREDITO DA FOTO-->Foto: Wesley Almeida<!--CREDITO DA FOTO--><\/div>\n<\/div>\n<p>Precisamos deixar o Esp&iacute;rito Santo agir em n&oacute;s e abandonarmos aquilo que n&atilde;o &eacute; fruto do Esp&iacute;rito Santo, precisamos sair do nosso ego&iacute;smo e nos importar com os outros. No mundo afora h&aacute; muitos precisando de n&oacute;s. <strong>Quem pode matar a sede do mundo, somos n&oacute;s! Quem matar&aacute; a sede da juventude &eacute; voc&ecirc; jovem. Jovens evangelizando jovens! Quem evangelizar&aacute; as fam&iacute;lias somos n&oacute;s. <\/strong><\/p>\n<p>Nosso ego&iacute;smo nos tira o c&eacute;u, se n&oacute;s compreendermos que nossa vida &eacute; uma doa&ccedil;&atilde;o, podemos ter a certeza de que o c&eacute;u nos espera. N&oacute;s precisamos compreender que somos mendigos que temos tudo, mas n&atilde;o temos nada, temos todos, mas n&atilde;o temos ningu&eacute;m. <\/p>\n<p>Ser&aacute; muito bom chegarmos ao fim da vida e podermos dizer: <em>&ldquo;eu amei tudo que tinha que amar, eu vivi como devia viver<\/em>. Jovem se voc&ecirc; morresse hoje, ser&aacute; que isso seria seu di&aacute;rio? Devia ter amado mais, ter feito, ter visto? O passado passou e no Sangue de Cristo ele est&aacute; sepultado. Escolha ent&atilde;o a vida, n&atilde;o uma vida qualquer, mas a vida que vem de Deus. <strong>Em um mundo que ousa a morte, que brinca com a morte, em um mundo em que a vida &eacute; t&atilde;o exposta, n&oacute;s queremos dizer que nossa escolha &eacute; pela vida.<\/strong><\/p>\n<p>Esp&iacute;rito Santo repousa em n&oacute;s para que sejamos arautos, mensageiros da vida em plenitude! <\/p>\n<p><em>Transcri&ccedil;&atilde;o: Fl&aacute;vio Costa <\/em><\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<p align=\"center\"><font size=\"2\"><strong>ADQUIRA ESTA PALESTRA PELO TELEFONE:<br \/>(12) 3186 2600<\/strong><\/font><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Padre L&aacute;zaro Foto: Wesley Almeida Hoje a Igreja celebra o mist&eacute;rio da Sant&iacute;ssima Trindade. E este mist&eacute;rio quer nos lembrar que este amor de Deus que se manifesta no Pai, no Filho e no Esp&iacute;rito Santo &eacute; t&atilde;o bonito, &eacute;&#8230;<\/p>\n","protected":false},"author":114,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7],"tags":[],"modified_by":"","_links":{"self":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/5966"}],"collection":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/users\/114"}],"replies":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/comments?post=5966"}],"version-history":[{"count":1,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/5966\/revisions"}],"predecessor-version":[{"id":5967,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/5966\/revisions\/5967"}],"wp:attachment":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media?parent=5966"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/categories?post=5966"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/tags?post=5966"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}