{"id":6144,"date":"2009-05-24T08:10:00","date_gmt":"2009-05-24T11:10:00","guid":{"rendered":"http:\/\/admin-canais.cancaonova.com\/eventos\/?p=6144"},"modified":"2014-08-13T03:13:48","modified_gmt":"2014-08-13T06:13:48","slug":"vencendo-os-medos-alcancando-milagres","status":"publish","type":"post","link":"https:\/\/admin-canais.cancaonova.com\/eventos\/pregacoes\/vencendo-os-medos-alcancando-milagres\/","title":{"rendered":"Vencendo os medos, alcan\u00e7ando milagres"},"content":{"rendered":"<div id=\"foto\" style=\"margin: 0pt auto;padding: 0px 5px;width: 180px;float: right\">\n<div id=\"foto\"><!--ABRE LINK DA FOTO--><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.cancaonova.com\/portal\/arquivos\/fotos\/2009\/maio\/24_eventos_004.jpg\" border=\"0\" width=\"180\" height=\"220\" \/><!--FECHA LINK DA FOTO--><\/div>\n<div id=\"texto\"><!--TEXTO DA FOTO-->Padre F&aacute;bio<!--TEXTO DA FOTO--><\/div>\n<div id=\"credito\"><!--CREDITO DA FOTO-->Foto: Wesley Almeida<!--CREDITO DA FOTO--><\/div>\n<\/div>\n<p>Se voc&ecirc; pegar os Evangelhos, eles narram in&uacute;meros encontros de Jesus com as pessoas. Mas, por que Jesus atra&iacute;a tantas pessoas? Por que Jesus atraiu voc&ecirc;?<\/p>\n<p>  Eu n&atilde;o tenho d&uacute;vida de que &eacute; porque Ele era portador de uma palavra capaz de deter o medo. Voc&ecirc; sente medo de ser s&oacute;, de ser tra&iacute;do, de ser injusti&ccedil;ado, medo de doen&ccedil;a, medo de morrer. O medo &eacute; universal.<\/p>\n<p>  A presen&ccedil;a de Deus na hist&oacute;ria ofereceu &agrave; humanidade um bra&ccedil;o que pudesse nos sustentar no momento do medo e nos dar um alento. <\/p>\n<p>  E isso voc&ecirc; experimenta na sua carne, na sua alma. E precisa gritar por algu&eacute;m, porque n&atilde;o d&aacute; conta sozinho.<br \/> Jesus quando passava pelo povo, despertava isso. Aqueles que passavam por Jesus eram aliviados. &ldquo;Vinde a mim todos vos que estais cansados e eu vos aliviarei&rdquo;. Jesus tinha o poder de fazer a pessoa se encorajar para a vida. <\/p>\n<p>  O medo come&ccedil;a a diminuir quando somos olhados nos olhos. A psicologia nos ensina quando somos olhados do jeito certo cresce em n&oacute;s a cren&ccedil;a em n&oacute;s mesmos.<\/p>\n<p>  <strong>O olhar &eacute; o lugar da nossa seguran&ccedil;a. Se no medo n&atilde;o temos ao nosso lado quem nos ama, ou a quem olharmos, tudo se torna dif&iacute;cil.<\/strong><\/p>\n<p>  Isso que fascinava em Jesus. N&atilde;o era apenas a for&ccedil;a de um argumento, de uma prega&ccedil;&atilde;o. Mas pela for&ccedil;a de um olhar Ele penetrava na pessoa e vivia o mesmo tempo que ela. <strong>Amar &eacute; viver o tempo do outro.<\/strong><\/p>\n<p>  Minha m&atilde;e est&aacute; idosa, velhinha, lenta. Est&aacute; num tempo diferente. Eu ando depressa. Minha m&atilde;e n&atilde;o. &Agrave;s vezes eu preciso olhar para tr&aacute;s para ver onde ela est&aacute;.<\/p>\n<p>  A gente diminui o medo quando entramos no tempo do outro.<\/p>\n<p>  Voc&ecirc; est&aacute; devagar e com medo. Algu&eacute;m segura na sua m&atilde;o e diz:<em> &ldquo;N&atilde;o se preocupe, estarei ao seu lado.&rdquo;<\/em> E voc&ecirc; fala:<em> &ldquo;Mas voc&ecirc; n&atilde;o tem que ir?&rdquo;<\/em> E ouve: <em>&ldquo;Tenho que ir, mas decidi ficar com voc&ecirc;&rdquo;<\/em>. Essa pessoa aceitou sua lentid&atilde;o e n&atilde;o dispensou voc&ecirc;. <\/p>\n<p>  Na correria ningu&eacute;m vai encontrar o outro. Ningu&eacute;m vai livrar-se dos medos.<br \/> Jesus quando passava transformava o tempo das pessoas.<\/p>\n<p>  Fico pensando no medo de Madalena. Passou a vida inteira sendo usada, um objeto. Como ela se enxergava? Pare para entrar no tempo da prostituta. Entre no tempo dela e pensa nos muitos medos que ela devia ter. Quantas doen&ccedil;as f&iacute;sicas ela devia trazer no corpo. Quantas doen&ccedil;as trazia na alma e no cora&ccedil;&atilde;o?<\/p>\n<p>  E Jesus olha pra ela, e a coloca em outro tempo, desacelerando o processo dos medos. Olhando pra ela um jeito novo.<\/p>\n<p>  Quando me deparo com meus limites e &agrave;s vezes n&atilde;o consigo mud&aacute;-los, posso olhar pra eles de forma diferente.<\/p>\n<p>  Quantos de n&oacute;s tem medo de mudan&ccedil;a? Muitas vezes porque n&atilde;o sabemos encarar as mudan&ccedil;as. Mas se nesses momentos tem algu&eacute;m junto com voc&ecirc;, o medo diminui.<\/p>\n<div id=\"foto\" style=\"margin: 0pt auto;padding: 0px;width: 370px;float: none\">\n<div id=\"foto\"><!--ABRE LINK DA FOTO--><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.cancaonova.com\/portal\/arquivos\/fotos\/2009\/maio\/24_eventos_003.jpg\" border=\"0\" width=\"370\" height=\"250\" \/><!--FECHA LINK DA FOTO--><\/div>\n<div id=\"texto\"><!--TEXTO DA FOTO-->&#039;Na correria ningu&eacute;m vai encontrar o outro. Ningu&eacute;m vai livrar-se dos medos&#039;<!--TEXTO DA FOTO--><\/div>\n<div id=\"credito\"><!--CREDITO DA FOTO-->Foto: Wesley Almeida<!--CREDITO DA FOTO--><\/div>\n<\/div>\n<p><\/p>\n<div align=\"center\"><a href=\"http:\/\/www.flickr.com\/photos\/cancaonova\/sets\/72157618623467243\/\" target=\"_blank\" title=\"Fotos\"><strong><font color=\"#0033cc\">Veja mais fotos no<\/font> <font color=\"#0033cc\">Flick<\/font><font color=\"#ff0066\">r<\/font><\/strong>&nbsp; <\/a><\/div>\n<p>Uma cena marcou meu cora&ccedil;&atilde;o: Quando meu amigo Robinho come&ccedil;ou a fazer a quimioterapia. <br \/> Ele era vaidoso e bonito. E nesse processo da quimio, a primeira coisa que fazem &eacute; raspar a cabe&ccedil;a do paciente. Talvez para diminuir o medo, quem sabe pra tentar aliviar a dor. <br \/> Antes dele ficar careca, seu irm&atilde;o Denilson raspou a cabe&ccedil;a. O que ele queria? O que pode uma cabe&ccedil;a raspada fazer no cora&ccedil;&atilde;o do outro? Ele entrou no mesmo tempo. Demonstrando que estava com ele. Que o amava.<\/p>\n<p>  Foi algu&eacute;m que abriu m&atilde;o do que &eacute; seu e pela for&ccedil;a do amor que os unia se decidiu viver o tempo do outro.<\/p>\n<p>  Como quando voc&ecirc; tem uma festa pra ir e sua m&atilde;e est&aacute; doente em casa e voc&ecirc; decide ficar. Talvez estejamos perdendo isso, pois o tempo moderno est&aacute; nos deixando mais ego&iacute;stas, mais centrados em n&oacute;s mesmos. Quanto seus pais entraram no seu tempo? E agora, quanto voc&ecirc; entra no tempo deles?<\/p>\n<p>  Uma vez tive como superior, o padre Herculano. Ele me apresentou Jesus assim. Como  aquele que entra no meu tempo e olha minhas mis&eacute;rias, mesmo sendo santo.<\/p>\n<p>  <strong>Chorar na frente de quem nos ama, &eacute; choro de ressurrei&ccedil;&atilde;o.<\/strong><\/p>\n<p>  Agrade&ccedil;o a Deus porque um dia me colocou num corredor escuro com um padre moderno demais, eu achava. Eu o olhava com desconfian&ccedil;a. O achava esquisito. O dia que eu descobri o cora&ccedil;&atilde;o daquele homem, percebi que ele tinha o cora&ccedil;&atilde;o como o de Jesus. <br \/> Descobri que ele tinha pecados como eu, mas n&atilde;o desistia de sua salva&ccedil;&atilde;o. Olhava para os drogados e n&atilde;o se sentia melhor, superior, mas vivia o tempo deles.<\/p>\n<p>  O tempo do padre L&eacute;o era lit&uacute;rgico. <br \/> Quantas vezes p&ocirc;s a m&atilde;o na minha cabe&ccedil;a e me deitou em seu colo e diminuiu o meu medo? Da mesma forma que Jesus diminuiu o medo de quem O encontrava.<\/p>\n<p>  <strong>A Palavra de Jesus nos liberta, abre nossos cativeiros. Por isso precismos correr atr&aacute;s d&#039;Ele, nos revestir de m&iacute;stica, ter contato com a ora&ccedil;&atilde;o, com a m&uacute;sica que fala d&#039;Ele, com a celebra&ccedil;&atilde;o Eucar&iacute;stica. <\/strong><\/p>\n<p> Quantas vezes na minha vida tive a oportunidade de experimentar Jesus concretamente nas palavras do Padre L&eacute;o. Quantas vezes nosso medo vai embora quando algu&eacute;m nos faz olhar de outra forma e nos mostra uma sa&iacute;da poss&iacute;vel na <em>&#039;casa&#039;<\/em> de nossos medos?<\/p>\n<div id=\"foto\" style=\"margin: 0pt auto;padding: 0px;width: 370px;float: none\">\n<div id=\"foto\"><!--ABRE LINK DA FOTO--><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.cancaonova.com\/portal\/arquivos\/fotos\/2009\/maio\/24_eventos_002.jpg\" border=\"0\" width=\"370\" height=\"250\" \/><!--FECHA LINK DA FOTO--><\/div>\n<div id=\"texto\"><!--TEXTO DA FOTO-->&#039;Coloque os seus olhos nos olhos de Jesus&#039;<!--TEXTO DA FOTO--><\/div>\n<div id=\"credito\"><!--CREDITO DA FOTO-->Foto: Wesley Almeida<!--CREDITO DA FOTO--><\/div>\n<\/div>\n<p>Deus para mim n&atilde;o &eacute; fuga. Estou tocado pela for&ccedil;a de um Deus que me renova e me tira do medo cada vez que me recordo do que Ele falou e fez. <strong>Se Ele fez naquele tempo, Ele faz hoje tamb&eacute;m<\/strong>. Ele age mesmo que n&atilde;o mere&ccedil;amos.<\/p>\n<p>  Se voc&ecirc; n&atilde;o se sente merecedor, &eacute; um bom passo. Jesus tem predile&ccedil;&atilde;o pelos miser&aacute;veis e faz deles sinal de contradi&ccedil;&atilde;o para as na&ccedil;&otilde;es. N&atilde;o tenha medo! Deus quer agir em todos n&oacute;s, quer nos transformar. A gente n&atilde;o alcan&ccedil;a a gra&ccedil;a se n&atilde;o vence a cadeia do medo. Para qu&ecirc; cultivar os fracassos? Para legitimar a presen&ccedil;a do diabo? N&atilde;o! Foi para cima que voc&ecirc; foi projetado. Para o alto, para o c&eacute;u!<\/p>\n<p>  Quando a gente vai fazer uma constru&ccedil;&atilde;o, o arquiteto faz um projeto maravilhoso. E a&iacute; n&oacute;s olhamos e queremos tirar uma pilastra, ter um telhado mais pobrezinho, simplificar o piso.<br \/> Tem gente que leva a santidade do mesmo jeito. Querendo fazer &ldquo;meia-&aacute;gua&rdquo;. <strong>Deus quer &#039;mans&atilde;o&#039; na sua santidade!<\/strong><br \/> N&atilde;o economize no seu processo humano! N&atilde;o &eacute; qualquer coisa o que Deus projetou pra voc&ecirc;. Seus limites n&atilde;o podem ser impedimento para voc&ecirc; chegar ao final dessa constru&ccedil;&atilde;o.<\/p>\n<p>  A humildade precisa nos fazer pequenos, mas o que Deus nos prop&otilde;e &eacute; grande!<\/p>\n<p>   A Can&ccedil;&atilde;o Nova n&atilde;o foi constru&iacute;da para trazer santos. Mas pra trazer gente que aceitou o desafio de viver o processo de crescimento espiritual e de santidade. E &eacute; l&aacute; na sua vida, no seu dia a dia que isso precisa ser praticado.<\/p>\n<p>  <strong>N&oacute;s n&atilde;o nascemos para o fracasso. Ser feliz &eacute; urgente.<\/strong><\/p>\n<p>  Olha para o projeto inicial. O momento que Deus colocou nas suas m&atilde;os o projeto que Ele quer que voc&ecirc; seja. Na pregui&ccedil;a voc&ecirc; n&atilde;o chega l&aacute;. &Eacute; preciso empenho!   N&atilde;o simplifique o projeto, pe&ccedil;a para Deus for&ccedil;a para chegar at&eacute; l&aacute;.<\/p>\n<p>  N&atilde;o tenha medo do processo e do projeto inicial. <strong>Corra atr&aacute;s daquilo que &eacute; santo e honesto e voc&ecirc; vai purificar sua vida e seu cora&ccedil;&atilde;o aos poucos. A gente vence dando passos.<\/strong><\/p>\n<p>  Quantas vezes precisamos do tombo para voltar ao nosso lugar? Quantas vezes usamos das futilidades da vida? Isso n&atilde;o agrega nada em n&oacute;s! N&atilde;o nos faz avan&ccedil;ar em nada no processo.<\/p>\n<p>  Religi&atilde;o n&atilde;o &eacute; um conjunto de regras, mas &eacute; o olhar de Deus fixo em n&oacute;s, nos oferecendo a vit&oacute;ria. Pra gente chegar a ela basta ter coragem de se erguer, olhar nos olhos daquele que nos ama, desse Jesus que amou a tantos, e passa pela sua vida mais uma vez ou pela primeira, para te convencer que muita coisa precisa ser buscada e que voc&ecirc; n&atilde;o precisa ser ref&eacute;m dos medos. E que hoje voc&ecirc; pode se transformar numa pessoa nova pela for&ccedil;a do olhar de Cristo que nos diz que tudo podemos n&#039;Ele que nos fortalece.  Que n&oacute;s tudo podemos se nossos olhos estiverem fitos n&#039;Ele.<\/p>\n<p>  A fraqueza se transforma em for&ccedil;a assim. Coloque os seus olhos nos olhos de Jesus. Quando a f&eacute; que eu tenho em Deus se revela em mim, eu tudo posso. Mesmo quando tudo parece nublado e o cora&ccedil;&atilde;o s&oacute; chora. <\/p>\n<p>  Esse processo &eacute; lento, mas ele chega! N&atilde;o vamos desistir!<\/p>\n<p>  Pe&ccedil;a para que Deus lhe d&ecirc; coragem! Pe&ccedil;a o Esp&iacute;rito Santo!<\/p>\n<p>  <em>Transcri&ccedil;&atilde;o e adapta&ccedil;&atilde;o: Nara Bessa<\/em><\/p>\n<hr \/>\n<div align=\"center\"> <strong>ADQUIRA ESTA PALESTRA PELO TELEFONE <br \/>(12) 3186 2600 <\/strong><\/div>\n<hr \/>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Padre F&aacute;bio Foto: Wesley Almeida Se voc&ecirc; pegar os Evangelhos, eles narram in&uacute;meros encontros de Jesus com as pessoas. Mas, por que Jesus atra&iacute;a tantas pessoas? Por que Jesus atraiu voc&ecirc;? Eu n&atilde;o tenho d&uacute;vida de que &eacute; porque Ele&#8230;<\/p>\n","protected":false},"author":114,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7],"tags":[],"modified_by":"","_links":{"self":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/6144"}],"collection":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/users\/114"}],"replies":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/comments?post=6144"}],"version-history":[{"count":1,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/6144\/revisions"}],"predecessor-version":[{"id":6145,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/6144\/revisions\/6145"}],"wp:attachment":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media?parent=6144"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/categories?post=6144"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/tags?post=6144"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}