{"id":62064,"date":"2022-01-07T10:00:32","date_gmt":"2022-01-07T13:00:32","guid":{"rendered":"https:\/\/admin-canais.cancaonova.com\/eventos\/?p=62064"},"modified":"2023-11-21T15:55:59","modified_gmt":"2023-11-21T18:55:59","slug":"os-planos-de-deus-sao-planos-de-bencaos","status":"publish","type":"post","link":"https:\/\/admin-canais.cancaonova.com\/eventos\/retiro-de-ano-novo\/pregacoes\/os-planos-de-deus-sao-planos-de-bencaos\/","title":{"rendered":"Os planos de Deus s\u00e3o planos de b\u00ean\u00e7\u00e3os!"},"content":{"rendered":"<h2>Os planos de Deus s\u00e3o planos de b\u00ean\u00e7\u00e3os!<\/h2>\n<p>Sacerdote da Comunidade Can\u00e7\u00e3o Nova, Padre Roger Luis pregou durante o retiro de Ano Novo com o tema &#8220;Os planos de Deus s\u00e3o planos de b\u00ean\u00e7\u00e3os!&#8221;.<\/p>\n<p>Meus irm\u00e3os e minhas irm\u00e3s, n\u00f3s somos muitos aben\u00e7oados, principalmente pela escolha que fizemos de estar aqui. \u00c9 desta maneira que precisamos nos posicionar o ano todo, nada pode nos impedir de estar com o Senhor.<\/p>\n<p>N\u00e3o foi f\u00e1cil chegar at\u00e9 aqui. A chuva que cai, neste momento, \u00e9 um sinal espiritual que nada poder\u00e1 nos impedir de buscar o Senhor. Com todo nosso cora\u00e7\u00e3o, com toda nossa for\u00e7a e entendimento, n\u00f3s precisamos, neste ano, fazer este prop\u00f3sito de buscar o Senhor.<\/p>\n<p>\u00c9 importante entendermos algo, as realidades espirituais n\u00e3o s\u00e3o compreendidas por homens e mulheres carnais, isso \u00e9 b\u00edblico. Aben\u00e7oados tamb\u00e9m n\u00f3s somos por ouvir a Palavra de Deus neste ano.<\/p>\n<p>A n\u00f3s Deus revelou o mist\u00e9rio pelo Esp\u00edrito, pois o Esp\u00edrito sonda tudo. Quem dentre as pessoas conhece o que \u00e9 pr\u00f3prio do ser humano, a n\u00e3o ser Esp\u00edrito Santo?<\/p>\n<p>Leitura: 1 cor 2,10-14<\/p>\n<p>&#8220;10.Todavia, Deus nos revelou pelo seu Esp\u00edrito, porque o Esp\u00edrito penetra tudo, mesmo as profundezas de Deus.<br \/>\n 11.Pois quem conhe\u00adce as coisas que h\u00e1 no homem, sen\u00e3o o esp\u00edrito do homem que nele reside? Assim tamb\u00e9m as coisas de Deus ningu\u00e9m as conhece, sen\u00e3o o Esp\u00edrito de Deus.<br \/>\n 12.Ora, n\u00f3s n\u00e3o recebemos o esp\u00edrito do mundo, mas sim o Esp\u00edrito que vem de Deus, que nos d\u00e1 a conhecer as gra\u00e7as que Deus nos prodigalizou 13.e que pregamos numa linguagem que nos foi ensinada n\u00e3o pela sabedoria humana, mas pelo Esp\u00edrito, que exprime as coisas espirituais em termos espirituais.<br \/>\n 14.Mas o homem natural n\u00e3o aceita as coisas do Esp\u00edrito de Deus, pois para ele s\u00e3o loucuras. Nem as pode compreender, porque \u00e9 pelo Esp\u00edrito que se devem ponderar.&#8221;<\/p>\n<p>V\u00eddeo completo:<\/p>\n<p><iframe loading=\"lazy\" title=\"Os planos de Deus, sa\u00cc\u0083o planos de benc\u00cc\u00a7a\u00cc\u0083os! - Padre Roger Luis (31\/12\/2021)\" width=\"600\" height=\"338\" src=\"https:\/\/www.youtube.com\/embed\/jEAoWyI-l24?list=PLgzp587mOb1mbDBB3hzCBi9Gi54sqgj0U&amp;rel=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os planos de Deus s\u00e3o planos de b\u00ean\u00e7\u00e3os! Sacerdote da Comunidade Can\u00e7\u00e3o Nova, Padre Roger Luis pregou durante o retiro de Ano Novo com o tema &#8220;Os planos de Deus s\u00e3o planos de b\u00ean\u00e7\u00e3os!&#8221;. Meus irm\u00e3os e minhas irm\u00e3s, n\u00f3s&#8230;<\/p>\n","protected":false},"author":243,"featured_media":68622,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7],"tags":[],"modified_by":"aliane","_links":{"self":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/62064"}],"collection":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/users\/243"}],"replies":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/comments?post=62064"}],"version-history":[{"count":5,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/62064\/revisions"}],"predecessor-version":[{"id":68632,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/62064\/revisions\/68632"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media\/68622"}],"wp:attachment":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media?parent=62064"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/categories?post=62064"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/tags?post=62064"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}