{"id":62181,"date":"2022-01-17T09:00:06","date_gmt":"2022-01-17T12:00:06","guid":{"rendered":"https:\/\/admin-canais.cancaonova.com\/eventos\/?p=62181"},"modified":"2022-10-18T09:03:30","modified_gmt":"2022-10-18T12:03:30","slug":"da-morte-para-a-vida","status":"publish","type":"post","link":"https:\/\/admin-canais.cancaonova.com\/eventos\/acampamento-revolucao-jesus\/pregacoes\/da-morte-para-a-vida\/","title":{"rendered":"Da morte para a vida"},"content":{"rendered":"<h2>Da morte para a vida<\/h2>\n<p>O Mission\u00e1rio da Comunidade Can\u00e7\u00e3o Nova, Pitter Di Laura, pregou durante o Acampamento Revolu\u00e7\u00e3o Jesus sobre o tema \u201cDa morte para a vida\u201d.<\/p>\n<p>Quero come\u00e7ar esta prega\u00e7\u00e3o cantando uma can\u00e7\u00e3o para voc\u00ea, e eu pe\u00e7o que o Senhor me d\u00ea palavras acertadas, sintonia com o Esp\u00edrito, para que eu n\u00e3o seja empecilho entre aquilo que Deus quer dizer a voc\u00ea.<\/p>\n<blockquote><p>M\u00fasica:<br \/>\n&#8220;L\u00e1 est\u00e1 o meu tesouro<br \/>\nL\u00e1 onde n\u00e3o h\u00e1 choro<br \/>\nOnde todos cantaremos juntos hinos de louvor ao Senhor.&#8221;<\/p><\/blockquote>\n<p>A Palavra do Senhor para n\u00f3s est\u00e1 em Romanos 6, 2-4:\u00a0&#8220;N\u00f3s, que j\u00e1 morremos ao pecado, como poder\u00edamos ainda viver nele? Ou ignorais que todos os que fomos batizados em Jesus Cristo, fomos batizados na sua morte? Fomos, pois, sepultados com ele na sua morte pelo batismo para que, como Cristo ressurgiu dos mortos pela gl\u00f3ria do Pai, assim tamb\u00e9m n\u00f3s possamos <strong>caminhar numa vida nova<\/strong>.&#8221;<\/p>\n<p>Caminhar numa vida nova! N\u00f3s somos batizados, e h\u00e1 um significado muito profundo no batismo que recebemos. No batismo, fomos declarados mortos ao pecado, \u00e9 como se, no dia que voc\u00ea tivesse sido batizado, voc\u00ea recebesse a certid\u00e3o de batismo e tamb\u00e9m a certid\u00e3o de \u00f3bito. A Igreja n\u00e3o faria isso, mas essa certid\u00e3o tamb\u00e9m poderia ter sido entregue.<\/p>\n<p>\u00c9 isso que acontece quando somos batizados: somos declarado mortos para o pecado. N\u00f3s temos, agora, aptid\u00e3o para nos afastarmos cada vez mais do pecado.<\/p>\n<p>Como n\u00f3s, t\u00e3o agraciado que somos, podemos desejar ainda as coisas que passam, e n\u00e3o desejar as coisas que n\u00e3o passam?<\/p>\n<p>Como podemos cantar &#8220;L\u00e1 est\u00e1 o meu tesouro, l\u00e1 onde n\u00e3o h\u00e1 choro&#8230;&#8221;, e n\u00e3o querermos estar com todos cantando juntos hinos de louvor ao Senhor?<\/p>\n<p>Confira a prega\u00e7\u00e3o completa:<\/p>\n<p><iframe loading=\"lazy\" title=\"Da morte para a vida -  Pitter Di Laura (14\/01\/2022)\" width=\"600\" height=\"338\" src=\"https:\/\/www.youtube.com\/embed\/Wbn3AkeoiRY?feature=oembed&amp;rel=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Da morte para a vida O Mission\u00e1rio da Comunidade Can\u00e7\u00e3o Nova, Pitter Di Laura, pregou durante o Acampamento Revolu\u00e7\u00e3o Jesus sobre o tema \u201cDa morte para a vida\u201d. Quero come\u00e7ar esta prega\u00e7\u00e3o cantando uma can\u00e7\u00e3o para voc\u00ea, e eu pe\u00e7o&#8230;<\/p>\n","protected":false},"author":243,"featured_media":62182,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7],"tags":[],"modified_by":"Marc\u00edlia","_links":{"self":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/62181"}],"collection":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/users\/243"}],"replies":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/comments?post=62181"}],"version-history":[{"count":5,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/62181\/revisions"}],"predecessor-version":[{"id":65458,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/62181\/revisions\/65458"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media\/62182"}],"wp:attachment":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media?parent=62181"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/categories?post=62181"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/tags?post=62181"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}