{"id":63114,"date":"2022-04-21T15:30:55","date_gmt":"2022-04-21T18:30:55","guid":{"rendered":"https:\/\/admin-canais.cancaonova.com\/eventos\/?p=63114"},"modified":"2022-04-27T16:19:03","modified_gmt":"2022-04-27T19:19:03","slug":"a-misericordia-de-deus-em-nossas-familias","status":"publish","type":"post","link":"https:\/\/admin-canais.cancaonova.com\/eventos\/festa-da-misericordia\/pregacoes\/a-misericordia-de-deus-em-nossas-familias\/","title":{"rendered":"A Miserico\u0301rdia de Deus em nossas fami\u0301lias"},"content":{"rendered":"<h2 class=\"title style-scope ytd-video-primary-info-renderer\">A Miserico\u0301rdia de Deus em nossas fami\u0301lias<\/h2>\n<p>O casal de mission\u00e1rios Jimmy e Benedita Fioramonte pregou, no in\u00edcio da Festa da Miseric\u00f3rdia 20 anos na Can\u00e7\u00e3o Nova, sobre a salva\u00e7\u00e3o da fam\u00edlia. O tema da prega\u00e7\u00e3o foi: \u201cA Miseric\u00f3rdia de Deus em nossas fam\u00edlias\u201d.<\/p>\n<p>O Senhor quer falar para n\u00f3s da Miseric\u00f3rdia de Deus na nossa fam\u00edlia; inclusive, podemos dizer assim: \u201cA Miseric\u00f3rdia de Deus na minha fam\u00edlia\u201d, j\u00e1 tomando posse que o exerc\u00edcio da miseric\u00f3rdia precisa acontecer dentro de nossas casas.<\/p>\n<p>No Evangelho de S\u00e3o Jo\u00e3o, cap\u00edtulo 3,16-18, come\u00e7amos com esta palavra, pois a primeira coisa de que precisamos, ao viver essa Festa da Miseric\u00f3rdia, \u00e9 resgatar em n\u00f3s a certeza de que somos crist\u00e3os. E essa festa \u00e9 tamb\u00e9m para voc\u00ea que n\u00e3o \u00e9 crist\u00e3o e tem d\u00favidas de que a miseric\u00f3rdia do Senhor possa alcan\u00e7\u00e1-lo, a fim de que voc\u00ea fa\u00e7a a experi\u00eancia com este Jesus Misericordioso.<\/p>\n<p>Santa Faustina, em um dos seus di\u00e1logos com Jesus Misericordioso \u2013 como podemos ver no par\u00e1grafo 1485 do Di\u00e1rio de Santa Faustina, num di\u00e1logo de Deus com uma alma pecadora \u2013, ouve Jesus dizer assim: \u201cAlma pecadora, n\u00e3o tenhas medo do teu Salvador. Eu, por primeiro, tomo a iniciativa de Me aproximar de ti, pois sei que por ti mesma n\u00e3o \u00e9s capaz de elevar-te a Mim&#8230;\u201d<\/p>\n<p>Perceba que \u00e9 o Senhor Jesus quem toma a iniciativa de aproximar-se de n\u00f3s. Assim como Jesus toma a iniciativa de aproximar-se da sua fam\u00edlia. \u00c9 Ele quem quer entrar na sua fam\u00edlia atrav\u00e9s da Festa da Divina Miseric\u00f3rdia, e essa miseric\u00f3rdia se traduz na salva\u00e7\u00e3o da sua fam\u00edlia.<\/p>\n<p>Confira a prega\u00e7\u00e3o completa:<\/p>\n<p><iframe loading=\"lazy\" title=\"A Miserico\u00cc\u0081rdia de Deus em nossas fami\u00cc\u0081lias - Jimmy e Benedita Fioramonte (21\/04\/2022)\" width=\"600\" height=\"338\" src=\"https:\/\/www.youtube.com\/embed\/8MVgsg1Jviw?feature=oembed&amp;rel=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Miserico\u0301rdia de Deus em nossas fami\u0301lias O casal de mission\u00e1rios Jimmy e Benedita Fioramonte pregou, no in\u00edcio da Festa da Miseric\u00f3rdia 20 anos na Can\u00e7\u00e3o Nova, sobre a salva\u00e7\u00e3o da fam\u00edlia. O tema da prega\u00e7\u00e3o foi: \u201cA Miseric\u00f3rdia de&#8230;<\/p>\n","protected":false},"author":759,"featured_media":63137,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7],"tags":[],"modified_by":"aliane","_links":{"self":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/63114"}],"collection":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/users\/759"}],"replies":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/comments?post=63114"}],"version-history":[{"count":4,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/63114\/revisions"}],"predecessor-version":[{"id":63181,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/63114\/revisions\/63181"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media\/63137"}],"wp:attachment":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media?parent=63114"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/categories?post=63114"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/tags?post=63114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}