{"id":6435,"date":"2010-12-19T06:00:00","date_gmt":"2010-12-19T09:00:00","guid":{"rendered":"http:\/\/admin-canais.cancaonova.com\/eventos\/?p=6435"},"modified":"2014-08-13T03:24:38","modified_gmt":"2014-08-13T06:24:38","slug":"amar-tambem-e-se-sacrificar","status":"publish","type":"post","link":"https:\/\/admin-canais.cancaonova.com\/eventos\/pregacoes\/amar-tambem-e-se-sacrificar\/","title":{"rendered":"Amar tamb\u00e9m \u00e9 se sacrificar"},"content":{"rendered":"<div id=\"foto\" style=\"padding-bottom: 0px;margin: 0pt auto;padding-left: 0px;width: 180px;padding-right: 5px;float: left;padding-top: 0px\">\n<div id=\"foto\"><!--ABRE LINK DA FOTO--><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.cancaonova.com\/portal\/arquivos\/fotos\/2010\/dezembro\/19_eventos-001.jpg\" border=\"0\" width=\"180\" height=\"220\" \/><!--FECHA LINK DA FOTO--><\/div>\n<div id=\"texto\"><!--TEXTO DA FOTO-->Padre Fabr&iacute;cio Andrade<!--TEXTO DA FOTO--><\/div>\n<div id=\"credito\"><!--CREDITO DA FOTO-->Foto: Robson Siqueira<!--CREDITO DA FOTO--><\/div>\n<\/div>\n<p align=\"justify\">Hoje o nosso tema &eacute; o amor &aacute;gape. Voc&ecirc; sabe o que &eacute; esse amor? &Eacute; o amor de Deus, amor superior que tudo faz. O Esp&iacute;rito Santo infundiu em n&oacute;s esse amor para que&nbsp; n&oacute;s o transbordemos. Essa &eacute; a miss&atilde;o da Can&ccedil;&atilde;o Nova, passar esse amor do Pai a todos voc&ecirc;s. Em I Cor&iacute;ntios 13, 4-7 temos a defini&ccedil;&atilde;o mais clara desse sentimento t&atilde;o intenso: <\/p>\n<p><em>&ldquo;O amor &eacute; paciente, &eacute; bondoso. N&atilde;o tem inveja. O amor n&atilde;o &eacute; orgulhoso. N&atilde;o &eacute; arrogante. Nem escandaloso. N&atilde;o busca os seus pr&oacute;prios interesses, n&atilde;o se irrita, n&atilde;o guarda rancor. N&atilde;o se alegra com a injusti&ccedil;a, mas se rejubila com a verdade. Tudo desculpa, tudo cr&ecirc;, tudo espera, tudo suporta&rdquo;.<\/em><\/p>\n<p>Amar &eacute; querer o bem do outro. E amar n&atilde;o &eacute; somente entre namorados, noivos e casados. Voc&ecirc; pode, e deve, amar os seus irm&atilde;os. <\/p>\n<p>Comece a dar amor e voc&ecirc; vai ver como as coisas v&atilde;o mudar na sua vida. Brigaram com voc&ecirc;? Humilharam-no? Devolva as ofensas com amor!<\/p>\n<p><strong>Muitos dos relacionamentos de hoje est&atilde;o marcados pela superficialidade. As pessoas se preocupam mais com o f&iacute;sico do que com a alma.<\/strong> Voc&ecirc; n&atilde;o pode ser assim, voc&ecirc; deve amar. Se voc&ecirc; entender esse amor de Deus, nunca vai se sentir carente porque esse sentimento infundindo em n&oacute;s &eacute; muito grande.<\/p>\n<p>Voc&ecirc; n&atilde;o precisa de um &ldquo;amorzinho&rdquo; do mundo se tem o &ldquo;amorz&atilde;o&rdquo; de Deus. Esse amor n&atilde;o deseja o mal para o outro, quer o bem a todo pre&ccedil;o. Com tamanho amor, n&atilde;o tem como voc&ecirc; se vender, se prostituir, viver no pecado.<\/p>\n<p>O amor n&atilde;o &eacute; invejoso porque &eacute; para o outro. Sabe por que muitas mulheres n&atilde;o encontram um amor verdadeiro? Porque querem um homem perfeito, sem nenhum defeito. Amar tamb&eacute;m &eacute; pegar uma pessoa imatura e torn&aacute;-la melhor. &Eacute; muito mais gostoso amar uma pessoa que foi amadurecendo com voc&ecirc; do que uma que j&aacute; veio pronta. O crescimento fortalece o amor!<\/p>\n<div id=\"foto\" style=\"padding-bottom: 10px;margin: 0pt auto;padding-left: 0px;width: 370px;padding-right: 0px;float: none;padding-top: 10px\">\n<div id=\"foto\"><!--ABRE LINK DA FOTO--><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.cancaonova.com\/portal\/arquivos\/fotos\/2010\/dezembro\/19_eventos-003.jpg\" border=\"0\" width=\"370\" height=\"250\" \/><!--FECHA LINK DA FOTO--><\/div>\n<div id=\"texto\">&quot;&Eacute; muito mais gostoso amar uma pessoa que foi amadurecendo com voc&ecirc; do que uma que j&aacute; veio pronta&quot;<!--TEXTO DA FOTO--><!--TEXTO DA FOTO--><\/div>\n<div id=\"credito\"><!--CREDITO DA FOTO-->Foto: Robson Siqueira<!--CREDITO DA FOTO--><\/div>\n<\/div>\n<p>Hoje as pessoas amam os filhos, mas usam o mesmo amor para um cachorrinho. Eu n&atilde;o sou contra os animais, muito pelo contr&aacute;rio, mas cachorro n&atilde;o &eacute; filho. E tem muito filho andando pelas ruas mendigando amor.<\/p>\n<p>O sin&ocirc;nimo de amor se transformou em prostitui&ccedil;&atilde;o. Isso n&atilde;o &eacute; amor, gente! Jovens, se o relacionamento de voc&ecirc;s &eacute; assim, isso n&atilde;o &eacute; amor. Se depois voc&ecirc; se sente sujo, fica com medo de algu&eacute;m ver e saber o que voc&ecirc; fez isso, &eacute; porque est&aacute; totalmente errado.<\/p>\n<p>Muita gente diz: &ldquo;O corpo &eacute; meu, eu fa&ccedil;o o que eu quiser!&rdquo; Mentira! O seu corpo &eacute; templo do Esp&iacute;rito Santo, respeite-o! O amor n&atilde;o &eacute; baseado naquilo que o outro pode me dar. Que tristeza &eacute; quando n&oacute;s vendemos esse sentimento t&atilde;o grande!<\/p>\n<p>Uma fam&iacute;lia cresce n&atilde;o quando desaparecem os problemas, mas quando ela aprende dar e receber perd&atilde;o. Pai, o seu relacionamento com seu filho vai crescer quando voc&ecirc; souber perdoar os atos dele; ele n&atilde;o &eacute; perfeito, muito menos voc&ecirc; o &eacute;.<\/p>\n<p>&nbsp;<\/p>\n<div id=\"foto\" style=\"padding-bottom: 10px;margin: 0pt auto;padding-left: 0px;width: 370px;padding-right: 0px;float: none;padding-top: 10px\">\n<div id=\"foto\"><!--ABRE LINK DA FOTO--><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.cancaonova.com\/portal\/arquivos\/fotos\/2010\/dezembro\/19_eventos-002.jpg\" border=\"0\" width=\"370\" height=\"250\" \/><!--FECHA LINK DA FOTO--><\/div>\n<div id=\"texto\">&quot;Voc&ecirc; n&atilde;o precisa de um &ldquo;amorzinho&rdquo; do mundo se tem o &ldquo;amorz&atilde;o&rdquo; de Deus&quot;<!--TEXTO DA FOTO--><!--TEXTO DA FOTO--><\/div>\n<div id=\"credito\"><!--CREDITO DA FOTO-->Foto: Robson Siqueira<!--CREDITO DA FOTO--><\/div>\n<\/div>\n<p>O amor n&atilde;o se alegra com a injusti&ccedil;a. Namorado que mata a ex-namorada e diz que fez isso por amor &eacute; uma grande mentira. Amor n&atilde;o tira, amor d&aacute;! O amor &aacute;gape &eacute; capaz de acompanhar o envelhecimento do outro e v&ecirc;-lo cada vez mais bonito, como uma princesa e um pr&iacute;ncipe. Isso &eacute; um sentimento verdadeiro! <\/p>\n<div style=\"text-align: center\"><\/div>\n<p>L&aacute; fora, suportar o amor &eacute; sin&ocirc;nimo de sacrif&iacute;cio e, para muitos, amor com sacrifico n&atilde;o &eacute; amor. Tudo errado! Amar tamb&eacute;m &eacute; se sacrificar, &eacute; abaixar a cabe&ccedil;a quando necess&aacute;rio, aprender a ceder&#8230; Lembre-se: o amor &aacute;gape &eacute; o que tem coragem de ficar do lado do outro, aconte&ccedil;a o que acontecer!<\/p>\n<p><em>Transcri&ccedil;&atilde;o e adapta&ccedil;&atilde;o: Ariane Fonseca<\/p>\n<hr width=\"100%\" size=\"2\" \/><\/em><\/p>\n<p>&nbsp;<\/p>\n<div align=\"center\"><strong><font size=\"2\">Adquira essa prega&ccedil;&atilde;o pelo telefone<\/font><\/strong><br \/><strong><font size=\"2\">(12) 3186-2600<\/font><\/strong><\/div>\n<hr \/>\n<p align=\"justify\"><strong>Conhe&ccedil;a mais do nosso conte&uacute;do:<\/strong><\/p>\n<p><a href=\"http:\/\/www.webtvcn.com\/\" target=\"_blank\"><font color=\"#0033cc\">:: WebTVCN, muitos v&iacute;deos para voc&ecirc;<\/font><\/a><br \/><a href=\"http:\/\/gentedefe.com\/\" target=\"_blank\"><font color=\"#0033cc\">:: Gente de f&eacute;, a sua comunidade crist&atilde; de relacionamento<\/font><\/a><br \/><a href=\"http:\/\/podcast.cancaonova.com\/\" target=\"_blank\"><font color=\"#0033cc\">:: Podcasts: ou&ccedil;a &aacute;udios sobre variados assuntos<\/font><\/a><br \/><a href=\"http:\/\/paroquias.cancaonova.com\/\" target=\"_blank\"><font color=\"#0033cc\">:: Cadastre sua par&oacute;quia ou capela no Portal Can&ccedil;&atilde;o Nova<\/font><\/a><\/p>\n<p><strong>Para o seu celular:<\/strong><\/p>\n<p><a href=\"http:\/\/www.cancaonovamobile.com\/\" target=\"_blank\"><font color=\"#0033cc\">:: Can&ccedil;&atilde;o Nova Mobile<\/font><\/a><br \/><a href=\"http:\/\/cnchama.com.br\/\" target=\"_blank\"><font color=\"#0033cc\">:: CN Chama, a Palavra de Deus no seu celular<\/font><\/a><br \/><a href=\"http:\/\/iphone.cancaonova.com\/\" target=\"_blank\"><font color=\"#0033cc\">:: Iphone<\/font><\/a><\/p>\n<p><strong>Mais canais na web:<\/strong><\/p>\n<p><a href=\"http:\/\/meadiciona.com\/cancaonova\" target=\"_blank\"><font color=\"#0033cc\">:: meadiciona.com\/cancaonova <\/font><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Padre Fabr&iacute;cio Andrade Foto: Robson Siqueira Hoje o nosso tema &eacute; o amor &aacute;gape. Voc&ecirc; sabe o que &eacute; esse amor? &Eacute; o amor de Deus, amor superior que tudo faz. O Esp&iacute;rito Santo infundiu em n&oacute;s esse amor para&#8230;<\/p>\n","protected":false},"author":114,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7],"tags":[],"modified_by":"","_links":{"self":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/6435"}],"collection":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/users\/114"}],"replies":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/comments?post=6435"}],"version-history":[{"count":1,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/6435\/revisions"}],"predecessor-version":[{"id":6436,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/6435\/revisions\/6436"}],"wp:attachment":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media?parent=6435"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/categories?post=6435"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/tags?post=6435"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}