{"id":64788,"date":"2022-07-15T09:00:35","date_gmt":"2022-07-15T12:00:35","guid":{"rendered":"https:\/\/admin-canais.cancaonova.com\/eventos\/?p=64788"},"modified":"2024-07-05T13:53:43","modified_gmt":"2024-07-05T16:53:43","slug":"s-de-santidade","status":"publish","type":"post","link":"https:\/\/admin-canais.cancaonova.com\/eventos\/phn\/pregacoes\/s-de-santidade\/","title":{"rendered":"S de Santidade"},"content":{"rendered":"<h2>S de Santidade<\/h2>\n<p>O mission\u00e1rio da Comunidade Can\u00e7\u00e3o Nova,\u00a0Pitter Di Laura, pregou sobre o tema \u201cS de Santidade\u201d durante o acampamento PHN.<\/p>\n<p>Seja bem-vindos ao PHN, essa \u00e9 a 24\u00aa edi\u00e7\u00e3o do PHN, em 2023 celebraremos 25 anos de acampamento PHN.<\/p>\n<p>S\u00e3o 24 anos de hist\u00f3ria, ano passado &#8211; durante a pandemia do Covid 19 &#8211; no Centro de Evangeliza\u00e7\u00e3o eu corri com a bandeira escrita &#8220;PHN 2022&#8221;,\u00a0 naquela espa\u00e7o vazio, eu olhava para aquele lugar e eu j\u00e1 imaginava como seria o ano 2022 com p\u00fablico, e aqui estamos. Nestes 24 anos, s\u00e3o 24 anos de hist\u00f3ria.<\/p>\n<p>No PHN, em varias edi\u00e7\u00f5es n\u00f3s j\u00e1 cantamos:<\/p>\n<p>N\u00e3o d\u00e1 mais pra voltar<br \/>\nO barco est\u00e1 em alto mar<br \/>\nN\u00e3o d\u00e1 mais pra negar<br \/>\nO mar \u00e9 Deus e o barco sou eu<br \/>\nO vento forte<br \/>\nQue me leva pra frente<br \/>\n\u00c9 o amor de Deus<\/p>\n<p>E assim, tamb\u00e9m cantamos:<br \/>\nPare de se maltratar<br \/>\nN\u00e3o queira aos outros culpar<br \/>\nDiga por hoje n\u00e3o<br \/>\nPor hoje eu n\u00e3o vou mais pecar<\/p>\n<p>\u00c9 muito lindo quando a gente v\u00ea a sequencia dos fatos e a gente v\u00ea a a\u00e7\u00e3o de Deus conduzindo todas as coisas. Aqui neste palco, muitos grandes homens pregar\u00e3o, Padre Jonas Abib, Dunga, Padre L\u00e9o, muitos homens e mulheres de Deus passaram por aqui e \u00e9 lindo olhar e ver que n\u00f3s estamos continuando uma historia.<\/p>\n<p><strong>Prega\u00e7\u00e3o completa:<\/strong><\/p>\n<p><iframe loading=\"lazy\" title=\"S de Santidade- Pitter Di Laura (14\/07\/2022)\" width=\"600\" height=\"338\" src=\"https:\/\/www.youtube.com\/embed\/WWTrggTgZyE?feature=oembed&amp;rel=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>S de Santidade O mission\u00e1rio da Comunidade Can\u00e7\u00e3o Nova,\u00a0Pitter Di Laura, pregou sobre o tema \u201cS de Santidade\u201d durante o acampamento PHN. Seja bem-vindos ao PHN, essa \u00e9 a 24\u00aa edi\u00e7\u00e3o do PHN, em 2023 celebraremos 25 anos de acampamento&#8230;<\/p>\n","protected":false},"author":243,"featured_media":70587,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7],"tags":[],"modified_by":"aliane","_links":{"self":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/64788"}],"collection":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/users\/243"}],"replies":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/comments?post=64788"}],"version-history":[{"count":5,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/64788\/revisions"}],"predecessor-version":[{"id":70596,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/64788\/revisions\/70596"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media\/70587"}],"wp:attachment":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media?parent=64788"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/categories?post=64788"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/tags?post=64788"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}