{"id":67024,"date":"2023-01-16T10:00:48","date_gmt":"2023-01-16T13:00:48","guid":{"rendered":"https:\/\/admin-canais.cancaonova.com\/eventos\/?p=67024"},"modified":"2023-04-27T10:48:57","modified_gmt":"2023-04-27T13:48:57","slug":"show-com-ministerio-amor-e-adoracao-2","status":"publish","type":"post","link":"https:\/\/admin-canais.cancaonova.com\/eventos\/acampamento-revolucao-jesus\/cobertura\/show-com-ministerio-amor-e-adoracao-2\/","title":{"rendered":"Show com Minist\u00e9rio Amor e Adora\u00e7\u00e3o"},"content":{"rendered":"<p>S\u00e1bado, 14 de janeiro de 2023, a banda &#8220;Minist\u00e9rio Amor e Adora\u00e7\u00e3o&#8221; realizou um show no Rinc\u00e3o, em Cachoeira Paulista, S\u00e3o Paulo. Com um repert\u00f3rio autoral e mensagens inspiradoras, os integrantes Pedro Pinheiro, Amanda Carvalho e Sarah Sabar\u00e1 animaram o p\u00fablico presente na Can\u00e7\u00e3o Nova.<\/p>\n<p>Em entrevista exclusiva para nossa p\u00e1gina, os integrantes do Minist\u00e9rio Amor e Adora\u00e7\u00e3o falaram sobre a experi\u00eancia de se apresentar no evento e tamb\u00e9m sobre a recente mudan\u00e7a na forma\u00e7\u00e3o da banda.<\/p>\n<p>Segundo Pedro Pinheiro, o show foi uma oportunidade de celebrar a vida e compartilhar mensagens de amor e esperan\u00e7a com o p\u00fablico. &#8220;Foi uma noite muito especial. Sentimos a presen\u00e7a de Deus em cada m\u00fasica e em cada palavra que compartilhamos&#8221;, disse.<\/p>\n<p>Amanda Carvalho acrescentou que a apresenta\u00e7\u00e3o tamb\u00e9m marcou a estreia oficial de Sarah Sabar\u00e1 como integrante fixa da banda. &#8220;Estamos muito felizes em t\u00ea-la conosco. Ela tem um talento incr\u00edvel e acrescenta muito ao nosso som e \u00e0 nossa mensagem&#8221;, afirmou.<br \/>\nSarah, por sua vez, disse estar muito empolgada com a oportunidade de fazer parte do Minist\u00e9rio Amor e Adora\u00e7\u00e3o e de compartilhar a sua m\u00fasica e a sua f\u00e9 com outras pessoas. &#8220;\u00c9 um privil\u00e9gio poder servir a Deus dessa forma e fazer parte de uma equipe t\u00e3o talentosa e comprometida&#8221;, destacou.<\/p>\n<p>A mudan\u00e7a na forma\u00e7\u00e3o da banda ocorreu de forma natural, segundo os integrantes. Claudia Guedes, que integrava o grupo, decidiu se afastar temporariamente para se dedicar ao nascimento de seu segundo filho. &#8220;Desejamos a ela todo o amor e as b\u00ean\u00e7\u00e3os de Deus nessa nova fase de sua vida&#8221;, disse Pedro.<\/p>\n<p>O Minist\u00e9rio Amor e Adora\u00e7\u00e3o planeja seguir com sua agenda de shows e eventos ao longo do ano, levando a sua mensagem de amor e esperan\u00e7a para diversas cidades do Brasil. &#8220;Cada vez mais, queremos continuar compartilhando a nossa m\u00fasica e nossa f\u00e9 com as pessoas&#8221;, concluiu Amanda.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>S\u00e1bado, 14 de janeiro de 2023, a banda &#8220;Minist\u00e9rio Amor e Adora\u00e7\u00e3o&#8221; realizou um show no Rinc\u00e3o, em Cachoeira Paulista, S\u00e3o Paulo. Com um repert\u00f3rio autoral e mensagens inspiradoras, os integrantes Pedro Pinheiro, Amanda Carvalho e Sarah Sabar\u00e1 animaram o&#8230;<\/p>\n","protected":false},"author":243,"featured_media":67025,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[8],"tags":[],"modified_by":"aliane","_links":{"self":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/67024"}],"collection":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/users\/243"}],"replies":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/comments?post=67024"}],"version-history":[{"count":4,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/67024\/revisions"}],"predecessor-version":[{"id":67035,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/67024\/revisions\/67035"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media\/67025"}],"wp:attachment":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media?parent=67024"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/categories?post=67024"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/tags?post=67024"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}