{"id":68766,"date":"2023-12-14T11:42:08","date_gmt":"2023-12-14T14:42:08","guid":{"rendered":"https:\/\/admin-canais.cancaonova.com\/eventos\/?p=68766"},"modified":"2023-12-14T11:42:49","modified_gmt":"2023-12-14T14:42:49","slug":"cuidado-com-os-falsos-profetas","status":"publish","type":"post","link":"https:\/\/admin-canais.cancaonova.com\/eventos\/hosana-brasil\/pregacoes\/cuidado-com-os-falsos-profetas\/","title":{"rendered":"Cuidado com os falsos profetas"},"content":{"rendered":"<h2>\u201cCuidado com os falsos profetas\u201d (1 Jo 4, 1-6)<\/h2>\n<p>Nos tempos atuais, n\u00f3s precisamos assumir que somos de Deus. Precisamos ficar firmes, como se v\u00edssemos o invis\u00edvel. Aqueles que servem ao anticristo, tamb\u00e9m servem ao mundo que se op\u00f5e a Deus, que opta pelo pecado.<\/p>\n<p>A promessa para aqueles que permanecem nas coisas ensinadas por Jesus Cristo \u00e9 a vida eterna. N\u00e3o sabemos que horas vir\u00e1 o Senhor, mas Ele nos deixa sinais para que percebamos que a hora da Sua volta \u00e9 pr\u00f3xima.<\/p>\n<p>Aqueles que n\u00e3o escutam a Palavra de Deus caem nas l\u00e1bias dos falsos profetas.<\/p>\n<p>Jesus nos d\u00e1 o alerta, cuidado!<\/p>\n<p>Um falso profeta \u00e9 uma pessoa que finge falar em nome de Deus, por\u00e9m, n\u00e3o foi enviada por Ele. As palavras que ele proclama n\u00e3o se cumprem, os frutos da sua vida s\u00e3o frutos ruins, seus ensinamentos contradizem a escritura.<\/p>\n<p>\u00c9 preciso que estejamos atentos para distinguir os verdadeiros homens do Senhor.<\/p>\n<p><strong>Deus que fala comigo, fala com voc\u00ea.<\/strong><\/p>\n<p>A vida precisa seguir a Palavra, \u00e9 pelos frutos Espirituais na vida que conhecemos aqueles que s\u00e3o levantados por Deus. O Evangelho n\u00e3o pode ser adocicado, por isso, essa gera\u00e7\u00e3o est\u00e1 cada vez mais adoecida porque estamos esquecendo de falar da cruz.<\/p>\n<p>N\u00f3s precisamos conhecer a B\u00edblia e a Doutrina da Igreja. Tudo para que sigamos a vontade de Deus e n\u00e3o ca\u00edamos no relativismo do nosso tempo.<\/p>\n<p>S\u00f3 identifica os falsos profetas aquele que conhece a Verdade.<\/p>\n<p>Voc\u00ea acredita que a Igreja Cat\u00f3lica \u00e9 a Igreja de Jesus Cristo!? Ent\u00e3o, permane\u00e7a fiel \u00e0 Sagrada Tradi\u00e7\u00e3o, \u00e0 Sagrada Escritura. Diga: \u201cEu morrerei fiel \u00e0 santa Igreja Cat\u00f3lica\u201d.<\/p>\n<p>Maranath\u00e1, vem Senhor Jesus!<\/p>\n<p><iframe loading=\"lazy\" title=\"Cuidado com os falsos profetas! (1 Jo 4, 1-6) Padre Roger Luis (09\/12\/2023)\" width=\"600\" height=\"338\" src=\"https:\/\/www.youtube.com\/embed\/v1_xxklmKtQ?feature=oembed&amp;rel=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cCuidado com os falsos profetas\u201d (1 Jo 4, 1-6) Nos tempos atuais, n\u00f3s precisamos assumir que somos de Deus. Precisamos ficar firmes, como se v\u00edssemos o invis\u00edvel. Aqueles que servem ao anticristo, tamb\u00e9m servem ao mundo que se op\u00f5e a&#8230;<\/p>\n","protected":false},"author":243,"featured_media":68767,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7],"tags":[],"modified_by":"aliane","_links":{"self":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/68766"}],"collection":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/users\/243"}],"replies":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/comments?post=68766"}],"version-history":[{"count":3,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/68766\/revisions"}],"predecessor-version":[{"id":68776,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/posts\/68766\/revisions\/68776"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media\/68767"}],"wp:attachment":[{"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/media?parent=68766"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/categories?post=68766"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/admin-canais.cancaonova.com\/eventos\/wp-json\/wp\/v2\/tags?post=68766"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}